{"id":1459667,"date":"2025-03-08T09:03:41","date_gmt":"2025-03-08T17:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/"},"modified":"2025-03-08T09:03:41","modified_gmt":"2025-03-08T17:03:41","slug":"daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","title":{"rendered":"Daniel Sabsay sobre Lijo: &#171;Es el m\u00e1s corrupto de Comodoro Py&#187;"},"content":{"rendered":"<p><strong>Daniel Sabsay<\/strong>, abogado habl\u00f3 este s\u00e1bado con <strong>CNN Radio<\/strong> sobre lo que sucedi\u00f3 con Ariel Lijo, uno de los jueces de la Corte Suprema propuestos en comisi\u00f3n por decreto.<\/p>\n<p>En de Ida y Vuelta con Laura Di Marco indic\u00f3:<strong> \u201cEs algo in\u00e9dito, yo no recuerdo que para la designaci\u00f3n de dos miembros<\/strong> de la corte se haya tomado tanto tiempo, es totalmente novedoso\u201d, dijo.<\/p>\n<p><strong>\u201cSiempre apoy\u00e9 la designaci\u00f3n de Garc\u00eda Mancilla porque es un gran constitucionalista, <\/strong>un tipo sumamente preparado, una gran persona, yo lo conozco muy bien, por el contrario, lo de Lijo es algo que me parece inconcebible\u201d, a\u00f1adi\u00f3.<\/p>\n<p>En esta l\u00ednea el abogado hizo una fuerte declaraci\u00f3n. \u201c<strong>Es el m\u00e1s corrupto de Comodoro Py, <\/strong>el tipo que es absolutamente m\u00e1s casta que \u00e9l, es imposible, as\u00ed que es inconcebible\u201d, continu\u00f3.<\/p>\n<p><strong>\u201cMilei es un hombre muy terco y muy empecinado, \u00e9l va para adelante aunque el asunto no funcione, <\/strong>sigue por el mismo camino y se embarra cada vez m\u00e1s\u201d, asegur\u00f3.<\/p>\n<p>Sabsay remarc\u00f3 que el presidente es un hombre que desprecia las instituciones democr\u00e1ticas<strong> \u201c\u00c9l es un an\u00e1logo capitalista que no cree en el Estado, no cree en el Estado es no creer en una constituci\u00f3n,<\/strong>  porque la constituci\u00f3n en un sistema democr\u00e1tico es la base de un Estado\u201d, complet\u00f3.<\/p>\n<p><strong>\u201cEntonces dentro de esa concepci\u00f3n a m\u00ed no me sorprende que \u00e9l quiera capturar la corte, <\/strong>creo que su propuesta, lo que \u00e9l quiere es tener una corte adicta\u201d, puntualiz\u00f3.<\/p>\n<p>Por \u00faltimo, el penalista dijo que hay una presi\u00f3n muy grande en contra de Lijo. \u201c<strong>Veo algo positivo de la sociedad. La difusi\u00f3n tan grande que se dio de los antecedentes, algo tambi\u00e9n sin precedentes<\/strong>, designaci\u00f3n de miembro de la Corte, hizo que el rechazo sea muy muy grande\u201d, cerr\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Daniel Sabsay, abogado habl\u00f3 este s\u00e1bado con CNN Radio sobre lo que sucedi\u00f3 con Ariel Lijo, uno de los jueces de la Corte Suprema propuestos en comisi\u00f3n por decreto. En de Ida y Vuelta con Laura Di Marco indic\u00f3: \u201cEs algo in\u00e9dito, yo no recuerdo que para la designaci\u00f3n de dos miembros de la corte [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459667","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Daniel Sabsay sobre Lijo: &quot;Es el m\u00e1s corrupto de Comodoro Py&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Daniel Sabsay sobre Lijo: &quot;Es el m\u00e1s corrupto de Comodoro Py&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Daniel Sabsay, abogado habl\u00f3 este s\u00e1bado con CNN Radio sobre lo que sucedi\u00f3 con Ariel Lijo, uno de los jueces de la Corte Suprema propuestos en comisi\u00f3n por decreto. En de Ida y Vuelta con Laura Di Marco indic\u00f3: \u201cEs algo in\u00e9dito, yo no recuerdo que para la designaci\u00f3n de dos miembros de la corte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-08T17:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Daniel Sabsay sobre Lijo: &#171;Es el m\u00e1s corrupto de Comodoro Py&#187;\",\"datePublished\":\"2025-03-08T17:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\"},\"wordCount\":342,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\",\"name\":\"Daniel Sabsay sobre Lijo: \\\"Es el m\u00e1s corrupto de Comodoro Py\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-08T17:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Daniel Sabsay sobre Lijo: &#171;Es el m\u00e1s corrupto de Comodoro Py&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Daniel Sabsay sobre Lijo: \"Es el m\u00e1s corrupto de Comodoro Py\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","og_locale":"es_ES","og_type":"article","og_title":"Daniel Sabsay sobre Lijo: \"Es el m\u00e1s corrupto de Comodoro Py\" - Noticias","og_description":"Daniel Sabsay, abogado habl\u00f3 este s\u00e1bado con CNN Radio sobre lo que sucedi\u00f3 con Ariel Lijo, uno de los jueces de la Corte Suprema propuestos en comisi\u00f3n por decreto. En de Ida y Vuelta con Laura Di Marco indic\u00f3: \u201cEs algo in\u00e9dito, yo no recuerdo que para la designaci\u00f3n de dos miembros de la corte [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","og_site_name":"Noticias","article_published_time":"2025-03-08T17:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/"},"author":{"name":"","@id":""},"headline":"Daniel Sabsay sobre Lijo: &#171;Es el m\u00e1s corrupto de Comodoro Py&#187;","datePublished":"2025-03-08T17:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/"},"wordCount":342,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","url":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","name":"Daniel Sabsay sobre Lijo: \"Es el m\u00e1s corrupto de Comodoro Py\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-08T17:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Daniel Sabsay sobre Lijo: &#171;Es el m\u00e1s corrupto de Comodoro Py&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Daniel Sabsay sobre Lijo: &#171;Es el m\u00e1s corrupto de Comodoro Py&#187;","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/08\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-08T17:03:41Z","datePublished":"2025-03-08T17:03:41Z","dateModified":"2025-03-08T17:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Daniel Sabsay sobre Lijo: &#171;Es el m\\u00e1s corrupto de Comodoro Py&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/08\\\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/08\\\/daniel-sabsay-sobre-lijo-es-el-mas-corrupto-de-comodoro-py\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-08T17:03:41Z\",\"datePublished\":\"2025-03-08T17:03:41Z\",\"dateModified\":\"2025-03-08T17:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459239,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/26\/es-constitucional-el-decreto-de-milei-que-nombra-a-lijo-y-garcia-mansilla-en-la-corte\/","url_meta":{"origin":1459667,"position":0},"title":"\u00bfEs constitucional? El decreto de Milei que nombra a Lijo y Garc\u00eda Mansilla en la Corte","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Andr\u00e9s Gil Dom\u00ednguez, Doctor y profesor en Derecho de la UBA, asegur\u00f3 este mi\u00e9rcoles en CNN Radio que \u201clo que acaba de hacer el presidente es de nulidad absoluta y es inconstitucional\u201d en el marco del decreto para designar a los jueces Ariel Lijo y Manuel Garc\u00eda Mansilla en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459240,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/26\/es-constitucional-el-decreto-de-milei-para-nombrar-a-lijo-y-garcia-mansilla-para-la-corte\/","url_meta":{"origin":1459667,"position":1},"title":"\u00bfEs constitucional? El decreto de Milei para nombrar a Lijo y Garc\u00eda Mansilla para la Corte","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Andr\u00e9s Gil Dom\u00ednguez, Doctor y profesor en Derecho de la UBA, asegur\u00f3 este mi\u00e9rcoles en CNN Radio que \u201clo que acaba de hacer el presidente es de nulidad absoluta y es inconstitucional\u201d en el marco del decreto para designar a los jueces Ariel Lijo y Manuel Garc\u00eda Mansilla en la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459224,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/26\/la-designacion-de-lijo-y-mansilla-da-tristeza-pense-que-el-gobierno-iba-a-recapacitar\/","url_meta":{"origin":1459667,"position":2},"title":"&#171;La designaci\u00f3n de Lijo y Mansilla da tristeza: pens\u00e9 que el gobierno iba a recapacitar&#187;","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Carolina Losada, senadora nacional por Juntos por el Cambio y vicepresidenta del Senado, asegur\u00f3 este mi\u00e9rcoles en CNN Radio que \u201cla designaci\u00f3n de Lijo y Mansilla da tristeza: pens\u00e9 que el Gobierno iba a recapacitar\u201d.\u201cNo es que el Senado estuvo durmiendo: se trabaj\u00f3, pero no se lograron acuerdos\u201d, explic\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459216,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/26\/monica-fein-javier-milei-busca-la-concentracion-de-todo-el-poder-y-quizas-la-impunidad\/","url_meta":{"origin":1459667,"position":3},"title":"M\u00f3nica Fein: Javier &#171;Milei busca la concentraci\u00f3n de todo el poder y, quiz\u00e1s, la impunidad&#187;","author":"","date":"febrero 26, 2025","format":false,"excerpt":"M\u00f3nica Fein, diputada nacional de Encuentro Federal por Santa Fe, se refiri\u00f3 a la designaci\u00f3n por decreto de Ariel Lijo y Manuel Gonz\u00e1lez Mansilla como integrantes de la Cortes Suprema de Justicia de la Naci\u00f3n y a la conformaci\u00f3n de una comisi\u00f3n investigadora en la c\u00e1mara baja del esc\u00e1ndalo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458688,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/13\/francisco-paoltroni-sobre-lijo-y-ficha-limpia-milei-y-cristina-son-complices-y-quieren-polarizar\/","url_meta":{"origin":1459667,"position":4},"title":"Francisco Paoltroni, sobre Lijo y Ficha Limpia: &#171;Milei y Cristina son c\u00f3mplices y quieren polarizar&#187;","author":"","date":"febrero 13, 2025","format":false,"excerpt":"El senador nacional por Libertad, Trabajo y Progreso, exLibertad Avanza, desliz\u00f3 este jueves en CNN Radio que hay un acuerdo entre el Gobierno nacional y el kirchnerismo: \u201cSon c\u00f3mplices y quieren polarizar\u201d.En La Ma\u00f1ana de CNN, Paoltroni remarc\u00f3 que \u201cel objetivo de estas maniobras es que Lijo ingrese a la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459226,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/26\/el-kirchnerismo-quiere-tener-una-participacion-en-la-corte\/","url_meta":{"origin":1459667,"position":5},"title":"Miguel \u00c1ngel Toma: &#171;El kirchnerismo quiere tener una participaci\u00f3n en la Corte&#187;","author":"","date":"febrero 26, 2025","format":false,"excerpt":"Miguel \u00c1ngel Toma, exministro de Justicia de la Naci\u00f3n, habl\u00f3 este mi\u00e9rcoles en CNN Radio sobre el decreto presidencial que designa a los jueces Ariel Lijo y Manuel Garc\u00eda Mansilla en la Corte Suprema y dijo que \u201chay una traba pol\u00edtica y otra que es de naturaleza judicial por los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459667","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459667"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459667\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459667"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459667"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459667"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}