{"id":1459686,"date":"2025-03-09T03:03:49","date_gmt":"2025-03-09T10:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/"},"modified":"2025-03-09T03:03:49","modified_gmt":"2025-03-09T10:03:49","slug":"hasta-donde-podria-llegar-jd-vance-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","title":{"rendered":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?"},"content":{"rendered":"<p>J. D. Vance es un tipo diferente de vicepresidente.<\/p>\n<p>No es el amo maquiav\u00e9lico de Washington que trabaja en las sombras, como Dick Cheney, ni el hombre de confianza en pol\u00edtica exterior, como George H. W. Bush o Joe Biden.<\/p>\n<p>En cambio, el joven Vance parece haberse convertido en la personificaci\u00f3n de las publicaciones m\u00e1s extremas de su jefe, Donald Trump, en las redes sociales. Su <a href=\"https:\/\/e.newsletters.cnn.com\/click?Ec3RlcGhlbi5jb2xsaW5zb25AY25uLmNvbQ\/CeyJtaWQiOiIxNzQxMzE3NDE1MDUwNThjMjFhODQwODkxIiwiY3QiOiJjbm4tZjgyOWMwMzIzNWEzZGM1MTgwMzEyYzFiNDgyYzU3OTQtMSIsInJkIjoiY25uLmNvbSJ9\/VaHR0cHM6Ly93d3cuY25uLmNvbS8yMDI1LzAzLzA0L3BvbGl0aWNzL3ZpZGVvL2pkLXZhbmNlLXplbGVuc2t5LW92YWwtb2ZmaWNlLW1lZXRpbmctaGFubml0eS1kaWd2aWQ\/SWkhfQ05OX2lfTmV3c19OREJBTjAzMDcyMDI1YzE1ODI4MDFiMQ\/LY24x\/qP3V0bV9tZWRpdW09ZW1haWwmdXRtX3NvdXJjZT1jbm5fTWVhbndoaWxlK01hcmNoKzcmYnRfZWU9MHpKc09wN2t2NCUyQmNXb2dISyUyQkIxYktOWSUyQmhWU1VTQSUyRkJGaU4lMkZaQSUyRnQ3UEoySlglMkZFYjNXR2J2UG5pMmJJOWc2JmJ0X3RzPTE3NDEzMTc0MTUwNTI\/gZ8plLw\/s9p75972746\">provocaci\u00f3n al presidente de Ucrania, Volodymyr Zelensky<\/a>, en la Oficina Oval, la semana pasada, encendi\u00f3 una crisis diplom\u00e1tica. Disfrut\u00f3 viajando a Munich para insultar a los aliados europeos de Estados Unidos. Y Vance fue noticia de primera plana en el Reino Unido despu\u00e9s de decir que Ucrania necesitaba mejores garant\u00edas de seguridad que las ofrecidas por \u201calg\u00fan pa\u00eds al azar que no ha librado una guerra en 30 o 40 a\u00f1os\u201d. Vance dijo m\u00e1s tarde que era \u201cabsurdamente deshonesto\u201d decir que estaba hablando de Gran Breta\u00f1a y Francia, pero esos fueron los \u00fanicos aliados que se ofrecieron p\u00fablicamente como voluntarios para una fuerza de paz en Ucrania.<\/p>\n<p>Vance sabe hacia d\u00f3nde sopla el viento en el Partido Republicano. Por eso abandon\u00f3 su desprecio por el presidente, despu\u00e9s de que <a href=\"https:\/\/www.cnn.com\/2024\/06\/13\/politics\/kfile-jd-vance-harsh-twitter-likes-trump-vice-president\/index.html\">en 2016 se preguntara<\/a> si Trump no ser\u00eda el Hitler de Estados Unidos. Ahora, en un partido que rinde culto a su l\u00edder, el vicepresidente es uno de los admiradores p\u00fablicos m\u00e1s destacados del presidente.<\/p>\n<p>Pero Vance es un personaje fascinante. Pas\u00f3 de una infancia dif\u00edcil en los Apalaches a las universidades de \u00e9lite de EE.UU., conocidas como Ivy League. Es sumamente inteligente, una de las razones por las que su posicionamiento pol\u00edtico se suele considerar evidencia de un c\u00e1lculo nefasto. Vance, quien sirvi\u00f3 brevemente como senador de Ohio, desprecia a los medios tradicionales y a las \u00e9lites de Washington, por lo que encaja perfectamente con el populismo de Trump. Tambi\u00e9n es un veterano de la Marina de EE.UU., por lo que deber\u00eda saber m\u00e1s sobre la contribuci\u00f3n de los aliados de Estados Unidos a la guerra contra el terrorismo. Y se hizo rico en Silicon Valley y tiene una relaci\u00f3n con los grandes barones de la tecnolog\u00eda que se han desplazado marcadamente hacia la derecha y han apoyado a Trump en su segundo mandato.<\/p>\n<p>El vicepresidente se hizo famoso con \u201cHillbilly Elegy\u201d, una autobiograf\u00eda sobre su infancia en zonas pobres de Ohio y Kentucky. El libro, publicado en 2016, explicaba c\u00f3mo la desindustrializaci\u00f3n foment\u00f3 la pobreza y la adicci\u00f3n a las drogas y una eventual reacci\u00f3n pol\u00edtica contra las pol\u00edticas de libre comercio globalizadas. Se convirti\u00f3 en una especie de manual para entender a los partidarios de Trump en su primer mandato.<\/p>\n<p>Teniendo en cuenta esos antecedentes, no sorprende que Vance haya presentado los argumentos m\u00e1s elocuentes de la campa\u00f1a a favor de una pol\u00edtica econ\u00f3mica que priorice a Estados Unidos. A sus 40 a\u00f1os, es un heredero potencial de Trump, aunque el presidente se neg\u00f3, curiosamente, a ungirle en una reciente entrevista con Fox News, pues no estaba dispuesto a pensar en ceder su trono tan pronto.<\/p>\n<p>Vance es el ep\u00edtome de lo que muchos europeos desde\u00f1an de Estados Unidos. Es un aislacionista que no ve ning\u00fan inter\u00e9s nacional vital en Ucrania. Su franqueza y su dejo de presunci\u00f3n irritan a muchos extranjeros, como tambi\u00e9n su apoyo a la ultraderecha europea, incluida la extremista AfD de Alemania. Un d\u00eda antes de enfrentarse a Zelensky en la Oficina Oval, reprendi\u00f3 a Keir Starmer por la libertad de expresi\u00f3n en el Reino Unido, aunque el primer ministro brit\u00e1nico le hizo callar.<\/p>\n<p>Como Vance es joven, ambicioso, ideol\u00f3gico y tiene un aparente resentimiento hacia los intelectuales del establishment, hay un vicepresidente al que s\u00ed nos recuerda: Richard Nixon.<\/p>\n<p>Cuando Nixon se uni\u00f3 a la candidatura de Dwight Eisenhower, en 1952, hab\u00eda pasado suficiente tiempo en el Senado como para tomar una taza de caf\u00e9, al igual que Vance. Y al igual que su sucesor del siglo XXI, era una nueva raza de ide\u00f3logo republicano: mientras que el vicepresidente actual reprende a los liberales \u201cwoke\u201d, Nixon acosaba a los supuestos comunistas que viv\u00edan en Estados Unidos. Y al igual que Vance, Nixon ten\u00eda la vista puesta en cosas m\u00e1s elevadas. Sus ambiciones y su inclinaci\u00f3n por el lado oscuro de la pol\u00edtica a veces causaron tensiones con su jefe m\u00e1s experimentado, un posible presagio de la relaci\u00f3n entre Trump y Vance.<\/p>\n<p>Nixon utiliz\u00f3 sus ocho a\u00f1os como vicepresidente como un curso intensivo sobre asuntos globales que fue clave para su \u00e9xito como estadista despu\u00e9s de que finalmente gan\u00f3 el gran cargo en 1968. Sin embargo, parece poco probable que Vance emule las largas odiseas globales de Nixon: tiene intereses pol\u00edticos en su pa\u00eds.<\/p>\n<p>Pero no subestimemos a Vance. Ha ascendido alto y r\u00e1pido. Pero \u00bflo llevar\u00e1 la arrogancia a volar demasiado cerca del Sol?<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J. D. Vance es un tipo diferente de vicepresidente. No es el amo maquiav\u00e9lico de Washington que trabaja en las sombras, como Dick Cheney, ni el hombre de confianza en pol\u00edtica exterior, como George H. W. Bush o Joe Biden. En cambio, el joven Vance parece haberse convertido en la personificaci\u00f3n de las publicaciones m\u00e1s [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459686","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance? - Noticias\" \/>\n<meta property=\"og:description\" content=\"J. D. Vance es un tipo diferente de vicepresidente. No es el amo maquiav\u00e9lico de Washington que trabaja en las sombras, como Dick Cheney, ni el hombre de confianza en pol\u00edtica exterior, como George H. W. Bush o Joe Biden. En cambio, el joven Vance parece haberse convertido en la personificaci\u00f3n de las publicaciones m\u00e1s [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-09T10:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?\",\"datePublished\":\"2025-03-09T10:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\"},\"wordCount\":882,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\",\"name\":\"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-09T10:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance? - Noticias","og_description":"J. D. Vance es un tipo diferente de vicepresidente. No es el amo maquiav\u00e9lico de Washington que trabaja en las sombras, como Dick Cheney, ni el hombre de confianza en pol\u00edtica exterior, como George H. W. Bush o Joe Biden. En cambio, el joven Vance parece haberse convertido en la personificaci\u00f3n de las publicaciones m\u00e1s [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-09T10:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/"},"author":{"name":"","@id":""},"headline":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?","datePublished":"2025-03-09T10:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/"},"wordCount":882,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","name":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-09T10:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"\u00bfHasta d\u00f3nde podr\u00eda llegar J. D. Vance?","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/hasta-donde-podria-llegar-jd-vance-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-09T10:03:49Z","datePublished":"2025-03-09T10:03:49Z","dateModified":"2025-03-09T10:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"\\u00bfHasta d\\u00f3nde podr\\u00eda llegar J. D. Vance?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/09\\\/hasta-donde-podria-llegar-jd-vance-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/09\\\/hasta-donde-podria-llegar-jd-vance-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-09T10:03:49Z\",\"datePublished\":\"2025-03-09T10:03:49Z\",\"dateModified\":\"2025-03-09T10:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451281,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/20\/hillbilly-una-elegia-rural-ideas-j-d-vance-orix\/","url_meta":{"origin":1459686,"position":0},"title":"AN\u00c1LISIS | Lo que dice y no dice la pel\u00edcula &#171;Hillbilly, una eleg\u00eda rural&#187; de las ideas pol\u00edticas de J. D. Vance","author":"","date":"julio 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Fiel adaptaci\u00f3n de \"Hillbilly Elegy\", el libro de memorias publicado en 2016, la pel\u00edcula estrenada en Netflix en 2020 y distribuida en espa\u00f1ol como \"Hillbilly, una eleg\u00eda rural\", reconstruye la infancia y temprana vida adulta del senador de Ohio James Dean Vance, candidato a la vicepresidencia por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451495,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/30\/j-d-vance-menosprecio-personas-sin-hijos-mujeres-gatos-trax\/","url_meta":{"origin":1459686,"position":1},"title":"No son solo las &#171;mujeres con gatos&#187;: J. D. Vance tiene un historial de menosprecio a las personas sin hijos","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN) -- El candidato republicano a la vicepresidencia, el senador J. D. Vance, tiene un historial haciendo comentarios despectivos hacia las personas sin hijos, seg\u00fan muestra una revisi\u00f3n de sus comentarios por parte de CNN KFile. Eso incluye sus ahora infames comentarios sobre las \"mujeres con gatos sin hijos\" en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459071,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/22\/vance-numero-dos-trump-trax\/","url_meta":{"origin":1459686,"position":2},"title":"De criticar a Zelensky a presionar a los senadores, Vance se consolida como el n\u00famero dos de Trump","author":"","date":"febrero 22, 2025","format":false,"excerpt":"En los \u00faltimos 10 d\u00edas el vicepresidente J. D. Vance puso sobre aviso al presidente de Ucrania, Volodymyr Zelensky, sacudi\u00f3 la confianza de aliados centenarios en Europa occidental durante su primer viaje al exterior, se traslad\u00f3 al Capitolio para ayudar en las delicadas conversaciones presupuestarias y realiz\u00f3 una en\u00e9rgica defensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451172,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/16\/jd-vance-trump-frases-hitler-trax\/","url_meta":{"origin":1459686,"position":3},"title":"Las frases de J. D. Vance contra Trump en el pasado: una vez pregunt\u00f3 si era \u201cel Hitler de Estados Unidos\u201d","author":"","date":"julio 16, 2024","format":false,"excerpt":"(CNN) -- El senador de Ohio J. D. Vance, elegido como aspirante a vicepresidente por Donald Trump, fue alguna vez un ferviente cr\u00edtico del expresidente. En mensajes privados, antes de la elecci\u00f3n de Trump, se pregunt\u00f3 si \u00e9l era el \u201cHitler de Estados Unidos\u201d y en 2017 dijo que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461526,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/23\/vance-propuesta-paz-rusia-ucrania-fronteras-trax\/","url_meta":{"origin":1459686,"position":4},"title":"Propuesta de paz entre Rusia y Ucrania incluye congelar fronteras &#171;de forma similar&#187; a como est\u00e1n ahora, dice Vance","author":"","date":"abril 23, 2025","format":false,"excerpt":"El vicepresidente J. D. Vance declar\u00f3 este mi\u00e9rcoles por la ma\u00f1ana que considera que uno de los pasos finales para alcanzar la paz entre Ucrania y Rusia es un acuerdo para congelar las fronteras territoriales \u201cen un nivel cercano\u201d a su situaci\u00f3n actual, lo que significa que cada parte tendr\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460785,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/03\/vance-musk-amigo-asesor-despues-doge-trax\/","url_meta":{"origin":1459686,"position":5},"title":"Vance dice que Musk seguir\u00e1 siendo asesor y amigo despu\u00e9s de que termine su funci\u00f3n como empleado especial del gobierno","author":"","date":"abril 3, 2025","format":false,"excerpt":"El vicepresidente de EE.UU. J. D. Vance afirm\u00f3 que Elon Musk seguir\u00e1 siendo su asesor y amigo, tanto suyo como del presidente Donald Trump, incluso despu\u00e9s de que finalice su periodo como funcionario especial del gobierno tras 130 d\u00edas.\u201cDOGE tiene mucho trabajo por hacer, y s\u00ed, ese trabajo continuar\u00e1 despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459686"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459686\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}