{"id":1459697,"date":"2025-03-09T14:04:02","date_gmt":"2025-03-09T21:04:02","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/"},"modified":"2025-03-09T14:04:02","modified_gmt":"2025-03-09T21:04:02","slug":"eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","title":{"rendered":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema"},"content":{"rendered":"<p>Cada d\u00eda la <a href=\"https:\/\/www.faa.gov\/air_traffic\/by_the_numbers\">vida de millones de viajeros<\/a> est\u00e1 literalmente en el aire, dependiendo de la agudeza de los controladores de tr\u00e1fico a\u00e9reo para orquestar maniobras a alta velocidad y ayudar a prevenir accidentes de avi\u00f3n.<\/p>\n<p>Sin embargo, la <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/04\/eeuu\/estados-unidos-controladores-trafico-aereo-trax\">escasez de controladores de tr\u00e1fico a\u00e9reo<\/a> es <a href=\"https:\/\/transportation.house.gov\/uploadedfiles\/03-04-2025_aviation_hearing_-_nick_daniels_-_testimony.pdf\">casi la peor en 30 a\u00f1os<\/a>, dijo la Asociaci\u00f3n Nacional de Controladores de Tr\u00e1fico A\u00e9reo, que representa a 10.800 ATC certificados en todo el pa\u00eds.<\/p>\n<p>La falta ha obligado a muchos a trabajar \u201cseis d\u00edas a la semana, 10 horas al d\u00eda, durante a\u00f1os seguidos\u201d, testific\u00f3 el presidente del sindicato, Nick Daniels, en una audiencia de una subcomisi\u00f3n de la C\u00e1mara de Representantes esta semana.<\/p>\n<p>Estados Unidos necesita m\u00e1s de 3.000 nuevos controladores de tr\u00e1fico a\u00e9reo para alcanzar un nivel adecuado de personal, dijo. Y los recientes incidentes de alto perfil han destacado la escasez y la carga de trabajo de los controladores de tr\u00e1fico a\u00e9reo exhaustos.<\/p>\n<p>\u201cLo que es nuevo \u2014o m\u00e1s problem\u00e1tico o com\u00fan ahora\u2014 es el uso de horas extra\u201d, dijo Michael McCormick, profesor y coordinador de gesti\u00f3n del tr\u00e1fico a\u00e9reo en la Universidad Embry-Riddle Aeronautical.<\/p>\n<p>\u201cDir\u00eda que las instalaciones m\u00e1s grandes son probablemente m\u00e1s problem\u00e1ticas en el uso de horas extra que las instalaciones m\u00e1s peque\u00f1as, justo donde menos lo deseas\u201d.<\/p>\n<p>En enero, un avi\u00f3n comercial y un helic\u00f3ptero militar <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/14\/eeuu\/altimetro-helicoptero-black-hawk-choco-avion-washington-trax\">colisionaron en el aire<\/a> cerca del Aeropuerto Nacional Ronald Reagan de Washington, un incidente que dej\u00f3 67 personas muertas. Aunque las autoridades no han identificado la causa de esa cat\u00e1strofe, CNN confirm\u00f3 que un controlador de tr\u00e1fico a\u00e9reo <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/29\/eeuu\/avion-pasajeros-estrella-rio-potomac-aeropuerto-reagan-washington-trax\">estaba cubriendo dos trabajos diferentes<\/a> en la torre: manejando tanto el tr\u00e1fico a\u00e9reo local como el tr\u00e1fico de helic\u00f3pteros en el \u00e1rea.<\/p>\n<p>Y los investigadores dijeron recientemente que un incidente que casi termina en colisi\u00f3n en 2023 fue causado por un controlador de tr\u00e1fico a\u00e9reo que fue distra\u00eddo por un tercer avi\u00f3n, aunque su informe no cit\u00f3 expl\u00edcitamente escasez de personal o agotamiento.<\/p>\n<p>El gobierno federal anunci\u00f3 recientemente aumentos salariales para nuevos controladores de tr\u00e1fico a\u00e9reo y procesos de contrataci\u00f3n m\u00e1s eficientes. Pero cualquier persona mayor de 31 a\u00f1os es muy vieja para postularse, lo que limita el grupo de aspirantes. Y la gran mayor\u00eda de los controladores se ven obligados a dejar sus trabajos una d\u00e9cada antes de la <a href=\"https:\/\/www.ssa.gov\/benefits\/retirement\/planner\/agereduction.html\">edad de jubilaci\u00f3n est\u00e1ndar.<\/a><\/p>\n<p>Los solicitantes de control de tr\u00e1fico a\u00e9reo deben tener menos de 31 a\u00f1os para poder trabajar los 20 o 25 a\u00f1os obligatorios necesarios para calificar para pensiones antes de su edad de jubilaci\u00f3n obligatoria de 56 a\u00f1os, dijo un portavoz de la FAA.<\/p>\n<p>Aunque ese l\u00edmite de edad puede parecer joven, los ATC deben tener una incre\u00edble resistencia f\u00edsica y agudeza mental, dijo McCormick.<\/p>\n<p>\u201cCuando comienzas en una instalaci\u00f3n de control de tr\u00e1fico a\u00e9reo, tienes que memorizar mucho\u201d, dijo McCormick.<\/p>\n<p>\u201cTienes que memorizar lo que se conoce como el mapa de radar. Tienes que saber qu\u00e9 significa cada punto y l\u00ednea de guiones en el mapa. Tienes que memorizar c\u00f3mo est\u00e1 sectorizado el espacio a\u00e9reo. As\u00ed que piensa en Tetris. Hay m\u00faltiples capas y formas que encajan en un rompecabezas. As\u00ed es el espacio a\u00e9reo tambi\u00e9n\u201d.<\/p>\n<p>Sin embargo, este rompecabezas estilo Tetris est\u00e1 \u201cen tres dimensiones. As\u00ed que tienes que memorizar los l\u00edmites geogr\u00e1ficos de todos los sectores y las limitaciones de altitud\u201d, dijo McCormick.<\/p>\n<p>La mayor\u00eda de los controladores de tr\u00e1fico a\u00e9reo no solo monitorean un aeropuerto. Muchos hacen seguimiento a docenas de otros aeropuertos regionales para asegurarse de que los aviones mantengan una distancia segura entre s\u00ed.<\/p>\n<p>En el aeropuerto principal de Filadelfia, \u201ctambi\u00e9n hay 72 aeropuertos sat\u00e9lites en el espacio a\u00e9reo que tambi\u00e9n tienes que conocer\u201d, dijo McCormick, quien trabaj\u00f3 en la torre de control de tr\u00e1fico de ese aeropuerto.<\/p>\n<p>\u201cProporcionas servicios de control de aproximaci\u00f3n a todos esos aeropuertos tambi\u00e9n. As\u00ed que todo eso necesita ser memorizado\u2026 no puedes perder tiempo y energ\u00eda buscando algo o tratando de recordar algo\u201d.<\/p>\n<p>Los desaf\u00edos cognitivos se intensifican con la edad y cuando los controladores de tr\u00e1fico a\u00e9reo se trasladan a aeropuertos m\u00e1s grandes, oblig\u00e1ndolos a memorizar significativamente m\u00e1s datos y rastrear m\u00e1s aeropuertos regionales, dijo McCormick.<\/p>\n<p>El jefe del Departamento de Eficiencia Gubernamental, Elon Musk, ha promocionado la reducci\u00f3n de empleos gubernamentales en una variedad de departamentos. Pero recientemente pidi\u00f3 a los controladores de tr\u00e1fico a\u00e9reo jubilados que consideren volver al trabajo.<\/p>\n<p>\u201cHay una escasez de controladores de tr\u00e1fico a\u00e9reo de primer nivel\u201d, <a href=\"https:\/\/x.com\/elonmusk\/status\/1895136616441905228?s=46&#038;t=alBcPjoVzafXo5SWnDaKjw\">public\u00f3 Musk en X.<\/a> \u201cSi te has jubilado, pero est\u00e1s abierto a volver al trabajo, por favor considera hacerlo\u201d.<\/p>\n<p>Pero es poco probable que los jubilados regresen a las torres de control debido a una ley federal que <a href=\"https:\/\/uscode.house.gov\/view.xhtml?req=granuleid:USC-prelim-title5-section8335&#038;num=0&#038;edition=prelim\">requiere que los controladores de tr\u00e1fico a\u00e9reo se jubilen a los 56 a\u00f1os.<\/a><\/p>\n<p>En casos raros, los ATC pueden obtener excepciones de un a\u00f1o para seguir trabajando hasta los 60 a\u00f1os, si muestran una fuerte capacidad mental y f\u00edsica, dijo McCormick. Y los ATC a\u00fan pueden trabajar en otros lugares despu\u00e9s de su jubilaci\u00f3n obligatoria del control de tr\u00e1fico a\u00e9reo.<\/p>\n<p>Pero muchos eligen jubilarse a los 56 a\u00f1os \u2014si no antes\u2014 debido a las generosas pensiones, dijo McCormick.<\/p>\n<p>\u201cA diferencia de los empleados federales tradicionales que necesitan 30 a\u00f1os de servicio para jubilarse, los controladores de tr\u00e1fico a\u00e9reo pueden <a href=\"https:\/\/www.faa.gov\/atc-hiring\">jubilarse a los 50 a\u00f1os con al menos 20 a\u00f1os de servicio<\/a> o a cualquier edad con al menos 25 a\u00f1os\u201d, dijo la FAA.<\/p>\n<p>\u201cLa anualidad de jubilaci\u00f3n es un ingreso garantizado para una persona durante sus a\u00f1os de jubilaci\u00f3n. Los controladores de tr\u00e1fico a\u00e9reo reciben una anualidad <a href=\"https:\/\/www.opm.gov\/retirement-center\/fers-information\/computation\/\">m\u00e1s generosa que los empleados federales tradicionales<\/a>\u201d.<\/p>\n<p>Pero dada la escasez de controladores de tr\u00e1fico a\u00e9reo, McCormick recomienda estudiar si ser\u00eda seguro aumentar la edad de jubilaci\u00f3n obligatoria para permitir que aquellos que todav\u00eda est\u00e1n mental y f\u00edsicamente en forma trabajen m\u00e1s all\u00e1 de los 56 a\u00f1os si as\u00ed lo desean.<\/p>\n<p>\u201cEs necesario realizar investigaciones financiadas sobre \u2018\u00bfes todav\u00eda v\u00e1lida esa edad de jubilaci\u00f3n obligatoria?\u2019 Porque eso ha estado en vigor desde la d\u00e9cada de 1970\u201d, dijo McCormick.<\/p>\n<p>\u201cY desde ese tiempo, nunca ha habido ning\u00fan esfuerzo para validar: \u00bfEs bueno? \u00bfNo es bueno? \u00bfHa cambiado el proceso de envejecimiento con el tiempo?\u201d.<\/p>\n<p>Dado que las nuevas contrataciones a menudo requieren a\u00f1os de capacitaci\u00f3n, \u201csi puedes extender a las personas que son elegibles para jubilarse (de) uno a cinco a\u00f1os, eso le da una oportunidad a la FAA de reconstruir su fuerza laboral\u201d, dijo McCormick.<\/p>\n<p>El Departamento de Transporte de EE.UU. no ha respondido a por qu\u00e9 se eligi\u00f3 la edad espec\u00edfica de 56 a\u00f1os o si est\u00e1 considerando ajustar los l\u00edmites de edad.<\/p>\n<p>La escasez de controladores de tr\u00e1fico a\u00e9reo no se debe a la falta de solicitantes. Es la falta de solicitantes calificados que cumplen con los rigurosos requisitos de la FAA.<\/p>\n<p>\u201cMenos del 10% de todos los solicitantes cumplen con estos requisitos y son aceptados en el programa de capacitaci\u00f3n\u201d, dijo la FAA.<\/p>\n<p>Algunos solicitantes no pasan las<a href=\"https:\/\/www.faa.gov\/air-traffic-controller-qualifications\"> evaluaciones m\u00e9dicas y de seguridad.<\/a> Y muchos no logran completar la rigurosa academia y capacitaci\u00f3n.<\/p>\n<p>\u201cEs un proceso de entrenamiento riguroso\u201d, <a href=\"https:\/\/www.natca.org\/2025\/02\/02\/president-nick-daniels-on-cnn-newsroom-saturday\/\">dijo Daniels a CNN<\/a> el mes pasado. \u201cAs\u00ed que no es que hoy podr\u00edamos salir y contratar a los 3.600. Se necesitan de dos a tres a\u00f1os para que un controlador est\u00e9 calificado\u2026 solo para ingresar al trabajo\u201d.<\/p>\n<p>Despu\u00e9s de eso, hay \u201cm\u00faltiples puntos donde pueden fallar en ser un controlador de tr\u00e1fico a\u00e9reo: todo, desde la academia hasta el entrenamiento de simulaci\u00f3n local y luego, eventualmente, hablar con aeronaves por su cuenta\u201d.<\/p>\n<p>Con el actual d\u00e9ficit de personal, alrededor del 41% de los controladores de tr\u00e1fico a\u00e9reo deben trabajar semanas de 60 horas, dijo el sindicato.<\/p>\n<p>El per\u00edodo de descanso obligatorio entre turnos aument\u00f3 de ocho horas a 10 horas, aunque eso incluye el tiempo para regresar a casa.<\/p>\n<p>Sin embargo, no hay \u00f3rdenes que exijan dos d\u00edas libres al final de las semanas laborales, lo que significa que muchos ATC solo tienen un fin de semana de 24 horas antes de comenzar otra semana laboral.<\/p>\n<p>Si bien los controladores reciben pago adicional por horas extras obligatorias, las agotadoras semanas de trabajo de 60 horas pueden impulsar la deserci\u00f3n. Y cuanto m\u00e1s tiempo persistan las escaseces de personal, m\u00e1s tiempo algunos ATC corren el riesgo de agotamiento y <em>burnout<\/em>.<\/p>\n<p>\u201cLa tasa de contrataci\u00f3n pasada no se mantuvo al d\u00eda con la deserci\u00f3n natural de trabajadores que abandonan la profesi\u00f3n debido a la jubilaci\u00f3n u otras presiones del trabajo\u201d, dijo Galen Munroe, un portavoz del sindicato de ATC.<\/p>\n<p>McCormick atribuye la escasez continua a la \u201cincapacidad para contratar y entrenar controladores debido a cosas como el covid-19, la recesi\u00f3n, cierres del gobierno\u201d.<\/p>\n<p>El n\u00famero de controladores de tr\u00e1fico a\u00e9reo comenz\u00f3 a caer dr\u00e1sticamente alrededor de 2013, despu\u00e9s de un cierre gubernamental, dijo McCormick.<\/p>\n<p>Desde entonces, cada vez que el gobierno se ha cerrado, el entrenamiento y la contrataci\u00f3n de controladores de tr\u00e1fico a\u00e9reo se han detenido abruptamente. Los reclutas en la academia de formaci\u00f3n de la FAA en Oklahoma City deben ser enviados a casa.<\/p>\n<p>Ahora, los expertos temen que un posible cierre del gobierno el 14 de marzo empeore la escasez.<\/p>\n<p>\u201cSi hay un cierre del gobierno el 14 de marzo, va a desordenar nuestra contrataci\u00f3n y entrenamiento y control\u201d, dijo McCormick.<\/p>\n<p>Para combatir la escasez, el secretario de Transporte Sean Duffy anunci\u00f3 \u201c<a href=\"https:\/\/www.faa.gov\/newsroom\/us-transportation-secretary-sean-p-duffy-announces-air-traffic-controller-hiring\">un nuevo plan para impulsar la contrataci\u00f3n<\/a> de controladores de tr\u00e1fico a\u00e9reo\u201d.<\/p>\n<p>La ventana de contrataci\u00f3n actual est\u00e1 abierta hasta el 17 de marzo, \u201cy estamos haciendo que sea m\u00e1s eficiente que nunca aplicar y m\u00e1s asequible comenzar la capacitaci\u00f3n\u201d, dijo la FAA.<\/p>\n<p>El salario inicial durante la capacitaci\u00f3n en la academia aumentar\u00e1 de US$ 17,61 por hora a US$ 22,61, dijo la agencia. \u201cEl salario contin\u00faa aumentando a medida que adquieres m\u00e1s experiencia y obtienes certificaciones profesionales\u201d, dijo la FAA.<\/p>\n<p>\u201cEn tres a\u00f1os despu\u00e9s de graduarse de la Academia, el controlador profesional certificado promedio gana m\u00e1s de US$ 160.000 al a\u00f1o\u201d.<\/p>\n<p>Y el antiguo proceso de contrataci\u00f3n de ocho pasos, que puede durar m\u00e1s de un a\u00f1o, est\u00e1 siendo reemplazado por un m\u00e9todo de <a href=\"https:\/\/www.faa.gov\/atc-hiring\">contrataci\u00f3n m\u00e1s r\u00e1pido de cinco pasos.<\/a> Por ejemplo, la FAA ahora puede trabajar para procesar los permisos m\u00e9dicos y de seguridad al mismo tiempo, en lugar de esperar a que uno termine antes de comenzar el otro.<\/p>\n<p>El proceso simplificado \u201cacelerar\u00e1 el tiempo de contrataci\u00f3n para estos puestos cr\u00edticos al reducir m\u00e1s de cuatro meses del viejo proceso\u201d.<\/p>\n<p>La FAA dijo que ha logrado avances en el \u00faltimo a\u00f1o, <a href=\"https:\/\/www.faa.gov\/newsroom\/faa-hits-air-traffic-controller-hiring-goal\">superando su meta de contratar a 1.800 controladores de tr\u00e1fico a\u00e9reo <\/a>en 2024, el n\u00famero m\u00e1s alto en casi una d\u00e9cada.<\/p>\n<p>McCormick dijo que la FAA podr\u00eda hacer m\u00e1s para interesar a los j\u00f3venes en convertirse en controladores de tr\u00e1fico a\u00e9reo.<\/p>\n<p>\u201cCreo que deben comenzar a acercarse m\u00e1s a los estudiantes de secundaria y hacer reclutamiento m\u00e1s intenso a una edad m\u00e1s joven\u201d, coment\u00f3.<\/p>\n<p>Pero la escasez continua \u2014y la deserci\u00f3n interminable\u2014 significa que el problema no se resolver\u00e1 r\u00e1pidamente.<\/p>\n<p>\u201cVa a tomar tiempo\u201d, dijo. \u201cLlevar\u00e1 a\u00f1os llenar esa brecha\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cada d\u00eda la vida de millones de viajeros est\u00e1 literalmente en el aire, dependiendo de la agudeza de los controladores de tr\u00e1fico a\u00e9reo para orquestar maniobras a alta velocidad y ayudar a prevenir accidentes de avi\u00f3n. Sin embargo, la escasez de controladores de tr\u00e1fico a\u00e9reo es casi la peor en 30 a\u00f1os, dijo la Asociaci\u00f3n [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459697","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cada d\u00eda la vida de millones de viajeros est\u00e1 literalmente en el aire, dependiendo de la agudeza de los controladores de tr\u00e1fico a\u00e9reo para orquestar maniobras a alta velocidad y ayudar a prevenir accidentes de avi\u00f3n. Sin embargo, la escasez de controladores de tr\u00e1fico a\u00e9reo es casi la peor en 30 a\u00f1os, dijo la Asociaci\u00f3n [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-09T21:04:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema\",\"datePublished\":\"2025-03-09T21:04:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\"},\"wordCount\":2046,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\",\"name\":\"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-09T21:04:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","og_locale":"es_ES","og_type":"article","og_title":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema - Noticias","og_description":"Cada d\u00eda la vida de millones de viajeros est\u00e1 literalmente en el aire, dependiendo de la agudeza de los controladores de tr\u00e1fico a\u00e9reo para orquestar maniobras a alta velocidad y ayudar a prevenir accidentes de avi\u00f3n. Sin embargo, la escasez de controladores de tr\u00e1fico a\u00e9reo es casi la peor en 30 a\u00f1os, dijo la Asociaci\u00f3n [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-09T21:04:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/"},"author":{"name":"","@id":""},"headline":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema","datePublished":"2025-03-09T21:04:02+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/"},"wordCount":2046,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","name":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-09T21:04:02+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"EE.UU. tiene dificultades para contratar controladores de tr\u00e1fico a\u00e9reo y un l\u00edmite de edad agravar\u00eda el problema","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/09\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-09T21:04:02Z","datePublished":"2025-03-09T21:04:02Z","dateModified":"2025-03-09T21:04:02Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"EE.UU. tiene dificultades para contratar controladores de tr\\u00e1fico a\\u00e9reo y un l\\u00edmite de edad agravar\\u00eda el problema\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/09\\\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/09\\\/eeuu-dificultades-contratar-controladores-trafico-aereo-problema-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-09T21:04:02Z\",\"datePublished\":\"2025-03-09T21:04:02Z\",\"dateModified\":\"2025-03-09T21:04:02Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1458072,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/01\/31\/accidente-washington-controlador-torre-trax\/","url_meta":{"origin":1459697,"position":0},"title":"En el momento del accidente en Washington, un controlador estaba trabajando en dos posiciones de torre, dice una fuente","author":"","date":"enero 31, 2025","format":false,"excerpt":"Hab\u00eda un controlador de tr\u00e1fico a\u00e9reo trabajando en dos posiciones de torre diferentes en el momento de la colisi\u00f3n la noche de este mi\u00e9rcoles, seg\u00fan le dijo a CNN una fuente de control de tr\u00e1fico a\u00e9reo.La fuente describe la configuraci\u00f3n, que ten\u00eda a una persona manejando tanto el tr\u00e1fico local\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467853,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/10\/29\/control-trafico-aereo-incierto-cierre-gobierno-trax\/","url_meta":{"origin":1459697,"position":1},"title":"El futuro del control del tr\u00e1fico a\u00e9reo se vuelve m\u00e1s incierto a medida que contin\u00faa el cierre del Gobierno federal","author":"","date":"octubre 29, 2025","format":false,"excerpt":"El impacto del cierre del Gobierno federal en el sistema de control del tr\u00e1fico a\u00e9reo en Estados Unidos podr\u00eda extenderse mucho m\u00e1s all\u00e1 de la reapertura del Gobierno.Desde redundancias de seguridad y esfuerzos de modernizaci\u00f3n hasta la capacitaci\u00f3n de futuros controladores y la retenci\u00f3n del mejor personal, gran parte del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458235,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/04\/estados-unidos-controladores-trafico-aereo-trax\/","url_meta":{"origin":1459697,"position":2},"title":"EE.UU. necesita desesperadamente m\u00e1s controladores de tr\u00e1fico a\u00e9reo. Entonces, \u00bfpor qu\u00e9 es tan dif\u00edcil contratarlos?","author":"","date":"febrero 4, 2025","format":false,"excerpt":"El sistema de control de tr\u00e1fico a\u00e9reo de Estados Unidos ha estado sometido a una presi\u00f3n casi insostenible debido a una escasez de personal que lleva d\u00e9cadas. Esto est\u00e1 causando problemas no solo para los controladores de tr\u00e1fico a\u00e9reo que a\u00fan permanecen, sino tambi\u00e9n para el p\u00fablico que viaja en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467718,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/10\/24\/cierre-gobierno-retrasos-vuelos-viajes-seguridad-trax\/","url_meta":{"origin":1459697,"position":3},"title":"El prolongado cierre del Gobierno provoca retrasos en vuelos y hace que los viajes a\u00e9reos sean cada d\u00eda &#171;menos seguros&#187;","author":"","date":"octubre 24, 2025","format":false,"excerpt":"Cada d\u00eda del cierre del Gobierno federal, los controladores de tr\u00e1fico a\u00e9reo que se reportan enfermos est\u00e1n causando demoras en los vuelos, dijo este viernes el secretario de Transporte, Sean Duffy.\u201cEs diferente cada d\u00eda\u201d, dijo a los periodistas en una conferencia de prensa en el Aeropuerto Internacional de Filadelfia. \u201cEn\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472573,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/26\/colision-aeropuerto-laguardia-carga-controladores-aereos-trax\/","url_meta":{"origin":1459697,"position":4},"title":"Colisi\u00f3n mortal en el aeropuerto de LaGuardia revela la &#171;intensa carga de trabajo&#187; de los controladores a\u00e9reos en EE.UU.","author":"","date":"marzo 26, 2026","format":false,"excerpt":"Tras la colisi\u00f3n mortal esta semana en el aeropuerto de LaGuardia, en Nueva York, han resurgido las preocupaciones sobre cu\u00e1nta carga de trabajo puede soportar un solo controlador de tr\u00e1fico a\u00e9reo.En ocasiones, los controladores de la torre son responsables de los aviones que se preparan para despegar y tambi\u00e9n pueden\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456021,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/11\/21\/faa-ralentizar-trafico-aereo-feriado-accion-gracias-trax\/","url_meta":{"origin":1459697,"position":5},"title":"La FAA podr\u00eda ralentizar el tr\u00e1fico a\u00e9reo durante el per\u00edodo de Acci\u00f3n de Gracias en EE.UU.","author":"","date":"noviembre 21, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 La Administraci\u00f3n Federal de Aviaci\u00f3n de Estados Unidos (FAA, por sus siglas en ingl\u00e9s) podr\u00eda verse obligada a reducir la velocidad del tr\u00e1fico a\u00e9reo durante los momentos de mayor afluencia de viajes en vacaciones debido a la escasez de personal de controladores a\u00e9reos, especialmente en el noreste.El administrador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459697","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459697"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459697\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459697"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459697"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459697"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}