{"id":1459749,"date":"2025-03-10T18:03:49","date_gmt":"2025-03-11T01:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/"},"modified":"2025-03-10T18:03:49","modified_gmt":"2025-03-11T01:03:49","slug":"incautan-metanfetamina-botellas-agua-mineral-texas-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","title":{"rendered":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas"},"content":{"rendered":"<p>En una operaci\u00f3n conjunta entre M\u00e9xico y Estados Unidos, autoridades fronterizas incautaron m\u00e1s de una tonelada de metanfetamina l\u00edquida en botellas de agua mineral en el Puente Internacional Roma, Texas.<\/p>\n<p>La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) de M\u00e9xico inform\u00f3 este lunes en un comunicado que, como parte de la Operaci\u00f3n Frontera Norte, integrantes de la Secretar\u00eda de la Defensa Nacional (Sedena), la Secretar\u00eda de Marina (Semar), la Fiscal\u00eda General de la Rep\u00fablica (FGR), la Guardia Nacional (GN) y la propia SSPC, en coordinaci\u00f3n con la Oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos (CBP, por sus siglas en ingl\u00e9s), detuvieron a un hombre que transportaba la droga.<\/p>\n<p>Seg\u00fan el comunicado, la incautaci\u00f3n se llev\u00f3 a cabo bajo el procedimiento de Despacho Conjunto entre las aduanas de Ciudad Miguel Alem\u00e1n, Tamaulipas, y Roma, Texas.<\/p>\n<p>Durante la inspecci\u00f3n de un tractocami\u00f3n que transportaba chiles, papas, cebollas y botellas de agua mineral, las autoridades detectaron que 1.632 botellas no conten\u00edan gas.<\/p>\n<p>\u201cSe les realiz\u00f3 un an\u00e1lisis con el equipo de CBP, lo que dio resultado positivo a metanfetamina, con un peso estimado de 1.028,98 kilos\u201d, seg\u00fan el comunicado.<\/p>\n<p>La CBP estim\u00f3 que el valor de la droga incautada supera los US$ 20 millones.  Por su parte, la SSPC calcul\u00f3 que la afectaci\u00f3n econ\u00f3mica a la delincuencia organizada asciende a 302.9 millones de pesos (casi US$ 15 millones).<\/p>\n<p>\u201cEsta enorme incautaci\u00f3n de metanfetamina ilustra el trabajo fenomenal que nuestros oficiales de CBP realizan todos los d\u00edas para mantener seguras nuestras fronteras (\u2026) Nuestros oficiales utilizaron sus habilidades de inspecci\u00f3n, perros detectores y tecnolog\u00eda para identificar y decomisar esta importante carga de metanfetamina\u201d, dijo el Director del Puerto de Entrada Roma Andr\u00e9s Guerra.<\/p>\n<p>El conductor del tractocami\u00f3n fue detenido y, junto con la droga asegurada, puesto a disposici\u00f3n de las autoridades estadounidenses.<\/p>\n<p>Seg\u00fan el comunicado publicado por las autoridades mexicanas, el Despacho Conjunto es un programa de cooperaci\u00f3n bilateral que consiste en la revisi\u00f3n de mercanc\u00edas entre autoridades de M\u00e9xico y Estados Unidos en un solo sitio y de manera simult\u00e1nea.<\/p>\n<p>\u201cSu objetivo es simplificar los procedimientos aduaneros y fortalecer la seguridad de ambos pa\u00edses. Actualmente, se realiza en 14 de los 44 puentes internacionales de la frontera norte y en dos de los seis pasos ferroviarios\u201d dice el comunicado.<\/p>\n<p>A lo largo de los a\u00f1os, las autoridades han descubierto m\u00e9todos del crimen organizado para introducir drogas a Estados Unidos como el uso de t\u00faneles sofisticados equipados con iluminaci\u00f3n y ventilaci\u00f3n, adem\u00e1s de drogas ocultas en productos como aguacate, nopales y cocos.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En una operaci\u00f3n conjunta entre M\u00e9xico y Estados Unidos, autoridades fronterizas incautaron m\u00e1s de una tonelada de metanfetamina l\u00edquida en botellas de agua mineral en el Puente Internacional Roma, Texas. La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) de M\u00e9xico inform\u00f3 este lunes en un comunicado que, como parte de la Operaci\u00f3n Frontera Norte, integrantes [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459749","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas - Noticias\" \/>\n<meta property=\"og:description\" content=\"En una operaci\u00f3n conjunta entre M\u00e9xico y Estados Unidos, autoridades fronterizas incautaron m\u00e1s de una tonelada de metanfetamina l\u00edquida en botellas de agua mineral en el Puente Internacional Roma, Texas. La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) de M\u00e9xico inform\u00f3 este lunes en un comunicado que, como parte de la Operaci\u00f3n Frontera Norte, integrantes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T01:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas\",\"datePublished\":\"2025-03-11T01:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\"},\"wordCount\":492,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\",\"name\":\"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-11T01:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas - Noticias","og_description":"En una operaci\u00f3n conjunta entre M\u00e9xico y Estados Unidos, autoridades fronterizas incautaron m\u00e1s de una tonelada de metanfetamina l\u00edquida en botellas de agua mineral en el Puente Internacional Roma, Texas. La Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC) de M\u00e9xico inform\u00f3 este lunes en un comunicado que, como parte de la Operaci\u00f3n Frontera Norte, integrantes [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-11T01:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/"},"author":{"name":"","@id":""},"headline":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas","datePublished":"2025-03-11T01:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/"},"wordCount":492,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","name":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-11T01:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Incautan m\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/10\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-11T01:03:49Z","datePublished":"2025-03-11T01:03:49Z","dateModified":"2025-03-11T01:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Incautan m\\u00e1s de una tonelada de metanfetamina en botellas de agua mineral en el Puente Internacional Roma, Texas\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/10\\\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/10\\\/incautan-metanfetamina-botellas-agua-mineral-texas-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-11T01:03:49Z\",\"datePublished\":\"2025-03-11T01:03:49Z\",\"dateModified\":\"2025-03-11T01:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471648,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/25\/detencion-hacha-operador-cjng-tlaxcala-mencho-orix\/","url_meta":{"origin":1459749,"position":0},"title":"M\u00e9xico captura a &#171;El Hacha&#187;, supuesto operador clave del CJNG en Tlaxcala, d\u00edas despu\u00e9s de la muerte del Mencho","author":"","date":"febrero 25, 2026","format":false,"excerpt":"Las autoridades mexicanas detuvieron este mi\u00e9rcoles a Isaac Moreno Romero, alias \u201cEl Hacha\u201d, se\u00f1alado como l\u00edder de una c\u00e9lula del C\u00e1rtel Jalisco Nueva Generaci\u00f3n (CJNG) con presencia en el estado de Tlaxcala, en el centro de M\u00e9xico, y vinculado con secuestros, extorsiones, homicidios y tr\u00e1fico ilegal de combustibles, confirm\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462476,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/17\/doce-muertos-nueve-detenidos-operativo-michoacan-orix\/","url_meta":{"origin":1459749,"position":1},"title":"Doce muertos y nueve detenidos en operativo de seguridad en Michoac\u00e1n, al suroeste de M\u00e9xico","author":"","date":"mayo 17, 2025","format":false,"excerpt":"Doce personas murieron y nueve m\u00e1s fueron detenidas en un operativo de seguridad realizado por fuerzas federales en el estado de Michoac\u00e1n, al suroeste de M\u00e9xico, inform\u00f3 este s\u00e1bado la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC).Los hechos ocurrieron en el poblado de Huitzontla, al que autoridades acudieron tras recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457458,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/01\/12\/gobierno-mexico-tunel-frontera-ee-uu-orix\/","url_meta":{"origin":1459749,"position":2},"title":"Gobierno de M\u00e9xico reporta hallazgo de t\u00fanel que conecta con la frontera de EE.UU.","author":"","date":"enero 12, 2025","format":false,"excerpt":"La Secretar\u00eda de Seguridad de M\u00e9xico inform\u00f3 sobre el hallazgo, en la frontera de Ciudad Ju\u00e1rez, de un t\u00fanel con direcci\u00f3n a Estados Unidos. El anuncio fue realizado el pasado viernes a trav\u00e9s de un comunicado publicado en la p\u00e1gina web del organismo.El reporte a\u00f1ade que fue un operativo conjunto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452011,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/08\/20\/patrulla-fronteriza-ee-uu-decomisa-sandias-falsas-metanfetamina-valuadas-us-5-millones-orix\/","url_meta":{"origin":1459749,"position":3},"title":"Patrulla Fronteriza de EE.UU. decomisa sand\u00edas falsas con metanfetamina valuada en US$ 5 millones","author":"","date":"agosto 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La oficina de Aduanas y Protecci\u00f3n Fronteriza de Estados Unidos inform\u00f3 que incaut\u00f3 dos toneladas de metanfetamina valuada en US$ 5 millones que intentaba ser introducida a territorio estadounidense en envoltorios que asemejaban sand\u00edas, de acuerdo con un comunicado publicado este martes.Un hallazgo picante: agentes de aduana\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451446,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/07\/26\/mayo-zambada-asi-se-entero-gobierno-mexico-detencion-joaquin-guzman-orix\/","url_meta":{"origin":1459749,"position":4},"title":"As\u00ed se enter\u00f3 el Gobierno mexicano de la detenci\u00f3n de Ismael &#171;El Mayo&#187; Zambada y Joaqu\u00edn Guzm\u00e1n","author":"","date":"julio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La secretaria de Seguridad y Protecci\u00f3n Ciudadana de M\u00e9xico Rosa Icela Rodr\u00edguez confirm\u00f3 que el Gobierno de ese pa\u00eds no particip\u00f3 en la detenci\u00f3n de Ismael \"El Mayo\" Zambada y de Joaqu\u00edn Guzm\u00e1n L\u00f3pez. Rodr\u00edguez present\u00f3 un informe en la conferencia de prensa matutina del presidente Andr\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469718,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/01\/detienen-culiacan-pedro-insunza-noriega-sagitario-orix\/","url_meta":{"origin":1459749,"position":5},"title":"Detienen en Culiac\u00e1n a Pedro Insunza Noriega, alias &#171;Sagitario&#187;, acusado de narcoterrorismo en EE.UU.","author":"","date":"enero 1, 2026","format":false,"excerpt":"Pedro Insunza Noriega, alias \u201cSagitario\u201d o \u201cEl Se\u00f1or de la Silla\u201d, presunto operador del c\u00e1rtel de los Beltr\u00e1n Leyva, una facci\u00f3n del C\u00e1rtel de Sinaloa, se\u00f1alada por las autoridades estadounidenses como la mayor red conocida de producci\u00f3n de fentanilo en el mundo, fue detenido el mi\u00e9rcoles en Culiac\u00e1n, Sinaloa, de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459749","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459749"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459749\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459749"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459749"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459749"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}