{"id":1459789,"date":"2025-03-11T16:03:50","date_gmt":"2025-03-11T23:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/"},"modified":"2025-03-11T16:03:50","modified_gmt":"2025-03-11T23:03:50","slug":"champions-league-equipos-clasificados-cuartos-final-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","title":{"rendered":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final"},"content":{"rendered":"<p>El Barcelona gole\u00f3 3-1 al Benfica en los octavos de final de la Champions League (4-1 qued\u00f3 el global) y se clasific\u00f3 a cuartos, ratificando su favoritismo en el torneo de clubes europeo.<\/p>\n<p>El Bayern Munich consigui\u00f3 su boleto para los cuartos de final tras derrotar al Bayer Leverkusen 2-0 (5-0 en el marcador global), mientras que el Inter lo logr\u00f3 despu\u00e9s de vencer al Feyenoord 2-1 (4-1 en el marcador global).<\/p>\n<p>La clasificaci\u00f3n del PSG a la siguiente fase sobre el Liverpool qued\u00f3 definida en tanda de penales (4-1) despu\u00e9s de que ambos equipos empataron con un marcador global de 1-1.<\/p>\n<p>El mi\u00e9rcoles se disputar\u00e1n los cuatro partidos de vuelta pendientes de los octavos de final para definir qu\u00e9 clubes avanzar\u00e1n a la siguiente fase. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/02\/19\/deportes\/sorteo-octavos-champions-league-equipos-clasificados-fechas-como-ver-orix\">La idea de los cuartos de final<\/a> se jugar\u00e1 el 8 y 9 de abril, mientras que la vuelta ser\u00e1 el 15 y 16 de abril.<\/p>\n<ul>\n<li>Barcelona<\/li>\n<li>Bayern Munich<\/li>\n<li>Inter<\/li>\n<li>PSG<\/li>\n<\/ul>\n<ul>\n<li>Lille \/ Borussia Dortmund<\/li>\n<li>Aston Villa \/ Brujas<\/li>\n<li>Arsenal \/ PSV<\/li>\n<li>Atl\u00e9tico de Madrid \/ Real Madrid<\/li>\n<\/ul>\n<ul>\n<li>Arsenal o PSV \/ Atl\u00e9tico de Madrid o Real Madrid<\/li>\n<li>PSG \/ Aston Villa o Brujas<\/li>\n<li>Barcelona \/ Lille o Borussia Dortmund<\/li>\n<li>Bayern Munich \/ Inter<\/li>\n<\/ul>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Barcelona gole\u00f3 3-1 al Benfica en los octavos de final de la Champions League (4-1 qued\u00f3 el global) y se clasific\u00f3 a cuartos, ratificando su favoritismo en el torneo de clubes europeo. El Bayern Munich consigui\u00f3 su boleto para los cuartos de final tras derrotar al Bayer Leverkusen 2-0 (5-0 en el marcador global), [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459789","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final - Noticias\" \/>\n<meta property=\"og:description\" content=\"El Barcelona gole\u00f3 3-1 al Benfica en los octavos de final de la Champions League (4-1 qued\u00f3 el global) y se clasific\u00f3 a cuartos, ratificando su favoritismo en el torneo de clubes europeo. El Bayern Munich consigui\u00f3 su boleto para los cuartos de final tras derrotar al Bayer Leverkusen 2-0 (5-0 en el marcador global), [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T23:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final\",\"datePublished\":\"2025-03-11T23:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\"},\"wordCount\":226,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\",\"name\":\"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-11T23:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final - Noticias","og_description":"El Barcelona gole\u00f3 3-1 al Benfica en los octavos de final de la Champions League (4-1 qued\u00f3 el global) y se clasific\u00f3 a cuartos, ratificando su favoritismo en el torneo de clubes europeo. El Bayern Munich consigui\u00f3 su boleto para los cuartos de final tras derrotar al Bayer Leverkusen 2-0 (5-0 en el marcador global), [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","og_site_name":"Noticias","article_published_time":"2025-03-11T23:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/"},"author":{"name":"","@id":""},"headline":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final","datePublished":"2025-03-11T23:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/"},"wordCount":226,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","url":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","name":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-11T23:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Estos son los equipos clasificados en la Champions League 2024\/2025 a los cuartos de final","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/champions-league-equipos-clasificados-cuartos-final-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-11T23:03:50Z","datePublished":"2025-03-11T23:03:50Z","dateModified":"2025-03-11T23:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Estos son los equipos clasificados en la Champions League 2024\\\/2025 a los cuartos de final\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/11\\\/champions-league-equipos-clasificados-cuartos-final-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/11\\\/champions-league-equipos-clasificados-cuartos-final-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-11T23:03:50Z\",\"datePublished\":\"2025-03-11T23:03:50Z\",\"dateModified\":\"2025-03-11T23:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446926,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/03\/13\/sorteo-cuartos-champions-league-2023-2024-cuando-dia-hora-equipos-orix\/","url_meta":{"origin":1459789,"position":0},"title":"Sorteo de cuartos de la Champions League 2023\/2024: cu\u00e1ndo es, equipos clasificados, bombos, formato y m\u00e1s","author":"","date":"marzo 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Los ocho mejores equipos de la Champions League 2023\/2024 ya quedaron definidos y ahora es momento del sorteo para determinar cu\u00e1les ser\u00e1n los duelos en los cuartos de final de la competencia.Este sorteo se llevar\u00e1 a cabo el viernes 15 de marzo. A continuaci\u00f3n, te damos todos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471609,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/24\/sorteo-octavos-champions-league-2025-2026-orix\/","url_meta":{"origin":1459789,"position":1},"title":"Sorteo de octavos de la Champions League 2025\/2026: equipos, formato, fecha, a qu\u00e9 hora y c\u00f3mo ver","author":"","date":"febrero 24, 2026","format":false,"excerpt":"La Champions League conocer\u00e1 el camino definitivo hacia la gran final en Budapest, Hungr\u00eda, este viernes 27 de febrero, una vez que se hayan definido los cruces de playoff para determinar a los \u00faltimos ocho clasificados a los octavos de final. El sorteo, que se realizar\u00e1 en la Casa del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472319,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/18\/cruces-cuartos-final-champions-league-orix\/","url_meta":{"origin":1459789,"position":2},"title":"As\u00ed quedaron los cuartos de final de la Champions League 2025\/2026","author":"","date":"marzo 18, 2026","format":false,"excerpt":"Ocho equipos siguen con vida en la Champions League 2025\/2026 y Espa\u00f1a es el pa\u00eds con m\u00e1s representantes, tres: Real Madrid, FC, Barcelona y el Atl\u00e9tico de Madrid. Le sigue la Premier League de Inglaterra, con dos: Arsenal y Liverpool. Portugal, con el Sporting de Lisboa, Francia, con el PSG\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458065,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/01\/31\/sorteo-champions-league-partidos-cruces-fechas-orix\/","url_meta":{"origin":1459789,"position":3},"title":"Sorteo de eliminatorias y playoffs de la Champions League 24\/25: partidos, cruces y fechas","author":"","date":"enero 31, 2025","format":false,"excerpt":"El Real Madrid, vigente campe\u00f3n de Europa, y el Manchester City, ganador de la edici\u00f3n 2023, se enfrentar\u00e1n nuevamente en una electrizante eliminatoria de la Champions League. El sorteo celebrado este viernes en Nyon, Suiza, determin\u00f3 que ambos clubes medir\u00e1n fuerzas en los playoffs de la fase eliminatoria.Ni el conjunto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459457,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/03\/real-madrid-atletico-de-madrid-champions-league-hora-cuando-como-ver-orix\/","url_meta":{"origin":1459789,"position":4},"title":"Real Madrid \u2013 Atl\u00e9tico de Madrid en la Champions League 24\/25: previa, hora, cu\u00e1ndo y c\u00f3mo ver por TV e internet","author":"","date":"marzo 3, 2025","format":false,"excerpt":"Al Real Madrid le tom\u00f3 diez partidos llegar a octavos de final de la Champions League. Suena irreal si se tiene en cuenta la plantilla que posee, pero son las cosas que genera el nuevo formato de este torneo.En todo caso, los dirigidos por Carlo Ancelotti se enfrentar\u00e1n al Atl\u00e9tico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458934,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/19\/sorteo-octavos-champions-league-equipos-clasificados-fechas-como-ver-orix\/","url_meta":{"origin":1459789,"position":5},"title":"Sorteo de octavos de la Champions League 24\/25: equipos clasificados, cu\u00e1ndo es, fechas y c\u00f3mo ver por TV e internet","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Tras una larga primera fase con forma de liga y unos playoffs que se sienten como un abrebocas de mejor f\u00fatbol, no es descabellado pensar que ahora s\u00ed nos podemos poner en modo Champions League, el torneo que muestra lo m\u00e1s destacado del f\u00fatbol europeo.El modo Champions no es otra\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459789","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459789"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459789\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459789"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459789"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459789"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}