{"id":1459799,"date":"2025-03-11T20:03:48","date_gmt":"2025-03-12T03:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/"},"modified":"2025-03-11T20:03:48","modified_gmt":"2025-03-12T03:03:48","slug":"rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","title":{"rendered":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB"},"content":{"rendered":"<p>La ruta de helic\u00f3ptero que segu\u00eda un Black Hawk del Ej\u00e9rcito de EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/29\/ultima-hora-accidente-avion-aeropuerto-reagan-washington-orix\/\">cuando colision\u00f3 <\/a>con un jet regional de American Airlines el 29 de enero deber\u00eda cerrarse bajo ciertas condiciones, seg\u00fan dos nuevas recomendaciones de la Junta Nacional de Seguridad en el Transporte (NTSB, por sus siglas en ingl\u00e9s) anunciadas este martes.<\/p>\n<p>Las \u201crecomendaciones de seguridad urgentes\u201d de la agencia investigadora forman parte de su informe preliminar sobre la colisi\u00f3n en el aire que mat\u00f3 a 67 personas hace casi seis semanas.<\/p>\n<p>Los helic\u00f3pteros deber\u00edan ser excluidos de un tramo de 4 millas (6,4 kil\u00f3metros) sobre el r\u00edo Potomac cuando los vuelos est\u00e9n aterrizando en las pistas 33 y 15 del Aeropuerto Nacional Reagan, dijo la presidenta de la NTSB, Jennifer Homendy, en una conferencia informativa este martes.<\/p>\n<p>\u201cHemos determinado que las distancias de separaci\u00f3n existentes entre el tr\u00e1fico de helic\u00f3pteros que opera en la ruta cuatro y las aeronaves que aterrizan en la pista 33 son insuficientes y representan un riesgo intolerable para la seguridad de la aviaci\u00f3n al aumentar las posibilidades de una colisi\u00f3n en el aire en DCA\u201d, dijo. \u201cMe enfurece, pero tambi\u00e9n me siento incre\u00edblemente devastada por las familias que est\u00e1n de luto porque perdieron a sus seres queridos. No deber\u00eda ser necesario que ocurra una tragedia as\u00ed. Desafortunadamente, ocurri\u00f3 una\u201d.<\/p>\n<p>El vuelo 5342 de American Eagle estaba a segundos de aterrizar en esa pista cuando el helic\u00f3ptero militar choc\u00f3 con el lado derecho del jet a una altitud de aproximadamente 300 pies (91 metros), dijeron los investigadores.<\/p>\n<p>El informe de este martes no identific\u00f3 la \u201ccausa probable\u201d del accidente, que se espera que tome m\u00e1s de un a\u00f1o, pero Homendy dijo que el problema de seguridad que identific\u00f3 la NTSB no pod\u00eda esperar a ser abordado.<\/p>\n<p>\u201cEl an\u00e1lisis inicial encontr\u00f3 que al menos una alerta de resoluci\u00f3n del sistema de alerta de tr\u00e1fico y prevenci\u00f3n de colisiones, o TCAS, fue activada por mes desde 2011 hasta 2024 en DCA debido a la proximidad de un helic\u00f3ptero\u201d, dijo Homendy. \u201cEn m\u00e1s de la mitad de los encuentros que revisamos nuevamente desde 2011 hasta 2024, el helic\u00f3ptero podr\u00eda haber estado por encima de la restricci\u00f3n de altitud de la ruta. Dos tercios de los eventos ocurrieron de noche\u201d.<\/p>\n<p>Las se\u00f1ales de advertencia que llevaron al desastre sobre el r\u00edo Potomac estaban ah\u00ed, dijeron investigadores federales, citando datos que detallaban miles de casi colisiones en el aeropuerto a lo largo de varios a\u00f1os. La NTSB dijo este martes que los investigadores descubrieron m\u00e1s de 15.000 incidentes de proximidad cercana entre aviones comerciales y helic\u00f3pteros entre 2021 y 2024, donde las aeronaves estaban dentro de una milla n\u00e1utica (1,8 kil\u00f3metros) y 85 casos donde dos aeronaves estaban separadas por solo 1.500 pies  (457 metros) verticalmente y 200 pies (60 metros) lateralmente.<\/p>\n<p>Ahora le corresponde a la Administraci\u00f3n Federal de Aviaci\u00f3n (FAA) convertir la recomendaci\u00f3n de los investigadores en acci\u00f3n. La FAA ha efectivamente prohibido los helic\u00f3pteros en el \u00e1rea desde los d\u00edas posteriores al accidente con una restricci\u00f3n temporal sobre 6 millas cuadradas (15,54 kil\u00f3metros cuadrados) cerca del Aeropuerto Nacional Reagan.<\/p>\n<p>En este momento, los aviones en el aeropuerto son detenidos para los vuelos necesarios de helic\u00f3pteros, como cuando el presidente Donald Trump sale de la Casa Blanca en el Marine One, lo que ha llevado a retrasos y desv\u00edos de vuelos.<\/p>\n<p>La NTSB hace recomendaciones de seguridad para abordar preocupaciones descubiertas en sus investigaciones. Estas alertas se entregan al Gobierno, la industria o el p\u00fablico e identifican cambios cr\u00edticos que la junta cree que deben hacerse en relaci\u00f3n con la seguridad del transporte.<\/p>\n<p>Desde que se estableci\u00f3 la agencia en 1967, se han emitido m\u00e1s de 15.500 recomendaciones. La aviaci\u00f3n representa la mayor parte de esas recomendaciones con un 38%, de acuerdo con datos de la NTSB.<\/p>\n<p>En este momento, hay al menos 276 recomendaciones abiertas de aviaci\u00f3n de la NTSB, y m\u00e1s de 1.000 que est\u00e1n cerradas por la junta, pero se enumeran como que se ha tomado \u201cuna acci\u00f3n inaceptable\u201d.<\/p>\n<p>La NTSB es un investigador independiente y puede hacer recomendaciones, pero no puede hacerlas cumplir. Los cambios deben ser realizados por la FAA, las aerol\u00edneas, los aeropuertos u otras partes involucradas.<\/p>\n<p>La colisi\u00f3n, ocurrida hace casi seis semanas, fue el accidente de aviaci\u00f3n m\u00e1s mortal en Estados Unidos en casi dos d\u00e9cadas.<\/p>\n<p>Un controlador, dijeron los investigadores, tambi\u00e9n estaba trabajando en dos posiciones en la torre. Si bien eso est\u00e1 permitido bajo las reglas actuales, el informe preliminar muestra que comenzaron a manejar ambas posiciones a las 3:30 p.m., hora de Miami, y el accidente ocurri\u00f3 m\u00e1s de cinco horas despu\u00e9s, aproximadamente a las 8:50 p.m.<\/p>\n<p>El informe preliminar tambi\u00e9n incluye m\u00e1s detalles sobre un an\u00e1lisis de los datos de vuelo y la grabadora de voz recuperada del helic\u00f3ptero Black Hawk. Los investigadores encontraron que los pilotos podr\u00edan no haber escuchado algunas llamadas de la torre de control del Aeropuerto Nacional Ronald Reagan de Washington.<\/p>\n<p>La tripulaci\u00f3n del helic\u00f3ptero del Ej\u00e9rcito podr\u00eda no haberse dado cuenta de que estaban volando m\u00e1s alto de lo que se supon\u00eda que deb\u00edan cuando la aeronave colision\u00f3 con el jet regional de American Airlines, sugiere la informaci\u00f3n.<\/p>\n<p>El alt\u00edmetro de radio a bordo del Black Hawk marcaba 278 pies (84 metros). Ese alt\u00edmetro utiliza un haz de radio para mostrar la altitud del helic\u00f3ptero sobre el nivel del suelo, pero los pilotos del helic\u00f3ptero podr\u00edan haber hecho referencia a un alt\u00edmetro diferente que mostraba una altitud incorrecta en el momento del accidente.<\/p>\n<p>La NTSB tambi\u00e9n cree que la tripulaci\u00f3n del helic\u00f3ptero \u201cprobablemente\u201d estaba usando gafas de visi\u00f3n nocturna mientras realizaba un vuelo de verificaci\u00f3n o un examen pr\u00e1ctico. El Ej\u00e9rcito realiza tres tipos de vuelos de verificaci\u00f3n: instrumento, anual y gafas de visi\u00f3n nocturna. Este vuelo fue una combinaci\u00f3n de un vuelo de verificaci\u00f3n anual y de gafas de visi\u00f3n nocturna.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ruta de helic\u00f3ptero que segu\u00eda un Black Hawk del Ej\u00e9rcito de EE.UU. cuando colision\u00f3 con un jet regional de American Airlines el 29 de enero deber\u00eda cerrarse bajo ciertas condiciones, seg\u00fan dos nuevas recomendaciones de la Junta Nacional de Seguridad en el Transporte (NTSB, por sus siglas en ingl\u00e9s) anunciadas este martes. Las \u201crecomendaciones [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459799","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &quot;riesgo intolerable&quot;, dice la NTSB - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &quot;riesgo intolerable&quot;, dice la NTSB - Noticias\" \/>\n<meta property=\"og:description\" content=\"La ruta de helic\u00f3ptero que segu\u00eda un Black Hawk del Ej\u00e9rcito de EE.UU. cuando colision\u00f3 con un jet regional de American Airlines el 29 de enero deber\u00eda cerrarse bajo ciertas condiciones, seg\u00fan dos nuevas recomendaciones de la Junta Nacional de Seguridad en el Transporte (NTSB, por sus siglas en ingl\u00e9s) anunciadas este martes. Las \u201crecomendaciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T03:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB\",\"datePublished\":\"2025-03-12T03:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\"},\"wordCount\":1072,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\",\"name\":\"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un \\\"riesgo intolerable\\\", dice la NTSB - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-12T03:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un \"riesgo intolerable\", dice la NTSB - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un \"riesgo intolerable\", dice la NTSB - Noticias","og_description":"La ruta de helic\u00f3ptero que segu\u00eda un Black Hawk del Ej\u00e9rcito de EE.UU. cuando colision\u00f3 con un jet regional de American Airlines el 29 de enero deber\u00eda cerrarse bajo ciertas condiciones, seg\u00fan dos nuevas recomendaciones de la Junta Nacional de Seguridad en el Transporte (NTSB, por sus siglas en ingl\u00e9s) anunciadas este martes. Las \u201crecomendaciones [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-12T03:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/"},"author":{"name":"","@id":""},"headline":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB","datePublished":"2025-03-12T03:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/"},"wordCount":1072,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","name":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un \"riesgo intolerable\", dice la NTSB - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-12T03:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Rutas de helic\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-12T03:03:48Z","datePublished":"2025-03-12T03:03:48Z","dateModified":"2025-03-12T03:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Rutas de helic\\u00f3pteros cerca del aeropuerto de Washington representan un &#171;riesgo intolerable&#187;, dice la NTSB\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/11\\\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/11\\\/rutas-helicopteros-washington-riesgo-intolerable-ntsb-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-12T03:03:48Z\",\"datePublished\":\"2025-03-12T03:03:48Z\",\"dateModified\":\"2025-03-12T03:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1471360,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/17\/cadena-errores-colision-aerea-mortal-washington-trax\/","url_meta":{"origin":1459799,"position":0},"title":"Una cadena de errores provoc\u00f3 una colisi\u00f3n a\u00e9rea mortal cerca de Washington, concluyen los investigadores","author":"","date":"febrero 17, 2026","format":false,"excerpt":"M\u00faltiples fallas en distintas instancias del Gobierno provocaron que un helic\u00f3ptero Black Hawk del Ej\u00e9rcito chocara con un avi\u00f3n regional de American Airlines, operado por PSA Airlines, concluy\u00f3 la Junta Nacional de Seguridad en el Transporte (NTSB, por sus siglas en ingl\u00e9s) en un informe de casi 400 p\u00e1ginas publicado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471586,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/24\/camara-proyecto-de-ley-aviones-washington-trax\/","url_meta":{"origin":1459799,"position":1},"title":"La C\u00e1mara considera un proyecto de ley que, seg\u00fan algunos, habr\u00eda evitado una colisi\u00f3n mortal en el aire en Washington","author":"","date":"febrero 24, 2026","format":false,"excerpt":"La C\u00e1mara de Representantes se dispone a considerar si un sistema de prevenci\u00f3n de colisiones que, seg\u00fan sus partidarios, podr\u00eda haber evitado la mortal colisi\u00f3n a\u00e9rea del a\u00f1o pasado cerca de Washington, deber\u00eda ser obligatorio en todos los aviones de Estados Unidos.Sesenta y siete personas murieron el 29 de enero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464165,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/07\/02\/accidente-avion-paracaidismo-nueva-jersey-trax\/","url_meta":{"origin":1459799,"position":2},"title":"15 personas resultan heridas tras accidente de avi\u00f3n de paracaidismo en Nueva Jersey","author":"","date":"julio 2, 2025","format":false,"excerpt":"Un avi\u00f3n de paracaidismo con 15 personas a bordo se sali\u00f3 de la pista en un aeropuerto de Nueva Jersey la tarde del mi\u00e9rcoles, y varias personas fueron trasladadas al hospital, seg\u00fan informaron las autoridades.El Cessna 208B se estrell\u00f3 en un bosque en el aeropuerto Cross Keys, al sureste de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458936,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/19\/dos-aviones-chocan-arizona-un-muerto-trax\/","url_meta":{"origin":1459799,"position":3},"title":"Dos aviones peque\u00f1os chocan en el aire en Arizona, dejando al menos una persona muerta, informan las autoridades","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Al menos una persona muri\u00f3 despu\u00e9s de que dos aeronaves peque\u00f1as colisionaran en el aire cerca de un aeropuerto de Arizona este mi\u00e9rcoles, seg\u00fan informaron las autoridades.Una Cessna 172S y una Lancair 360 MK II colisionaron a las 8:28 a.m. (hora local) cerca del Aeropuerto Regional de Marana, de acuerdo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458316,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/05\/radar-black-hawk-volaba-demasiado-alto-washington-trax\/","url_meta":{"origin":1459799,"position":4},"title":"Pruebas recientes de radar sugieren que el Black Hawk que choc\u00f3 contra un avi\u00f3n en Washington volaba demasiado alto","author":"","date":"febrero 5, 2025","format":false,"excerpt":"El martes se publicaron nuevos datos procedentes de radares terrestres que sugieren que un helic\u00f3ptero del Ej\u00e9rcito volaba m\u00e1s alto de lo que deb\u00eda cuando colision\u00f3 con el vuelo 5342 de American Airlines hace una semana, matando a las 67 personas a bordo de ambas aeronaves.De acuerdo con los \u201cdatos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458331,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/06\/investigacion-colision-aire-washington-jueves-trax\/","url_meta":{"origin":1459799,"position":5},"title":"Investigadores informar\u00e1n a los legisladores sobre la colisi\u00f3n en pleno vuelo en Washington. Esto es lo que sabemos","author":"","date":"febrero 6, 2025","format":false,"excerpt":"Los investigadores que tratan de averiguar qu\u00e9 provoc\u00f3 la colisi\u00f3n mortal en pleno vuelo entre un helic\u00f3ptero militar Black Hawk y un avi\u00f3n de American Airlines cerca de Washington, la semana pasada, informar\u00e1n a los legisladores este jueves sobre lo que han aprendido despu\u00e9s de examinar los datos de ambas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459799","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459799"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459799\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459799"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459799"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459799"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}