{"id":1459806,"date":"2025-03-12T03:03:45","date_gmt":"2025-03-12T10:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/"},"modified":"2025-03-12T03:03:45","modified_gmt":"2025-03-12T10:03:45","slug":"mahmoud-khalil-trump-universidad-columbia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","title":{"rendered":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia"},"content":{"rendered":"<p>Cuando los abogados de Mahmoud Khalil entren el mi\u00e9rcoles en el Tribunal Thurgood Marshall de Estados Unidos, en Nueva York, tendr\u00e1n una misi\u00f3n en mente: conseguir que su cliente, un activista palestino, sea liberado de un centro del ICE en Louisiana y regrese a Nueva York para estar m\u00e1s cerca de su abogado y de su familia.<\/p>\n<p>Khalil fue detenido el s\u00e1bado por agentes federales por su participaci\u00f3n en las protestas contra la guerra entre Israel y Hamas en la Universidad de Columbia la primavera pasada. Su tarjeta verde fue revocada por la administraci\u00f3n Trump, dijo su abogado, pero un juez federal en Nueva York bloque\u00f3 cualquier esfuerzo inmediato para deportar a Khalil hasta que sus abogados y el Gobierno federal comparezcan ante el tribunal.<\/p>\n<p>El caso, aparentemente el primero de este tipo, sienta las bases de lo que podr\u00eda venir a medida que la administraci\u00f3n Trump intensifica su persecuci\u00f3n de los estudiantes extranjeros y las manifestaciones propalestinas en los campus universitarios.<\/p>\n<p>El presidente Donald Trump hab\u00eda elogiado la detenci\u00f3n de Khalil y prometi\u00f3 encontrar y deportar a otros como \u00e9l.<\/p>\n<p>\u201cSi apoyas el terrorismo, incluida la matanza de hombres, mujeres y ni\u00f1os inocentes, tu presencia es contraria a nuestros intereses nacionales y de pol\u00edtica exterior, y no eres bienvenido aqu\u00ed\u201d, dijo Trump en Truth Social el lunes.<\/p>\n<p>La Casa Blanca no ha aportado pruebas que respalden las acusaciones contra Khalil y no est\u00e1 claro si ha sido acusado de alg\u00fan delito.<\/p>\n<p>Los abogados de Khalil argumentaron en documentos judiciales que su traslado de Nueva York a un centro de detenci\u00f3n en Louisiana como represalia por su \u201cdiscurso y defensa protegidos\u201d es inconstitucional.<\/p>\n<p>Sus abogados presentaron una petici\u00f3n de h\u00e1beas corpus \u201cdesafiando la validez de su arresto y detenci\u00f3n\u201d, dijo uno de sus abogados el domingo.<\/p>\n<p>Los abogados de la administraci\u00f3n Trump no aceptar\u00e1n traer a Khalil de vuelta a Nueva York sin una orden judicial.<\/p>\n<p>Los abogados de ambas partes presentaron una carta conjunta en un tribunal federal el martes, diciendo a un juez que no pudieron llegar a un acuerdo para devolver a Khalil a Nueva York, estableciendo el enfrentamiento del mi\u00e9rcoles en la corte.<\/p>\n<p>Los abogados de la administraci\u00f3n Trump dijeron al tribunal que presentar\u00e1n una moci\u00f3n para transferir o desestimar la petici\u00f3n de h\u00e1beas corpus de Khalil, argumentando que el Distrito Sur de Nueva York es \u201cun lugar inapropiado\u201d y no tiene jurisdicci\u00f3n sobre el caso de Khalil.<\/p>\n<p>No se espera que presenten su petici\u00f3n hasta la medianoche del mi\u00e9rcoles y los abogados de Khalil tendr\u00e1n hasta la medianoche del viernes para responder. No est\u00e1 claro si el juez abordar\u00e1 alguna cuesti\u00f3n m\u00e1s all\u00e1 de la programaci\u00f3n durante la audiencia del mi\u00e9rcoles.<\/p>\n<p>Un portavoz del Distrito Sur de Nueva York no devolvi\u00f3 de inmediato una solicitud de comentarios.<\/p>\n<p>La administraci\u00f3n Trump hab\u00eda basado la detenci\u00f3n en una disposici\u00f3n de la ley de inmigraci\u00f3n que le otorga una amplia autoridad sobre qui\u00e9n puede ser objeto de deportaci\u00f3n, seg\u00fan un alto funcionario de Seguridad Nacional.<\/p>\n<p>\u201cSi planean buscar motivos de expulsi\u00f3n por terrorismo para Khalil, es probable que lo escuchemos del Departamento de Justicia ma\u00f1ana\u201d, dijo John Sandweg, exdirector interino de ICE, en un correo electr\u00f3nico a CNN el martes.<\/p>\n<p>Pero el juez del tribunal de distrito \u201cno puede ordenar ni aprobar\u201d la deportaci\u00f3n de Khalil, dijo Sandweg.<\/p>\n<p>El ICE y el Departamento de Justicia a\u00fan tendr\u00edan que presentar una demanda contra Khalil ante un tribunal de inmigraci\u00f3n, a\u00f1adi\u00f3, y un juez de inmigraci\u00f3n decidir\u00eda si se le debe retirar la tarjeta verde.<\/p>\n<p>En la sesi\u00f3n informativa del martes, la secretaria de Prensa de la Casa Blanca, Karoline Leavitt, dijo que el secretario de Estado, Marco Rubio, tiene autoridad para revocar una tarjeta verde o un visado a aquellas personas cuyas \u201cactividades en Estados Unidos pudieran tener consecuencias adversas graves para la pol\u00edtica exterior\u201d del pa\u00eds.<\/p>\n<p>Sandweg explic\u00f3 el lunes que es poco frecuente recurrir a esas disposiciones de la ley de inmigraci\u00f3n para deportar a un titular de una tarjeta verde. Normalmente se utilizan si el ICE alega que una persona estaba \u201cproporcionando apoyo financiero u operativo directo a una organizaci\u00f3n terrorista\u201d, a\u00f1adi\u00f3.<\/p>\n<p>\u201cEs mucho menos habitual que el ICE alegue que las opiniones o el discurso pol\u00edtico hacen que un titular de un permiso de residencia pueda ser deportado por motivos de terrorismo, ya que ello plantea importantes problemas relacionados con la Primera Enmienda\u201d, explic\u00f3 Sandweg.<\/p>\n<p>En una declaraci\u00f3n el martes, la esposa de Khalil -ciudadana estadounidense embarazada de ocho meses- se refiri\u00f3 a \u00e9l como su \u201croca\u201d.<\/p>\n<p>\u201cInmigraci\u00f3n estadounidense me arranc\u00f3 el alma cuando espos\u00f3 a mi marido y le oblig\u00f3 a entrar en un veh\u00edculo sin matr\u00edcula\u201d, dijo, se\u00f1alando tambi\u00e9n que su detenci\u00f3n se produjo cuando la pareja regresaba de una cena iftar, la comida que los musulmanes toman durante el Ramad\u00e1n para romper el ayuno.<\/p>\n<p>\u201cEn lugar de estar preparando la habitaci\u00f3n de nuestro beb\u00e9 y lavando la ropa para la llegada de nuestro primer hijo, me quedo sentada en nuestro apartamento, pregunt\u00e1ndome cu\u00e1ndo tendr\u00e1 Mahmoud la oportunidad de llamarme desde un centro de detenci\u00f3n\u201d, a\u00f1adi\u00f3.<\/p>\n<p><em>Gloria Pazmino, Sabrina Souza, Jeff Winter, Lauren Mascarenhas y Chelsea Bailey, de CNN, han contribuido a este reportaje.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando los abogados de Mahmoud Khalil entren el mi\u00e9rcoles en el Tribunal Thurgood Marshall de Estados Unidos, en Nueva York, tendr\u00e1n una misi\u00f3n en mente: conseguir que su cliente, un activista palestino, sea liberado de un centro del ICE en Louisiana y regrese a Nueva York para estar m\u00e1s cerca de su abogado y de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459806","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuando los abogados de Mahmoud Khalil entren el mi\u00e9rcoles en el Tribunal Thurgood Marshall de Estados Unidos, en Nueva York, tendr\u00e1n una misi\u00f3n en mente: conseguir que su cliente, un activista palestino, sea liberado de un centro del ICE en Louisiana y regrese a Nueva York para estar m\u00e1s cerca de su abogado y de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T10:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia\",\"datePublished\":\"2025-03-12T10:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\"},\"wordCount\":972,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\",\"name\":\"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-12T10:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia - Noticias","og_description":"Cuando los abogados de Mahmoud Khalil entren el mi\u00e9rcoles en el Tribunal Thurgood Marshall de Estados Unidos, en Nueva York, tendr\u00e1n una misi\u00f3n en mente: conseguir que su cliente, un activista palestino, sea liberado de un centro del ICE en Louisiana y regrese a Nueva York para estar m\u00e1s cerca de su abogado y de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-12T10:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/"},"author":{"name":"","@id":""},"headline":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia","datePublished":"2025-03-12T10:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/"},"wordCount":972,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","name":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-12T10:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El caso de un destacado activista palestino llega a tribunales a d\u00edas de ser detenido y revocada su tarjeta de residencia","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/mahmoud-khalil-trump-universidad-columbia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-12T10:03:45Z","datePublished":"2025-03-12T10:03:45Z","dateModified":"2025-03-12T10:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El caso de un destacado activista palestino llega a tribunales a d\\u00edas de ser detenido y revocada su tarjeta de residencia\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/12\\\/mahmoud-khalil-trump-universidad-columbia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/12\\\/mahmoud-khalil-trump-universidad-columbia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-12T10:03:45Z\",\"datePublished\":\"2025-03-12T10:03:45Z\",\"dateModified\":\"2025-03-12T10:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1459761,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/11\/mahmoud-khalil-columbia-ice-tarjeta-verde-trax\/","url_meta":{"origin":1459806,"position":0},"title":"\u00bfQui\u00e9n es Mahmoud Khalil, el activista palestino detenido por el ICE por las protestas en la Universidad de Columbia?","author":"","date":"marzo 11, 2025","format":false,"excerpt":"El presidente Donald Trump ha comparado a Mahmoud Khalil con un simpatizante terrorista. Otros lo describen como un activista palestino, se\u00f1alado por su abierto apoyo a su propio pueblo.Pero mucho antes de ser arrestado por agentes federales el s\u00e1bado por la noche, Khalil dijo a CNN que se sent\u00eda llamado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461132,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/13\/juez-autoriza-deportacion-mahmoud-khalil-trax\/","url_meta":{"origin":1459806,"position":1},"title":"Un juez de inmigraci\u00f3n autoriza la deportaci\u00f3n del activista Mahmoud Khalil. \u00bfQu\u00e9 sigue?","author":"","date":"abril 13, 2025","format":false,"excerpt":"Si bien la decisi\u00f3n de un juez de inmigraci\u00f3n de que Mahmoud Khalil, graduado de la Universidad de Columbia y residente legal permanente en EE.UU., puede ser deportado es una victoria para la administraci\u00f3n Trump, la batalla legal contra su detenci\u00f3n y deportaci\u00f3n est\u00e1 lejos de terminar.La decisi\u00f3n de este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463783,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/06\/20\/juez-activista-palestino-mahmoud-khalil-liberado-viernes-trax\/","url_meta":{"origin":1459806,"position":2},"title":"Juez ordena liberar a Mahmoud Khalil, el activista palestino en el centro de una larga batalla contra la deportaci\u00f3n","author":"","date":"junio 20, 2025","format":false,"excerpt":"Un juez federal orden\u00f3 este viernes que se ponga en libertad al activista palestino Mahmoud Khalil de un centro de detenci\u00f3n del Servicio de Control de Inmigraci\u00f3n y Aduanas (ICE, por sus siglas en ingl\u00e9s) de Louisiana, m\u00e1s de tres meses despu\u00e9s de que fuera detenido frente a su apartamento\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471816,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/03\/mamdani-trump-inmigracion-activistas-propalestinos-trax\/","url_meta":{"origin":1459806,"position":3},"title":"Mamdani asegura que le pidi\u00f3 a Trump retirar los cargos de inmigraci\u00f3n contra activistas propalestinos","author":"","date":"marzo 3, 2026","format":false,"excerpt":"Durante una reuni\u00f3n no anunciada con el presidente Donald Trump la semana pasada, el alcalde de la ciudad de Nueva York, Zohran Mamdani, mencion\u00f3 a cuatro manifestantes propalestinos perseguidos por las autoridades federales de inmigraci\u00f3n: Mahmoud Khalil, Yunseo Chung, Mohsen Mahdawi y Leqaa Kordia.\u201cPed\u00ed que se desestimaran estos casos\u201d, dijo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1461197,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/14\/mohsen-mahdawi-columbia-universidad-trump-trax\/","url_meta":{"origin":1459806,"position":4},"title":"Estudiante palestino iba a asistir a su \u00faltima entrevista para obtener la ciudadan\u00eda. Ahora se enfrenta a la deportaci\u00f3n","author":"","date":"abril 14, 2025","format":false,"excerpt":"Un estudiante palestino de la Universidad de Columbia acudi\u00f3 este lunes a una oficina de inmigraci\u00f3n de Vermont con la esperanza de comenzar el paso final para convertirse en ciudadano estadounidense. Pero en lugar de tener una entrevista, Mohsen Mahdawi, que ha vivido en Estados Unidos durante una d\u00e9cada, fue\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462685,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/22\/mahmoud-khalil-conoce-hijo-audiencia-deportacion-trax\/","url_meta":{"origin":1459806,"position":5},"title":"Mahmoud Khalil acaba de conocer a su hijo mientras un juez eval\u00faa una solicitud para detener su deportaci\u00f3n","author":"","date":"mayo 22, 2025","format":false,"excerpt":"Mahmoud Khalil, estudiante de posgrado de la Universidad de Columbia y residente permanente legal, quien se encuentra bajo custodia migratoria desde marzo, pudo sostener a su reci\u00e9n nacido por primera vez el jueves en el centro de detenci\u00f3n de Louisiana donde se encuentra recluido, seg\u00fan informaron sus abogados a CNN.La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459806","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459806"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459806\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459806"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459806"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459806"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}