{"id":1459814,"date":"2025-03-12T06:03:41","date_gmt":"2025-03-12T13:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/"},"modified":"2025-03-12T06:03:41","modified_gmt":"2025-03-12T13:03:41","slug":"estadounidense-colombia-detenido-venezuela-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","title":{"rendered":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela"},"content":{"rendered":"<p>A Lucas Hunter le encanta el kitesurf por lo que, junto a su hermana Sophie, plane\u00f3 un viaje a Colombia para aprovechar las \u201cbuenas olas\u201d del norte del pa\u00eds a finales de diciembre del a\u00f1o pasado.<\/p>\n<p>Su hermana no pudo ir por una enfermedad, y entonces Lucas viaj\u00f3 solo para lo que se supon\u00eda que ser\u00edan unas vacaciones de dos semanas y media.<\/p>\n<p>Sophie no lo ve ni sabe nada de \u00e9l desde hace m\u00e1s de dos meses, despu\u00e9s de que fue detenido cerca de la frontera con Venezuela.<\/p>\n<p>Sophie dijo que su hermano, un ciudadano estadounidense que vive en Londres, hab\u00eda ido a esa parte de Colombia \u201cporque ah\u00ed es donde hay competencias de kitesurf\u201d.<\/p>\n<p>\u201cEs bastante lejos, as\u00ed que b\u00e1sicamente tienes que conseguir una moto para ir a los diferentes lugares\u201d, dijo a CNN, y se\u00f1al\u00f3 que estaba \u201cen constante comunicaci\u00f3n con \u00e9l\u201d.<\/p>\n<p>El 7 de enero de 2025, en una zona remota cerca de la frontera, Lucas vio un puesto de control a lo lejos y dio marcha atr\u00e1s, seg\u00fan le cont\u00f3 a Sophie. Pero ya era demasiado tarde. Dijo que \u201cfue secuestrado, raptado por fuerzas militares venezolanas (\u2026) que lo llevaron al otro lado de la frontera\u201d, le coment\u00f3 ella a CNN.<\/p>\n<p>\u201cDijo: \u2018Te env\u00edo la ubicaci\u00f3n desde donde estoy detenido\u2019\u201d, detall\u00f3 Sophie. \u201cMe dec\u00eda: \u2018Han pasado cuatro horas. No entiendo qu\u00e9 pasa. No hablo espa\u00f1ol. Pero est\u00e1n redactando informes que dicen que no ten\u00eda intenci\u00f3n de cruzar\u2019\u201d.<\/p>\n<p>\u201cMe envi\u00f3 otro mensaje el d\u00eda ocho y me dijo: \u2018Est\u00e1n redactando un informe que dice que no ten\u00eda intenci\u00f3n de entrar a Venezuela. Creo que est\u00e1 bien. Deber\u00eda salir pronto\u2019\u201d, dijo.<\/p>\n<p>Esa fue la \u00faltima vez que Sophie supo de \u00e9l.<\/p>\n<p>Esta semana, declar\u00f3 a CNN que desconoce d\u00f3nde se encuentra detenido. No ha sido juzgado por ning\u00fan presunto delito. CNN se ha puesto en contacto con el Ministerio de Comunicaciones de Venezuela. La Fiscal\u00eda General de Venezuela declin\u00f3 hacer comentarios.<\/p>\n<p>Cuando se le pregunt\u00f3 si cree que Lucas fue detenido porque es ciudadano estadounidense, Sophie se\u00f1al\u00f3 que llevaba su pasaporte estadounidense cuando fue detenido.<\/p>\n<p>\u201cCreo que que llevara el pasaporte es un punto a favor\u201d, dijo. Lucas tambi\u00e9n tiene la ciudadan\u00eda francesa.<\/p>\n<p>Venezuela tiene un historial de detenci\u00f3n de ciudadanos estadounidenses como aparente moneda de cambio. Bajo la administraci\u00f3n de Biden, Estados Unidos negoci\u00f3 intercambios de prisioneros para repatriar a varios estadounidenses que hab\u00edan estado detenidos injustamente en Venezuela algunos durante a\u00f1os.<\/p>\n<p>El enviado especial de Estados Unidos Ric Grenell viaj\u00f3 a Caracas a fines de enero para reunirse con el l\u00edder Nicol\u00e1s Maduro <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/31\/venezuela\/liberan-estadounidenses-detenidos-venezuela-orix\">y logr\u00f3 la liberaci\u00f3n de seis estadounidenses<\/a> que estaban detenidos all\u00ed.<\/p>\n<p>La semana pasada, el secretario de Estado de Estados Unidos, Marco Rubio, design\u00f3 a nueve estadounidenses en Venezuela como detenidos injustamente. Seg\u00fan Sophie, su hermano es uno de ellos.<\/p>\n<p>Antes de esa designaci\u00f3n, Sophie afirm\u00f3 haber estado trabajando con la Embajada de Estados Unidos en Bogot\u00e1. Ahora que se le ha declarado detenido injustamente, su caso ser\u00e1 gestionado por la Oficina del Enviado Presidencial de Estados Unidos para Asuntos de Rehenes. Esta designaci\u00f3n proporciona al gobierno estadounidense m\u00e1s herramientas para intentar negociar su liberaci\u00f3n. Tambi\u00e9n facilita el acceso a recursos para las familias de las personas detenidas injustamente.<\/p>\n<p>Sophie dijo que estaba \u201cdecepcionada\u201d de que Lucas no estuviera entre los seis que regresaron a casa a finales de enero. Sin embargo, tiene la esperanza de que pronto lo liberen.<\/p>\n<p>\u201cEs inaceptable que el r\u00e9gimen haya arrestado y encarcelado a estadounidenses en circunstancias cuestionables y sin respetar sus derechos\u201d, declar\u00f3 un portavoz del Departamento de Estado. \u201cTodos los estadounidenses detenidos injustamente por el r\u00e9gimen de Maduro deben ser liberados de inmediato\u201d.<\/p>\n<p>\u201cEstados Unidos contin\u00faa sus esfuerzos para asegurar la liberaci\u00f3n de los restantes estadounidenses detenidos injustamente por el r\u00e9gimen en Venezuela\u201d, dijo el portavoz.<\/p>\n<p>Estados Unidos advierte a los estadounidenses que no viajen a la regi\u00f3n fronteriza entre Colombia y Venezuela \u201cdebido a la delincuencia, el secuestro y el riesgo de detenci\u00f3n al cruzar a Venezuela desde Colombia\u201d.<\/p>\n<p>\u201cCreo que deber\u00eda ser una campa\u00f1a masiva, especialmente para estudiantes universitarios o personas de mi edad que quieran explorar el mundo, y simplemente decirles: no se arriesguen\u201d, dijo Sophie.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Lucas Hunter le encanta el kitesurf por lo que, junto a su hermana Sophie, plane\u00f3 un viaje a Colombia para aprovechar las \u201cbuenas olas\u201d del norte del pa\u00eds a finales de diciembre del a\u00f1o pasado. Su hermana no pudo ir por una enfermedad, y entonces Lucas viaj\u00f3 solo para lo que se supon\u00eda que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459814","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"A Lucas Hunter le encanta el kitesurf por lo que, junto a su hermana Sophie, plane\u00f3 un viaje a Colombia para aprovechar las \u201cbuenas olas\u201d del norte del pa\u00eds a finales de diciembre del a\u00f1o pasado. Su hermana no pudo ir por una enfermedad, y entonces Lucas viaj\u00f3 solo para lo que se supon\u00eda que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T13:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela\",\"datePublished\":\"2025-03-12T13:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\"},\"wordCount\":774,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\",\"name\":\"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-12T13:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela - Noticias","og_description":"A Lucas Hunter le encanta el kitesurf por lo que, junto a su hermana Sophie, plane\u00f3 un viaje a Colombia para aprovechar las \u201cbuenas olas\u201d del norte del pa\u00eds a finales de diciembre del a\u00f1o pasado. Su hermana no pudo ir por una enfermedad, y entonces Lucas viaj\u00f3 solo para lo que se supon\u00eda que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-12T13:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/"},"author":{"name":"","@id":""},"headline":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela","datePublished":"2025-03-12T13:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/"},"wordCount":774,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","name":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-12T13:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/estadounidense-colombia-detenido-venezuela-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-12T13:03:41Z","datePublished":"2025-03-12T13:03:41Z","dateModified":"2025-03-12T13:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Este estadounidense fue a Colombia a practicar kitesurf. Ahora lleva meses detenido en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/12\\\/estadounidense-colombia-detenido-venezuela-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/12\\\/estadounidense-colombia-detenido-venezuela-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-12T13:03:41Z\",\"datePublished\":\"2025-03-12T13:03:41Z\",\"dateModified\":\"2025-03-12T13:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461308,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/17\/lucas-hunter-estadounidense-detenido-venezuela-orix\/","url_meta":{"origin":1459814,"position":0},"title":"La desesperada b\u00fasqueda de la familia de un estadounidense detenido en Venezuela","author":"","date":"abril 17, 2025","format":false,"excerpt":"Una noche de enero, Sophie Hunter recibi\u00f3 una serie de mensajes de su hermano Lucas mientras cenaba. Ten\u00eda un importante examen de trabajo a la ma\u00f1ana siguiente, pero los mensajes \u2013 un audio y un pin de localizaci\u00f3n - la sobresaltaron.\u201cAntes de escuchar el mensaje de voz, cuando vi la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447657,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/04\/02\/estadounidense-medellin-hotel-menores-servicios-sexuales-orix\/","url_meta":{"origin":1459814,"position":1},"title":"Tras caso de estadounidense hallado con dos menores en un hotel de Medell\u00edn, la ciudad proh\u00edbe los servicios sexuales por seis meses","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La Alcald\u00eda de Medell\u00edn en Colombia anunci\u00f3 este lunes una prohibici\u00f3n de seis meses para la oferta y demanda de servicios sexuales, una medida que surge luego del reciente hallazgo de un ciudadano estadounidense que fue encontrado en un hotel acompa\u00f1ado por dos menores de edad.Hasta este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450043,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/04\/condenan-colombia-john-poulos-feminicidio-valentina-trespalacios-orix\/","url_meta":{"origin":1459814,"position":2},"title":"Condenan en Colombia a 42 a\u00f1os de prisi\u00f3n al estadounidense John Poulos por el feminicidio de Valentina Trespalacios","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Juzgado 10 de Conocimiento de Bogot\u00e1 conden\u00f3 este martes a 42 a\u00f1os y ocho meses de prisi\u00f3n al estadounidense John Poulos, a quien declar\u00f3 culpable del feminicidio agravado de la joven colombiana Valentina Trespalacios, as\u00ed como de los delitos de ocultamiento, alteraci\u00f3n o destrucci\u00f3n de pruebas.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449308,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/05\/08\/detienen-esposo-ana-maria-knezevich-henao-colombia-desaparecida-espana-trax\/","url_meta":{"origin":1459814,"position":3},"title":"Detienen en Florida al esposo de Ana Mar\u00eda Knezevich Henao, la mujer estadounidense nacida en Colombia dada por desaparecida en Espa\u00f1a, seg\u00fan el FBI","author":"","date":"mayo 8, 2024","format":false,"excerpt":"(CNN) -- El marido de Ana Mar\u00eda Knezevich Henao, una mujer estadounidense nacida en Colombia, cuya desaparici\u00f3n se denunci\u00f3 cuando se encontraba en Espa\u00f1a en febrero de este a\u00f1o, fue detenido en Florida, seg\u00fan confirm\u00f3 este lunes el FBI.David Knezevich, de 36 a\u00f1os y residente en Fort Lauderdale, Florida, se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458612,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/11\/marc-fogel-detenido-regresa-rusia-intercambio-trax\/","url_meta":{"origin":1459814,"position":4},"title":"El profesor estadounidense Marc Fogel, detenido injustamente, regresa a EE.UU. tras ser liberado de Rusia en un &#171;intercambio&#187;","author":"","date":"febrero 11, 2025","format":false,"excerpt":"Marc Fogel, un profesor estadounidense detenido durante m\u00e1s de tres a\u00f1os en Rusia, arrib\u00f3 a EE.UU. este martes por la noche despu\u00e9s de que la administraci\u00f3n Trump asegurara su liberaci\u00f3n en un \u201cintercambio\u201d.El acuerdo para liberar a Fogel, quien fue designado como detenido injustamente por el Departamento de Estado de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466234,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/09\/07\/testimonios-latinos-redada-hyundai-georgia-orix\/","url_meta":{"origin":1459814,"position":5},"title":"&#171;Llegaron, atropellaron y no aceptaron ning\u00fan documento&#187;: tres latinos relatan  redada masiva en planta de Hyundai en Georgia","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"\u201cTengo todo (en regla), no tengo por qu\u00e9 correr\u201d, fue lo que le dijo su esposo por tel\u00e9fono en medio de la sorpresiva redada migratoria del jueves en una planta de fabricaci\u00f3n de Hyundai, en Georgia. Luz Dary Su\u00e1rez, inmigrante colombiana, le hab\u00eda avisado del operativo masivo en el lugar,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459814"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459814\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}