{"id":1459818,"date":"2025-03-12T07:03:43","date_gmt":"2025-03-12T14:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/"},"modified":"2025-03-12T07:03:43","modified_gmt":"2025-03-12T14:03:43","slug":"eliminar-programa-aditivos-alimentarios-fda-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","title":{"rendered":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?"},"content":{"rendered":"<p>El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy, ha iniciado el proceso de eliminaci\u00f3n de un programa de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) llamado GRAS, o \u201cgeneralmente reconocido como seguro\u201d. Seg\u00fan los cr\u00edticos, la industria alimentaria ha hecho un abuso del mismo durante d\u00e9cadas.<\/p>\n<p>Seg\u00fan un <a href=\"https:\/\/www.ewg.org\/news-insights\/news\/2022\/04\/ewg-analysis-almost-all-new-food-chemicals-greenlighted-industry-not-fda\">an\u00e1lisis de 2022<\/a>, casi el 99% de los nuevos productos qu\u00edmicos utilizados en alimentos o envases de alimentos desde el a\u00f1o 2000 recibieron luz verde para su uso, no por parte de la FDA, sino de la industria alimentaria y qu\u00edmica.<\/p>\n<p>Durante ese per\u00edodo, los fabricantes de alimentos pidieron permiso a la FDA para introducir una nueva sustancia solo 10 veces, seg\u00fan el an\u00e1lisis realizado por el Environmental Working Group, o EWG, una organizaci\u00f3n de defensa del medio ambiente y la salud con sede en Washington.<\/p>\n<p>\u201cDurante demasiado tiempo, los fabricantes de ingredientes y los patrocinadores han explotado una laguna legal que ha permitido que nuevos ingredientes y productos qu\u00edmicos, a menudo con datos de seguridad desconocidos, se introduzcan en el suministro de alimentos de EE.UU. sin notificar a la FDA ni al p\u00fablico\u201d, dijo Kennedy en un comunicado este lunes.<\/p>\n<p>\u201cEliminar esta laguna legal brindar\u00e1 transparencia a los consumidores\u201d, dijo, y \u201cayudar\u00e1 a restablecer el suministro de alimentos de nuestro pa\u00eds al garantizar que los ingredientes que se introducen en los alimentos sean seguros\u201d.<\/p>\n<p>Los expertos aplaudieron la medida, consider\u00e1ndola muy necesaria, pero cuestionaron cu\u00e1n realista ser\u00e1 el cambio.<\/p>\n<p>\u201cEstoy totalmente a favor de abordar la laguna jur\u00eddica GRAS. Ya es hora de que la FDA la cierre\u201d, dijo Marion Nestle, profesora em\u00e9rita Paulette Goddard de nutrici\u00f3n, estudios alimentarios y salud p\u00fablica en la Universidad de Nueva York, en un correo electr\u00f3nico.<\/p>\n<p>\u201cLas empresas alimentarias no deber\u00edan decidir por s\u00ed mismas si sus aditivos son seguros\u201d, afirm\u00f3 Nestle, que ha <a href=\"https:\/\/steinhardt.nyu.edu\/people\/marion-nestle\">escrito libros<\/a> sobre la pol\u00edtica de la industria alimentaria.<\/p>\n<p>\u201cSin embargo, me resulta dif\u00edcil creer que esta administraci\u00f3n le dar\u00e1 a la FDA los recursos que necesita \u2014y esto significa expertos bien pagados en toxicolog\u00eda alimentaria\u2014 para encargarse de las evaluaciones de aditivos, especialmente mientras el personal de la agencia est\u00e1 siendo despedido a diestro y siniestro\u201d, a\u00f1adi\u00f3.<\/p>\n<p>El excomisionado de la FDA, Dr. Robert Califf, quien renunci\u00f3 a su cargo el 20 de enero, agreg\u00f3 que cualquier reforma tendr\u00eda que pasar por el poderoso lobby de la industria alimentaria, que tradicionalmente ha luchado contra el cambio.<\/p>\n<p>\u201cSi esto sucediera, ser\u00eda un verdadero cambio radical tras a\u00f1os de presi\u00f3n pol\u00edtica y pol\u00edticos que, en su mayor\u00eda, bloqueaban los esfuerzos para lograrlo\u201d, dijo Califf. \u201cLa industria se ha resistido; el Congreso republicano lo ha bloqueado. Ahora bien, si est\u00e1n a favor, aprovech\u00e9moslo y logr\u00e9moslo. Estoy totalmente a favor\u201d.<\/p>\n<p>El lunes, <a href=\"https:\/\/x.com\/seckennedy\/status\/1899235126732566904?s=46\">Kennedy anunci\u00f3<\/a> que se hab\u00eda reunido con los directores ejecutivos de Kraft Heinz, General Mills, Tyson Foods, Kellogg\u2019s, Smuckers y Pepsi para discutir una soluci\u00f3n.<\/p>\n<p>\u201cDeber\u00edas poder tomar decisiones informadas. Deber\u00edas saber qu\u00e9 producto es, qu\u00e9 contiene tu comida y cu\u00e1les son sus efectos sobre la salud, y eso es todo lo que vamos a hacer\u201d, <a href=\"https:\/\/x.com\/foxnews\/status\/1899281056970248400?s=46\">declar\u00f3 Kennedy<\/a> al presentador de Fox News Sean Hannity en una entrevista transmitida el lunes por la noche.<\/p>\n<p>\u201cVamos a incentivar a la gente y a las empresas a ser transparentes, y vamos a informar a los estadounidenses sobre qu\u00e9 les est\u00e1 causando la enfermedad\u201d, dijo Kennedy. \u201cNadie quiere estar enfermo\u201d.<\/p>\n<p>Melissa Hockstad, presidenta y CEO de la Consumer Brands Association, que representa a la industria alimentaria, dijo a CNN en un correo electr\u00f3nico que la reuni\u00f3n fue \u201cconstructiva\u201d.<\/p>\n<p>\u201cEsperamos seguir colaborando con el secretario y los expertos calificados del Departamento de Salud y Servicios Humanos para apoyar la salud p\u00fablica, generar confianza en los consumidores y promover su elecci\u00f3n\u201d, afirm\u00f3 Hockstad.<\/p>\n<p>Creado mediante <a href=\"https:\/\/www.fda.gov\/food\/generally-recognized-safe-gras\/fdas-approach-gras-provision-history-processes\">una enmienda de 1958<\/a> a la <a href=\"https:\/\/uscode.house.gov\/view.xhtml?path=\/prelim@title21\/chapter9&#038;edition=prelim\">Ley Federal de Alimentos, Medicamentos y Cosm\u00e9ticos de 1938<\/a>, el programa GRAS se concibi\u00f3 para aplicarse estrictamente a ingredientes seguros y de uso com\u00fan, como el ajo, el aceite, el vinagre y el bicarbonato de sodio. Sin embargo, en 1997, la FDA, desbordada y con fondos insuficientes, convirti\u00f3 el <a href=\"https:\/\/www.fda.gov\/food\/food-ingredients-packaging\/food-chemical-safety#:~:text=The%20FDA%20has%20established%20a,intend%20to%20use%20in%20food.\">programa en voluntario<\/a>, lo que permiti\u00f3 a la industria declarar que una sustancia era GRAS sin proporcionar previamente datos de seguridad a la agencia.<\/p>\n<p>Desde entonces, dicen los cr\u00edticos, los fabricantes de alimentos han introducido numerosos aditivos no probados en el suministro de alimentos, muchos de los cuales luego fueron identificados como da\u00f1inos.<\/p>\n<p>Uno de ellos, el aceite vegetal bromado o BVO (un aceite vegetal utilizado en refrescos c\u00edtricos y bebidas deportivas), dej\u00f3 <a href=\"https:\/\/www.federalregister.gov\/citation\/35-FR-1049\">de ser GRAS en 1970.<\/a> Sin embargo, la FDA no prohibi\u00f3 oficialmente su uso en el suministro de alimentos de EE.UU. <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/11\/03\/fda-prohibir-ingrediente-potencialmente-nocivo-algunos-refrescos-trax#:~:text=La%20FDA%20propone%20prohibir%20un%20ingrediente%20potencialmente%20nocivo%20presente%20en%20algunos%20refrescos,-Por%20Kristen%20Rogers&#038;text=(CNN)%20%E2%80%93%20La%20Administraci%C3%B3n%20de,(BVO)%20como%20aditivo%20alimentario.\">hasta julio de 2024<\/a>.<\/p>\n<p>\u201cLa FDA supo durante d\u00e9cadas que el aceite vegetal bromado, o BVO, ser\u00eda perjudicial, pero se permiti\u00f3 su uso a petici\u00f3n de los fabricantes de alimentos\u201d, declar\u00f3 el secretario de Estado de Illinois, Alexi Giannoulias, en una rueda de prensa celebrada en septiembre. Giannoulias fue coautor de la <a href=\"https:\/\/www.ilsos.gov\/news\/2024\/january\/240123d1.pdf\">Ley de Seguridad Alimentaria de Illinois<\/a>, aprobada por el Senado de Illinois y actualmente en tr\u00e1mite en la C\u00e1mara de Representantes.<\/p>\n<p>Cansados \u200b\u200bde esperar a la FDA, otros estados tambi\u00e9n han actuado. En <a href=\"https:\/\/leginfo.legislature.ca.gov\/faces\/billNavClient.xhtml?bill_id=202320240AB418\">octubre de 2023<\/a>, California prohibi\u00f3 cuatro sustancias ( <a href=\"https:\/\/www.fda.gov\/food\/food-additives-petitions\/brominated-vegetable-oil-bvo\">BVO<\/a>, <a href=\"https:\/\/www.inchem.org\/documents\/iarc\/vol73\/73-17.html\">bromato de potasio<\/a>  <a href=\"https:\/\/efsa.onlinelibrary.wiley.com\/doi\/epdf\/10.2903\/j.efsa.2004.83\">propilparabeno<\/a> y <a href=\"https:\/\/cnnespanol.cnn.com\/2023\/10\/10\/california-prohibe-sustancias-quimicas-nocivas-alimentos-trax#:~:text=(CNN)%20%E2%80%93%20El%20gobernador%20de,UU.\">colorante rojo n.\u00b03<\/a>) debido a su relaci\u00f3n con graves problemas de salud, como c\u00e1ncer, problemas endocrinos y reproductivos, y problemas card\u00edacos y hep\u00e1ticos.<\/p>\n<p>La FDA prohibi\u00f3 el colorante rojo n.\u00ba3 en <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/01\/15\/salud\/fda-prohibe-colorante-rojo-alimentos-ee-uu-trax#:~:text=(FDA%2C%20por%20sus%20siglas%20en,anunci%C3%B3%20la%20agencia%20este%20mi%C3%A9rcoles.\">enero<\/a>, m\u00e1s de 30 a\u00f1os despu\u00e9s de que los cient\u00edficos descubrieran su relaci\u00f3n con el c\u00e1ncer en animales. <a href=\"https:\/\/www.fda.gov\/industry\/color-additives\/fdc-red-no-3\">El colorante rojo n.\u00ba3,<\/a> un aditivo colorante sint\u00e9tico derivado del petr\u00f3leo y conocido qu\u00edmicamente como eritrosina, se utilizaba para dar a alimentos, dulces y bebidas un color rojo cereza brillante.<\/p>\n<p>Entre los productos qu\u00edmicos adicionales que est\u00e1n en la mira de los proyectos de ley legislativos en <a href=\"https:\/\/ewg.maps.arcgis.com\/apps\/dashboards\/64f81d77752347138e57fde7a285c8ee\">11 estados<\/a> se incluyen el colorante rojo n. \u00ba40; los colorantes azules n. \u00ba1 y n. \u00ba2; el colorante verde n. \u00ba3; los colorantes amarillos n. \u00ba5 y n. \u00ba6; el di\u00f3xido de titanio y <a href=\"https:\/\/pubchem.ncbi.nlm.nih.gov\/compound\/Azodicarbonamide#section=Fire-Hazards\">la azodicarbonamida<\/a>, un acondicionador de masa que tambi\u00e9n se <a href=\"https:\/\/www.ewg.org\/research\/nearly-500-ways-make-yoga-mat-sandwich\">usa en colchonetas de yoga<\/a>, seg\u00fan el Grupo de Trabajo Ambiental.<\/p>\n<p>Eliminar la laguna legal GRAS requerir\u00eda que las empresas \u201cnotifiquen p\u00fablicamente a la FDA sobre el uso previsto de [nuevos] ingredientes, junto con los datos de seguridad subyacentes, antes de que se introduzcan en el suministro de alimentos\u201d, <a href=\"https:\/\/www.hhs.gov\/about\/news\/2025\/03\/10\/hhs-secretary-kennedy-directs-fda-explore-rulemaking-eliminate-pathway-companies-self-affirm-food-ingredients-safe.html#:~:text=Today%2C%20as%20part%20of%20this,the%20self%2Daffirmed%20GRAS%20pathway.\">dijo el <\/a>Departamento de Salud y Servicios Humanos de los Estados Unidos (<a href=\"https:\/\/www.hhs.gov\/about\/news\/2025\/03\/10\/hhs-secretary-kennedy-directs-fda-explore-rulemaking-eliminate-pathway-companies-self-affirm-food-ingredients-safe.html#:~:text=Today%2C%20as%20part%20of%20this,the%20self%2Daffirmed%20GRAS%20pathway.\">HHS, por sus siglas en ingl\u00e9s) en la declaraci\u00f3n.<\/a><\/p>\n<p>Sin embargo, los representantes de las empresas de alimentos dicen que el proceso GRAS juega un papel importante al permitir a las empresas \u201cinnovar para satisfacer la demanda de los consumidores\u201d.<\/p>\n<p>\u201cMientras la administraci\u00f3n busca revisar el GRAS, estamos listos para trabajar con expertos de la agencia en el an\u00e1lisis continuo de ingredientes seguros y aumentar la transparencia para el consumidor\u201d, dijo Sarah Gallo, vicepresidenta s\u00e9nior de pol\u00edtica de productos y asuntos federales de la Consumer Brands Association, en un correo electr\u00f3nico.<\/p>\n<p>Eliminar el GRAS no es tan simple como eliminar las regulaciones, dijo Jensen Jose, funcionario regulador del Centro para la Ciencia en el Inter\u00e9s P\u00fablico, una organizaci\u00f3n sin fines de lucro de seguridad alimentaria.<\/p>\n<p>\u201cExisten muchas sustancias qu\u00edmicas GRAS secretas que ya se encuentran en nuestro suministro de alimentos\u201d, escribi\u00f3 en un correo electr\u00f3nico. \u201cIlegalizar estas sustancias qu\u00edmicas inmediatamente hasta obtener la aprobaci\u00f3n de la FDA podr\u00eda causar interrupciones en el suministro de alimentos. Garantizar que las sustancias qu\u00edmicas GRAS existentes permanezcan seguras en nuestros alimentos deber\u00eda ser un proceso sistem\u00e1tico\u201d.<\/p>\n<p>Adem\u00e1s, no todo lo que es GRAS deber\u00eda eliminarse durante la reforma, dijo Jennifer Pomeranz, profesora asociada de pol\u00edticas y gesti\u00f3n de salud p\u00fablica en la Escuela de Salud Global y P\u00fablica de la Universidad de Nueva York en la ciudad de Nueva York.<\/p>\n<p>\u201cDeber\u00edan eximir del uso de ingredientes que eran GRAS en 1958, cuando el Congreso cre\u00f3 la enmienda alimentaria, como el ajo, la sal y la pimienta, que hemos consumido durante d\u00e9cadas sin sufrir da\u00f1os\u201d, dijo. \u201cAdem\u00e1s, que todo se someta a una petici\u00f3n de aditivos alimentarios para garantizar su seguridad\u201d.<\/p>\n<p>Tambi\u00e9n es posible que al cambiar el proceso GRAS, la industria alimentaria pueda trasladar el costo a los consumidores en forma de precios m\u00e1s altos, dijo Califf.<\/p>\n<p>\u201cHacer esta investigaci\u00f3n cuesta dinero. Eso es muy diferente a simplemente declarar que nuestro material es seguro, en comparaci\u00f3n con hacer el trabajo de manera rigurosa y contar con una evaluaci\u00f3n gubernamental independiente\u201d, dijo.<\/p>\n<p>Califf afirm\u00f3 que determinar el impacto de los aditivos alimentarios en la salud durante largos per\u00edodos de tiempo tambi\u00e9n es dif\u00edcil y lleva mucho tiempo: \u201cNo se trata de que las personas desarrollen c\u00e1ncer en una semana, sino de un mayor riesgo de c\u00e1ncer 20 a\u00f1os despu\u00e9s\u201d.<\/p>\n<p>\u201cSe necesita una epidemiolog\u00eda a gran escala, mucha experiencia y equipos de personas, incluidas personas que conozcan la qu\u00edmica, la biolog\u00eda, la epidemiolog\u00eda y las enfermedades humanas, y no es f\u00e1cil\u201d, afirm\u00f3. \u201cMe parece que aumentar el presupuesto de la FDA ser\u00eda un buen acuerdo para el pueblo estadounidense\u201d.<\/p>\n<p><em>Meg Tirrell de CNN contribuy\u00f3 a este informe.<\/em><\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy, ha iniciado el proceso de eliminaci\u00f3n de un programa de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) llamado GRAS, o \u201cgeneralmente reconocido como seguro\u201d. Seg\u00fan los cr\u00edticos, la industria alimentaria ha hecho un abuso [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1459818","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy, ha iniciado el proceso de eliminaci\u00f3n de un programa de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) llamado GRAS, o \u201cgeneralmente reconocido como seguro\u201d. Seg\u00fan los cr\u00edticos, la industria alimentaria ha hecho un abuso [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-12T14:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?\",\"datePublished\":\"2025-03-12T14:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\"},\"wordCount\":1662,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\",\"name\":\"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-03-12T14:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","og_locale":"es_ES","og_type":"article","og_title":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante? - Noticias","og_description":"El secretario de Salud y Servicios Humanos de Estados Unidos, Robert F. Kennedy, ha iniciado el proceso de eliminaci\u00f3n de un programa de la Administraci\u00f3n de Alimentos y Medicamentos de Estados Unidos (FDA, por sus siglas en ingl\u00e9s) llamado GRAS, o \u201cgeneralmente reconocido como seguro\u201d. Seg\u00fan los cr\u00edticos, la industria alimentaria ha hecho un abuso [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","og_site_name":"Noticias","article_published_time":"2025-03-12T14:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/"},"author":{"name":"","@id":""},"headline":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?","datePublished":"2025-03-12T14:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/"},"wordCount":1662,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","url":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","name":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-03-12T14:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \u00bfPor qu\u00e9 es importante?","url":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2025\/03\/12\/eliminar-programa-aditivos-alimentarios-fda-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-03-12T14:03:43Z","datePublished":"2025-03-12T14:03:43Z","dateModified":"2025-03-12T14:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"RFK Jr. quiere eliminar el programa de aditivos alimentarios de la FDA. \\u00bfPor qu\\u00e9 es importante?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/12\\\/eliminar-programa-aditivos-alimentarios-fda-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2025\\\/03\\\/12\\\/eliminar-programa-aditivos-alimentarios-fda-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-03-12T14:03:43Z\",\"datePublished\":\"2025-03-12T14:03:43Z\",\"dateModified\":\"2025-03-12T14:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1461512,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/04\/22\/fda-eliminara-colorantes-alimentarios-petroleo-trax\/","url_meta":{"origin":1459818,"position":0},"title":"La FDA eliminar\u00e1 gradualmente los colorantes alimentarios a base de petr\u00f3leo; autorizar\u00e1 cuatro aditivos de color naturales","author":"","date":"abril 22, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos (FDA, por sus siglas en ingl\u00e9s) de EE.UU. planea eliminar gradualmente el uso de colorantes sint\u00e9ticos a base de petr\u00f3leo en el suministro de alimentos del pa\u00eds debido a preocupaciones de salud, anunci\u00f3 este martes el comisionado Dr. Marty Makary.\u201cDurante los \u00faltimos 50 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457553,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/01\/15\/fda-prohibe-colorante-rojo-alimentos-ee-uu-trax\/","url_meta":{"origin":1459818,"position":1},"title":"FDA proh\u00edbe el colorante rojo n\u00famero 3, vinculado con c\u00e1ncer en estudios, en alimentos, bebidas y medicamentos","author":"","date":"enero 15, 2025","format":false,"excerpt":"La Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA, por sus siglas en ingl\u00e9s) prohibi\u00f3 el uso del colorante rojo n\u00famero 3 en alimentos, bebidas y medicamentos ingeridos, m\u00e1s de 30 a\u00f1os despu\u00e9s de que los cient\u00edficos descubrieran v\u00ednculos con el c\u00e1ncer en animales, anunci\u00f3 la agencia este mi\u00e9rcoles.Un aditivo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471817,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/03\/quimicos-secretos-alimentos-eeuu-trax\/","url_meta":{"origin":1459818,"position":2},"title":"Investigaci\u00f3n descubre qu\u00edmicos a\u00f1adidos &#171;en secreto&#187; de riesgos desconocidos en miles de alimentos en EE.UU.","author":"","date":"marzo 3, 2026","format":false,"excerpt":"Una nueva investigaci\u00f3n revel\u00f3 que al menos 111 sustancias cuyo estatus de seguridad se desconoce han sido a\u00f1adidas a alimentos, bebidas y suplementos vendidos en Estados Unidos sin alertar a la Administraci\u00f3n de Alimentos y Medicamentos (FDA).\u201cLas empresas alimentarias est\u00e1n decidiendo por s\u00ed mismas a\u00f1adir en secreto ingredientes qu\u00edmicos no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452300,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/08\/30\/california-ley-prohibe-seis-sustancias-quimicas-conducta-ninos-trax\/","url_meta":{"origin":1459818,"position":3},"title":"California aprueba un proyecto de ley que proh\u00edbe seis sustancias qu\u00edmicas relacionadas con problemas de conducta en los ni\u00f1os","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- La Legislatura de California aprob\u00f3 un proyecto de ley con apoyo bipartidista que proh\u00edbe el uso del colorante rojo n\u00ba 40 y otras cinco sustancias qu\u00edmicas presentes en los alimentos que se sirven en las escuelas p\u00fablicas.El jueves, el llamado Estado Dorado se convirti\u00f3 en el primero del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457602,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/01\/17\/colorante-rojo-3-prohibido-estudios-otros-colorantes-trax\/","url_meta":{"origin":1459818,"position":4},"title":"El colorante rojo n\u00famero 3 ya est\u00e1 prohibido en Estados Unidos. \u00bfQu\u00e9 dicen los estudios sobre otros colorantes?","author":"","date":"enero 17, 2025","format":false,"excerpt":"Ahora que la Administraci\u00f3n de Alimentos y Medicamentos de EE.UU. (FDA) prohibi\u00f3 el colorante rojo n\u00famero 3, son muchos los que critican o cuestionan la seguridad y la autorizaci\u00f3n por parte de la FDA del colorante rojo n\u00famero 40 y otros cinco aditivos colorantes de uso com\u00fan en Estados Unidos.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455360,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/10\/25\/mcdonalds-e-coli-primera-demanda-trax\/","url_meta":{"origin":1459818,"position":5},"title":"Presentan la primera demanda contra McDonald\u2019s por su brote de E. coli","author":"","date":"octubre 25, 2024","format":false,"excerpt":"(CNN) -- Un hombre de Colorado present\u00f3 la primera demanda contra McDonald\u2019s relacionada con su brote de E. coli vinculado a las hamburguesas Cuarto de Libra que hasta ahora ha provocado al menos 49 enfermedades en 10 estados, incluida una muerte.La demanda se present\u00f3 un d\u00eda despu\u00e9s de que los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459818","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1459818"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1459818\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1459818"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1459818"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1459818"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}