{"id":1472618,"date":"2026-03-27T12:03:57","date_gmt":"2026-03-27T19:03:57","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/"},"modified":"2026-03-27T12:03:57","modified_gmt":"2026-03-27T19:03:57","slug":"confianza-consumidor-economia-eeuu-guerra-iran-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","title":{"rendered":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU."},"content":{"rendered":"<p>Los estadounidenses se est\u00e1n volviendo m\u00e1s pesimistas sobre la econom\u00eda de Estados Unidos a medida que la guerra con Ir\u00e1n sigue sacudiendo los mercados, con el \u00e1nimo deterior\u00e1ndose en todos los grupos de ingresos \u2014incluidos los m\u00e1s ricos.<\/p>\n<p>La confianza del consumidor cay\u00f3 un 6 % este mes hasta una lectura final de 53,3, dijo el viernes la Universidad de Michigan, una ca\u00edda m\u00e1s pronunciada que la informada a principios de mes, cuando la guerra acababa de comenzar. La confianza se encuentra ahora en su punto m\u00e1s bajo desde diciembre. El nivel del viernes fue inferior a la lectura de 54,2 que los economistas proyectaron en una encuesta de la firma de datos FactSet.<\/p>\n<p>El conflicto en Medio Oriente ha impulsado al alza los precios mundiales de la energ\u00eda durante el \u00faltimo mes, lo que ha llevado a que los principales \u00edndices burs\u00e1tiles de Estados Unidos oscilen bruscamente mientras los inversores buscan se\u00f1ales de que podr\u00eda terminar pronto. El presidente Donald Trump dice que su Gobierno est\u00e1 participando en conversaciones con Ir\u00e1n.<\/p>\n<p>\u201cSe observaron descensos en todos los grupos de edad y partidos pol\u00edticos\u201d, dijo Joanne Hsu, directora de la encuesta, en un comunicado. \u201cLos consumidores con ingresos medios y altos y riqueza en acciones, golpeados tanto por el aumento de los precios de la gasolina como por la volatilidad de los mercados financieros a ra\u00edz del conflicto con Ir\u00e1n, mostraron ca\u00eddas particularmente grandes en la confianza.\u201d<\/p>\n<p>Una guerra prolongada podr\u00eda tanto disparar la inflaci\u00f3n como llevar a la econom\u00eda estadounidense a una recesi\u00f3n. Los precios de la gasolina en todo Estados Unidos ya se han disparado desde el inicio del conflicto.<\/p>\n<p>Las expectativas de los estadounidenses sobre la inflaci\u00f3n en el a\u00f1o pr\u00f3ximo registraron el mayor aumento mensual en aproximadamente un a\u00f1o, subiendo al 3,8 % desde el 3,4 % en febrero, por encima de cualquier nivel visto en 2024.<\/p>\n<p>Sin embargo, los encuestados no esperan que una inflaci\u00f3n m\u00e1s alta impulsada por la guerra se mantenga durante los pr\u00f3ximos cinco a 10 a\u00f1os, y las expectativas de inflaci\u00f3n a largo plazo de hecho bajaron ligeramente este mes hasta el 3,2 %.<\/p>\n<p>\u201cEs posible que los consumidores no esperen que los acontecimientos negativos recientes persistan muy lejos en el futuro\u201d, dijo Hsu. \u201cEstas opiniones est\u00e1n sujetas a cambios, sin embargo, si el conflicto con Ir\u00e1n se prolonga o si los precios m\u00e1s altos de la energ\u00eda se trasladan a la inflaci\u00f3n general\u201d.<\/p>\n<p>Eso es tranquilizador para los responsables de pol\u00edtica de la Reserva Federal, que prestan mucha atenci\u00f3n a la percepci\u00f3n de las personas sobre los precios, particularmente a largo plazo. Las expectativas de inflaci\u00f3n a largo plazo sirven como un indicador de la confianza de los estadounidenses en la capacidad de la Fed para frenar los aumentos de precios. La Fed apunta a una inflaci\u00f3n del 2 % anual, medida por el \u00edndice de precios del Gasto en Consumo Personal, que actualmente se sit\u00faa en el 2,8 %, a enero.<\/p>\n<p>La ca\u00edda de la confianza del consumidor no se ha traducido en un gasto m\u00e1s d\u00e9bil en los \u00faltimos a\u00f1os.<\/p>\n<p>Cada vez que la confianza se desplom\u00f3 despu\u00e9s de la pandemia \u2014como en 2022, cuando la inflaci\u00f3n estaba en su nivel m\u00e1s alto en 40 a\u00f1os, o en 2023 durante un enfrentamiento en el Congreso por el techo de la deuda\u2014 los estadounidenses siguieron abriendo sus carteras.<\/p>\n<p>El gasto del consumidor, que representa alrededor de dos tercios de la econom\u00eda estadounidense, est\u00e1 m\u00e1s influido por el estado del mercado laboral; espec\u00edficamente, por si los despidos est\u00e1n aumentando m\u00e1s de lo habitual o no. Si bien el crecimiento del empleo ha sido an\u00e9mico durante el \u00faltimo a\u00f1o, las nuevas solicitudes de prestaciones por desempleo se mantienen en niveles hist\u00f3ricamente bajos. Y desde mediados de 2023, el crecimiento de los salarios ha superado a la inflaci\u00f3n.<\/p>\n<p>Eso significa que los estadounidenses todav\u00eda tienen los medios para seguir gastando \u2014hasta que dejan de tenerlos. Un fuerte repunte de los despidos, combinado con la realidad de que hoy en d\u00eda se ha vuelto m\u00e1s dif\u00edcil encontrar trabajo, probablemente obligar\u00eda a los estadounidenses a recortar su gasto.<\/p>\n<p>Y el gasto en los \u00faltimos meses ya ha sido m\u00e1s bien d\u00e9bil. Las ventas minoristas, que constituyen una parte considerable del gasto total, cayeron un 0,2 % en enero, despu\u00e9s de mantenerse sin cambios en diciembre. Es probable que el fr\u00edo intenso haya lastrado el gasto en enero.<\/p>\n<p>Si la guerra con Ir\u00e1n se prolonga durante meses, las perspectivas podr\u00edan oscurecerse r\u00e1pidamente, desencadenando una espiral econ\u00f3mica descendente a medida que la ca\u00edda de las acciones d\u00e9 paso a un gasto m\u00e1s d\u00e9bil y, en \u00faltima instancia, a una recesi\u00f3n.<\/p>\n<p>\u201cEn una econom\u00eda en forma de K, lo que impacta a la cima puede propagarse r\u00e1pidamente\u201d, dijo Heather Long, economista jefe de Navy Federal Credit Union, en un comentario emitido el viernes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los estadounidenses se est\u00e1n volviendo m\u00e1s pesimistas sobre la econom\u00eda de Estados Unidos a medida que la guerra con Ir\u00e1n sigue sacudiendo los mercados, con el \u00e1nimo deterior\u00e1ndose en todos los grupos de ingresos \u2014incluidos los m\u00e1s ricos. La confianza del consumidor cay\u00f3 un 6 % este mes hasta una lectura final de 53,3, dijo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472618","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los estadounidenses se est\u00e1n volviendo m\u00e1s pesimistas sobre la econom\u00eda de Estados Unidos a medida que la guerra con Ir\u00e1n sigue sacudiendo los mercados, con el \u00e1nimo deterior\u00e1ndose en todos los grupos de ingresos \u2014incluidos los m\u00e1s ricos. La confianza del consumidor cay\u00f3 un 6 % este mes hasta una lectura final de 53,3, dijo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-27T19:03:57+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU.\",\"datePublished\":\"2026-03-27T19:03:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\"},\"wordCount\":894,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\",\"name\":\"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-27T19:03:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU. - Noticias","og_description":"Los estadounidenses se est\u00e1n volviendo m\u00e1s pesimistas sobre la econom\u00eda de Estados Unidos a medida que la guerra con Ir\u00e1n sigue sacudiendo los mercados, con el \u00e1nimo deterior\u00e1ndose en todos los grupos de ingresos \u2014incluidos los m\u00e1s ricos. La confianza del consumidor cay\u00f3 un 6 % este mes hasta una lectura final de 53,3, dijo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-27T19:03:57+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/"},"author":{"name":"","@id":""},"headline":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU.","datePublished":"2026-03-27T19:03:57+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/"},"wordCount":894,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","name":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-27T19:03:57+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Incluso los ricos est\u00e1n perdiendo la confianza en el rumbo econ\u00f3mico de EE.UU.","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/27\/confianza-consumidor-economia-eeuu-guerra-iran-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-27T19:03:57Z","datePublished":"2026-03-27T19:03:57Z","dateModified":"2026-03-27T19:03:57Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Incluso los ricos est\\u00e1n perdiendo la confianza en el rumbo econ\\u00f3mico de EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/27\\\/confianza-consumidor-economia-eeuu-guerra-iran-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/27\\\/confianza-consumidor-economia-eeuu-guerra-iran-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-27T19:03:57Z\",\"datePublished\":\"2026-03-27T19:03:57Z\",\"dateModified\":\"2026-03-27T19:03:57Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1473495,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/25\/confianza-consumidores-repunta-ligeramente-trax\/","url_meta":{"origin":1472618,"position":0},"title":"La confianza de los consumidores repunta ligeramente tras alcanzar su nivel m\u00e1s bajo jam\u00e1s registrado","author":"","date":"abril 25, 2026","format":false,"excerpt":"Los estadounidenses siguen sinti\u00e9ndose mal respecto de la econom\u00eda y temen que la guerra entre Estados Unidos e Israel con Ir\u00e1n siga empujando los precios al alza.La lectura final de abril del \u00edndice de confianza del consumidor de la Universidad de Michigan se ubic\u00f3 en 49,8, una leve mejora frente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460573,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/03\/28\/estadounidenses-preocupados-aumento-desempleo-encuesta-trax\/","url_meta":{"origin":1472618,"position":1},"title":"Los estadounidenses no hab\u00edan estado tan preocupados por el aumento del desempleo desde 2009, seg\u00fan una encuesta","author":"","date":"marzo 28, 2025","format":false,"excerpt":"Los estadounidenses no solo temen cada vez m\u00e1s una mayor inflaci\u00f3n, con el presidente Donald Trump a punto de anunciar una serie de aranceles en pocos d\u00edas, sino que muchos m\u00e1s ahora temen un aumento del desempleo.La confianza del consumidor se desplom\u00f3 un 12% este mes, seg\u00fan inform\u00f3 la Universidad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462444,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/16\/optimismo-estadounidenses-economia-minimo-historico-trax\/","url_meta":{"origin":1472618,"position":2},"title":"El optimismo de los estadounidenses respecto a la econom\u00eda se encuentra en un m\u00ednimo casi hist\u00f3rico","author":"","date":"mayo 16, 2025","format":false,"excerpt":"La percepci\u00f3n de los estadounidenses sobre la econom\u00eda contin\u00faa estancada tras la aplicaci\u00f3n de los aranceles del presidente Donald Trump: la confianza del consumidor sigi\u00f3 en ca\u00edda libre este mes, ubic\u00e1ndse en un m\u00ednimo casi hist\u00f3rico.El \u00edndice de confianza del consumidor de la Universidad de Michigan cay\u00f3 un 2,7 %\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462850,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/27\/trump-guerra-comercial-bonos-economia-afronta-semana-dificil-trax\/","url_meta":{"origin":1472618,"position":3},"title":"Con Trump reavivando la guerra comercial y la tensi\u00f3n en bonos, la econom\u00eda afronta una semana dif\u00edcil","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Al final de la semana, quedar\u00e1 mucho m\u00e1s claro c\u00f3mo se mantiene la econom\u00eda estadounidense en medio de los cambios radicales de pol\u00edtica del presidente Donald Trump.La err\u00e1tica guerra comercial de Trump ya ha inquietado a los consumidores y afectado el crecimiento econ\u00f3mico, principalmente porque las empresas estadounidenses se han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459033,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/21\/confianza-consumidores-estadounidenses-desploma-aranceles-inflacion-trax\/","url_meta":{"origin":1472618,"position":4},"title":"La confianza de los consumidores estadounidenses se desploma por los temores a los aranceles y la inflaci\u00f3n","author":"","date":"febrero 21, 2025","format":false,"excerpt":"La inflaci\u00f3n est\u00e1 repuntando de nuevo y el presidente Donald Trump dijo esta semana que todo es culpa de su predecesor. Pero no importa a qui\u00e9n culpe Trump, el estado de \u00e1nimo econ\u00f3mico de Estados Unidos se est\u00e1 agriando, y \u00e9l es quien recibe las cr\u00edticas por ello.La encuesta m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470526,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/27\/confianza-consumidor-desplome-nivel-mas-bajo-2014-trax\/","url_meta":{"origin":1472618,"position":5},"title":"La confianza del consumidor se desploma al nivel m\u00e1s bajo desde 2014","author":"","date":"enero 27, 2026","format":false,"excerpt":"El \u00e1nimo econ\u00f3mico de Estados Unidos se deterior\u00f3 en enero hasta su nivel m\u00e1s bajo en m\u00e1s de una d\u00e9cada, debido a que los consumidores se mostraron preocupados por las tensiones geopol\u00edticas, la asequibilidad y la incesante guerra comercial del presidente Donald Trump.El \u00cdndice de Confianza del Consumidor de The\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472618","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472618"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472618\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}