{"id":1472726,"date":"2026-03-31T08:03:41","date_gmt":"2026-03-31T15:03:41","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/"},"modified":"2026-03-31T08:03:41","modified_gmt":"2026-03-31T15:03:41","slug":"corte-suprema-terapias-conversion-gays-transgeneros-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","title":{"rendered":"Corte Suprema permite impugnar la prohibici\u00f3n de &#171;terapias de conversi\u00f3n&#187; para j\u00f3venes gays y transg\u00e9nero"},"content":{"rendered":"<p>La Corte Suprema respald\u00f3 este martes la impugnaci\u00f3n presentada por un consejero religioso contra la prohibici\u00f3n de Colorado sobre la \u201cterapia de conversi\u00f3n\u201d para menores gays y transg\u00e9nero. Se trata de un nuevo rev\u00e9s legal para la comunidad LGBTQ que tendr\u00e1 repercusiones en casi la mitad del pa\u00eds.<\/p>\n<p>T\u00e9cnicamente, la decisi\u00f3n no anula la ley \u2014la cual permanece vigente por el momento\u2014, pero implica que los tribunales inferiores deber\u00e1n revisarla nuevamente aplicando el nivel m\u00e1s estricto de escrutinio judicial; un resultado que deja a dicha prohibici\u00f3n en una situaci\u00f3n sumamente precaria.<\/p>\n<p>El juez Neil Gorsuch redact\u00f3 la opini\u00f3n mayoritaria del tribunal, que se resolvi\u00f3 con 8 votos a favor y 1 en contra. La jueza Ketanji Jackson, de tendencia liberal, emiti\u00f3 un voto disidente.<\/p>\n<p>Gorsuch dijo que la ley de Colorado requer\u00eda una revisi\u00f3n mucho m\u00e1s rigurosa bajo la Primera Enmienda.<\/p>\n<p>\u201cColorado puede considerar su pol\u00edtica esencial para la salud y la seguridad p\u00fablicas\u201d, escribi\u00f3 Gorsuch. \u201cSin duda, los gobiernos censores a lo largo de la historia han cre\u00eddo lo mismo. Pero la Primera Enmienda sirve de escudo contra cualquier intento de imponer la ortodoxia en el pensamiento o la expresi\u00f3n en este pa\u00eds\u201d.<\/p>\n<p>Por su parte, la jueza Jackson, la \u00fanica disidente, dijo que cre\u00eda que la decisi\u00f3n de sus colegas \u201cabre una caja de Pandora peligrosa\u201d al socavar el derecho de los estados a regular la atenci\u00f3n m\u00e9dica.<\/p>\n<p>\u201cLa Constituci\u00f3n no supone un obst\u00e1culo para la regulaci\u00f3n razonable de los tratamientos m\u00e9dicos perjudiciales solo porque la atenci\u00f3n m\u00e9dica deficiente se brinde a trav\u00e9s de la palabra en lugar de mediante un bistur\u00ed\u201d, escribi\u00f3 Jackson, miembro del ala liberal del tribunal, nombrado por el expresidente Joe Biden.<\/p>\n<p>Tambi\u00e9n advirti\u00f3 que sus colegas no hab\u00edan considerado \u201clas posibles implicaciones a largo plazo y desastrosas\u201d de su decisi\u00f3n.<\/p>\n<p>\u201cEn definitiva, dado que la mayor\u00eda est\u00e1 jugando con fuego en este caso, me temo que la gente de este pa\u00eds acabar\u00e1 quem\u00e1ndose\u201d, escribi\u00f3.<\/p>\n<p>\u201cNos encontramos en una pendiente resbaladiza: por primera vez, la Corte Suprema ha interpretado la Primera Enmienda para avalar el riesgo de da\u00f1o terap\u00e9utico a los ni\u00f1os al limitar la capacidad del Estado para regular a los proveedores m\u00e9dicos que tratan a pacientes mediante el habla\u201d, escribi\u00f3 Jackson.<\/p>\n<p>Continu\u00f3: \u201c\u00bfQu\u00e9 sigue? En el peor de los casos, nuestro sistema m\u00e9dico se desmorona a medida que diversos profesionales de la salud con licencia \u2014terapeutas, psiquiatras y presumiblemente cualquier otra persona que afirme utilizar el lenguaje al administrar tratamientos a los pacientes\u2014 comienzan a ejercer ampliamente su reci\u00e9n adquirido derecho constitucional a brindar atenci\u00f3n m\u00e9dica deficiente\u201d.<\/p>\n<p>En respuesta a la decisi\u00f3n del Tribunal Supremo, el Proyecto Trevor, una organizaci\u00f3n sin fines de lucro dedicada a la prevenci\u00f3n del suicidio y la intervenci\u00f3n en crisis que apoya a j\u00f3venes LGBTQ, dijo que el fallo era \u201cun tr\u00e1gico paso atr\u00e1s para nuestro pa\u00eds que pondr\u00e1 en riesgo la vida de los j\u00f3venes\u201d.<\/p>\n<p>\u201cEstos esfuerzos, independientemente de c\u00f3mo los denominen sus defensores o de lo que diga cualquier tribunal, siguen demostrando causar da\u00f1os psicol\u00f3gicos duraderos\u201d, declar\u00f3 el director ejecutivo del grupo, Jaymes Black, en un comunicado.<\/p>\n<p>\u201cLos j\u00f3venes LGBTQ+ sometidos a terapias de conversi\u00f3n tienen m\u00e1s del doble de probabilidades de intentar suicidarse que sus pares\u201d, agreg\u00f3 Black. \u201cPor eso se han promulgado leyes de protecci\u00f3n en m\u00e1s de 20 estados, y cuentan con el apoyo de todas las principales asociaciones m\u00e9dicas y de salud mental del pa\u00eds\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Corte Suprema respald\u00f3 este martes la impugnaci\u00f3n presentada por un consejero religioso contra la prohibici\u00f3n de Colorado sobre la \u201cterapia de conversi\u00f3n\u201d para menores gays y transg\u00e9nero. Se trata de un nuevo rev\u00e9s legal para la comunidad LGBTQ que tendr\u00e1 repercusiones en casi la mitad del pa\u00eds. T\u00e9cnicamente, la decisi\u00f3n no anula la ley [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472726","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Corte Suprema permite impugnar la prohibici\u00f3n de &quot;terapias de conversi\u00f3n&quot; para j\u00f3venes gays y transg\u00e9nero - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Corte Suprema permite impugnar la prohibici\u00f3n de &quot;terapias de conversi\u00f3n&quot; para j\u00f3venes gays y transg\u00e9nero - Noticias\" \/>\n<meta property=\"og:description\" content=\"La Corte Suprema respald\u00f3 este martes la impugnaci\u00f3n presentada por un consejero religioso contra la prohibici\u00f3n de Colorado sobre la \u201cterapia de conversi\u00f3n\u201d para menores gays y transg\u00e9nero. Se trata de un nuevo rev\u00e9s legal para la comunidad LGBTQ que tendr\u00e1 repercusiones en casi la mitad del pa\u00eds. T\u00e9cnicamente, la decisi\u00f3n no anula la ley [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T15:03:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Corte Suprema permite impugnar la prohibici\u00f3n de &#171;terapias de conversi\u00f3n&#187; para j\u00f3venes gays y transg\u00e9nero\",\"datePublished\":\"2026-03-31T15:03:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\"},\"wordCount\":661,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\",\"name\":\"Corte Suprema permite impugnar la prohibici\u00f3n de \\\"terapias de conversi\u00f3n\\\" para j\u00f3venes gays y transg\u00e9nero - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-31T15:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Corte Suprema permite impugnar la prohibici\u00f3n de &#171;terapias de conversi\u00f3n&#187; para j\u00f3venes gays y transg\u00e9nero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Corte Suprema permite impugnar la prohibici\u00f3n de \"terapias de conversi\u00f3n\" para j\u00f3venes gays y transg\u00e9nero - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Corte Suprema permite impugnar la prohibici\u00f3n de \"terapias de conversi\u00f3n\" para j\u00f3venes gays y transg\u00e9nero - Noticias","og_description":"La Corte Suprema respald\u00f3 este martes la impugnaci\u00f3n presentada por un consejero religioso contra la prohibici\u00f3n de Colorado sobre la \u201cterapia de conversi\u00f3n\u201d para menores gays y transg\u00e9nero. Se trata de un nuevo rev\u00e9s legal para la comunidad LGBTQ que tendr\u00e1 repercusiones en casi la mitad del pa\u00eds. T\u00e9cnicamente, la decisi\u00f3n no anula la ley [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","og_site_name":"Noticias","article_published_time":"2026-03-31T15:03:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/"},"author":{"name":"","@id":""},"headline":"Corte Suprema permite impugnar la prohibici\u00f3n de &#171;terapias de conversi\u00f3n&#187; para j\u00f3venes gays y transg\u00e9nero","datePublished":"2026-03-31T15:03:41+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/"},"wordCount":661,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","name":"Corte Suprema permite impugnar la prohibici\u00f3n de \"terapias de conversi\u00f3n\" para j\u00f3venes gays y transg\u00e9nero - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-31T15:03:41+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Corte Suprema permite impugnar la prohibici\u00f3n de &#171;terapias de conversi\u00f3n&#187; para j\u00f3venes gays y transg\u00e9nero"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Corte Suprema permite impugnar la prohibici\u00f3n de &#171;terapias de conversi\u00f3n&#187; para j\u00f3venes gays y transg\u00e9nero","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/corte-suprema-terapias-conversion-gays-transgeneros-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-31T15:03:41Z","datePublished":"2026-03-31T15:03:41Z","dateModified":"2026-03-31T15:03:41Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Corte Suprema permite impugnar la prohibici\\u00f3n de &#171;terapias de conversi\\u00f3n&#187; para j\\u00f3venes gays y transg\\u00e9nero\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/31\\\/corte-suprema-terapias-conversion-gays-transgeneros-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/31\\\/corte-suprema-terapias-conversion-gays-transgeneros-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-31T15:03:41Z\",\"datePublished\":\"2026-03-31T15:03:41Z\",\"dateModified\":\"2026-03-31T15:03:41Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1467188,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/10\/07\/corte-suprema-terapias-conversion-trax\/","url_meta":{"origin":1472726,"position":0},"title":"La mayor\u00eda conservadora de la Corte Suprema se dispone a revertir la prohibici\u00f3n de las terapias de conversi\u00f3n","author":"","date":"octubre 7, 2025","format":false,"excerpt":"Una mayor\u00eda de la Corte Suprema de EE.UU. indic\u00f3 este martes que fallar\u00e1 en contra de la prohibici\u00f3n de Colorado sobre las \u201cterapias de conversi\u00f3n\u201d de menores, con varios de los jueces de acuerdo con una consejera del estado que afirma que la ley viola sus derechos de la Primera\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468100,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/11\/06\/corte-suprema-marcadores-sexo-pasaportes-trax\/","url_meta":{"origin":1472726,"position":1},"title":"La Corte Suprema avala restricciones de Trump a pasaportes para personas trans y no binarias","author":"","date":"noviembre 6, 2025","format":false,"excerpt":"La Corte Suprema permiti\u00f3 este jueves que el Gobierno de Trump exija que la designaci\u00f3n de sexo en los pasaportes estadounidenses coincida con el sexo biol\u00f3gico del viajero, un golpe para los estadounidenses transg\u00e9nero y no binarios que han argumentado que la pol\u00edtica es inconstitucional.La orden represent\u00f3 otra victoria para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459278,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/02\/27\/pentagono-expulsar-miembros-transgenero-trax\/","url_meta":{"origin":1472726,"position":2},"title":"El Pent\u00e1gono planea expulsar a los miembros transg\u00e9nero del servicio, bajo una nueva pol\u00edtica del Gobierno de Trump","author":"","date":"febrero 27, 2025","format":false,"excerpt":"El Pent\u00e1gono planea expulsar a los miembros transg\u00e9nero que actualmente est\u00e9n en servicio y que no cumplen con los requisitos espec\u00edficos bajo su nueva directiva pol\u00edtica, seg\u00fan la gu\u00eda oficial hecha p\u00fablica en una presentaci\u00f3n judicial del mi\u00e9rcoles.\u201cLos miembros del servicio que tengan un diagn\u00f3stico actual o antecedentes de disforia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457029,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/27\/trump-pide-corte-suprema-pausa-prohibicion-tiktok-trax\/","url_meta":{"origin":1472726,"position":3},"title":"Trump pide a la Corte Suprema que suspenda prohibici\u00f3n de TikTok; Biden dice que la aplicaci\u00f3n representa una amenaza &#171;grave&#187;","author":"","date":"diciembre 27, 2024","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, solicit\u00f3 a la Corte Suprema suspender una pol\u00e9mica prohibici\u00f3n de TikTok que est\u00e1 programada para entrar en vigencia el pr\u00f3ximo mes, y dijo a los jueces en una presentaci\u00f3n legal este viernes que la medida permitir\u00eda a su Gobierno \u201cbuscar una resoluci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456237,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/03\/derechos-personas-transgenero-corte-suprema-estados-unidos-trax\/","url_meta":{"origin":1472726,"position":4},"title":"Los derechos de las personas transg\u00e9nero est\u00e1n al centro de la discusi\u00f3n en la Corte Suprema de Estados Unidos","author":"","date":"diciembre 3, 2024","format":false,"excerpt":"Washington (CNN) --\u00a0La Corte Suprema abordar\u00e1 el mi\u00e9rcoles el tema, pol\u00edticamente tenso, de los derechos de las personas transg\u00e9nero cuando escuche la impugnaci\u00f3n a la prohibici\u00f3n de Tennessee de que los menores reciban tratamiento de afirmaci\u00f3n de g\u00e9nero, en el caso de mayor repercusi\u00f3n del oto\u00f1o.Los abogados del Gobierno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462864,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/05\/27\/corte-suprema-recta-final-ciudadania-nacimiento-transgenero-religion-trax\/","url_meta":{"origin":1472726,"position":5},"title":"Corte Suprema est\u00e1 en la recta final para decidir sobre ciudadan\u00eda por nacimiento, atenci\u00f3n a personas transg\u00e9nero y religi\u00f3n","author":"","date":"mayo 27, 2025","format":false,"excerpt":"La Corte Suprema se acerca a las \u00faltimas semanas de un intenso periodo que comenz\u00f3 con apelaciones importantes sobre los derechos de las personas transg\u00e9nero y TikTok, pero que ahora est\u00e1 cada vez m\u00e1s centrado en las pol\u00edticas y controversias relacionadas con el presidente Donald Trump.Con m\u00e1s de la mitad\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472726","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472726"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472726\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472726"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472726"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472726"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}