{"id":1472730,"date":"2026-03-31T09:03:55","date_gmt":"2026-03-31T16:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/"},"modified":"2026-03-31T09:03:55","modified_gmt":"2026-03-31T16:03:55","slug":"portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","title":{"rendered":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds"},"content":{"rendered":"<p>Entre la expectativa y las cr\u00edticas, el ingreso del portaaviones Nimitz, un buque de la Armada de Estados Unidos, en aguas paname\u00f1as no pas\u00f3 desapercibido esta semana. Se trata de una embarcaci\u00f3n con capacidad para alojar a 90 aeronaves, entre aviones y helic\u00f3pteros, y capaz de soportar unas 100 mil toneladas. En su primera etapa de una gira por Am\u00e9rica latina, lleg\u00f3 a Panam\u00e1 acompa\u00f1ado del destructor USS Gridley.<\/p>\n<p>Estos buques estaban en la costa oeste de los Estados Unidos y ahora se reposicionan sobre el este, justo cuando hay tensiones entre Estados Unidos y Cuba, intensificadas despu\u00e9s del operativo militar estadounidense que deriv\u00f3 en la captura del derrocado presidente de Venezuela, Nicol\u00e1s Maduro.<\/p>\n<p>La administraci\u00f3n de Donald Trump busca <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/28\/latinoamerica\/eeuu-portaviones-uss-nimitz-aguas-panama-orix\">estrechar alianzas<\/a> con pa\u00edses que considera cercanos, a trav\u00e9s de iniciativas como la Cumbre Escudo de las Am\u00e9ricas, en la que el presidente Donald Trump convoc\u00f3 a una docena de l\u00edderes de la regi\u00f3n para acordar acciones conjuntas en materia de seguridad. La llegada del Nimitz tambi\u00e9n fue le\u00edda en ese contexto en Panam\u00e1, por lo que gener\u00f3 divisiones en el escenario pol\u00edtico.<\/p>\n<p>Entre los primeros visitantes al Nimitz, adem\u00e1s del embajador de Estados Unidos en Panam\u00e1, Kevin Marino Cabrera, estuvo un grupo de diputados de la Asamblea Nacional, as\u00ed como el alcalde de la ciudad de Panam\u00e1, Mayer Mizrachi.<\/p>\n<p>Varios de los diputados compartieron en sus redes sociales im\u00e1genes y su alegr\u00eda de abordar el Nimitz y desataron una serie de cuestionamientos entre los usuarios. El mensaje del alcalde Mizrachi, sin embargo, gener\u00f3 incluso m\u00e1s cr\u00edticas.<\/p>\n<p>\u201cDisney ni sabe. Locura. Qu\u00e9 experiencia m\u00e1s incre\u00edble conocer el USS Nimitz. Jam\u00e1s pens\u00e9 poder estar en un portaavi\u00f3n en mi vida y espero que mis historias te hagan sentir la experiencia como si estuvieras all\u00ed. Gracias por la invitaci\u00f3n\u201d, escribi\u00f3 el alcalde, quien tambi\u00e9n comparti\u00f3 fotos y videos.<\/p>\n<p>Esa emoci\u00f3n fue cuestionada inmediatamente por defensores de causas nacionalistas en Panam\u00e1.<\/p>\n<p>El comunicador Manolo \u00c1lvarez manifest\u00f3 sus cr\u00edticas a quienes celebraron la visita al portaaviones. \u201cComo no jugaron con soldaditos de plomo en su infancia, ahora de \u201cmayuyones\u201d se exhiben felices en un barco de guerra de Estados Unidos que est\u00e1 en Panam\u00e1, y cuya misi\u00f3n es matar gente\u201d, dijo en di\u00e1logo con CNN. \u201cY todo en medio de la guerra que Estados Unidos e Israel desataron contra Ir\u00e1n, y de la retaliaci\u00f3n iran\u00ed\u201d, a\u00f1adi\u00f3.<\/p>\n<p>Pero m\u00e1s all\u00e1 de cr\u00edticas contra pol\u00edticos, otros expresan un supuesto contrasentido en el discurso de neutralidad de Panam\u00e1.<\/p>\n<p>\u201cLa presencia de estos buques me genera incomodidad por el simple hecho de que Panam\u00e1 se supone un pa\u00eds neutro y la presencia de ellos (el destructor y el portaaviones) no indica esa neutralidad que tanto se profesa\u201d, dijo a CNN Arturo Manzzo, un ciudadano que asegura, por el contrario, estos buques \u201ccomprometen al pa\u00eds\u201d.<\/p>\n<p>En ese sentido, el m\u00e9dico Xavier S\u00e1ez Llorens escribi\u00f3 en sus redes sociales que \u201cPanam\u00e1 ha sido tradicionalmente un pa\u00eds mediador de conflictos internacionales y con la neutralidad como bandera de una franja interoce\u00e1nica que le sirve al globo terr\u00e1queo, sin excepciones\u201d. Por eso, opin\u00f3, \u201csubirse emocionado a un barco destructor estadounidense es carecer de dignidad pol\u00edtica y nos pone en riesgo, como naci\u00f3n, de sufrir consecuencias imprevistas a futuro\u201d.<\/p>\n<p>CNN intent\u00f3 contact\u00f3 al alcalde Mizrachi para obtener comentarios sobre las cr\u00edticas y est\u00e1 a la espera de respuesta.<\/p>\n<p>Este domingo, durante una ceremonia en el destructor Gridley, un buque de guerra que navega como centinela del portaaviones Nimitz y que est\u00e1 anclado en el puerto de cruceros de Amador, en la ciudad de Panam\u00e1, el embajador de EE.UU. en el pa\u00eds se refiri\u00f3 a la importancia de que haya sociedad entre ambos pa\u00edses para proteger el Canal de Panam\u00e1.<\/p>\n<p>El embajador dijo que este recorrido y los ejercicios conjuntos destacan el \u201ccompromiso con un entorno mar\u00edtimo seguro, el libre flujo del comercio a trav\u00e9s del canal y la hist\u00f3rica amistad\u201d entre Estados Unidos y Panam\u00e1. \u201cEl canal es una arteria estrat\u00e9gica para el comercio mundial y protegerlo de amenazas como el narcotr\u00e1fico y el crimen organizado, es una responsabilidad que asumimos juntos\u201d, asegur\u00f3.<\/p>\n<p>En la misma actividad en el destructor Gridley, que tiene radares y misiles de alta tecnolog\u00eda, CNN pregunt\u00f3 al ministro de Seguridad de Panam\u00e1, Frank \u00c1brego, sobre los se\u00f1alamientos de que, supuestamente, la presencia de los dos buques compromete al pa\u00eds y su seguridad.<\/p>\n<p>\u201cEllos (los militares de EE.UU.) andan en un ejercicio a nivel hemisf\u00e9rico. Eso es todo el mensaje que yo puedo decir. No nos compromete en nada en particular, considero yo\u201d, dijo \u00c1brego.<\/p>\n<p>Previamente CNN pregunt\u00f3 al ministro para Asuntos del Canal, Jose Ram\u00f3n Icaza, sobre el mismo tema. \u201cEsto forma parte de una traves\u00eda normal como cualquier otro buque de guerra que pasa por nuestro pa\u00eds. Este es un recorrido hacia el sur, Sudam\u00e9rica, tiene varias paradas en Sudam\u00e9rica, tanto en el lado pac\u00edfico, como el lado atl\u00e1ntico, hasta llegar a la costa este de Estados Unidos, o sea que no hay de qu\u00e9 preocuparse\u201d, asegur\u00f3 Icaza.<\/p>\n<p>El portaviones USS Nimitz es una embarcaci\u00f3n de propulsi\u00f3n nuclear y el m\u00e1s antiguo en su tipo, de Estados Unidos. Seg\u00fan el embajador Kevin Marino Cabrera, este buque tiene 51 a\u00f1os y est\u00e1 en su \u00faltimo a\u00f1o de servicio.<\/p>\n<p>Por sus dimensiones, no cabe por el tercer juego de esclusas del Canal de Panam\u00e1, es decir, por el canal ampliado, ni tampoco pasa, por su altura, por debajo del Puente de Las Am\u00e9ricas, en la capital paname\u00f1a.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre la expectativa y las cr\u00edticas, el ingreso del portaaviones Nimitz, un buque de la Armada de Estados Unidos, en aguas paname\u00f1as no pas\u00f3 desapercibido esta semana. Se trata de una embarcaci\u00f3n con capacidad para alojar a 90 aeronaves, entre aviones y helic\u00f3pteros, y capaz de soportar unas 100 mil toneladas. En su primera etapa [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472730","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"Entre la expectativa y las cr\u00edticas, el ingreso del portaaviones Nimitz, un buque de la Armada de Estados Unidos, en aguas paname\u00f1as no pas\u00f3 desapercibido esta semana. Se trata de una embarcaci\u00f3n con capacidad para alojar a 90 aeronaves, entre aviones y helic\u00f3pteros, y capaz de soportar unas 100 mil toneladas. En su primera etapa [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-31T16:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds\",\"datePublished\":\"2026-03-31T16:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\"},\"wordCount\":1017,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\",\"name\":\"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-03-31T16:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds - Noticias","og_description":"Entre la expectativa y las cr\u00edticas, el ingreso del portaaviones Nimitz, un buque de la Armada de Estados Unidos, en aguas paname\u00f1as no pas\u00f3 desapercibido esta semana. Se trata de una embarcaci\u00f3n con capacidad para alojar a 90 aeronaves, entre aviones y helic\u00f3pteros, y capaz de soportar unas 100 mil toneladas. En su primera etapa [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","og_site_name":"Noticias","article_published_time":"2026-03-31T16:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/"},"author":{"name":"","@id":""},"headline":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds","datePublished":"2026-03-31T16:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/"},"wordCount":1017,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","url":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","name":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-03-31T16:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La llegada del Nimitz a Panam\u00e1 despierta desde elogios hasta cr\u00edticas y dudas sobre la neutralidad del pa\u00eds","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-03-31T16:03:55Z","datePublished":"2026-03-31T16:03:55Z","dateModified":"2026-03-31T16:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La llegada del Nimitz a Panam\\u00e1 despierta desde elogios hasta cr\\u00edticas y dudas sobre la neutralidad del pa\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/31\\\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/31\\\/portaaviones-nimitz-panama-elogios-criticas-neutralidad-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-03-31T16:03:55Z\",\"datePublished\":\"2026-03-31T16:03:55Z\",\"dateModified\":\"2026-03-31T16:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472649,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/28\/eeuu-portaviones-uss-nimitz-aguas-panama-orix\/","url_meta":{"origin":1472730,"position":0},"title":"El portaviones USS Nimitz llega a aguas de Panam\u00e1 en su gira por varios pa\u00edses de Am\u00e9rica Latina","author":"","date":"marzo 28, 2026","format":false,"excerpt":"El portaviones USS Nimitz, una embarcaci\u00f3n de propulsi\u00f3n nuclear y el veh\u00edculo en su tipo m\u00e1s antiguo de Estados Unidos, lleg\u00f3 este s\u00e1bado a aguas de Panam\u00e1 como parte de una gira que realizar\u00e1 por varios pa\u00edses de Am\u00e9rica Latina, confirm\u00f3 un equipo de CNN que visit\u00f3 el buque.El USS\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472451,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/22\/portaviones-destructor-armada-gira-panama-orix\/","url_meta":{"origin":1472730,"position":1},"title":"Panam\u00e1 dice que un portaviones y un destructor de la Armada de EE.UU. visitar\u00e1n aguas paname\u00f1as en &#171;gira por las Am\u00e9ricas&#187;","author":"","date":"marzo 22, 2026","format":false,"excerpt":"El portaviones de propulsi\u00f3n nuclear USS Nimitz y el destructor USS Gridley, de la Armada de Estados Unidos, estar\u00e1n en aguas paname\u00f1as desde el 29 de marzo al pr\u00f3ximo 2 de abril como parte de \u201cuna gira por las Am\u00e9ricas\u201d, inform\u00f3 el Servicio Nacional Aeronaval de Panam\u00e1.El recorrido incluye paradas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472491,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/24\/uss-nimitz-portaaviones-america-latina-orix\/","url_meta":{"origin":1472730,"position":2},"title":"As\u00ed es el USS Nimitz, el longevo portaviones de EE.UU. que ser\u00e1 enviado a Am\u00e9rica Latina en una de sus \u00faltimas misiones","author":"","date":"marzo 24, 2026","format":false,"excerpt":"El portaviones m\u00e1s antiguo de EE.UU., el USS Nimitz, visitar\u00e1 al menos cuatro pa\u00edses durante una extensa gira por Am\u00e9rica Latina que llega en el contexto de crecientes tensiones entre Washington y La Habana, y a casi tres meses de la operaci\u00f3n militar estadounidense que llev\u00f3 a la captura del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472468,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/23\/portaviones-nimitz-america-latina-gira-orix\/","url_meta":{"origin":1472730,"position":3},"title":"EE.UU. confirma la gira de un portaviones en Am\u00e9rica Latina: visitar\u00e1 cuatro pa\u00edses y tendr\u00e1 encuentros con 10 naciones","author":"","date":"marzo 23, 2026","format":false,"excerpt":"El Comando Sur de Estados Unidos confirm\u00f3 este lunes la gira que realizar\u00e1 el portaviones USS Nimitz en Am\u00e9rica Latina, donde anclar\u00e1 en puertos de cuatro pa\u00edses en los pr\u00f3ximos meses y tendr\u00e1 actividades con las fuerzas de 10 naciones de la regi\u00f3n.La nave, que llevar\u00e1 varios aviones y helic\u00f3pteros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456848,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/22\/trump-podria-exigir-canal-panama-estados-unidos-orix\/","url_meta":{"origin":1472730,"position":4},"title":"Trump dice que podr\u00eda exigir que el Canal de Panam\u00e1 sea devuelto a Estados Unidos","author":"","date":"diciembre 22, 2024","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, dijo este s\u00e1bado que durante su pr\u00f3ximo mandato podr\u00eda exigir que el Canal de Panam\u00e1 sea devuelto al pa\u00eds, si contin\u00faa lo que describi\u00f3 como una \u201ccompleta estafa\u201d contra la Marina y las empresas estadounidenses.Trump hizo estas declaraciones en su plataforma Truth\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456899,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/12\/23\/historia-canal-panama-por-que-trump-amenaza-control-trax\/","url_meta":{"origin":1472730,"position":5},"title":"\u00bfCu\u00e1l es la historia del Canal de Panam\u00e1 y por qu\u00e9 Trump amenaza con retomar su control?","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"El presidente electo de Estados Unidos, Donald Trump, sugiri\u00f3 el fin de semana que EE.UU. deber\u00eda retomar el Canal de Panam\u00e1, una idea que fue inmediatamente rechazada por el Gobierno de Panam\u00e1, que ha controlado el paso durante d\u00e9cadas.En mensajes en redes sociales y comentarios a sus simpatizantes, Trump acus\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472730","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472730"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472730\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472730"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472730"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472730"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}