{"id":1472739,"date":"2026-03-31T17:03:38","date_gmt":"2026-04-01T00:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/"},"modified":"2026-03-31T17:03:38","modified_gmt":"2026-04-01T00:03:38","slug":"periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","title":{"rendered":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson"},"content":{"rendered":"<p>La periodista estadounidense <a href=\"https:\/\/www.cnn.com\/2026\/03\/31\/world\/live-news\/iran-war-us-trump-oil?post-id=cmnexyew9000l3b6sbfn0gn0r\">Shelly Kittleson<\/a> fue secuestrada este martes en Bagdad, Iraq, seg\u00fan informaron fuentes y el medio de comunicaci\u00f3n para el que trabaja.<\/p>\n<p>El Gobierno de Estados Unidos est\u00e1 siguiendo de cerca su secuestro y trabajando con los iraqu\u00edes para asegurar su liberaci\u00f3n, dijo un funcionario estadounidense.<\/p>\n<p>No est\u00e1 claro qui\u00e9n es responsable de su secuestro, pero las fuentes dijeron que se le advirti\u00f3 de amenazas en su contra, incluido el secuestro, por parte del grupo Kataib Hezbollah, aliado de Ir\u00e1n.<\/p>\n<p>El subsecretario de Estado de Estados Unidos, Dylan Johnson, dijo en <a href=\"https:\/\/x.com\/ASDylanJohnson\/status\/2039068022451613858\">una publicaci\u00f3n en X <\/a>que \u201cun individuo con v\u00ednculos con el grupo de milicia alineado con Ir\u00e1n, Kataib Hezbollah, que se cree est\u00e1 involucrado en el secuestro, ha sido puesto bajo custodia por las autoridades iraqu\u00edes\u201d.<\/p>\n<p>Kataib Hezbollah es un grupo de milicia respaldado por Ir\u00e1n que ha atacado repetidamente a estadounidenses. Kittleson es una periodista especializada en Medio Oriente y Afganist\u00e1n, con trabajos publicados en medios internacionales, estadounidenses e italianos.<\/p>\n<p>Seg\u00fan una fuente familiarizada con la advertencia, el Gobierno de Estados Unidos le avis\u00f3 recientemente a Kittleson sobre un plan de Kataib Hezbollah para secuestrarla o matarla. La advertencia se produjo mientras ella ya estaba trabajando en Iraq.<\/p>\n<p>Otra fuente dijo que funcionarios estadounidenses e iraqu\u00edes hab\u00edan estado siguiendo amenazas de un grupo aliado de Ir\u00e1n contra Kittleson, incluidas amenazas de secuestrarla o matarla, y le hab\u00edan recomendado que se fuera del pa\u00eds en m\u00faltiples ocasiones en las \u00faltimas semanas.<\/p>\n<p>\u201cEl Departamento de Estado cumpli\u00f3 previamente con nuestro deber de advertir a esta persona sobre amenazas en su contra y seguiremos coordinando con el FBI para asegurar su liberaci\u00f3n lo antes posible\u201d, dijo Johnson el martes, sin dar m\u00e1s detalles sobre las amenazas.<\/p>\n<p>Al-Monitor, una organizaci\u00f3n de noticias con sede en Estados Unidos, confirm\u00f3 el secuestro de Kittleson a primera hora del martes y pidi\u00f3 su \u201cliberaci\u00f3n segura e inmediata\u201d.<\/p>\n<p>Al-Monitor dijo estar \u201cprofundamente alarmado\u201d por el secuestro de Kittleson, quien trabaja como colaboradora para el medio.<\/p>\n<p>\u201cPedimos su liberaci\u00f3n segura e inmediata. Respaldamos su vital labor informativa desde la regi\u00f3n y pedimos su pronto regreso para que contin\u00fae su importante trabajo\u201d, a\u00f1adi\u00f3 el comunicado.<\/p>\n<p>El Ministerio del Interior de Iraq dijo en un comunicado anterior que una periodista extranjera hab\u00eda sido secuestrada en el centro de Bagdad por individuos desconocidos en la noche del martes.<\/p>\n<p>Las fuerzas de seguridad iraqu\u00edes detuvieron a uno de los sospechosos e incautaron uno de los veh\u00edculos utilizados en el secuestro, seg\u00fan el comunicado. Se\u00f1al\u00f3 que las fuerzas de seguridad han lanzado una operaci\u00f3n para localizar a los responsables y asegurar la liberaci\u00f3n de la periodista.<\/p>\n<p>La Embajada de Estados Unidos en Iraq ha pedido repetidamente a los ciudadanos estadounidenses que abandonen el pa\u00eds desde que el conflicto con Ir\u00e1n comenz\u00f3 a finales de febrero, advirtiendo que milicias respaldadas por Ir\u00e1n podr\u00edan intentar secuestrar a estadounidenses. \u201cNo viaje a Iraq por ning\u00fan motivo. Salga inmediatamente si se encuentra all\u00ed\u201d, dijo la embajada en su \u00faltimo comunicado, difundido durante el fin de semana.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La periodista estadounidense Shelly Kittleson fue secuestrada este martes en Bagdad, Iraq, seg\u00fan informaron fuentes y el medio de comunicaci\u00f3n para el que trabaja. El Gobierno de Estados Unidos est\u00e1 siguiendo de cerca su secuestro y trabajando con los iraqu\u00edes para asegurar su liberaci\u00f3n, dijo un funcionario estadounidense. No est\u00e1 claro qui\u00e9n es responsable de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472739","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Secuestran en Iraq a la periodista estadounidense Shelly Kittleson - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson - Noticias\" \/>\n<meta property=\"og:description\" content=\"La periodista estadounidense Shelly Kittleson fue secuestrada este martes en Bagdad, Iraq, seg\u00fan informaron fuentes y el medio de comunicaci\u00f3n para el que trabaja. El Gobierno de Estados Unidos est\u00e1 siguiendo de cerca su secuestro y trabajando con los iraqu\u00edes para asegurar su liberaci\u00f3n, dijo un funcionario estadounidense. No est\u00e1 claro qui\u00e9n es responsable de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-01T00:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson\",\"datePublished\":\"2026-04-01T00:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\"},\"wordCount\":566,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\",\"name\":\"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-01T00:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson - Noticias","og_description":"La periodista estadounidense Shelly Kittleson fue secuestrada este martes en Bagdad, Iraq, seg\u00fan informaron fuentes y el medio de comunicaci\u00f3n para el que trabaja. El Gobierno de Estados Unidos est\u00e1 siguiendo de cerca su secuestro y trabajando con los iraqu\u00edes para asegurar su liberaci\u00f3n, dijo un funcionario estadounidense. No est\u00e1 claro qui\u00e9n es responsable de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-01T00:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/"},"author":{"name":"","@id":""},"headline":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson","datePublished":"2026-04-01T00:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/"},"wordCount":566,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","url":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","name":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-01T00:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/03\/31\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-01T00:03:38Z","datePublished":"2026-04-01T00:03:38Z","dateModified":"2026-04-01T00:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Secuestran en Iraq a la periodista estadounidense Shelly Kittleson\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/31\\\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/03\\\/31\\\/periodista-estadounidense-shelly-kittleson-secuestrada-iraq-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-01T00:03:38Z\",\"datePublished\":\"2026-04-01T00:03:38Z\",\"dateModified\":\"2026-04-01T00:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472938,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/07\/shelly-kittleson-liberada-iraq-periodista-estadounidense-trax\/","url_meta":{"origin":1472739,"position":0},"title":"Milicia proiran\u00ed en Iraq dice que decidi\u00f3 liberar a periodista estadounidense secuestrada","author":"","date":"abril 7, 2026","format":false,"excerpt":"Kataib Hezbollah, una milicia proiran\u00ed en Iraq, dijo que decidi\u00f3 liberar a una periodista estadounidense que fue secuestrada en Bagdad el mes pasado.La milicia \u201cdecidi\u00f3 liberar a la sospechosa estadounidense, Shelly Kittleson, con la condici\u00f3n de que abandone el pa\u00eds de inmediato\u201d, dijo el jefe de seguridad de Kataib Hezbollah,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470222,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/19\/iraq-retirada-total-fuerzas-estadounidenses-trax\/","url_meta":{"origin":1472739,"position":1},"title":"Iraq anuncia la retirada total de las fuerzas estadounidenses de su territorio federal","author":"","date":"enero 19, 2026","format":false,"excerpt":"El Gobierno de Iraq anunci\u00f3 el domingo que las fuerzas estadounidenses hab\u00edan completado una \u201cretirada total\u201d de las instalaciones militares dentro del territorio federal del pa\u00eds, lo que excluye la regi\u00f3n semiaut\u00f3noma del Kurdist\u00e1n, donde las tropas estadounidenses permanecen.El Ministerio de Defensa de Iraq inform\u00f3 que el \u00faltimo contingente de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452318,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/08\/31\/siete-militares-estadounidenses-heridos-isis-iraq-trax\/","url_meta":{"origin":1472739,"position":2},"title":"Siete militares estadounidenses resultaron heridos durante una redada en la que murieron 15 operativos de ISIS en Iraq","author":"","date":"agosto 31, 2024","format":false,"excerpt":"(CNN) --\u00a0Siete militares estadounidenses resultaron heridos en una incursi\u00f3n en Irak el jueves por la noche en la que murieron 15 miembros del ISIS, seg\u00fan informaron tres funcionarios de defensa.Cinco de los miembros del personal resultaron heridos durante la operaci\u00f3n, y uno de ellos fue evacuado para recibir tratamiento adicional.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452310,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/08\/30\/fuerzas-eeuu-seguridad-iraquies-mantan-15-agentes-isis-trax\/","url_meta":{"origin":1472739,"position":3},"title":"Fuerzas de EE.UU. y de seguridad iraqu\u00edes matan a 15 agentes de ISIS en una redada en Iraq, seg\u00fan el ej\u00e9rcito estadounidense","author":"","date":"agosto 30, 2024","format":false,"excerpt":"(CNN) -- Fuerzas de EE.UU. y de seguridad iraqu\u00edes mataron a m\u00e1s de una decena de agentes de ISIS en una redada en la madrugada del jueves en el oeste de Iraq, inform\u00f3 el ej\u00e9rcito estadounidense.Los 15 agentes de ISIS que murieron estaban \u201carmados con numerosas armas, granadas y cinturones\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443085,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/01\/03\/investigan-el-secuestro-de-31-migrantes-que-viajaban-en-un-autobus-en-tamaulipas-en-el-noreste-de-mexico\/","url_meta":{"origin":1472739,"position":4},"title":"Investigan el secuestro de 31 migrantes que viajaban en un autob\u00fas en Tamaulipas, en el noreste de M\u00e9xico","author":"","date":"enero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, inform\u00f3 que su Gobierno investiga el presunto secuestro de al menos 31 migrantes en Tamaulipas, en el noreste del pa\u00eds, al responder a preguntas de periodistas que lo esperaban tras su conferencia matutina diaria, que este martes se realiz\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443087,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/01\/03\/investigan-el-secuestro-de-31-migrantes-que-viajaban-en-un-autobus-en-tamaulipas-en-el-noreste-de-mexico-2\/","url_meta":{"origin":1472739,"position":5},"title":"Investigan el secuestro de 31 migrantes que viajaban en un autob\u00fas en Tamaulipas, en el noreste de M\u00e9xico","author":"","date":"enero 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de M\u00e9xico, Andr\u00e9s Manuel L\u00f3pez Obrador, inform\u00f3 que su Gobierno investiga el presunto secuestro de al menos 31 migrantes en Tamaulipas, en el noreste del pa\u00eds, al responder a preguntas de periodistas que lo esperaban tras su conferencia matutina diaria, que este martes se realiz\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472739"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472739\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}