{"id":1472805,"date":"2026-04-02T10:03:53","date_gmt":"2026-04-02T17:03:53","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/"},"modified":"2026-04-02T10:03:53","modified_gmt":"2026-04-02T17:03:53","slug":"funcionarios-chavistas-sancionados-tesoro-eeuu-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","title":{"rendered":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable?"},"content":{"rendered":"<p>El <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/04\/01\/venezuela\/eeuu-levanta-sanciones-delcy-rodriguez-orix\">levantamiento de sanciones<\/a> de EE.UU. contra la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, puso en relieve el alto n\u00famero de funcionarios del Gobierno sobre los que todav\u00eda pesan las medidas del Departamento del Tesoro. Aunque algunos de esos miembros fueron desplazados de sus puestos en las \u00faltimas semanas, parte de sus reemplazantes tambi\u00e9n tienen restricciones dictadas por Washington.<\/p>\n<p>El caso m\u00e1s notable entre la reconfigurada c\u00fapula chavista tras la captura del presidente Nicol\u00e1s Maduro es la del hermano de la mandataria, Jorge Rodr\u00edguez. El actual titular de la Asamblea Nacional fue <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sm495\">sancionado en 2018<\/a>, cuando era ministro de Comunicaci\u00f3n, junto a otras destacadas figuras cercanas a Maduro. Seg\u00fan la Oficina de Control de Activos Extranjeros (OFAC), <a href=\"https:\/\/2017-2021.state.gov\/the-united-states-imposes-sanctions-on-venezuelan-individuals-and-entities\/\">estos funcionarios colaboraron<\/a> para que el presidente mantenga el poder y contribuyeron \u201ca la destrucci\u00f3n de la democracia en Venezuela\u201d.<\/p>\n<p>Otro personaje clave que sigue sancionado es el ministro de Interior y Justicia, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/01\/07\/venezuela\/diosdado-cabello-poder-gobierno-perfil-orix\">Diosdado Cabello<\/a>, que fue <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sm0389\">designado en 2018<\/a>, acusado de pertenecer a una presunta red de lavado de dinero, corrupci\u00f3n y narcotr\u00e1fico. El entonces constituyente <a href=\"https:\/\/cnnespanol.cnn.com\/2018\/05\/18\/departamento-del-tesoro-de-estados-unidos-sanciona-a-diosdado-cabello\">respondi\u00f3<\/a> que se trata de \u201csanciones inmorales del imperialismo\u201d.<\/p>\n<p>A mediados de marzo, Rodr\u00edguez sustituy\u00f3 al ministro de Defensa, Vladimir Padrino L\u00f3pez, quien estaba sancionado y llevaba m\u00e1s de una d\u00e9cada en el cargo. La presidenta nombr\u00f3 en su lugar a Gustavo Gonz\u00e1lez L\u00f3pez, quien tambi\u00e9n fue <a href=\"https:\/\/ofac.treasury.gov\/recent-actions\/20150309\">designado por el Departamento del Tesoro en 2015<\/a>, durante el gobierno de Barack Obama, por violaciones a derechos humanos cuando dirig\u00eda el Servicio Bolivariano de Inteligencia Nacional (Sebin).<\/p>\n<p>Las sanciones implican el congelamiento de los bienes en Estados Unidos y la prohibici\u00f3n de que ciudadanos estadounidenses realicen negocios con los individuos designados.<\/p>\n<p>La decisi\u00f3n del Gobierno de EE.UU. de sacar a la presidenta de la lista de funcionarios sancionados \u201ces importante, pero podr\u00eda tener varias interpretaciones\u201d, dijo a CNN Benigno Alarc\u00f3n, exdirector del Centro de Estudios Pol\u00edticos de la Universidad Cat\u00f3lica Andr\u00e9s Bello (Caracas). Para el investigador, la m\u00e1s plausible es que se trata de una reducci\u00f3n de costos con miras a un posible cambio de r\u00e9gimen que termine con la salida de Rodr\u00edguez. \u201cEstados Unidos le dice \u2018usted va a estar libre, si ma\u00f1ana decide irse del pa\u00eds, no la vamos a perseguir\u2019\u201d, afirm\u00f3.<\/p>\n<p>Alarc\u00f3n destac\u00f3 adem\u00e1s que el levantamiento, junto al reconocimiento formal de Rodr\u00edguez como presidenta, reduce la posibilidad de que un juez invalide contratos firmados por la mandataria encargada con empresas multinacionales. \u201cEsa es la raz\u00f3n para reconocerla y levantar ciertas sanciones que le permitan operar en representaci\u00f3n del pa\u00eds\u201d, sostuvo.<\/p>\n<p>Bajo ese escenario, la decisi\u00f3n no requerir\u00eda avanzar con el levantamiento de sanciones a otros miembros del Gobierno, aunque Alarc\u00f3n considera que \u201ctarde o temprano\u201d Jorge Rodr\u00edguez tambi\u00e9n saldr\u00e1 de la lista, una medida que, en cambio, no ve probable para Cabello, todav\u00eda buscado por la Justicia de EE.UU. con una recompensa de US$ 25 millones.<\/p>\n<p>Otros funcionarios del gabinete tambi\u00e9n est\u00e1n en la lista negra del Departamento del Tesoro. Jorge M\u00e1rquez, actual ministro de Vivienda y estrecho colaborador de Maduro, fue <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sm0214\">designado en 2017<\/a> por su gesti\u00f3n al frente de la Comisi\u00f3n Nacional de Telecomunicaciones, durante la cual retir\u00f3 del aire a dos canales colombianos y anunci\u00f3 la suspensi\u00f3n de la se\u00f1al de CNN en Espa\u00f1ol por su cobertura del Gobierno. En esa tanda de designaciones tambi\u00e9n fue <a href=\"https:\/\/2017-2021-translations.state.gov\/2017\/11\/09\/el-tesoro-sanciona-a-diez-funcionarios-del-gobierno-venezolano\/\">incluido Ernesto Villegas<\/a>, quien fue ministro de Comunicaci\u00f3n y presidente de Venezolana de Televisi\u00f3n, y actualmente dirige la cartera de Cultura.<\/p>\n<p>En 2024, tras las elecciones presidenciales en las que Maduro fue declarado ganador sin la divulgaci\u00f3n de resultados detallados, lo que no fue reconocido por la oposici\u00f3n, EE.UU. sancion\u00f3 a <a href=\"https:\/\/2021-2025.state.gov\/translations\/spanish\/el-departamento-del-tesoro-de-ee-uu-sanciona-a-funcionarios-venezolanos-alineados-con-nicolas-maduro-que-dirigen-la-represion-postelectoral-en-venezuela\/\">una larga lista de individuos<\/a>, entre ellos el actual ministro de Planificaci\u00f3n, Ricardo Men\u00e9ndez, y al entonces titular de Comunicaci\u00f3n, Freddy \u00d1a\u00f1ez (recientemente nombrado ministro de Ecosocialismo), as\u00ed como a numerosos funcionarios del sistema y la justicia electoral.<\/p>\n<p>El presidente del Consejo Nacional Electoral, Elvis Amoroso, ya estaba sancionado <a href=\"https:\/\/2017-2021-translations.state.gov\/2017\/11\/09\/el-tesoro-sanciona-a-diez-funcionarios-del-gobierno-venezolano\/\">desde 2017<\/a>, y el Tesoro design\u00f3 semanas despu\u00e9s de la elecci\u00f3n \u201cen respuesta al fraude electoral\u201d a la presidenta del Tribunal Supremo de Justicia, Caryslia Rodr\u00edguez, y a <a href=\"https:\/\/2021-2025.state.gov\/translations\/spanish\/el-departamento-del-tesoro-sanciona-a-funcionarios-venezolanos-alineados-con-nicolas-maduro-en-respuesta-al-fraude-electoral\/\">numerosos magistrados, fiscales, rectores y varios dirigentes<\/a> de las fuerzas de seguridad, algunos de los cuales ya no est\u00e1n en el cargo.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El levantamiento de sanciones de EE.UU. contra la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, puso en relieve el alto n\u00famero de funcionarios del Gobierno sobre los que todav\u00eda pesan las medidas del Departamento del Tesoro. Aunque algunos de esos miembros fueron desplazados de sus puestos en las \u00faltimas semanas, parte de sus reemplazantes tambi\u00e9n tienen [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472805","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable? - Noticias\" \/>\n<meta property=\"og:description\" content=\"El levantamiento de sanciones de EE.UU. contra la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, puso en relieve el alto n\u00famero de funcionarios del Gobierno sobre los que todav\u00eda pesan las medidas del Departamento del Tesoro. Aunque algunos de esos miembros fueron desplazados de sus puestos en las \u00faltimas semanas, parte de sus reemplazantes tambi\u00e9n tienen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T17:03:53+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable?\",\"datePublished\":\"2026-04-02T17:03:53+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\"},\"wordCount\":801,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\",\"name\":\"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-02T17:03:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable? - Noticias","og_description":"El levantamiento de sanciones de EE.UU. contra la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, puso en relieve el alto n\u00famero de funcionarios del Gobierno sobre los que todav\u00eda pesan las medidas del Departamento del Tesoro. Aunque algunos de esos miembros fueron desplazados de sus puestos en las \u00faltimas semanas, parte de sus reemplazantes tambi\u00e9n tienen [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-02T17:03:53+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/"},"author":{"name":"","@id":""},"headline":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable?","datePublished":"2026-04-02T17:03:53+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/"},"wordCount":801,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","name":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-02T17:03:53+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Delcy Rodr\u00edguez ya no est\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\u00ed: \u00bfcu\u00e1l es el caso m\u00e1s notable?","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-02T17:03:53Z","datePublished":"2026-04-02T17:03:53Z","dateModified":"2026-04-02T17:03:53Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Delcy Rodr\\u00edguez ya no est\\u00e1 sancionada por EE.UU., pero varios miembros clave de su gobierno s\\u00ed: \\u00bfcu\\u00e1l es el caso m\\u00e1s notable?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/04\\\/02\\\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/04\\\/02\\\/funcionarios-chavistas-sancionados-tesoro-eeuu-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-02T17:03:53Z\",\"datePublished\":\"2026-04-02T17:03:53Z\",\"dateModified\":\"2026-04-02T17:03:53Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1469789,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/05\/5-cosas-5-enero-orix\/","url_meta":{"origin":1472805,"position":0},"title":"Las 5 cosas que debes saber este 5 de enero: Delcy Rodr\u00edguez asume en Venezuela, Maduro ante un tribunal de EE.UU.","author":"","date":"enero 5, 2026","format":false,"excerpt":"Trump lanza advertencias a otros pa\u00edses de Am\u00e9rica Latina. Maduro har\u00e1 su primera aparici\u00f3n ante un tribunal en Nueva York. La oposici\u00f3n venezolana pide que se respeten los resultados de las elecciones de 2024. Esto es lo que debes saber para comenzar el d\u00eda. Primero la verdad.Suscr\u00edbete aqu\u00ed para recibir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469807,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/05\/delcy-rodriguez-jura-presidenta-encargada-orix\/","url_meta":{"origin":1472805,"position":1},"title":"Delcy Rodr\u00edguez asume formalmente como presidenta encargada y rechaza &#171;agresi\u00f3n militar ileg\u00edtima&#187; contra Venezuela","author":"","date":"enero 5, 2026","format":false,"excerpt":"La vicepresidenta Delcy Rodr\u00edguez asumi\u00f3 este lunes formalmente como presidenta encargada de Venezuela, luego de la captura del presidente Nicol\u00e1s Maduro en un operativo militar de Estados Unidos.La juramentaci\u00f3n se dio en una ceremonia en la Asamblea Nacional, encabezada por el diputado Jorge Rodr\u00edguez, hermano de la presidenta encargada y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472776,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/01\/eeuu-levanta-sanciones-delcy-rodriguez-orix\/","url_meta":{"origin":1472805,"position":2},"title":"EE.UU. levanta las sanciones que hab\u00eda impuesto a Delcy Rodr\u00edguez en 2018","author":"","date":"abril 1, 2026","format":false,"excerpt":"El Gobierno de Estados Unidos levant\u00f3 este mi\u00e9rcoles las sanciones que desde 2018 manten\u00eda contra la actual presidenta encargada de Venezuela, Delcy Rodr\u00edguez, de acuerdo con una actualizaci\u00f3n de la lista de personas sancionadas de la Oficina de Control de Activos Extranjeros (OFAC, por sus siglas en ingl\u00e9s), perteneciente al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469761,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/03\/nicolas-maduro-delcy-rodriguez-chavismo-poder-orix\/","url_meta":{"origin":1472805,"position":3},"title":"Con Maduro capturado y Delcy Rodr\u00edguez sin alianzas definidas, \u00bfqu\u00e9 carta le queda al chavismo (y a todos los dem\u00e1s)?","author":"","date":"enero 3, 2026","format":false,"excerpt":"Con una asombrosa rapidez, Nicol\u00e1s Maduro fue capturado junto con su esposa, Cilia Flores y, con ello, derrocado.No se puede decir que haya sido una sorpresa, claro, pero ya han pasado varias horas y muchos l\u00edderes del chavismo a\u00fan no lo han aceptado p\u00fablicamente. Delcy Rodr\u00edguez y Diosdado Cabello reconocieron\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471205,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/13\/trump-relacion-venezuela-10-elogia-delcy-trax\/","url_meta":{"origin":1472805,"position":4},"title":"Trump afirma que la relaci\u00f3n con Venezuela &#171;ahora es un 10&#187; y elogia a Delcy Rodr\u00edguez","author":"","date":"febrero 13, 2026","format":false,"excerpt":"El presidente de EE.UU., Donald Trump, elogi\u00f3 este viernes a la presidenta encargada de Venezuela, Delcy Rodr\u00edguez, mientras se preparaba para reunirse con militares estadounidenses involucrados en la operaci\u00f3n que captur\u00f3 a Nicol\u00e1s Maduro. Trump afirm\u00f3 que la relaci\u00f3n entre ambos pa\u00edses \u201cahora es un 10\u201d.\u201cTenemos una muy buena relaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471880,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/04\/delcy-rodriguez-trump-burgum-cooperacion-eeuu-orix\/","url_meta":{"origin":1472805,"position":5},"title":"Delcy Rodr\u00edguez recibe al secretario del Interior de EE.UU. y reitera que Venezuela &#171;est\u00e1 a disposici\u00f3n&#187; para cooperar","author":"","date":"marzo 4, 2026","format":false,"excerpt":"La presidenta encargada de Venezuela, Delcy Rodr\u00edguez, se reuni\u00f3 este mi\u00e9rcoles con el secretario del Interior de Estados Unidos, Doug Burgum, con quien habl\u00f3 de una agenda bilateral en sectores como la energ\u00eda y a quien reiter\u00f3 que su gobierno \u201cest\u00e1 a la disposici\u00f3n\u201d para cooperar con Estados Unidos.Rodr\u00edguez recibi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472805","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472805"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472805\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472805"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472805"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472805"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}