{"id":1472808,"date":"2026-04-02T12:03:50","date_gmt":"2026-04-02T19:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/"},"modified":"2026-04-02T12:03:50","modified_gmt":"2026-04-02T19:03:50","slug":"estructura-poder-cuba-castro-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","title":{"rendered":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado"},"content":{"rendered":"<p>Cuba parece estar al <a href=\"https:\/\/www.cnn.com\/2026\/03\/06\/americas\/trump-cuba-pressure-havana-latam-intl\">borde del colapso. <\/a>Sin petr\u00f3leo desde la ca\u00edda de Nicol\u00e1s Maduro en Venezuela en enero, sin el <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/11\/latinoamerica\/aliados-socios-cuba-region-orix\">apoyo pol\u00edtico de muchos de sus antiguos aliados<\/a> y en medio de una<a href=\"https:\/\/www.cnn.com\/2026\/03\/06\/americas\/trump-cuba-pressure-havana-latam-intl\"> perpetua crisis econ\u00f3mica<\/a>, el pa\u00eds comunista atraviesa la que es posiblemente la crisis m\u00e1s importante desde la revoluci\u00f3n de 1959.<\/p>\n<p>Y aunque la isla ha estado muchas veces en situaciones precarias, especialmente tras la ca\u00edda de la Uni\u00f3n Sovi\u00e9tica, su principal aliado y socio comercial, en 1991, esta vez la presi\u00f3n de Estados Unidos, su<a href=\"https:\/\/cnnespanol.cnn.com\/2021\/10\/26\/crisis-misiles-cuba-guerra-dusa-documentales-orix\"> rival principal al menos desde la crisis de los misiles<\/a>, ha llegado a niveles no antes vistos, y ocurre apenas dos meses despu\u00e9s de que Washington derrocara al presidente de Venezuela y luego lanzara una campa\u00f1a de bombardeo a\u00e9reo sobre Ir\u00e1n.<\/p>\n<p>\u201cCuba caer\u00e1 muy pronto. Est\u00e1n deseando llegar a un acuerdo\u201d, dijo a comienzos de marzo el presidente de EE.UU., Donald Trump, a Dana Bash de CNN en una entrevista telef\u00f3nica.<\/p>\n<p>Apenas un d\u00eda antes, Trump habl\u00f3 de una \u201ctoma de control amistosa\u201d de Cuba y sugiri\u00f3 que la isla ser\u00eda el objetivo de su atenci\u00f3n despu\u00e9s de Ir\u00e1n.<\/p>\n<p>\u201cLo que est\u00e1 pasando con Cuba es incre\u00edble, y creemos que queremos arreglar\u2026 terminar esto primero, pero ser\u00e1 solo una cuesti\u00f3n de tiempo\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/05\/eeuu\/trump-cuba-proximo-agenda-gobierno-trax\">dijo <\/a>el mandatario estadounidense.<\/p>\n<p>\u201cPodr\u00edamos muy bien terminar con una toma de control amistosa de Cuba despu\u00e9s de muchos, muchos a\u00f1os\u201d, agreg\u00f3.<\/p>\n<p>Pero Cuba a\u00fan no cae, y el Gobierno mantiene el control sobre la isla. Este es un vistazo a la estructura de poder en la isla.<\/p>\n<p>El m\u00e1s importante de los tripulantes del Granma \u2014el yate en el que 82 revolucionarios al mando del fallecido Fidel Castro llegaron a las costas de Cuba en 1956\u2014 que a\u00fan sigue con vida y ocupa un lugar en la estructura de poder cubana es Ra\u00fal Castro, ex presidente y precisamente hermano de Fidel.<\/p>\n<p>Ra\u00fal, de<a href=\"https:\/\/cnnespanol.cnn.com\/2015\/09\/15\/el-presidente-cubano-raul-castro-en-datos\"> 94 a\u00f1os<\/a>, fue el primer Ministro de Defensa de Cuba tras el triunfo de la Revoluci\u00f3n en 1959 y ocup\u00f3 el cargo hasta 2008, cuando Fidel dio un paso al costado y su hermano lleg\u00f3 a la presidencia. Diez a\u00f1os despu\u00e9s, Ra\u00fal hizo <a href=\"https:\/\/cnnespanol.cnn.com\/2015\/09\/15\/el-presidente-cubano-raul-castro-en-datos\">lo mismo y dej\u00f3 el puesto al actual presidente, Miguel D\u00edaz-Canel<\/a>, pero a\u00fan a pesar de dejar formalmente el poder y de su edad, sigue siendo una de las figuras pol\u00edticas m\u00e1s importantes en Cuba y un s\u00edmbolo \u2014para bien y para mal\u2014 de la Revoluci\u00f3n y del comunismo latinoamericano.<\/p>\n<p>Ramiro Vald\u00e9s, tambi\u00e9n tripulante del Granma y revolucionario hist\u00f3rico, es otro de los miembros de la Vieja Guardia que mantienen influencia en Cuba.<\/p>\n<p>Vald\u00e9s tiene 93 a\u00f1os y <a href=\"https:\/\/www.parlamentocubano.gob.cu\/ramiro-valdes-menendez\">ocup\u00f3 diversos cargos en el gobierno cubano,<\/a> entre ellos ministro del Interior y de Inform\u00e1tica y las Comunicaciones, y actualmente es <a href=\"https:\/\/x.com\/ValdesMenendez\">viceprimer ministro<\/a> de Cuba.<\/p>\n<p>D\u00edaz-Canel es el actual presidente, pero desde la salida de los Castro, el cargo no concentra el poder en Cuba de manera tan clara, y tambi\u00e9n existen otros pol\u00edticos con influencia en el gobierno.<\/p>\n<p>Aun as\u00ed, la figura de D\u00edaz-Canel ha quedado en el centro de esta crisis especialmente luego de que el secretario de Estado de EE.UU., Marco Rubio, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/18\/mundo\/presidente-cuba-intento-ee-uu-controlar-resistencia-inexpugnable-trax\">dijera <\/a>que Cuba necesita \u201cnueva gente al mando\u201d.<\/p>\n<p>\u201cNi el presidente ni el cargo de ning\u00fan directivo en Cuba es objeto de negociaci\u00f3n con Estados Unidos\u201d, <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/20\/latinoamerica\/gobierno-cuba-presidente-miguel-diaz-canel-no-objeto-negociacion-eeuu-orix\">dijo <\/a>en respuesta el viceministro de Relaciones Exteriores de Cuba, Carlos Fern\u00e1ndez de Cossio.<\/p>\n<p>Antes de ser elegido por la Asamblea Nacional del Poder Popular de Cuba (ANPP) en 2018, D\u00edaz-Canel, de 65 a\u00f1os, hab\u00eda sido ministro de<a href=\"https:\/\/www.ecured.cu\/Miguel_D%C3%ADaz-Canel\"> Educaci\u00f3n y primer vicepresidente<\/a>.<\/p>\n<p>Otra figura influyente es Manuel Marrero, designado primer ministro de Cuba en 2019, un a\u00f1o despu\u00e9s del ascenso de D\u00edaz-Canel. Hac\u00eda cuatro d\u00e9cadas que Cuba no ten\u00eda este cargo, y la resurrecci\u00f3n de l<a href=\"https:\/\/cnnespanol.cnn.com\/2019\/12\/21\/cuba-nombra-primer-ministro-por-primera-vez-en-mas-de-40-anos\">a cartera en manos de un coronel retirado <\/a>pareci\u00f3 un intento de distribuir funciones.<\/p>\n<p>Dentro del gabinete de D\u00edaz-Canel, en los \u00faltimos a\u00f1os han cobrado fuerza tambi\u00e9n el canciller Bruno Rodr\u00edguez y el vicecanciller Carlos Fern\u00e1ndez de Cossio, un poco m\u00e1s visibles en la \u00faltima crisis con Estados Unidos.<\/p>\n<p>Las Fuerzas Armadas Revolucionarias (FAR), surgidas de la guerrilla que combati\u00f3 en la Sierra Maestra contra el gobierno del dictador Fulgencio Batista entre 1956 y 1959, han desempe\u00f1ado un papel trascendental en los asuntos pol\u00edticos de Cuba.<\/p>\n<p>Resulta dif\u00edcil definir d\u00f3nde termina el Estado cubano y empiezan las FAR, que entre 1959 y 2008 estuvieron lideradas precisamente por Ra\u00fal Castro.<\/p>\n<p>Actualmente las FAR est\u00e1n comandadas por el ministro <a href=\"https:\/\/www.minfar.gob.cu\/node\/128\">\u00c1lvaro L\u00f3pez Miera<\/a>, un militar de carrera de 82 a\u00f1os que particip\u00f3 en las campa\u00f1as cubanas en <a href=\"https:\/\/www.minfar.gob.cu\/node\/128\">Angola y Etiop\u00eda<\/a>, dos de las operaciones militares en el extranjero m\u00e1s emblem\u00e1ticas de Cuba, en plena Guerra Fr\u00eda.<\/p>\n<p>Adem\u00e1s de L\u00f3pez Miera, la otra figura influyente del mundo militar cubano es Ania Lastres Morera,<a href=\"https:\/\/www.pcc.cu\/general-de-brigada-ania-guillermina-lastres-morera\"> presidenta ejecutiva<\/a> del Grupo Administraci\u00f3n Empresarial de las FAR S.A. (GAESA) desde 2022.<\/p>\n<p>GAESA controla im<a href=\"https:\/\/cnnespanol.cnn.com\/2017\/06\/16\/los-cambios-en-la-politica-de-ee-uu-con-cuba-podrian-afectar-negativamente-a-los-competidores-hoteleros-de-trump\">portantes sectores de la econom\u00eda cubana, incluyendo buena parte del turismo \u2014principal fuente de divisas extranjeras\u2014<\/a> a trav\u00e9s de su filial hotelera Gaviota.<\/p>\n<p>El Tesoro de EE.UU. <a href=\"https:\/\/home.treasury.gov\/news\/press-releases\/sm1217\">sancion\u00f3 a GAESA <\/a>en 2020 por presuntamente haber sido utilizada para evadir otras sanciones de Washington contra La Habana.<\/p>\n<p>Lastres Morera tiene 64 a\u00f1os, es <a href=\"https:\/\/www.pcc.cu\/general-de-brigada-ania-guillermina-lastres-morera\">licenciada en Planificaci\u00f3n de la Econom\u00eda <\/a>y realiz\u00f3 toda su carrera en las FAR.<\/p>\n<p>En las nuevas generaciones pol\u00edticas de Cuba, destaca, por su linaje e influencia, la figura de Ra\u00fal Guillermo Rodr\u00edguez Castro, nieto de Ra\u00fal.<\/p>\n<p>Apodado \u201cel Cangrejo\u201d, Rodr\u00edguez Castro<a href=\"https:\/\/cnnespanol.cnn.com\/2026\/02\/20\/latinoamerica\/cuba-marco-rubio-embajador-especulaciones-negociacion-eeuu-efe\"> cobr\u00f3 notoriedad a finales de febrero cuando el portal estadounidense Axios r<\/a>eport\u00f3 que manten\u00eda contactos secretos con el secretario de Estado de EE.UU., Marco Rubio, en medio de las tensiones entre EE.UU. y Cuba.<\/p>\n<p>El Gobierno de Cuba calific\u00f3 el reporte de \u201cespeculaci\u00f3n\u201d, aunque sin negarlo, mientras que Washington no se ha pronunciado. CNN contact\u00f3 al Departamento de Estado para consultar sobre estos contactos, pero no ha recibido respuesta.<\/p>\n<p>M\u00e1s all\u00e1 de este reporte y del parentesco con el \u201cCangrejo\u201d, poco se sabe a ciencia cierta del nieto de Ra\u00fal Castro.<\/p>\n<p>Pero no es el \u00fanico miembro de la familia Castro en tener influencia: Alejandro Castro Esp\u00edn, hijo de Ra\u00fal Castro; Oscar P\u00e9rez Oliva Fraga, sobrino-nieto de Ra\u00fal y Fidel; y Mariela Castro Esp\u00edn, hija de Ra\u00fal y diputada tambi\u00e9n, emergen como figuras de recambio en el gobierno cubano.<\/p>\n<p>Ingeniero y doctor en Ciencias Pol\u00edticas,<a href=\"https:\/\/www.ecured.cu\/Alejandro_Castro_Esp%C3%ADn\"> Alejandro Castro Esp\u00edn tiene 60 a\u00f1os y<\/a> se ha mostrado s<a href=\"https:\/\/cnnespanol.cnn.com\/2015\/09\/18\/el-papa-francisco-viaja-a-cuba-despues-de-meses-de-diplomacia-secreta\">iempre cerca de su padre, Ra\u00fal, y de su t\u00edo Fidel.<\/a> Castro Esp\u00edn <a href=\"https:\/\/cnnespanol.cnn.com\/2015\/09\/18\/el-papa-francisco-viaja-a-cuba-despues-de-meses-de-diplomacia-secreta\">fue asociado en 2014<\/a>, durante el acercamiento con Cuba buscado por el expresidente estadounidense Barack Obama, con negociaciones entre Cuba y EE.UU. para el intercambio de esp\u00edas.<\/p>\n<p>Por otro lado, su hermana Mariela Castro Esp\u00edn<a href=\"https:\/\/www.parlamentocubano.gob.cu\/mariela-castro-espin-0\"> tiene 63 a\u00f1os, <\/a>es licenciada en Educaci\u00f3n y diputada en la Asamblea Nacional del Poder Popular de Cuba.<\/p>\n<p>Mientras que <a href=\"https:\/\/www.ecured.cu\/Oscar_P%C3%A9rez-Oliva_Fraga\">Oscar P\u00e9rez-Oliva Fraga<\/a>, de 55 a\u00f1os, es v<a href=\"https:\/\/www.parlamentocubano.gob.cu\/oscar-perez-oliva-fraga\">iceprimer ministro<\/a> y ministro de Comercio Exterior e Inversi\u00f3n Extranjera, y tambi\u00e9n fue diputado en la ANPP.<\/p>\n<p>A mediados de marzo, P\u00e9rez-Oliva Fraga cobr\u00f3 mayor notoriedad cuando <a href=\"https:\/\/cnnespanol.cnn.com\/2026\/03\/16\/latinoamerica\/cuba-exiliados-inversiones-orix\">anunci\u00f3 a mediados de marzo una serie de reformas econ\u00f3micas <\/a>para intentar atraer inversiones de cubanos residentes fuera de la isla.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuba parece estar al borde del colapso. Sin petr\u00f3leo desde la ca\u00edda de Nicol\u00e1s Maduro en Venezuela en enero, sin el apoyo pol\u00edtico de muchos de sus antiguos aliados y en medio de una perpetua crisis econ\u00f3mica, el pa\u00eds comunista atraviesa la que es posiblemente la crisis m\u00e1s importante desde la revoluci\u00f3n de 1959. Y [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472808","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado - Noticias\" \/>\n<meta property=\"og:description\" content=\"Cuba parece estar al borde del colapso. Sin petr\u00f3leo desde la ca\u00edda de Nicol\u00e1s Maduro en Venezuela en enero, sin el apoyo pol\u00edtico de muchos de sus antiguos aliados y en medio de una perpetua crisis econ\u00f3mica, el pa\u00eds comunista atraviesa la que es posiblemente la crisis m\u00e1s importante desde la revoluci\u00f3n de 1959. Y [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T19:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado\",\"datePublished\":\"2026-04-02T19:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\"},\"wordCount\":1319,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\",\"name\":\"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-02T19:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado - Noticias","og_description":"Cuba parece estar al borde del colapso. Sin petr\u00f3leo desde la ca\u00edda de Nicol\u00e1s Maduro en Venezuela en enero, sin el apoyo pol\u00edtico de muchos de sus antiguos aliados y en medio de una perpetua crisis econ\u00f3mica, el pa\u00eds comunista atraviesa la que es posiblemente la crisis m\u00e1s importante desde la revoluci\u00f3n de 1959. Y [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","og_site_name":"Noticias","article_published_time":"2026-04-02T19:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/"},"author":{"name":"","@id":""},"headline":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado","datePublished":"2026-04-02T19:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/"},"wordCount":1319,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","url":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","name":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-02T19:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\u00ed est\u00e1 conformado","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/04\/02\/estructura-poder-cuba-castro-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-02T19:03:50Z","datePublished":"2026-04-02T19:03:50Z","dateModified":"2026-04-02T19:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobierno de Trump insiste en que Cuba debe cambiar su liderazgo: as\\u00ed est\\u00e1 conformado\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/04\\\/02\\\/estructura-poder-cuba-castro-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/04\\\/02\\\/estructura-poder-cuba-castro-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-02T19:03:50Z\",\"datePublished\":\"2026-04-02T19:03:50Z\",\"dateModified\":\"2026-04-02T19:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472320,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/03\/18\/desesperacion-familiares-expectativa-cuba-crisis-orix\/","url_meta":{"origin":1472808,"position":0},"title":"Entre la desesperaci\u00f3n por sus familiares y la expectativa de un cambio: as\u00ed viven los cubanos de Miami la crisis en la isla","author":"","date":"marzo 18, 2026","format":false,"excerpt":"Una vida en el exilio, pero el coraz\u00f3n todav\u00eda en la isla. Desde la Calle 8, protagonista del barrio de Miami conocido como la Peque\u00f1a Habana, los cubanos ven la grave crisis pol\u00edtica y econ\u00f3mica que por estas horas atraviesa su pa\u00eds con algo mucho m\u00e1s urgente que una simple\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471066,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/10\/cuba-medidas-crisis-energetica-orix\/","url_meta":{"origin":1472808,"position":1},"title":"&#171;Estos son tiempos muy dif\u00edciles&#187;: c\u00f3mo es el plan de Cuba para sobrevivir a una de sus peores crisis","author":"","date":"febrero 10, 2026","format":false,"excerpt":"El Gobierno de Cuba, asediado por la presi\u00f3n de Estados Unidos en materia energ\u00e9tica, ha desplegado una serie de medidas para intentar cubrir servicios elementales en un plan de supervivencia que ya tiene paralelos con el \u201cper\u00edodo especial\u201d de la d\u00e9cada de los 90 tras la ca\u00edda del bloque sovi\u00e9tico.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450457,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/06\/17\/aliados-guerra-fria-socios-relaciones-cuba-rusia-orix\/","url_meta":{"origin":1472808,"position":2},"title":"De aliados en la Guerra Fr\u00eda a socios en la actualidad: as\u00ed han sido las persistentes relaciones entre Cuba y Rusia","author":"","date":"junio 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Fue una de las relaciones diplom\u00e1ticas m\u00e1s famosas del siglo XX, vidriera de la Guerra Fr\u00eda y de la competencia entre grandes potencias, y persiste con fuerza en la actualidad: Cuba y Rusia mantienen una cercan\u00eda pol\u00edtica desde el restablecimiento de las relaciones, en 1959, justo despu\u00e9s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470982,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/07\/cuba-cierra-hoteles-desabastecimiento-combustible-efe\/","url_meta":{"origin":1472808,"position":3},"title":"Cuba empieza a cerrar hoteles y reubicar turistas ante el desabastecimiento de combustible","author":"","date":"febrero 7, 2026","format":false,"excerpt":"El Gobierno de Cuba ha empezado a cerrar algunos hoteles de la isla y a trasladar a los turistas a otras instalaciones como parte del paquete de medidas adoptado ante el asedio petrolero de EE.UU., confirmaron a EFE este s\u00e1bado fuentes del sector.El viceprimer ministro Oscar P\u00e9rez-Oliva Fraga asegur\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469880,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/01\/07\/mexico-cuba-venezuela-mapa-petroleo-orix\/","url_meta":{"origin":1472808,"position":4},"title":"M\u00e9xico, Cuba y el nuevo mapa del petr\u00f3leo en la regi\u00f3n tras la captura del presidente de Venezuela","author":"","date":"enero 7, 2026","format":false,"excerpt":"Helyn de la Paz sonr\u00ede cuando se sube al cami\u00f3n que la lleva a su trabajo en una pasteler\u00eda de Veracruz, en el este de M\u00e9xico, hasta donde lleg\u00f3 en caravana de Tapachula, Chiapas, en el sur, en noviembre pasado, tras salir de Cuba.En el trabajo, comparte turno con su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471194,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/02\/13\/cuba-preguntas-trump-sheinbaum-diaz-canel-orix\/","url_meta":{"origin":1472808,"position":5},"title":"Trump, Sheinbaum, D\u00edaz-Canel y la eterna pregunta de los cubanos: &#171;\u00bfCu\u00e1ndo cambiar\u00e1 esto?&#187;","author":"","date":"febrero 13, 2026","format":false,"excerpt":"De ni\u00f1os, no eran pocos los cubanos que, hace algunas d\u00e9cadas, acompa\u00f1aban a sus padres en los paseos en coche hasta el malec\u00f3n de La Habana. A orillas del mar, pasaban horas observando los barcos que entraban a la bah\u00eda. Aquel espect\u00e1culo trasmit\u00eda paz y, tambi\u00e9n, una sensaci\u00f3n de esperanza,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472808","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472808"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472808\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472808"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472808"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472808"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}