{"id":1472836,"date":"2026-04-03T09:03:42","date_gmt":"2026-04-03T16:03:42","guid":{"rendered":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/"},"modified":"2026-04-03T09:03:42","modified_gmt":"2026-04-03T16:03:42","slug":"nasa-imagenes-tierra-artemis-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","title":{"rendered":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II"},"content":{"rendered":"<p>La NASA public\u00f3 las primeras im\u00e1genes tomadas por los astronautas a bordo de la c\u00e1psula Orion de la misi\u00f3n Artemis II durante su viaje a la Luna.<\/p>\n<p>Las impresionantes fotograf\u00edas fueron capturadas por el comandante de la misi\u00f3n, Reid Wiseman, utilizando su dispositivo personal (una tableta con c\u00e1mara) y ambas muestran la Tierra.<\/p>\n<p>La primera fue descrita por el centro de control de la misi\u00f3n de la NASA en el Centro Espacial Johnson en Houston como un recordatorio de que, sin importar cu\u00e1n lejos vayamos, seguimos siendo un solo mundo, observando, esperando y aspirando a m\u00e1s.<\/p>\n<p>La segunda imagen fue tomada desde una de las ventanas de la nave Orion; otra vista de la Tierra descrita como un punto azul p\u00e1lido visto a trav\u00e9s de los ojos de la tripulaci\u00f3n.<\/p>\n<p>Las im\u00e1genes complementan a la perfecci\u00f3n algunos comentarios de la especialista de misi\u00f3n Christina Koch durante una transmisi\u00f3n en directo con los medios de comunicaci\u00f3n el segundo d\u00eda del vuelo.<\/p>\n<p>\u201cTras haber disfrutado de vistas incre\u00edbles del planeta Tierra, vi\u00e9ndolo entero a trav\u00e9s de la ventana, saber que pronto tendremos vistas similares de la Luna me emociona a\u00fan m\u00e1s\u201d, dijo. \u201cSab\u00eda que eso era lo que ver\u00edamos. Pero nada te prepara para la impresionante sensaci\u00f3n de ver tu planeta iluminado como si fuera de d\u00eda y, adem\u00e1s, con el resplandor de la Luna por la noche, con el hermoso rayo del atardecer. Y saber que vamos a tener vistas similares de la Luna\u2026 Estoy realmente emocionada\u201d.<\/p>\n<p>Durante la misma conversaci\u00f3n, Wiseman coment\u00f3: \u201cHace aproximadamente una hora, el Centro de Control de Misi\u00f3n de Houston reorient\u00f3 nuestra nave espacial mientras el sol se pon\u00eda tras la Tierra. No s\u00e9 qu\u00e9 esper\u00e1bamos ver en ese momento, pero se pod\u00eda ver el globo entero, de polo a polo. Se ve\u00eda \u00c1frica, Europa, y si uno se fijaba bien, pod\u00eda ver la aurora boreal. Fue un momento espectacular que nos dej\u00f3 a los cuatro sin palabras\u201d.<\/p>\n<p>Wiseman tambi\u00e9n coment\u00f3 que las ventanas de Orion ya est\u00e1n sucias porque la tripulaci\u00f3n ha disfrutado mucho mirando hacia afuera. Pregunt\u00f3 por los procedimientos adecuados para limpiarlas.<\/p>\n<p>La tripulaci\u00f3n estuvo ocupada tomando fotos durante un momento que inclu\u00eda su primera comida juntos en el espacio, pero la pospusieron un poco para mirar hacia afuera y tomar fotos.<\/p>\n<p>\u201cEstamos disfrutando de una vista preciosa del lado oscuro de la Tierra iluminado por la Luna\u201d, dijo Jeremy Hansen, astronauta y especialista de misi\u00f3n de la Agencia Espacial Canadiense. \u201cEs fenomenal. Ninguno de nosotros puede almorzar porque estamos pegados a la ventana. Estamos tomando fotos. Reid dijo que ya no aguanta m\u00e1s\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2026 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La NASA public\u00f3 las primeras im\u00e1genes tomadas por los astronautas a bordo de la c\u00e1psula Orion de la misi\u00f3n Artemis II durante su viaje a la Luna. Las impresionantes fotograf\u00edas fueron capturadas por el comandante de la misi\u00f3n, Reid Wiseman, utilizando su dispositivo personal (una tableta con c\u00e1mara) y ambas muestran la Tierra. La primera [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1472836","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II - Noticias\" \/>\n<meta property=\"og:description\" content=\"La NASA public\u00f3 las primeras im\u00e1genes tomadas por los astronautas a bordo de la c\u00e1psula Orion de la misi\u00f3n Artemis II durante su viaje a la Luna. Las impresionantes fotograf\u00edas fueron capturadas por el comandante de la misi\u00f3n, Reid Wiseman, utilizando su dispositivo personal (una tableta con c\u00e1mara) y ambas muestran la Tierra. La primera [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-03T16:03:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II\",\"datePublished\":\"2026-04-03T16:03:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\"},\"wordCount\":510,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\",\"name\":\"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2026-04-03T16:03:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II - Noticias","og_description":"La NASA public\u00f3 las primeras im\u00e1genes tomadas por los astronautas a bordo de la c\u00e1psula Orion de la misi\u00f3n Artemis II durante su viaje a la Luna. Las impresionantes fotograf\u00edas fueron capturadas por el comandante de la misi\u00f3n, Reid Wiseman, utilizando su dispositivo personal (una tableta con c\u00e1mara) y ambas muestran la Tierra. La primera [&hellip;]","og_url":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","og_site_name":"Noticias","article_published_time":"2026-04-03T16:03:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/"},"author":{"name":"","@id":""},"headline":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II","datePublished":"2026-04-03T16:03:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/"},"wordCount":510,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","url":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","name":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2026-04-03T16:03:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La NASA publica las impresionantes primeras im\u00e1genes de la Tierra tomadas por los astronautas de la misi\u00f3n Artemis II","url":"http:\/\/noticiasya.com\/corpus-christi\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/corpus-christi\/2026\/04\/03\/nasa-imagenes-tierra-artemis-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2026-04-03T16:03:42Z","datePublished":"2026-04-03T16:03:42Z","dateModified":"2026-04-03T16:03:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La NASA publica las impresionantes primeras im\\u00e1genes de la Tierra tomadas por los astronautas de la misi\\u00f3n Artemis II\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/04\\\/03\\\/nasa-imagenes-tierra-artemis-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/corpus-christi\\\/2026\\\/04\\\/03\\\/nasa-imagenes-tierra-artemis-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2026-04-03T16:03:42Z\",\"datePublished\":\"2026-04-03T16:03:42Z\",\"dateModified\":\"2026-04-03T16:03:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1472865,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/04\/artemis-ii-nuevas-imagenes-lunares-camino-luna-trax\/","url_meta":{"origin":1472836,"position":0},"title":"Artemis II comparte nuevas im\u00e1genes lunares mientras est\u00e1 a m\u00e1s de la mitad del camino hacia la Luna","author":"","date":"abril 4, 2026","format":false,"excerpt":"Impresionantes nuevas fotos capturadas por los astronautas de Artemis II muestran la Luna y el interior de la nave espacial Ori\u00f3n, que ofrecen un vistazo de su vida en el espacio mientras se acercan a otro hito hist\u00f3rico.Una de las im\u00e1genes de la Luna incluso capt\u00f3 una parte de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452861,"url":"https:\/\/noticiasya.com\/corpus-christi\/2024\/09\/19\/maniquies-luna-camino-astronautas-espacio-trax\/","url_meta":{"origin":1472836,"position":1},"title":"Dos maniqu\u00edes volaron alrededor de la Luna; los cient\u00edficos acaban de revelar c\u00f3mo les fue y c\u00f3mo podr\u00eda afectar a los astronautas","author":"","date":"septiembre 19, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 A medida que se acerca Artemis II, la misi\u00f3n de la NASA que enviar\u00e1 cuatro astronautas a circunnavegar la Luna el a\u00f1o pr\u00f3ximo, un nuevo estudio revela qu\u00e9 tan bien proteger\u00e1 a la tripulaci\u00f3n su nave espacial Orion.Los hallazgos se basan en datos de Artemis I, un viaje\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469701,"url":"https:\/\/noticiasya.com\/corpus-christi\/2025\/12\/31\/nasa-luna-mision-artemis-2-trax\/","url_meta":{"origin":1472836,"position":2},"title":"La NASA estar\u00eda a semanas de su mayor desaf\u00edo en d\u00e9cadas: un viaje tripulado a la Luna","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"La aspiraci\u00f3n de devolver astronautas estadounidenses a la Luna ha estado en limbo durante d\u00e9cadas, debido a que los planes han sido adoptados y rechazados de una administraci\u00f3n presidencial a otra. Sin embargo, en 2026, ese objetivo cobrar\u00e1 un enfoque m\u00e1s claro.El programa Artemis de la NASA \u2014una iniciativa anunciada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1473024,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/10\/regreso-parte-arriesgada-mision-lunar-artemis-trax\/","url_meta":{"origin":1472836,"position":3},"title":"De regreso a casa: la parte m\u00e1s arriesgada de la misi\u00f3n lunar Artemis II a\u00fan est\u00e1 por llegar","author":"","date":"abril 10, 2026","format":false,"excerpt":"Los astronautas de Artemis II se han enfrentado a numerosos peligros en su hist\u00f3rica misi\u00f3n lunar, incluyendo la tensi\u00f3n extrema durante el despegue el 1 de abril, cuando su cohete consumi\u00f3 millones de galones de combustible, y el desaf\u00edo de sortear peligrosos campos de radiaci\u00f3n en ruta hacia la Luna.Pero\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472845,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/03\/donde-esta-orion-que-sigue-artemis-ii-luna-trax\/","url_meta":{"origin":1472836,"position":4},"title":"D\u00f3nde est\u00e1 la nave Orion y qu\u00e9 sigue para la misi\u00f3n Artemis II en su camino a la Luna","author":"","date":"abril 3, 2026","format":false,"excerpt":"La misi\u00f3n Artemis II cruz\u00f3 un umbral crucial e hist\u00f3rico el jueves, cuando la nave espacial Orion encendi\u00f3 su motor e impuls\u00f3 a cuatro astronautas hacia la Luna, en un viaje de varios d\u00edas que los llevar\u00e1 m\u00e1s lejos en el espacio de lo que cualquier ser humano ha viajado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472895,"url":"https:\/\/noticiasya.com\/corpus-christi\/2026\/04\/06\/donde-esta-artemis-orion-que-sigue-luna-trax\/","url_meta":{"origin":1472836,"position":5},"title":"D\u00f3nde est\u00e1 la nave Orion y qu\u00e9 sigue para la misi\u00f3n Artemis II en su camino a la Luna","author":"","date":"abril 6, 2026","format":false,"excerpt":"La misi\u00f3n Artemis II est\u00e1 ahora m\u00e1s cerca de la Luna que de la Tierra, con cuatro astronautas avanzando hacia su objetivo en una trayectoria de asistencia gravitatoria que los llevar\u00e1 m\u00e1s lejos en el espacio de lo que ning\u00fan ser humano ha llegado antes.El viaje \u2014tripulado por Reid Wiseman,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/corpus-christi\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/comments?post=1472836"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/posts\/1472836\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/media?parent=1472836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/categories?post=1472836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/corpus-christi\/wp-json\/wp\/v2\/tags?post=1472836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}