{"id":1446471,"date":"2024-03-04T09:48:36","date_gmt":"2024-03-04T17:48:36","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/"},"modified":"2024-03-07T04:50:06","modified_gmt":"2024-03-07T12:50:06","slug":"corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","title":{"rendered":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Sala de Apelaciones de la Corte Penal Internacional (CPI) de La Haya decidi\u00f3 este viernes que la Fiscal\u00eda continuar\u00e1 con la investigaci\u00f3n por posibles cr\u00edmenes de lesa humanidad contra el Estado venezolano tras desestimar los seis argumentos de apelaci\u00f3n planteados por el Gobierno del presidente Nicol\u00e1s Maduro.<\/p>\n<p>&#171;La Sala de Apelaciones ha estimado procedente confirmar la decisi\u00f3n impugnada&#187;, afirm\u00f3 el presidente de la misma, el juez Marc Perrin de Brichambaut.<\/p>\n<p>El fallo de la Sala de Apelaciones autoriz\u00f3 as\u00ed al fiscal Karim Khan a seguir las pesquisas como parte del caso abierto en noviembre de 2021.<\/p>\n<p>La Sala Preliminar de la Corte Penal Internacional fall\u00f3 en noviembre de 2023 que las autoridades venezolanas &#171;no est\u00e1n investigando o no han investigado los hechos penales que podr\u00edan constituir cr\u00edmenes de lesa humanidad&#187;.<\/p>\n<p>El Gobierno de Chile rechaza reportes de supuesta colaboraci\u00f3n con Venezuela en el presunto secuestro de Ronald Ojeda<\/p>\n<p>En la audiencia de\u00a0este viernes\u00a0estuvieron presentes la Fiscal\u00eda de la CPI, los representantes del gobierno venezolano \u00ad\u2013entre ellos Larry Lavoe, representante de Venezuela para el Sistema Internacional de Derechos Humanos\u2013 as\u00ed como representantes de la Oficina P\u00fablica de Defensa de las V\u00edctimas.<\/p>\n<p>El canciller de Venezuela, Yv\u00e1n Gil, rechaz\u00f3 el fallo en su cuenta de X, antes Twitter,\u00a0al decir que\u00a0&#171;responde a la intenci\u00f3n de instrumentalizar los mecanismos de justicia penal internacional con fines pol\u00edticos, todo ello sobre la base de una acusaci\u00f3n por supuestos cr\u00edmenes de lesa humanidad que nunca han ocurrido&#187;.<\/p>\n<p>En oportunidades previas \u2013y espec\u00edficamente tras una visita a Caracas en junio del fiscal de la CPI, Karim Khan\u2013 el fiscal general Tarek William Saab dijo que el Estado venezolano tiene &#171;intenci\u00f3n de hacer justicia&#187;.<\/p>\n<p>Hace dos semanas, mediante un comunicado emitido por la Canciller\u00eda de Venezuela, el gobierno de Maduro anunci\u00f3 la expulsi\u00f3n de todo el personal de la oficina en Caracas que representaba al Alto Comisionado de las Naciones Unidas para los DD.HH.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; La Sala de Apelaciones de la Corte Penal Internacional (CPI) de La Haya decidi\u00f3 este viernes que la Fiscal\u00eda continuar\u00e1 con la investigaci\u00f3n por posibles cr\u00edmenes de lesa humanidad contra el Estado venezolano tras desestimar los seis argumentos de apelaci\u00f3n planteados por el Gobierno del presidente Nicol\u00e1s Maduro. &#171;La Sala de Apelaciones [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446471","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; La Sala de Apelaciones de la Corte Penal Internacional (CPI) de La Haya decidi\u00f3 este viernes que la Fiscal\u00eda continuar\u00e1 con la investigaci\u00f3n por posibles cr\u00edmenes de lesa humanidad contra el Estado venezolano tras desestimar los seis argumentos de apelaci\u00f3n planteados por el Gobierno del presidente Nicol\u00e1s Maduro. &#171;La Sala de Apelaciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-04T17:48:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:50:06+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad\",\"datePublished\":\"2024-03-04T17:48:36+00:00\",\"dateModified\":\"2024-03-07T12:50:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\"},\"wordCount\":383,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\",\"url\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\",\"name\":\"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-04T17:48:36+00:00\",\"dateModified\":\"2024-03-07T12:50:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; La Sala de Apelaciones de la Corte Penal Internacional (CPI) de La Haya decidi\u00f3 este viernes que la Fiscal\u00eda continuar\u00e1 con la investigaci\u00f3n por posibles cr\u00edmenes de lesa humanidad contra el Estado venezolano tras desestimar los seis argumentos de apelaci\u00f3n planteados por el Gobierno del presidente Nicol\u00e1s Maduro. &#171;La Sala de Apelaciones [&hellip;]","og_url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-04T17:48:36+00:00","article_modified_time":"2024-03-07T12:50:06+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/"},"author":{"name":"","@id":""},"headline":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad","datePublished":"2024-03-04T17:48:36+00:00","dateModified":"2024-03-07T12:50:06+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/"},"wordCount":383,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","url":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","name":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-04T17:48:36+00:00","dateModified":"2024-03-07T12:50:06+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/las-vegas\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La Corte Penal Internacional decide avanzar con la investigaci\u00f3n contra el Gobierno de Venezuela por posibles cr\u00edmenes de lesa humanidad","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-04T17:48:36Z","datePublished":"2024-03-04T17:48:36Z","dateModified":"2024-03-07T12:50:06Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La Corte Penal Internacional decide avanzar con la investigaci\\u00f3n contra el Gobierno de Venezuela por posibles cr\\u00edmenes de lesa humanidad\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/04\\\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/04\\\/corte-penal-internacional-investigacion-venezuela-crimenes-de-lesa-humanidad-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-04T17:48:36Z\",\"datePublished\":\"2024-03-04T17:48:36Z\",\"dateModified\":\"2024-03-07T12:50:06Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1465639,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/08\/19\/fiscal-karim-khan-aparta-investigacion-cpi-orix\/","url_meta":{"origin":1446471,"position":0},"title":"El fiscal Karim Khan se aparta de la investigaci\u00f3n Venezuela 1 de la CPI, tras se\u00f1alamientos por posible conflicto de inter\u00e9s","author":"","date":"agosto 19, 2025","format":false,"excerpt":"El fiscal Karim Kahn present\u00f3 formalmente un escrito en el que se aparta de la investigaci\u00f3n de la Corte Penal Internacional (CPI) sobre posibles cr\u00edmenes de lesa humanidad en Venezuela, cumpliendo la orden de la Sala de Apelaciones del tribunal por posible conflicto de inter\u00e9s.En un escrito remitido el lunes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465050,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/08\/01\/cpi-ordena-karim-khan-apartar-caso-conflicto-interes-orix\/","url_meta":{"origin":1446471,"position":1},"title":"La CPI ordena al fiscal Karim Khan que se aparte del caso sobre Venezuela por posible conflicto de inter\u00e9s","author":"","date":"agosto 1, 2025","format":false,"excerpt":"La Sala de Apelaciones de la Corte Penal Internacional (CPI) orden\u00f3 este viernes al fiscal Karim Khan que se aparte del caso sobre la situaci\u00f3n de derechos humanos en Venezuela por posible conflicto de inter\u00e9s.\u201cLa Sala de Apelaciones considera que existen motivos para creer que existe una causa de recusaci\u00f3n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451879,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/15\/corte-penal-internacional-mision-onu-violaciones-derechos-humanos-venezuela-respondido-gobierno-orix\/","url_meta":{"origin":1446471,"position":2},"title":"\u00bfQu\u00e9 ha dicho la Corte Penal Internacional y la Misi\u00f3n de la ONU sobre las violaciones a derechos humanos en Venezuela y qu\u00e9 ha respondido el Gobierno?","author":"","date":"agosto 15, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Desde hace varios a\u00f1os, la Corte Penal Internacional (CPI), con sede en La Haya, lleva adelante una investigaci\u00f3n en Venezuela por posibles cr\u00edmenes de lesa humanidad en Venezuela, mientras los fiscales y otros organismos contin\u00faan reuniendo pruebas sobre la actuaci\u00f3n del Gobierno de Nicol\u00e1s Maduro, quien hasta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468858,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/12\/01\/fiscalia-cpi-cierra-oficina-venezuela-orix\/","url_meta":{"origin":1446471,"position":3},"title":"La Fiscal\u00eda de la CPI anuncia el cierre de su oficina en Caracas por falta de &#171;progreso real&#187; con Venezuela","author":"","date":"diciembre 1, 2025","format":false,"excerpt":"La Fiscal\u00eda de la Corte Penal Internacional (CPI) anunci\u00f3 este lunes que cerrar\u00e1 su oficina en Caracas. El fiscal adjunto del organismo, Mame Mandiaye Niang, explic\u00f3 su discurso de apertura de la 24\u00aa Asamblea de Estados Parte que, pese al \u201ccompromiso sostenido\u201d mantenido con las autoridades venezolanas, la CPI concluy\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456521,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/12\/12\/espana-cpi-detencion-maduro-orix\/","url_meta":{"origin":1446471,"position":4},"title":"Parlamento espa\u00f1ol insta al Gobierno a solicitar a la Corte Penal Internacional la detenci\u00f3n de Nicol\u00e1s Maduro","author":"","date":"diciembre 12, 2024","format":false,"excerpt":"El Congreso de los Diputados de Espa\u00f1a ha aprobado este jueves una Proposici\u00f3n no de Ley (PNL) para instar al Gobierno a que respalde la investigaci\u00f3n de la Fiscal\u00eda de la Corte Penal Internacional (CPI) relativa a la comisi\u00f3n de cr\u00edmenes de lesa humanidad en Venezuela.La propuesta, registrada por el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452973,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/23\/justicia-argentina-ordena-detencion-nicolas-maduro-venezuela-orix\/","url_meta":{"origin":1446471,"position":5},"title":"La Justicia de Argentina ordena la detenci\u00f3n del presidente de Venezuela, Nicol\u00e1s Maduro, en una causa por delitos de lesa humanidad","author":"","date":"septiembre 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Sala 1 de la C\u00e1mara Criminal y Correccional Federal de Argentina orden\u00f3 este lunes a un juzgado federal de ese pa\u00eds que ordene la inmediata detenci\u00f3n del presidente de Venezuela, Nicol\u00e1s Maduro y del ministro del Interior, Justicia y Paz, Diosdado Cabello, en el marco de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446471"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446471\/revisions"}],"predecessor-version":[{"id":1446655,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446471\/revisions\/1446655"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446471"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446471"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}