{"id":1446510,"date":"2024-03-04T19:22:37","date_gmt":"2024-03-05T03:22:37","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/"},"modified":"2024-03-07T04:49:42","modified_gmt":"2024-03-07T12:49:42","slug":"jack-teixeira-culpable-declaracion-fltracion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","title":{"rendered":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Jack Teixeira, el miembro de la Guardia Nacional A\u00e9rea de Massachusetts acusado de publicar una gran cantidad de informes de inteligencia altamente clasificados y otros documentos confidenciales en redes sociales, se declar\u00f3 culpable este lunes de retener y difundir intencionalmente informaci\u00f3n de defensa nacional.<\/p>\n<p>Acusan a Jack Teixeira con seis cargos por publicar documentos clasificados en l\u00ednea<\/p>\n<p>Teixeira, de 22 a\u00f1os, acept\u00f3 su responsabilidad en los seis cargos que enfrenta en virtud de la Ley de Espionaje, durante una audiencia celebrada este lunes.<\/p>\n<p>Adem\u00e1s, acord\u00f3 reunirse con miembros de la comunidad de inteligencia y del Departamento de Defensa, seg\u00fan informaci\u00f3n judicial, as\u00ed como entregar todos los documentos relevantes que tiene o cuya ubicaci\u00f3n conoce.<\/p>\n<p>A cambio, los fiscales informaron que le pedir\u00e1n al juez que imponga una pena de 200 meses de prisi\u00f3n, o m\u00e1s de 16 a\u00f1os. Si bien la pena es alta, esta recomendaci\u00f3n de sentencia resulta mucho menor que la posible condena a d\u00e9cadas de prisi\u00f3n que Teixeira podr\u00eda haber enfrentado si no hubiera llegado a un acuerdo. Los fiscales tambi\u00e9n prometieron no acusar al joven de cargos adicionales en virtud de la Ley de Espionaje, seg\u00fan documentos judiciales.<\/p>\n<p>Lo que sabemos de Jack Teixeira, vinculado a la filtraci\u00f3n de documentos clasificados del Pent\u00e1gono<\/p>\n<p>\u201cJack Teixeira nunca podr\u00e1 acercarse a una informaci\u00f3n clasificada por el resto de su vida\u201d, dijo el fiscal federal para el distrito de Massachusetts, Josh Levy, en una conferencia de prensa luego de que el joven se declarara culpable.<\/p>\n<p>&#171;Esta declaraci\u00f3n de culpabilidad implica responsabilidad y supone una medida de cierre a un cap\u00edtulo que cre\u00f3 da\u00f1os profundos a la seguridad de nuestra naci\u00f3n&#187;, dijo Matt Olsen, fiscal general adjunto para seguridad nacional del Departamento de Justicia.<\/p>\n<p>La ret\u00f3rica violenta del acusado de filtrar documentos del Pent\u00e1gono plantea una nueva pregunta sobre el proceso de veto de informaci\u00f3n ultrasecreta<\/p>\n<p>La sentencia final la decidir\u00e1 en \u00faltima instancia un juez federal en septiembre. El nativo de Massachusetts ha estado bajo custodia desde que lo arrestaron, en abril de 2023.<\/p>\n<p>La filtraci\u00f3n de los documentos sacudi\u00f3 al mundo de la inteligencia cuando salieron a la luz por primera vez el a\u00f1o pasado. La filtraci\u00f3n gener\u00f3 dudas sobre el proceso de investigaci\u00f3n de secretos del Gobierno de Estados Unidos, mientras los funcionarios intentaban saber c\u00f3mo un especialista en inform\u00e1tica de 21 a\u00f1os que, seg\u00fan los fiscales, ten\u00eda un arsenal de armas y un historial de ret\u00f3rica violenta, pudo obtener una autorizaci\u00f3n de seguridad ultrasecreta.<\/p>\n<p>Tambi\u00e9n revel\u00f3 lo que fuentes de defensa e inteligencia calificaron en ese momento como &#171;debilidades evidentes&#187; en la forma en que el Pent\u00e1gono salvaguarda sus secretos m\u00e1s sensibles.<\/p>\n<p>Teixeira estuvo entre sus dos abogados defensores cuando se declar\u00f3 culpable, el lunes por la ma\u00f1ana. Llevaba un uniforme naranja de prisi\u00f3n y un rosario alrededor del cuello. Detr\u00e1s de \u00e9l se sentaban seguidores y familiares, incluido su padre.<\/p>\n<p>Seg\u00fan documentos judiciales, Teixeira dirig\u00eda una oscura sala de chat en la plataforma de redes sociales Discord llamada \u201cThug Shaker Central\u201d, donde los miembros publicaban memes y hablaban sobre armas y religi\u00f3n.<\/p>\n<p>Mientras trabajaba en una base militar en Cape Cod, Teixeira supuestamente realiz\u00f3 b\u00fasquedas no autorizadas en bases de datos gubernamentales a pesar de las repetidas advertencias de sus superiores de que no lo hiciera. Primero comenz\u00f3 a publicar mensajes con informaci\u00f3n clasificada en el chat de Discord, seg\u00fan los fiscales, y finalmente difundi\u00f3 fotograf\u00edas de documentos marcados como clasificados.<\/p>\n<p>El filtrador acusado de Discord, Jack Teixeira, cita a Trump al pedir ser enjuiciado en libertad<\/p>\n<p>Los documentos, algunos de los cuales han sido revisados por CNN, inclu\u00edan una amplia gama de informaci\u00f3n altamente clasificada, entre ellas escuchas a aliados y adversarios clave, as\u00ed como evaluaciones contundentes sobre el estado de la guerra entre Rusia y Ucrania. Los fiscales se\u00f1alan\u00a0 que los documentos que public\u00f3 Teixeira tambi\u00e9n incluyen informaci\u00f3n sobre las cuentas de una empresa estadounidense an\u00f3nima que resultaron comprometidas por un \u201cadversario extranjero\u201d, as\u00ed como un documento que analiza un \u201ccomplot de un adversario extranjero para atacar a las fuerzas estadounidenses en el extranjero\u201d.<\/p>\n<p>La jueza Indira Talwani ley\u00f3 en voz alta los detalles de las acciones de las que se acusa a Teixeira \u2013\u2013y la informaci\u00f3n que se le acusa de filtrar\u2013\u2013 durante la audiencia del lunes. Tambi\u00e9n le pregunt\u00f3 a Teixeira si ten\u00eda \u201calg\u00fan desacuerdo\u201d con las acusaciones.<\/p>\n<p>\u201cNo, su se\u00f1or\u00eda\u201d, dijo Teixeira.<\/p>\n<p>\u201cCualquier desacuerdo\u2026 de que cada uno de esos documentos estaba clasificado como ultrasecreto, y que la divulgaci\u00f3n no autorizada podr\u00eda afectar razonablemente la seguridad nacional\u201d, pregunt\u00f3 la jueza.<\/p>\n<p>Teixeira respondi\u00f3: \u201cNo, su se\u00f1or\u00eda\u201d.<\/p>\n<p>AN\u00c1LISIS |\u00a0El arresto de un joven de 21 a\u00f1os expone un problema m\u00e1s grande sobre los documentos clasificados de EE.UU.<\/p>\n<p>Los fiscales dicen que, despu\u00e9s de que se hiciera p\u00fablica la filtraci\u00f3n, Teixeira destruy\u00f3 sus dispositivos electr\u00f3nicos y obtuvo un nuevo n\u00famero de tel\u00e9fono, as\u00ed como una nueva direcci\u00f3n de correo electr\u00f3nico. Fue detenido en su casa de Massachusetts aproximadamente una semana despu\u00e9s.<\/p>\n<p>Tras esa acusaci\u00f3n, la Fuerza A\u00e9rea de EE.UU. sancion\u00f3 a 15 personas que \u201cintencionalmente no informaron\u201d sobre la alerta documentada en relaci\u00f3n al comportamiento de Teixeira antes de las filtraciones, incluido el comandante de la unidad de Teixeira que fue relevado de su mando.<\/p>\n<p>Afuera del tribunal federal de Boston, el abogado de Teixeira, Michael Bachrach, dijo que su cliente se declar\u00f3 culpable de \u201chacer lo correcto\u201d y \u201cen absoluto\u201d est\u00e1 vendiendo secretos clasificados a gobiernos extranjeros.<\/p>\n<p>En una declaraci\u00f3n a CNN, la familia de Teixeira dijo que \u201ces incre\u00edble pensar que Jack alguna vez estar\u00eda involucrado en algo tan serio, pero \u00e9l ha asumido la responsabilidad de su parte en esto y aqu\u00ed estamos\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Jack Teixeira, el miembro de la Guardia Nacional A\u00e9rea de Massachusetts acusado de publicar una gran cantidad de informes de inteligencia altamente clasificados y otros documentos confidenciales en redes sociales, se declar\u00f3 culpable este lunes de retener y difundir intencionalmente informaci\u00f3n de defensa nacional. Acusan a Jack Teixeira con seis cargos por publicar [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446510","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Jack Teixeira, el miembro de la Guardia Nacional A\u00e9rea de Massachusetts acusado de publicar una gran cantidad de informes de inteligencia altamente clasificados y otros documentos confidenciales en redes sociales, se declar\u00f3 culpable este lunes de retener y difundir intencionalmente informaci\u00f3n de defensa nacional. Acusan a Jack Teixeira con seis cargos por publicar [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T03:22:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:49:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional\",\"datePublished\":\"2024-03-05T03:22:37+00:00\",\"dateModified\":\"2024-03-07T12:49:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\"},\"wordCount\":1047,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\",\"name\":\"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-05T03:22:37+00:00\",\"dateModified\":\"2024-03-07T12:49:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional - Noticias","og_description":"(CNN) \u2013\u2013 Jack Teixeira, el miembro de la Guardia Nacional A\u00e9rea de Massachusetts acusado de publicar una gran cantidad de informes de inteligencia altamente clasificados y otros documentos confidenciales en redes sociales, se declar\u00f3 culpable este lunes de retener y difundir intencionalmente informaci\u00f3n de defensa nacional. Acusan a Jack Teixeira con seis cargos por publicar [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-05T03:22:37+00:00","article_modified_time":"2024-03-07T12:49:42+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/"},"author":{"name":"","@id":""},"headline":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional","datePublished":"2024-03-05T03:22:37+00:00","dateModified":"2024-03-07T12:49:42+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/"},"wordCount":1047,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","name":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-05T03:22:37+00:00","dateModified":"2024-03-07T12:49:42+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Jack Teixeira se declara culpable de filtrar informaci\u00f3n clasificada en l\u00ednea sobre defensa nacional","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/jack-teixeira-culpable-declaracion-fltracion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-05T03:22:37Z","datePublished":"2024-03-05T03:22:37Z","dateModified":"2024-03-07T12:49:42Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Jack Teixeira se declara culpable de filtrar informaci\\u00f3n clasificada en l\\u00ednea sobre defensa nacional\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/04\\\/jack-teixeira-culpable-declaracion-fltracion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/04\\\/jack-teixeira-culpable-declaracion-fltracion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-05T03:22:37Z\",\"datePublished\":\"2024-03-05T03:22:37Z\",\"dateModified\":\"2024-03-07T12:49:42Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446970,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/14\/conclusiones-audiencia-trump-documentos-clasificados-trax\/","url_meta":{"origin":1446510,"position":0},"title":"Conclusiones de la audiencia de Trump para desestimar las acusaciones sobre documentos clasificados","author":"","date":"marzo 14, 2024","format":false,"excerpt":"Fort Pierce, Florida (CNN) --\u00a0La jueza del Tribunal de Distrito de Estados Unidos Aileen Cannon rechaz\u00f3 este jueves desestimar el caso de los documentos clasificados contra Donald Trump tras horas de discusiones en parte sobre si los cargos contra el expresidente eran demasiado vagos.Ante la jueza se plantearon dos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449765,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/25\/ex-oficial-cia-se-declara-culpable-espiar-para-china-dice-el-departamento-de-justicia-trax\/","url_meta":{"origin":1446510,"position":1},"title":"Ex oficial de la CIA se declara culpable de espiar para China, dice el Departamento de Justicia","author":"","date":"mayo 25, 2024","format":false,"excerpt":"(CNN) -- Un ex oficial de la CIA objetivo de una operaci\u00f3n encubierta del FBI se declar\u00f3 culpable este viernes de proporcionar informaci\u00f3n de defensa nacional a la Rep\u00fablica Popular China, dijo el Departamento de Justicia.Alexander Yuk Ching Ma, de 71 a\u00f1os, de Honolulu, que sirvi\u00f3 como oficial de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444304,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/23\/grupo-de-medios-busca-revelar-informacion-en-caso-de-documentos-clasificados-de-trump\/","url_meta":{"origin":1446510,"position":2},"title":"Grupo de medios busca revelar informaci\u00f3n en caso de documentos clasificados de Trump","author":"","date":"enero 23, 2024","format":false,"excerpt":"(CNN) -- Un grupo de m\u00e1s de 30 importantes organizaciones de medios, incluida CNN, est\u00e1 buscando que se revele informaci\u00f3n sobre el caso de los documentos de Mar-a-Lago de Donald Trump, incluidos los nombres de algunos posibles testigos.\"Cualquiera que sea el resultado de este juicio, el p\u00fablico debe tener confianza\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462209,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/10\/fiscal-clave-documentos-clasificados-trump-testificara-camara-trax\/","url_meta":{"origin":1446510,"position":3},"title":"Fiscal clave en el caso de documentos clasificados de Trump testificar\u00e1 ante el Comit\u00e9 Judicial de la C\u00e1mara","author":"","date":"mayo 10, 2025","format":false,"excerpt":"Se espera que un fiscal federal clave en el caso de documentos clasificados contra el presidente de EE.UU., Donald Trump, testifique en privado ante el Comit\u00e9 Judicial de la C\u00e1mara en los pr\u00f3ximos d\u00edas, dijo una fuente familiarizada con el proceso a CNN.La declaraci\u00f3n de Jay Bratt, que fue reportada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447740,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/04\/jueza-cannon-rechaza-intento-trump-desestimar-cargos-penales-caso-documentos-clasificados-trax\/","url_meta":{"origin":1446510,"position":4},"title":"Jueza rechaza el intento de Trump por desestimar los cargos penales en el caso de documentos clasificados","author":"","date":"abril 4, 2024","format":false,"excerpt":"(CNN) -- La jueza federal Aileen Cannon rechaz\u00f3 desestimar los cargos penales contra el expresidente de Estados Unidos Donald Trump en el caso de los documentos clasificados, luego de que el exmandatario argumentara que ten\u00eda autoridad para llevarse consigo material clasificado o sensible tras dejar la Casa Blanca.La breve orden\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447756,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/05\/jueza-cannon-rechaza-intento-trump-desestimar-cargos-penales-trax\/","url_meta":{"origin":1446510,"position":5},"title":"Trump sufre reveses en sus esfuerzos por cerrar dos de las causas penales en su contra","author":"","date":"abril 5, 2024","format":false,"excerpt":"(CNN) -- El expresidente Donald Trump sufri\u00f3 dos importantes reveses el jueves en sus esfuerzos por hacer descarrilar los casos penales en su contra: los jueces del caso de interferencia electoral en Georgia y del caso federal de documentos clasificados rechazaron sendas peticiones del posible candidato presidencial del Partido Republicano\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446510"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446510\/revisions"}],"predecessor-version":[{"id":1446610,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446510\/revisions\/1446610"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446510"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446510"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}