{"id":1446527,"date":"2024-03-05T07:52:41","date_gmt":"2024-03-05T15:52:41","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/"},"modified":"2024-03-07T04:45:13","modified_gmt":"2024-03-07T12:45:13","slug":"haiti-violencia-fotos-pandilla-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","title":{"rendered":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds"},"content":{"rendered":"<p>(CNN) &#8212; Mientras estaba en Puerto Pr\u00edncipe, la capital haitiana, esperando la oportunidad de entrevistar al l\u00edder de un pandilla m\u00e1s notorio, Jimmy \u201cBarbecue\u201d Cherizier, Giles Clarke escuch\u00f3 disparos semiautom\u00e1ticos desde lo que parec\u00edan solo dos o tres cuadras de distancia.<\/p>\n<p>\u201cMir\u00e9 al grupo de lugare\u00f1os, pregunt\u00e1ndome si podr\u00edan responder, pero apenas movieron un m\u00fasculo\u201d, record\u00f3 el fotoperiodista. &#171;Era solo un d\u00eda m\u00e1s en (el vecindario) Delmas 6, y la constante r\u00e1faga de balas que volaba sobre el edificio cercano no parec\u00eda nada inusual&#187;.<\/p>\n<p>Cada pocos minutos se produc\u00eda otra r\u00e1faga, seguida de fuego de respuesta.<\/p>\n<p>As\u00ed es la vida ahora en Puerto Pr\u00edncipe, donde las pandillas controlan el 80% de la ciudad, estima la ONU, y contin\u00faan luchando por el resto.<\/p>\n<p>Las pandillas controlan la capital de Hait\u00ed. Algunos dicen que tambi\u00e9n est\u00e1n dispuestos a derrocar al Gobierno<\/p>\n<p>Cientos de haitianos que huyeron de la violencia de las pandillas viven en tiendas de campa\u00f1a afuera de un centro de desplazados en Puerto Pr\u00edncipe. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Un pandillero afiliado a la alianza G9 de Jimmy \u201cBarbecue\u201d Cherizier sostiene un rifle en Puerto Pr\u00edncipe. Las pandillas controlan el 80% de la capital, estima la ONU. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>La polic\u00eda haitiana inspecciona documentos en un puesto de control en una calle que va del centro de la ciudad al puerto. Es uno de los pocos lugares controlados por la polic\u00eda, afirm\u00f3 el fotoperiodista Giles Clarke. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Hait\u00ed ha estado en un estado de agitaci\u00f3n durante a\u00f1os, pero m\u00faltiples fuentes de seguridad en la capital le dijeron a CNN que el aumento m\u00e1s reciente de violencia de pandillas, que se ha dirigido a estaciones de polic\u00eda, el aeropuerto internacional y la penitenciar\u00eda nacional, no tiene precedentes.<\/p>\n<p>El Gobierno de Hait\u00ed declar\u00f3 el domingo el estado de emergencia, citando el \u201cdeterioro de la seguridad\u201d y \u201cactos criminales cada vez m\u00e1s violentos perpetrados por bandas armadas\u201d, incluidos secuestros y asesinatos de ciudadanos, violencia contra mujeres y ni\u00f1os y saqueos.<\/p>\n<p>Grupos armados atacaron las dos prisiones m\u00e1s grandes del pa\u00eds el s\u00e1bado, y una fuente de las Naciones Unidas dijo que se cree que alrededor de 3.500 prisioneros escaparon de la Penitenciar\u00eda Nacional en Puerto Pr\u00edncipe durante el fin de semana.<\/p>\n<p>Pheguens, un conductor de autob\u00fas escolar de 29 a\u00f1os, recibi\u00f3 un disparo en la espalda el mes pasado. Clarke vio a muchos civiles heridos mientras estaba en Hait\u00ed. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Un vidrio roto dentro de uno de los veh\u00edculos blindados antipandillas del departamento de polic\u00eda. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Mientras tanto, m\u00e1s de 300.000 civiles haitianos se han visto obligados a huir de sus hogares debido a la violencia de las pandillas, seg\u00fan las Naciones Unidas.<\/p>\n<p>As\u00ed es vivir bajo el control de las pandillas en Hait\u00ed 6:17<\/p>\n<p>\u201cTodos los sitios de desplazamiento a los que fui en septiembre probablemente hayan duplicado su capacidad ahora\u201d, dijo Clarke, un fotoperiodista radicado en Nueva York que ha estado visitando el pa\u00eds caribe\u00f1o de forma intermitente desde 2011.<\/p>\n<p>Clarke regres\u00f3 el mes pasado para documentar los disturbios en Puerto Pr\u00edncipe. Fue testigo de escenas m\u00e1s angustiosas, incluido un hospital donde vio a innumerables personas sufriendo heridas de bala.<\/p>\n<p>\u201cMuchos de ellos eran civiles afectados por el fuego cruzado de las pandillas y la mayor\u00eda cerca de los mercados. Es gente que simplemente sigue con su d\u00eda a d\u00eda\u201d, dijo Clarke. \u201cLos m\u00e9dicos estaban abrumados. Faltaban suministros\u201d.<\/p>\n<p>Una procesi\u00f3n f\u00fanebre en el Gran Cementerio del centro de Puerto Pr\u00edncipe. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Las morgues tambi\u00e9n estaban abarrotadas en la ciudad.<\/p>\n<p>\u201cSe pod\u00eda olerlo en la calle\u201d, dijo Clarke. \u201cRecuerdo que le pregunt\u00e9 a (mi gu\u00eda) Joe: \u2018\u00bfQu\u00e9 es eso?\u2019 Y \u00e9l dijo: \u2018Gente muerta&#8217;\u201d.<\/p>\n<p>Clarke dijo que muchos de ellos eran v\u00edctimas de la violencia de pandillas cuyos cuerpos no hab\u00edan sido reclamados por las familias.<\/p>\n<p>\u201cSi no los reclamas o si nadie paga, estos cuerpos simplemente se pudrir\u00e1n\u201d, dijo. &#171;Hay muy poca refrigeraci\u00f3n&#187;.<\/p>\n<p>Un ata\u00fad yace en una morgue del centro. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Cherizier, en el centro, pasea por las calles de la capital. Lidera una alianza de pandillas en la ciudad. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Mientras estuvo en Hait\u00ed, Clarke tambi\u00e9n logr\u00f3 encontrarse cara a cara con Jimmy \u201cBarbecue\u201d Cherizier, un exagente de polic\u00eda que lidera una alianza de pandillas en Puerto Pr\u00edncipe.<\/p>\n<p>Cherizier ha dejado claro que su objetivo es derribar el Gobierno del primer ministro Ariel Henry.<\/p>\n<p>Le dijo a Clarke que las pandillas quieren cambiar el sistema actual y crear un nuevo Hait\u00ed. Si bien los hombres de Cherizier usaban pasamonta\u00f1as para proteger sus identidades, \u00e9l no ten\u00eda.<\/p>\n<p>\u201cA menudo es el \u00fanico que no usa m\u00e1scara: un rostro desafiante de la resistencia haitiana\u201d, dijo Clarke.<\/p>\n<p>Un pandillero armado en el barrio Delmas 3. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Gherisse, de 42 a\u00f1os, se recupera en el Hospital General dos d\u00edas despu\u00e9s de quedar atrapada en un fuego cruzado entre pandillas y recibir un disparo en el cuello. Ella trabajaba como vendedora de comida en el centro. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Violet, de 63 a\u00f1os, yace en el suelo del Hospital General tras recibir dos disparos en el brazo. Ella dice que su hija de 34 a\u00f1os fue asesinada cuando dos pandillas en guerra arrasaron su vecindario apenas una hora antes. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Se supon\u00eda que Henry, quien asumi\u00f3 el liderazgo del pa\u00eds despu\u00e9s del asesinato del presidente Jovenel Moise en 2021, celebrar\u00eda elecciones y transferir\u00eda el poder antes del 7 de febrero. Pero el mes pasado dijo que no pod\u00eda dimitir porque las condiciones en el pa\u00eds no eran lo suficientemente seguras para organizar una elecci\u00f3n.<\/p>\n<p>&#171;Mi Gobierno interino est\u00e1 trabajando mano a mano con la polic\u00eda para restaurar la vida normal en el pa\u00eds&#187;, dijo en un discurso a la naci\u00f3n. \u201cSomos conscientes de que muchas cosas tienen que cambiar, pero debemos hacer esos cambios juntos y con calma\u201d.<\/p>\n<p>Eso no es aceptable para Cherizier, quien el viernes reiter\u00f3 su exigencia de que Henry sea arrestado.<\/p>\n<p>\u201cPedimos a la Polic\u00eda Nacional de Hait\u00ed y al Ej\u00e9rcito que asuman su responsabilidad y arresten a Ariel Henry\u201d, dijo. \u201cUna vez m\u00e1s, la poblaci\u00f3n no es nuestro enemigo; los grupos armados no son el enemigo. Arresten a Ariel Henry por la liberaci\u00f3n del pa\u00eds. \u2026 Con estas armas, liberaremos al pa\u00eds, y estas armas cambiar\u00e1n el pa\u00eds\u201d.<\/p>\n<p>Cherizier y su perra Barbie. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Una ni\u00f1a se encuentra en las gradas de un antiguo estadio deportivo escolar que ahora es un centro para desplazados. Ella es una de los m\u00e1s de 600 ni\u00f1os que ahora viven en el abarrotado refugio, dijo Clarke. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Cherizier ha enfrentado sanciones tanto de la ONU como del Departamento del Tesoro de Estados Unidos. La ONU ha acusado a Cherizier de abusos contra los derechos humanos, incluida la orquestaci\u00f3n de ataques mortales contra civiles a lo largo de los a\u00f1os, diciendo que sus acciones \u201chan contribuido directamente a la par\u00e1lisis econ\u00f3mica y la crisis humanitaria en Hait\u00ed\u201d.<\/p>\n<p>Clarke lo visit\u00f3 a finales de febrero en su modesta casa en la cima de una colina en Delmas 6.<\/p>\n<p>&#171;De hecho, hicimos la entrevista en el edificio abandonado frente a \u00e9l&#187;, dijo Clarke. &#171;Se dice que no quer\u00eda que mucha gente viviera tan cerca de \u00e9l&#187;.<\/p>\n<p>Despu\u00e9s de una breve entrevista en la que Cherizier expuso su visi\u00f3n para Hait\u00ed, Clarke camin\u00f3 con \u00e9l por las calles. Clarke recuerda lo tranquilo que era cuando estaba con Cherizier. &#171;No hubo disparos porque (los hombres) estaban todos con Jimmy&#187;, dijo.<\/p>\n<p>Una vista desde el interior de un veh\u00edculo blindado de la polic\u00eda haitiana. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Un hombre se para en la parte trasera de un cami\u00f3n mientras cruza hacia el vecindario Delmas 6. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Para intentar restablecer el orden en su pa\u00eds, Henry ha pedido ayuda militar. El despliegue de una fuerza de seguridad multinacional encabezada por Kenya recibi\u00f3 luz verde del Consejo de Seguridad de la ONU el a\u00f1o pasado y Henry visit\u00f3 recientemente Kenya para ultimar los detalles, pero no est\u00e1 claro cu\u00e1ndo podr\u00edan llegar esas tropas.<\/p>\n<p>Estados Unidos acord\u00f3 proporcionar US$ 200 millones a la misi\u00f3n, y el secretario de Estado Antony Blinken calific\u00f3 la situaci\u00f3n en Hait\u00ed como \u201cuno de los desaf\u00edos m\u00e1s urgentes que enfrentamos como comunidad internacional\u201d.<\/p>\n<p>Jean Junior Joseph, asesor asesor del primer ministro Henry, dijo a CNN que el Gobierno tiene opciones limitadas en este momento.<\/p>\n<p>&#171;Las pandillas tienen m\u00e1s municiones que nosotros&#187;, afirm\u00f3.<\/p>\n<p>Un hombre y una mujer, desplazados por la violencia de las pandillas, ahora viven en un antiguo edificio escolar en el barrio Delmas 4. (Cr\u00e9dito: Giles Clarke)<\/p>\n<p>Cr\u00e9ditos<br \/>\nFot\u00f3grafo: Giles Clarke<br \/>\nEscritor: Kyle Almond<br \/>\nEditores de fotograf\u00edas: Bernadette Tuazon, Brett Roegiers y Will Lanzoni<br \/>\nReporteros contribuyentes: David Culver, Jeremy Dupin, Caitlin Stephen Hu, Stefano Pozzebon, Manveena Suri y Michelle Velez<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Mientras estaba en Puerto Pr\u00edncipe, la capital haitiana, esperando la oportunidad de entrevistar al l\u00edder de un pandilla m\u00e1s notorio, Jimmy \u201cBarbecue\u201d Cherizier, Giles Clarke escuch\u00f3 disparos semiautom\u00e1ticos desde lo que parec\u00edan solo dos o tres cuadras de distancia. \u201cMir\u00e9 al grupo de lugare\u00f1os, pregunt\u00e1ndome si podr\u00edan responder, pero apenas movieron un m\u00fasculo\u201d, [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446527","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Mientras estaba en Puerto Pr\u00edncipe, la capital haitiana, esperando la oportunidad de entrevistar al l\u00edder de un pandilla m\u00e1s notorio, Jimmy \u201cBarbecue\u201d Cherizier, Giles Clarke escuch\u00f3 disparos semiautom\u00e1ticos desde lo que parec\u00edan solo dos o tres cuadras de distancia. \u201cMir\u00e9 al grupo de lugare\u00f1os, pregunt\u00e1ndome si podr\u00edan responder, pero apenas movieron un m\u00fasculo\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T15:52:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds\",\"datePublished\":\"2024-03-05T15:52:41+00:00\",\"dateModified\":\"2024-03-07T12:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\"},\"wordCount\":1605,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\",\"url\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\",\"name\":\"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-05T15:52:41+00:00\",\"dateModified\":\"2024-03-07T12:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds - Noticias","og_description":"(CNN) &#8212; Mientras estaba en Puerto Pr\u00edncipe, la capital haitiana, esperando la oportunidad de entrevistar al l\u00edder de un pandilla m\u00e1s notorio, Jimmy \u201cBarbecue\u201d Cherizier, Giles Clarke escuch\u00f3 disparos semiautom\u00e1ticos desde lo que parec\u00edan solo dos o tres cuadras de distancia. \u201cMir\u00e9 al grupo de lugare\u00f1os, pregunt\u00e1ndome si podr\u00edan responder, pero apenas movieron un m\u00fasculo\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-05T15:52:41+00:00","article_modified_time":"2024-03-07T12:45:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/"},"author":{"name":"","@id":""},"headline":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds","datePublished":"2024-03-05T15:52:41+00:00","dateModified":"2024-03-07T12:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/"},"wordCount":1605,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","url":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","name":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-05T15:52:41+00:00","dateModified":"2024-03-07T12:45:13+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/aspen\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mientras Hait\u00ed es consumido por la violencia, el pandillero m\u00e1s notorio pide la \u201cliberaci\u00f3n\u201d del pa\u00eds","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/haiti-violencia-fotos-pandilla-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-05T15:52:41Z","datePublished":"2024-03-05T15:52:41Z","dateModified":"2024-03-07T12:45:13Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mientras Hait\\u00ed es consumido por la violencia, el pandillero m\\u00e1s notorio pide la \\u201cliberaci\\u00f3n\\u201d del pa\\u00eds\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/haiti-violencia-fotos-pandilla-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/haiti-violencia-fotos-pandilla-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-05T15:52:41Z\",\"datePublished\":\"2024-03-05T15:52:41Z\",\"dateModified\":\"2024-03-07T12:45:13Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447010,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/15\/haiti-dentro-violencia-pandillas-culver-trax\/","url_meta":{"origin":1446527,"position":0},"title":"Dentro de Hait\u00ed: unos pocos afortunados escapan, mientras millones enfrentan el dominio de las pandillas, el hambre y el caos","author":"","date":"marzo 15, 2024","format":false,"excerpt":"Puerto Pr\u00edncipe, Hait\u00ed (CNN) \u2013\u2013 En una ciudad silenciada por las pandillas, todos escuchan el ruido de un helic\u00f3ptero sobrevolando en la noche: una breve se\u00f1al de que alguien muy afortunado ha podido salir de Puerto Pr\u00edncipe.CNN pudo aterrizar en la capital de Hait\u00ed en un helic\u00f3ptero este viernes, luego\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447221,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/21\/matanza-calles-puerto-principe-estancamiento-intervencion-haiti-trax\/","url_meta":{"origin":1446527,"position":1},"title":"Matanza en las calles de Puerto Pr\u00edncipe mientras el mundo se detiene en una intervenci\u00f3n prometida para Hait\u00ed","author":"","date":"marzo 21, 2024","format":false,"excerpt":"Puerto Pr\u00edncipe (CNN) -- Una mujer mete a su hijo peque\u00f1o en un autom\u00f2vil que espera, medio arrastr\u00e1ndolo mientras le protege los ojos. Otros miembros de la familia lo siguen con pesadas maletas, desviando tambi\u00e9n la mirada. Est\u00e1n abandonando la ciudad, a pesar de que conducir por carreteras controladas por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447705,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/03\/hambre-haiti-puerto-principe-crisis-pandillas-falta-suministros-trax\/","url_meta":{"origin":1446527,"position":2},"title":"El hambre en Hait\u00ed se extiende en medio de la violencia de las pandillas, advierten trabajadores humanitarios","author":"","date":"abril 3, 2024","format":false,"excerpt":"(CNN) -- Cada vez m\u00e1s personas pasan hambre en Hait\u00ed, advierten con creciente urgencia trabajadores humanitarios, m\u00e9dicos y misioneros, mientras la naci\u00f3n caribe\u00f1a lucha por encontrar una salida al estancamiento pol\u00edtico y a una epidemia de violencia mortal de pandillas.Un misionero estadounidense cuya organizaci\u00f3n entrega alimentos y agua a los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446279,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/haiti-pandillas-capital-derrocar-trax\/","url_meta":{"origin":1446527,"position":3},"title":"Las pandillas controlan la capital de Hait\u00ed. Algunos dicen que tambi\u00e9n est\u00e1n dispuestos a derrocar al Gobierno","author":"","date":"marzo 4, 2024","format":false,"excerpt":"Puerto Pr\u00edncipe, Hait\u00ed (CNN) -- Desde arriba, Puerto Pr\u00edncipe, la capital de Hait\u00ed, todav\u00eda parece serena, con sus casas encaladas trepando por empinadas colinas verdes que rodean una bah\u00eda resplandeciente. Pero para pisar sus agrietadas calles se requiere un c\u00e1lculo cuidadoso del riesgo.Las pandillas despiadadas tienen un dominio absoluto sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446400,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/haiti-pandillas-capital-derrocar-trax-2\/","url_meta":{"origin":1446527,"position":4},"title":"Las pandillas controlan la capital de Hait\u00ed. Algunos dicen que tambi\u00e9n est\u00e1n dispuestos a derrocar al Gobierno","author":"agomez","date":"marzo 4, 2024","format":false,"excerpt":"Puerto Pr\u00edncipe, Hait\u00ed (CNN) -- Desde arriba, Puerto Pr\u00edncipe, la capital de Hait\u00ed, todav\u00eda parece serena, con sus casas encaladas trepando por empinadas colinas verdes que rodean una bah\u00eda resplandeciente. Pero para pisar sus agrietadas calles se requiere un c\u00e1lculo cuidadoso del riesgo.Las pandillas despiadadas tienen un dominio absoluto sobre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447011,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/15\/operativo-captura-jimmy-barbecue-cherizier-haiti-pandillas-trax\/","url_meta":{"origin":1446527,"position":5},"title":"Intentan capturar al l\u00edder pandillero Jimmy &#171;Barbecue&#187; Cherizier en Hait\u00ed con un gran operativo, dicen fuentes","author":"agomez","date":"marzo 15, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un gran operativo se lleva a cabo en Puerto Pr\u00edncipe, capital de Hait\u00ed, para capturar al l\u00edder pandillero Jimmy Cherizier, alias \"Barbecue\", seg\u00fan dijeron dos fuentes policiales a CNN. De acuerdo a las fuentes, m\u00faltiples unidades de fuerzas especiales participan en el esfuerzo.El operativo se despliega espec\u00edficamente en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446527"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446527\/revisions"}],"predecessor-version":[{"id":1446594,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446527\/revisions\/1446594"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446527"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446527"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}