{"id":1446532,"date":"2024-03-05T11:37:32","date_gmt":"2024-03-05T19:37:32","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/"},"modified":"2024-03-07T04:45:12","modified_gmt":"2024-03-07T12:45:12","slug":"juan-orlando-hernandez-testifica-juicio-narotrafico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","title":{"rendered":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU."},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El expresidente de Honduras Juan Orlando Hern\u00e1ndez testific\u00f3 este martes en el juicio que se le sigue por tr\u00e1fico de drogas y conspiraci\u00f3n para poseer armas de fuego, inform\u00f3 una reportera de CNN en Espa\u00f1ol presente en la audiencia.<\/p>\n<p>\u00bfDe qu\u00e9 acusan al expresidente de Honduras Juan Orlando Hern\u00e1ndez y qu\u00e9 puede pasar con \u00e9l?<\/p>\n<p>En su declaraci\u00f3n, y mientras ve\u00eda directamente a los miembros del jurado, Hern\u00e1ndez neg\u00f3 haberse reunido y aceptado sobornos de narcotraficantes.<\/p>\n<p>\u00c9l es el primer presidente de Am\u00e9rica Latina en testificar en una corte de Estados Unidos.<\/p>\n<p>Juicio a Juan Orlando Hern\u00e1ndez: gu\u00eda espiritual del expresidente de Honduras dice a CNN que \u00e9l \u201cest\u00e1 fuerte\u201d<\/p>\n<p>Noticia en desarrollo&#8230;<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013\u2013 El expresidente de Honduras Juan Orlando Hern\u00e1ndez testific\u00f3 este martes en el juicio que se le sigue por tr\u00e1fico de drogas y conspiraci\u00f3n para poseer armas de fuego, inform\u00f3 una reportera de CNN en Espa\u00f1ol presente en la audiencia. \u00bfDe qu\u00e9 acusan al expresidente de Honduras Juan Orlando Hern\u00e1ndez y qu\u00e9 puede [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446532","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU. - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU. - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013\u2013 El expresidente de Honduras Juan Orlando Hern\u00e1ndez testific\u00f3 este martes en el juicio que se le sigue por tr\u00e1fico de drogas y conspiraci\u00f3n para poseer armas de fuego, inform\u00f3 una reportera de CNN en Espa\u00f1ol presente en la audiencia. \u00bfDe qu\u00e9 acusan al expresidente de Honduras Juan Orlando Hern\u00e1ndez y qu\u00e9 puede [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-05T19:37:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU.\",\"datePublished\":\"2024-03-05T19:37:32+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\"},\"wordCount\":159,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\",\"name\":\"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU. - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-05T19:37:32+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU. - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU. - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013\u2013 El expresidente de Honduras Juan Orlando Hern\u00e1ndez testific\u00f3 este martes en el juicio que se le sigue por tr\u00e1fico de drogas y conspiraci\u00f3n para poseer armas de fuego, inform\u00f3 una reportera de CNN en Espa\u00f1ol presente en la audiencia. \u00bfDe qu\u00e9 acusan al expresidente de Honduras Juan Orlando Hern\u00e1ndez y qu\u00e9 puede [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-05T19:37:32+00:00","article_modified_time":"2024-03-07T12:45:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/"},"author":{"name":"","@id":""},"headline":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU.","datePublished":"2024-03-05T19:37:32+00:00","dateModified":"2024-03-07T12:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/"},"wordCount":159,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","url":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","name":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU. - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-05T19:37:32+00:00","dateModified":"2024-03-07T12:45:12+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU."}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Juan Orlando Hern\u00e1ndez testifica en el juicio que enfrenta por narcotr\u00e1fico en EE.UU.","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-05T19:37:32Z","datePublished":"2024-03-05T19:37:32Z","dateModified":"2024-03-07T12:45:12Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Juan Orlando Hern\\u00e1ndez testifica en el juicio que enfrenta por narcotr\\u00e1fico en EE.UU.\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/juan-orlando-hernandez-testifica-juicio-narotrafico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-05T19:37:32Z\",\"datePublished\":\"2024-03-05T19:37:32Z\",\"dateModified\":\"2024-03-07T12:45:12Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446907,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/12\/ana-garcia-esposa-juan-orlando-hernandez-presidencia-orix\/","url_meta":{"origin":1446532,"position":0},"title":"Ana Garc\u00eda, esposa de Juan Orlando Hern\u00e1ndez, anuncia que buscar\u00e1 ser precandidata a la presidencia de Honduras","author":"","date":"marzo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 La ex primera dama de Honduras Ana Garc\u00eda, esposa del expresidente Juan Orlando Hern\u00e1ndez, anunci\u00f3 este martes que buscar\u00e1 ser precandidata presidencial por el Partido Nacional de Honduras, en el cual milita.\u00bfC\u00f3mo reaccion\u00f3 Juan Orlando Hern\u00e1ndez, expresidente de Honduras, al ser declarado culpable de narcotr\u00e1fico su juicio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447114,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/19\/incanutan-131-bienes-expresidente-honduras-juan-orlando-hernandez-familia-orix\/","url_meta":{"origin":1446532,"position":1},"title":"Fiscal\u00eda incauta 131 bienes al expresidente Juan Orlando Hern\u00e1ndez y su familia cercana en Honduras","author":"","date":"marzo 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Fiscal\u00eda Especial Contra el Crimen Organizado (FESCCO) de Honduras, en conjunto con la Unidad Fiscal de Apoyo al Proceso de la depuraci\u00f3n policial (UF-ADPOL) y la Direcci\u00f3n de Lucha Contra el Narcotr\u00e1fico (DLCN), incautaron 131 bienes supuestamente de origen il\u00edcito que estaban inscritos a nombre del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444346,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/24\/retrasan-juicio-contra-el-expresidente-juan-orlando-hernandez-en-ee-uu-y-comenzara-el-12-de-febrero\/","url_meta":{"origin":1446532,"position":2},"title":"Retrasan juicio contra el expresidente Juan Orlando Hern\u00e1ndez en EE.UU. y comenzar\u00e1 el 12 de febrero","author":"","date":"enero 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El inicio del juicio en Estados Unidos contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras y acusado de conspiraci\u00f3n para traficar drogas y otros delitos, se pospuso para el pr\u00f3ximo 12 de febrero, dijo a CNN el abogado C\u00e9sar de Castro, asesor legal de Juan Carlos Bonilla Valladares,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445849,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/21\/juicio-expresidente-honduras-juan-orlando-hernandez-primera-testigo-orix\/","url_meta":{"origin":1446532,"position":3},"title":"Comenz\u00f3 el juicio contra el expresidente de Honduras Juan Orlando Hern\u00e1ndez: los abogados definieron qui\u00e9n ser\u00e1 la primera testigo","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Mientras seleccionaban este martes al jurado del juicio contra Juan Orlando Hern\u00e1ndez, expresidente de Honduras, por cargos de tr\u00e1fico de drogas y uso de armas, el tribunal, la fiscal\u00eda y la defensa del exmandatario definieron qui\u00e9n ser\u00e1 el primer testigo que llevar\u00e1n al estrado. Se trata de una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450723,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/26\/juan-orlando-hernandez-expresidente-honduras-ningun-remordimiento-inocente-condenado-45-anios-ee-uu-trax\/","url_meta":{"origin":1446532,"position":4},"title":"Juan Orlando Hern\u00e1ndez, expresidente de Honduras, dijo que no tiene ning\u00fan remordimiento y reiter\u00f3 ser inocente antes de ser condenado a 45 a\u00f1os en EE.UU.","author":"","date":"junio 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- \u201cEs mi \u00fanica oportunidad, porque lo m\u00e1s seguro es que voy a estar preso de por vida\u201d, dijo el expresidente de Honduras Juan Orlando Hern\u00e1ndez al dar un extenso mensaje este mi\u00e9rcoles, antes de que un juez estadounidense lo sentenciara a 45 a\u00f1os de c\u00e1rcel luego de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446121,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/29\/juicio-juan-orlando-hernandez-hijo-expresidente-lobo-sobornos-honduras-orix\/","url_meta":{"origin":1446532,"position":5},"title":"Juicio a Juan Orlando Hern\u00e1ndez: hijo del expresidente Lobo afirm\u00f3 que pag\u00f3 dos sobornos al exmandatario de Honduras","author":"","date":"febrero 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0En el momento m\u00e1s dram\u00e1tico en lo que va del juicio, Fabio Lobo, hijo del expresidente de Honduras Porfirio Lobo, declar\u00f3 bajo juramento este jueves que pag\u00f3 dos sobornos a Juan Orlando Hern\u00e1ndez, quien sucedi\u00f3 a su padre en el cargo y es actualmente juzgado en Nueva York\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446532","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446532"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446532\/revisions"}],"predecessor-version":[{"id":1446589,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446532\/revisions\/1446589"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446532"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446532"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446532"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}