{"id":1446539,"date":"2024-03-05T16:37:45","date_gmt":"2024-03-06T00:37:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/"},"modified":"2024-03-07T04:45:12","modified_gmt":"2024-03-07T12:45:12","slug":"exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","title":{"rendered":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l"},"content":{"rendered":"<p>(CNN) &#8212; Paul Whelan, estadounidense detenido en Rusia desde hace m\u00e1s de cinco a\u00f1os, dijo este martes a CNN que la muerte del opositor ruso Alexey Navalny en una prisi\u00f3n el mes pasado resulta &#171;extremadamente preocupante&#187; para \u00e9l.<\/p>\n<p>&#171;No puedo hablar demasiado por razones obvias, pero una cosa que s\u00ed dir\u00e9 es que si pudieron llegar a \u00e9l (Navalny), pueden llegar a m\u00ed&#187;, manifest\u00f3 Whelan, quien llam\u00f3 a CNN mientras pasaba otro cumplea\u00f1os en su remoto campo de prisioneros en Mordovia.<\/p>\n<p>&#171;Es extremadamente preocupante que alguien como Navalny muera en circunstancias sospechosas, pero tambi\u00e9n es extremadamente preocupante para m\u00ed que este sea el tipo de cosas que ocurren&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Paul Whelan cumple 5 a\u00f1os detenido en Rusia<\/p>\n<p>&#171;Si ellos est\u00e1n dispuestos a enfrentarse a las represalias del mundo por cargarse a alguien como Navalny, no se lo van a pensar dos veces antes de cargarse a alguien como yo, y luego culpar a Estados Unidos por no molestarse en llevarme de vuelta en cinco a\u00f1os&#187;, dijo. &#171;As\u00ed que cuando he dicho en el pasado que mi sentencia de muerte ha sido firmada, este es el tipo de cosas a las que me refiero&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Como CNN report\u00f3 el mes pasado, hab\u00eda conversaciones preliminares en curso entre Estados Unidos y Alemania sobre un intercambio de prisioneros por Navalny y ciudadanos estadounidenses, seg\u00fan un funcionario de Occidente, pero no hubo ninguna oferta formal antes de la muerte de Navalny.<\/p>\n<p>Whelan fue detenido en Mosc\u00fa en diciembre de 2018 y encarcelado por cargos de espionaje, los cuales \u00e9l ha negado sistem\u00e1tica y vehementemente. Fue condenado a 16 a\u00f1os de prisi\u00f3n en junio de 2020. El Departamento de Estado de Estados Unidos lo design\u00f3 como detenido injustamente.<\/p>\n<p>Whelan calific\u00f3 de &#171;extremadamente extra\u00f1o&#187; pasar su cumplea\u00f1os n\u00famero 54 en una prisi\u00f3n rusa.<\/p>\n<p>&#171;Ha sido un d\u00eda divertido con todo tipo de peque\u00f1as fiestas, bebiendo t\u00e9 y caf\u00e9, y comiendo pasteles y dulces y teniendo una cena decente y tarta, y todo tipo de cosas con amigos aqu\u00ed&#187;, dijo. &#171;Realmente te saca del hecho de estar en prisi\u00f3n y hace que la vida parezca soportable durante unos minutos aqu\u00ed y all\u00e1&#187;.<\/p>\n<p>Paul Whelan dice que sufri\u00f3 agresi\u00f3n de otro preso en Rusia<\/p>\n<p>El secretario de Estado, Antony Blinken, habl\u00f3 con Whelan a mediados de febrero, en lo que fue al menos la tercera conversaci\u00f3n entre los dos. Ambos hablaron tambi\u00e9n en agosto de 2023 y diciembre de 2022.<\/p>\n<p>&#171;Nuestros intensos esfuerzos para traer a Paul a casa contin\u00faan cada d\u00eda. Y lo har\u00e1n hasta que \u00e9l y (el periodista del Wall Street Journal) Evan Gershkovich y todos los dem\u00e1s estadounidenses detenidos injustamente est\u00e9n de vuelta con sus seres queridos&#187;, dijo Blinken en ese momento.<\/p>\n<p>Whelan dijo a CNN que fue &#171;una llamada muy, muy buena&#187;.<\/p>\n<p>&#171;Termin\u00e9 la llamada con la buena sensaci\u00f3n de que el secretario y otros miembros del Consejo de Seguridad Nacional est\u00e1n comprometidos y est\u00e1n tratando de resolver esto&#187;, dijo.<\/p>\n<p>A\u00fan as\u00ed, Whelan dijo que le gustar\u00eda hablar con el presidente Joe Biden, y declar\u00f3 a CNN que le ha &#171;pedido varias veces tener una llamada&#187;.<\/p>\n<p>Afirm\u00f3 que le gustar\u00eda &#171;recordar al presidente y al Consejo de Seguridad Nacional que sigo aqu\u00ed, como reh\u00e9n del gobierno ruso, y que la administraci\u00f3n Biden tiene que tomar medidas decisivas para garantizar mi liberaci\u00f3n. Si no hacen nada, estoy atrapado aqu\u00ed. Y si estoy atrapado aqu\u00ed, morir\u00e9 aqu\u00ed&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Paul Whelan, estadounidense detenido en Rusia desde hace m\u00e1s de cinco a\u00f1os, dijo este martes a CNN que la muerte del opositor ruso Alexey Navalny en una prisi\u00f3n el mes pasado resulta &#171;extremadamente preocupante&#187; para \u00e9l. &#171;No puedo hablar demasiado por razones obvias, pero una cosa que s\u00ed dir\u00e9 es que si pudieron [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446539","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &quot;extremadamente preocupante&quot; para \u00e9l - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &quot;extremadamente preocupante&quot; para \u00e9l - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Paul Whelan, estadounidense detenido en Rusia desde hace m\u00e1s de cinco a\u00f1os, dijo este martes a CNN que la muerte del opositor ruso Alexey Navalny en una prisi\u00f3n el mes pasado resulta &#171;extremadamente preocupante&#187; para \u00e9l. &#171;No puedo hablar demasiado por razones obvias, pero una cosa que s\u00ed dir\u00e9 es que si pudieron [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T00:37:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l\",\"datePublished\":\"2024-03-06T00:37:45+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\"},\"wordCount\":629,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\",\"url\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\",\"name\":\"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es \\\"extremadamente preocupante\\\" para \u00e9l - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-06T00:37:45+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es \"extremadamente preocupante\" para \u00e9l - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es \"extremadamente preocupante\" para \u00e9l - Noticias","og_description":"(CNN) &#8212; Paul Whelan, estadounidense detenido en Rusia desde hace m\u00e1s de cinco a\u00f1os, dijo este martes a CNN que la muerte del opositor ruso Alexey Navalny en una prisi\u00f3n el mes pasado resulta &#171;extremadamente preocupante&#187; para \u00e9l. &#171;No puedo hablar demasiado por razones obvias, pero una cosa que s\u00ed dir\u00e9 es que si pudieron [&hellip;]","og_url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-06T00:37:45+00:00","article_modified_time":"2024-03-07T12:45:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/"},"author":{"name":"","@id":""},"headline":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l","datePublished":"2024-03-06T00:37:45+00:00","dateModified":"2024-03-07T12:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/"},"wordCount":629,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","url":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","name":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es \"extremadamente preocupante\" para \u00e9l - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-06T00:37:45+00:00","dateModified":"2024-03-07T12:45:12+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/colorado-springs\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\u00f3n es &#171;extremadamente preocupante&#187; para \u00e9l","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-06T00:37:45Z","datePublished":"2024-03-06T00:37:45Z","dateModified":"2024-03-07T12:45:12Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Exclusiva: Paul Whelan dice a CNN que la muerte de Navalny en prisi\\u00f3n es &#171;extremadamente preocupante&#187; para \\u00e9l\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/exclusiva-cnn-paul-whelan-muerte-navalny-prision-extremadamente-preocupante-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-06T00:37:45Z\",\"datePublished\":\"2024-03-06T00:37:45Z\",\"dateModified\":\"2024-03-07T12:45:12Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1451542,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/01\/quien-es-paul-whelan-detenido-rusia-orix\/","url_meta":{"origin":1446539,"position":0},"title":"Qui\u00e9n es Paul Whelan, el ex infante de Marina detenido por cinco a\u00f1os en Rusia y liberado en un intercambio de prisioneros","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Tras cinco a\u00f1os encarcelado en Rusia, el ex infante de Marina Paul Whelan fue liberado este jueves en un intercambio de prisioneros a gran escala que incluy\u00f3 tambi\u00e9n al periodista del Wall Street Journal Evan Gershkovich, seg\u00fan confirm\u00f3 Turqu\u00eda.El acuerdo entre Estados Unidos y Rusia puso fin\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451553,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/01\/quien-liberado-intercambio-prisioneros-rusia-occidente-trax\/","url_meta":{"origin":1446539,"position":1},"title":"\u00bfQui\u00e9n fue liberado en el importante intercambio de prisioneros entre Rusia y Occidente?","author":"","date":"agosto 1, 2024","format":false,"excerpt":"(CNN) --\u00a0El periodista estadounidense Evan Gershkovich y el ex infante de Marina Paul Whelan figuran entre los 24 detenidos liberados en el marco de un complejo intercambio de prisioneros entre Rusia, Estados Unidos y otros pa\u00edses occidentales.Tambi\u00e9n fueron liberados numerosos disidentes rusos, mientras que Mosc\u00fa obtuvo a cambio un ex\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465034,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/08\/01\/paul-whelan-un-ano-liberacion-prision-rusia-trax\/","url_meta":{"origin":1446539,"position":2},"title":"Paul Whelan, un a\u00f1o despu\u00e9s de su liberaci\u00f3n de una prisi\u00f3n en Rusia: &#171;La casa ya no est\u00e1. Los autos ya no est\u00e1n&#187;","author":"","date":"agosto 1, 2025","format":false,"excerpt":"Para Paul Whelan, regresar a la vida en Estados Unidos despu\u00e9s de m\u00e1s de medio decenio de encarcelamiento en Rusia ha sido \u201cinteresante\u201d, y no ha estado exento de desaf\u00edos.\u201cLiteralmente tuve que empezar de nuevo\u201d, dijo a CNN antes del primer aniversario del amplio acuerdo de intercambio de prisioneros entre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445552,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/17\/analisis-putin-vio-una-amenaza-existencial-en-navalny-el-lider-de-la-oposicion-cuyo-nombre-no-se-atrevio-a-decir\/","url_meta":{"origin":1446539,"position":3},"title":"AN\u00c1LISIS | Putin vio una amenaza existencial en Navalny, el l\u00edder de la oposici\u00f3n cuyo nombre no se atrevi\u00f3 a decir","author":"","date":"febrero 17, 2024","format":false,"excerpt":"(CNN) -- Alexey Navalny represent\u00f3 en su momento un futuro alternativo para Rusia: un lugar optimista y con visi\u00f3n de futuro, libre del gobierno unipersonal del presidente Vladimir Putin.Con la muerte del l\u00edder de la oposici\u00f3n en una prisi\u00f3n en el norte del C\u00edrculo Polar \u00c1rtico, el sombr\u00edo panorama pol\u00edtico\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445574,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/17\/la-portavoz-de-navalny-exige-la-devolucion-de-su-cuerpo-mientras-acusa-a-los-funcionarios-rusos-de-mentir\/","url_meta":{"origin":1446539,"position":4},"title":"La portavoz de Navalny exige la devoluci\u00f3n de su cuerpo mientras acusa a los funcionarios rusos de &#171;mentir&#187;","author":"","date":"febrero 17, 2024","format":false,"excerpt":"(CNN) --\u00a0El cuerpo del opositor ruso encarcelado Alexey Navalny debe ser entregado a su familia \"inmediatamente\", dijo este s\u00e1bado su portavoz Kira Yarmysh, acusando a los funcionarios rusos de mentir para retrasar el proceso.El feroz cr\u00edtico del presidente de Rusia Vladimir Putin, de 47 a\u00f1os, muri\u00f3 el viernes despu\u00e9s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471231,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/14\/alexei-navalny-toxina-venenosa-trax\/","url_meta":{"origin":1446539,"position":5},"title":"El opositor ruso Alexey Navalny muri\u00f3 por una toxina encontrada en ranas venenosas, seg\u00fan nuevo informe","author":"","date":"febrero 14, 2026","format":false,"excerpt":"El opositor ruso y cr\u00edtico declarado del Kremlin, Alexey Navalny, fallecido hace dos a\u00f1os, muri\u00f3 mientras se encontraba en prisi\u00f3n por una toxina letal hallada en ranas venenosas de Sudam\u00e9rica, seg\u00fan informaron cinco pa\u00edses europeos en un comunicado publicado este s\u00e1bado.Los an\u00e1lisis de las muestras tomadas del cuerpo de Navalny\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446539"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446539\/revisions"}],"predecessor-version":[{"id":1446582,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446539\/revisions\/1446582"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}