{"id":1446542,"date":"2024-03-05T17:52:31","date_gmt":"2024-03-06T01:52:31","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/"},"modified":"2024-03-07T04:45:12","modified_gmt":"2024-03-07T12:45:12","slug":"maduro-corte-internacional-justicia-gaza-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","title":{"rendered":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza"},"content":{"rendered":"<p>(CNN) &#8212; El presidente de Venezuela, Nicol\u00e1s Maduro, se refiri\u00f3 este lunes a la guerra entre Israel y Hamas y se\u00f1al\u00f3 que la Corte Internacional de Justicia no hace \u201cnada\u201d para frenar la violencia en Gaza.<\/p>\n<p>Durante una intervenci\u00f3n en el programa \u201cCon Maduro+\u201d, el presidente critic\u00f3 tanto a la Corte Internacional de Justicia (CIJ) como a la Corte Penal Internacional (CPI), al asegurar que ambos organismos son omisos frente a la situaci\u00f3n en Gaza y que eso los hace \u201cc\u00f3mplices indirectos de un genocidio\u201d.<\/p>\n<p>Acerca de la Corte Internacional de Justicia en particular, Maduro dijo que este organismo podr\u00eda ordenar un alto a la guerra pero no lo hace.<\/p>\n<p>\u201cUna decisi\u00f3n de la Corte Internacional de Justicia pudiera parar inmediatamente el genocidio de Israel. \u00bfY qu\u00e9 hacen? Nada, porque la Corte Internacional de Justicia est\u00e1 en las manos del imperio global de Occidente, de Estados Unidos y de Europa, esa es la verdad\u201d, se\u00f1al\u00f3.<\/p>\n<p>A finales de enero pasado, tras analizar una petici\u00f3n de Sud\u00e1frica, la Corte Internacional de Justicia orden\u00f3 a Israel \u201ctomar todas las medidas\u201d posibles para \u201cprevenir\u201d un genocidio en Gaza. La corte, sin embargo, no orden\u00f3 un cese del fuego.<\/p>\n<p>Los ataques del 7 de octubre de Hamas contra Israel causaron la muerte de 1.200 personas, seg\u00fan autoridades israel\u00edes. Israel respondi\u00f3 entonces con una ofensiva que hasta ahora ha dejado un saldo de m\u00e1s de 30.000 muertos en Gaza, seg\u00fan cifras del Ministerio de Salud local, controlado por Hamas.<\/p>\n<p>La Corte Internacional de Justicia es un organismo de las Naciones Unidas, en sus decisiones juzga a pa\u00edses y su trabajo es independiente del que realiza la Corte Penal Internacional, que no depende de la ONU aunque tiene su respaldo y analiza casos de posibles cr\u00edmenes de lesa humanidad.<\/p>\n<p>La CIJ tiene pendiente de resoluci\u00f3n un caso por el diferendo entre Venezuela y Guyana por el Esequibo, un territorio actualmente bajo control de Guyana pero reclamado por Venezuela.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El presidente de Venezuela, Nicol\u00e1s Maduro, se refiri\u00f3 este lunes a la guerra entre Israel y Hamas y se\u00f1al\u00f3 que la Corte Internacional de Justicia no hace \u201cnada\u201d para frenar la violencia en Gaza. Durante una intervenci\u00f3n en el programa \u201cCon Maduro+\u201d, el presidente critic\u00f3 tanto a la Corte Internacional de Justicia (CIJ) [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446542","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El presidente de Venezuela, Nicol\u00e1s Maduro, se refiri\u00f3 este lunes a la guerra entre Israel y Hamas y se\u00f1al\u00f3 que la Corte Internacional de Justicia no hace \u201cnada\u201d para frenar la violencia en Gaza. Durante una intervenci\u00f3n en el programa \u201cCon Maduro+\u201d, el presidente critic\u00f3 tanto a la Corte Internacional de Justicia (CIJ) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T01:52:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza\",\"datePublished\":\"2024-03-06T01:52:31+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\"},\"wordCount\":369,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\",\"url\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\",\"name\":\"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-06T01:52:31+00:00\",\"dateModified\":\"2024-03-07T12:45:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza - Noticias","og_description":"(CNN) &#8212; El presidente de Venezuela, Nicol\u00e1s Maduro, se refiri\u00f3 este lunes a la guerra entre Israel y Hamas y se\u00f1al\u00f3 que la Corte Internacional de Justicia no hace \u201cnada\u201d para frenar la violencia en Gaza. Durante una intervenci\u00f3n en el programa \u201cCon Maduro+\u201d, el presidente critic\u00f3 tanto a la Corte Internacional de Justicia (CIJ) [&hellip;]","og_url":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-06T01:52:31+00:00","article_modified_time":"2024-03-07T12:45:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/"},"author":{"name":"","@id":""},"headline":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza","datePublished":"2024-03-06T01:52:31+00:00","dateModified":"2024-03-07T12:45:12+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/"},"wordCount":369,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","url":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","name":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-06T01:52:31+00:00","dateModified":"2024-03-07T12:45:12+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/washington-dc\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Maduro dice que la Corte Internacional de Justicia no hace \u201cnada\u201d ante la situaci\u00f3n en Gaza","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/maduro-corte-internacional-justicia-gaza-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-06T01:52:31Z","datePublished":"2024-03-06T01:52:31Z","dateModified":"2024-03-07T12:45:12Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Maduro dice que la Corte Internacional de Justicia no hace \\u201cnada\\u201d ante la situaci\\u00f3n en Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/maduro-corte-internacional-justicia-gaza-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/maduro-corte-internacional-justicia-gaza-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-06T01:52:31Z\",\"datePublished\":\"2024-03-06T01:52:31Z\",\"dateModified\":\"2024-03-07T12:45:12Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446459,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/nicaragua-alemania-corte-internacional-justicia-ayuda-israel-trax\/","url_meta":{"origin":1446542,"position":0},"title":"Nicaragua presenta caso contra Alemania ante la Corte Internacional de Justicia por brindar ayuda a Israel y facilitar &#171;la comisi\u00f3n de genocidio&#187;","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Nicaragua present\u00f3 un caso contra Alemania ante la Corte Internacional de Justicia (CIJ) por proporcionar ayuda militar a Israel y retirar el financiamiento de la agencia de la ONU para los refugiados palestinos (UNRWA, por sus siglas en ingl\u00e9s), inform\u00f3 el tribunal en un comunicado este viernes.En su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450603,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/21\/cuba-une-caso-israel-sudafrica-cij-guerra-gaza-trax\/","url_meta":{"origin":1446542,"position":1},"title":"Cuba se unir\u00e1 al caso contra Israel que present\u00f3 Sud\u00e1frica ante la Corte Internacional de Justicia por la guerra en Gaza","author":"","date":"junio 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Cuba anunci\u00f3 este viernes que se sumar\u00e1 al caso de Sud\u00e1frica ante la Corte Internacional de Justicia (CIJ) contra Israel por la guerra en Gaza.La naci\u00f3n insular caribe\u00f1a invoc\u00f3 el art\u00edculo 63 del Estatuto de la Corte, que otorga a pa\u00edses distintos de los interesados \u200b\u200ben el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444092,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/19\/mexico-y-chile-piden-a-la-corte-penal-internacional-que-investigue-posibles-crimenes-en-territorios-palestinos\/","url_meta":{"origin":1446542,"position":2},"title":"M\u00e9xico y Chile piden a la Corte Penal Internacional que investigue posibles cr\u00edmenes en territorios palestinos","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN) -- M\u00e9xico y Chile pidieron a la Corte Penal Internacional (CPI) que investigue si se han cometido cr\u00edmenes en los territorios palestinos, ya sea por \"agentes de la potencia ocupante o de la potencia ocupada\", inform\u00f3 el jueves la canciller\u00eda mexicana en un comunicado.\"La acci\u00f3n de M\u00e9xico y Chile\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457330,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/07\/irlanda-genocidio-israel-corte-internacional-justicia-trax\/","url_meta":{"origin":1446542,"position":3},"title":"Irlanda se une al caso de genocidio contra Israel en la Corte Internacional de Justicia","author":"","date":"enero 7, 2025","format":false,"excerpt":"Irlanda se sum\u00f3 al caso de genocidio presentado por Sud\u00e1frica contra Israel, anunci\u00f3 el martes por la ma\u00f1ana la Corte Internacional de Justicia.En un breve comunicado de prensa, la CIJ dijo que Irlanda se hab\u00eda unido el lunes a Nicaragua, Colombia, M\u00e9xico, Libia, Bolivia, Turqu\u00eda, Maldivas, Chile, Espa\u00f1a y el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466174,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/09\/05\/ee-uu-sanciona-defensores-derechos-palestinos-trax\/","url_meta":{"origin":1446542,"position":4},"title":"EE.UU. sanciona a grupos defensores de los derechos palestinos que pidieron investigar los cr\u00edmenes de guerra de Israel","author":"","date":"septiembre 5, 2025","format":false,"excerpt":"El Departamento de Estado de Estados Unidos ha impuesto sanciones a tres grupos defensores de los derechos humanos de los palestinos que pidieron a la Corte Penal Internacional (CPI) que investigue y arreste a l\u00edderes israel\u00edes por acusaciones de cr\u00edmenes de guerra en Gaza.A finales del a\u00f1o pasado, la CPI\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467632,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/10\/22\/corte-onu-israel-ayuda-gaza-genocidio-trax\/","url_meta":{"origin":1446542,"position":5},"title":"El m\u00e1ximo tribunal de la ONU reprende a Israel por las restricciones de ayuda en Gaza durante su guerra","author":"","date":"octubre 22, 2025","format":false,"excerpt":"El m\u00e1ximo tribunal de las Naciones Unidas emiti\u00f3 el mi\u00e9rcoles una opini\u00f3n legal en la que afirma que Israel, como potencia ocupante, est\u00e1 obligada a trabajar con agencias de la ONU para facilitar la ayuda humanitaria en Gaza, una reprimenda al bloqueo impuesto por Israel al enclave palestino a principios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446542"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446542\/revisions"}],"predecessor-version":[{"id":1446579,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446542\/revisions\/1446579"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}