{"id":1446545,"date":"2024-03-05T22:02:31","date_gmt":"2024-03-06T06:02:31","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/"},"modified":"2024-03-07T04:45:11","modified_gmt":"2024-03-07T12:45:11","slug":"diferenciara-eclipse-solar-total-sol-2024-2017-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","title":{"rendered":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017"},"content":{"rendered":"<p>(CNN) &#8212; Cuando un eclipse solar total cree un espect\u00e1culo en los cielos de M\u00e9xico y Am\u00e9rica del Norte el 8 de abril, marcar\u00e1 la primera vez que un evento de este tipo ocurra en esta parte del mundo en casi siete a\u00f1os, y la \u00faltima vez que ocurrir\u00e1 hasta 2044.<\/p>\n<p>Los eclipses solares totales ocurren cuando la luna pasa entre la Tierra y el sol, bloqueando completamente la cara del sol. Pero estos eventos celestiales no son todos exactamente iguales.<\/p>\n<p>Si bien el eclipse de abril tiene una trayectoria similar al que ocurri\u00f3 el 21 de agosto de 2017, aunque se mueve en la direcci\u00f3n opuesta y cubre m\u00e1s terreno, hay bastantes diferencias entre los dos que hacen que la ocurrencia de 2024 sea algo que se debe anticipar, seg\u00fan NASA. Un factor clave que distingue al evento de este a\u00f1o es qui\u00e9n podr\u00e1 verlo.<\/p>\n<p>La NASA estima que 215 millones de adultos en todo Estados Unidos vieron el eclipse de 2017 directa o virtualmente.<\/p>\n<p>\u201cEl eclipse solar total de este a\u00f1o ser\u00e1 al menos parcialmente visible para todos en Estados Unidos contiguos, lo que lo convierte en el eclipse m\u00e1s accesible que esta naci\u00f3n haya experimentado en esta generaci\u00f3n\u201d, dijo Nicola Fox, administradora asociada de la Direcci\u00f3n de Misiones Cient\u00edficas de la NASA, en una declaraci\u00f3n.<\/p>\n<p>\u00bfCu\u00e1ndo y d\u00f3nde se ver\u00e1 el pr\u00f3ximo eclipse solar total? Todo lo que debes saber<\/p>\n<p>Un eclipse m\u00e1s largo y visible<\/p>\n<p>M\u00e1s personas podr\u00e1n ver el eclipse de 2024 porque la trayectoria de totalidad, o los lugares donde las personas presenciar\u00e1n la sombra de la luna cubriendo completamente el sol, ser\u00e1 m\u00e1s amplia. La distancia de la Luna a la Tierra var\u00eda a medida que orbita nuestro planeta, y durante el eclipse solar total de 2017, la Luna estaba m\u00e1s alejada de la Tierra y caus\u00f3 que el \u00e1rea de totalidad fuera m\u00e1s estrecha, extendi\u00e9ndose de aproximadamente de 100 a 114 kil\u00f3metros de ancho.<\/p>\n<p>Pero la Luna estar\u00e1 m\u00e1s cerca de nuestro planeta durante el evento de este a\u00f1o, por lo que se espera que la trayectoria que seguir\u00e1 su sombra sobre Am\u00e9rica del Norte se extienda entre 174 a 196 kil\u00f3metros de ancho.<\/p>\n<p>La trayectoria del eclipse de 2024 tambi\u00e9n pasa por \u00e1reas m\u00e1s densamente pobladas y ciudades importantes que antes. Solo 12 millones de personas vivieron dentro del \u00e1rea de totalidad del eclipse de 2017, mientras que casi 32 millones est\u00e1n en la trayectoria de 2024 y 150 millones de personas viven dentro de 322 kil\u00f3metros.<\/p>\n<p>\u00bfC\u00f3mo proteger tus ojos durante el eclipse de sol anular?<\/p>\n<p>Esta imagen compuesta muestra la progresi\u00f3n de un eclipse solar parcial sobre el lago Ross en el Parque Nacional Northern Cascades en Washington el 21 de agosto de 2017. (Cr\u00e9dito: Bill Ingalls\/NAS<\/p>\n<p>Personas fuera del camino de la totalidad todav\u00eda podremos ver un eclipse solar parcial, donde la luna s\u00f3lo bloquea parte de la cara del sol. Un sorprendente 99% de quienes viven en EE.UU., incluidas partes de Haw\u00e1i y Alaska, podr\u00e1n vislumbrar al menos un eclipse solar parcial sin tener que viajar.<\/p>\n<p>El eclipse de abril tambi\u00e9n tendr\u00e1 un per\u00edodo de totalidad m\u00e1s largo que el de 2017 debido a la proximidad de la Luna a la Tierra. La totalidad es una de las fases m\u00e1s cortas de un eclipse y su duraci\u00f3n depende del lugar de observaci\u00f3n. Los observadores m\u00e1s cercanos al centro del camino experimentar\u00e1n la totalidad m\u00e1s larga, y la longitud de esa ventana disminuye m\u00e1s cerca del borde del camino.<\/p>\n<p>En 2017, los observadores del cielo que vislumbraron la totalidad m\u00e1s larga la experimentaron durante dos minutos y 42 segundos cerca de Carbondale, Illinois.<\/p>\n<p>Este a\u00f1o, un \u00e1rea a unos 25 minutos al noroeste de Torre\u00f3n, M\u00e9xico, ofrecer\u00e1 la totalidad m\u00e1s larga con cuatro minutos y 28 segundos, pero las personas en todo Texas e incluso en lugares tan al norte como Economy, Indiana, ver\u00e1n una totalidad que dura m\u00e1s de cuatro minutos. Y cuando el eclipse cruce hacia Canad\u00e1, los espectadores a\u00fan pueden esperar verlo en su totalidad durante 3 minutos y 21 segundos.<\/p>\n<p>El per\u00edodo de totalidad m\u00e1s largo en la historia reciente fue de siete minutos y 8 segundos y ocurri\u00f3 al oeste de Filipinas el 20 de junio de 1955, seg\u00fan el Libro Guinness de los R\u00e9cords Mundiales.<\/p>\n<p>\u00bfQuieres saber qu\u00e9 ver\u00e1s durante el eclipse? Utiliza nuestro mapa interactivo para determinar d\u00f3nde se encontrar\u00e1 en el camino. Y no olvides llevar un par de anteojos para observar el eclipse de manera segura.<\/p>\n<p>\u00bfPor qu\u00e9 son \u00fanicos los eclipses solares y c\u00f3mo protegerse los ojos durante ellos?<\/p>\n<p>El gran experimento solar<\/p>\n<p>Si bien el eclipse es un placer para los observadores del cielo, el evento tambi\u00e9n ofrece a los cient\u00edficos la oportunidad de estudiar el sol de maneras \u00fanicas. Y el eclipse de abril permitir\u00e1 a los cient\u00edficos vislumbrar especialmente el sol durante uno de sus per\u00edodos m\u00e1s activos, llamado m\u00e1ximo solar.<\/p>\n<p>El sol experimenta un ciclo regular de 11 a\u00f1os de actividad creciente y menguante vinculado al momento en que el campo magn\u00e9tico de la estrella cambia. El eclipse de 2017 ocurri\u00f3 cuando el Sol se acercaba al m\u00ednimo solar, cuando la estrella experimenta menos actividad.<\/p>\n<p>Los expertos han predicho que el m\u00e1ximo solar, el pico de actividad del campo magn\u00e9tico solar, ocurrir\u00e1 a finales de este a\u00f1o. Los cient\u00edficos anticipan que caracter\u00edsticas interesantes parecidas a bucles, serpentinas y rizos brillantes ser\u00e1n visibles en la c\u00e1lida atm\u00f3sfera exterior del sol, conocida como corona, cuando la luna bloquee la vista de la superficie de la estrella durante el pr\u00f3ximo eclipse. La corona, que es m\u00e1s tenue que la superficie del Sol, es m\u00e1s f\u00e1cil de ver durante un eclipse, lo que permite a los cient\u00edficos estudiarla con mayor detalle.<\/p>\n<p>Tambi\u00e9n es posible que durante el eclipse sea visible una erupci\u00f3n de material desde la superficie del Sol, llamada eyecci\u00f3n de masa coronal.<\/p>\n<p>Varios experimentos volar\u00e1n a bordo del avi\u00f3n de investigaci\u00f3n de gran altitud WB-57 de la NASA durante el eclipse para estudiar la corona con la esperanza de capturar nuevos detalles sobre su estructura en diferentes longitudes de onda de luz.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Cuando un eclipse solar total cree un espect\u00e1culo en los cielos de M\u00e9xico y Am\u00e9rica del Norte el 8 de abril, marcar\u00e1 la primera vez que un evento de este tipo ocurra en esta parte del mundo en casi siete a\u00f1os, y la \u00faltima vez que ocurrir\u00e1 hasta 2044. Los eclipses solares totales [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446545","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Cuando un eclipse solar total cree un espect\u00e1culo en los cielos de M\u00e9xico y Am\u00e9rica del Norte el 8 de abril, marcar\u00e1 la primera vez que un evento de este tipo ocurra en esta parte del mundo en casi siete a\u00f1os, y la \u00faltima vez que ocurrir\u00e1 hasta 2044. Los eclipses solares totales [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T06:02:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:11+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017\",\"datePublished\":\"2024-03-06T06:02:31+00:00\",\"dateModified\":\"2024-03-07T12:45:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\"},\"wordCount\":1107,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\",\"url\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\",\"name\":\"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-06T06:02:31+00:00\",\"dateModified\":\"2024-03-07T12:45:11+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","og_locale":"es_ES","og_type":"article","og_title":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017 - Noticias","og_description":"(CNN) &#8212; Cuando un eclipse solar total cree un espect\u00e1culo en los cielos de M\u00e9xico y Am\u00e9rica del Norte el 8 de abril, marcar\u00e1 la primera vez que un evento de este tipo ocurra en esta parte del mundo en casi siete a\u00f1os, y la \u00faltima vez que ocurrir\u00e1 hasta 2044. Los eclipses solares totales [&hellip;]","og_url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-06T06:02:31+00:00","article_modified_time":"2024-03-07T12:45:11+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/"},"author":{"name":"","@id":""},"headline":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017","datePublished":"2024-03-06T06:02:31+00:00","dateModified":"2024-03-07T12:45:11+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/"},"wordCount":1107,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","url":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","name":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-06T06:02:31+00:00","dateModified":"2024-03-07T12:45:11+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/el-valle\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"En qu\u00e9 se diferenciar\u00e1 el eclipse solar total de 2024 del de 2017","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-06T06:02:31Z","datePublished":"2024-03-06T06:02:31Z","dateModified":"2024-03-07T12:45:11Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"En qu\\u00e9 se diferenciar\\u00e1 el eclipse solar total de 2024 del de 2017\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/05\\\/diferenciara-eclipse-solar-total-sol-2024-2017-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-06T06:02:31Z\",\"datePublished\":\"2024-03-06T06:02:31Z\",\"dateModified\":\"2024-03-07T12:45:11Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1447709,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/03\/que-es-eclipse-solar-luna-llena-orix\/","url_meta":{"origin":1446545,"position":0},"title":"\u00bfQu\u00e9 es un eclipse solar y qu\u00e9 pasa durante el mismo? \u00bfEs cierto que ocurren con luna llena?","author":"","date":"abril 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Para fortuna de todos los amantes de la astronom\u00eda, el continente americano est\u00e1 a punto de vivir su segundo eclipse solar en menos de seis meses.El eclipse solar de 2024 tendr\u00e1 lugar el lunes 8 de abril y ser\u00e1 total en Norteam\u00e9rica (solo en algunas partes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447599,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/01\/cuando-eclipse-solar-abril-2024-hora-como-ver-en-vivo-orix\/","url_meta":{"origin":1446545,"position":1},"title":"Eclipse solar total de abril de 2024: a qu\u00e9 hora es, cu\u00e1ndo y desde d\u00f3nde ver","author":"","date":"abril 1, 2024","format":false,"excerpt":"(CNN) -- Si te perdiste el eclipse anular que cre\u00f3 un \"anillo de fuego\" sobre Am\u00e9rica en octubre de 2023\u00a0no te preocupes: otro eclipse est\u00e1 en camino, y ofrecer\u00e1 un espect\u00e1culo diferente.Ahora puedes seguirnos en WhatsApp ChannelEl 8 de abril, los observadores del cielo de Norteam\u00e9rica disfrutar\u00e1n de un eclipse\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446157,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/01\/proximo-eclipse-solar-total-abril-2024-trax\/","url_meta":{"origin":1446545,"position":2},"title":"\u00bfCu\u00e1ndo y d\u00f3nde se ver\u00e1 el pr\u00f3ximo eclipse solar total? Todo lo que debes saber","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN) -- Si te perdiste el eclipse anular que cre\u00f3 un \"anillo de fuego\" sobre Am\u00e9rica en octubre de 2023\u00a0no te preocupes: otro eclipse est\u00e1 en camino, y ofrecer\u00e1 un espect\u00e1culo diferente.En 2024, los observadores del cielo de Norteam\u00e9rica disfrutar\u00e1n de un eclipse solar total que pasar\u00e1 por M\u00e9xico, Estados\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446427,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/proximo-eclipse-solar-total-abril-2024-trax-2\/","url_meta":{"origin":1446545,"position":3},"title":"\u00bfCu\u00e1ndo y d\u00f3nde se ver\u00e1 el pr\u00f3ximo eclipse solar total? Todo lo que debes saber","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN) -- Si te perdiste el eclipse anular que cre\u00f3 un \"anillo de fuego\" sobre Am\u00e9rica en octubre de 2023\u00a0no te preocupes: otro eclipse est\u00e1 en camino, y ofrecer\u00e1 un espect\u00e1culo diferente.Ahora puedes seguirnos en WhatsApp ChannelEn 2024, los observadores del cielo de Norteam\u00e9rica disfrutar\u00e1n de un eclipse solar total\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1454917,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/03\/eclipse-solar-anillo-fuego-ver-proximo-evento-solar-trax\/","url_meta":{"origin":1446545,"position":4},"title":"\u00bfTe perdiste el eclipse solar en forma de &#171;anillo de fuego&#187;? Aqu\u00ed te contamos d\u00f3nde y cu\u00e1ndo podr\u00e1s ver el pr\u00f3ximo evento solar","author":"","date":"octubre 3, 2024","format":false,"excerpt":"(CNN) -- Si las fotos del deslumbrante \"anillo de fuego\" que danz\u00f3 por los cielos de Sudam\u00e9rica\u200b\u200b el mi\u00e9rcoles provocaron la fiebre del eclipse, los observadores del cielo no tendr\u00e1n que esperar demasiado para ver m\u00e1s espect\u00e1culos celestiales el a\u00f1o que viene.Si bien no habr\u00e1 otro evento de \"anillo de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447860,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/08\/fotos-eclipse-solar-total-2024-mexico-eeuu-orix\/","url_meta":{"origin":1446545,"position":5},"title":"FOTOS | As\u00ed se vivi\u00f3 el eclipse solar total de 2024","author":"","date":"abril 8, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El eclipse solar total de este lunes ofreci\u00f3 un espect\u00e1culo sorprendente para millones de personas en M\u00e9xico, Estados Unidos y Canad\u00e1. Alrededor de las 2:00 p.m., hora de Miami, la Luna bloque\u00f3 el Sol total o parcialmente durante unos minutos en algunas zonas de Norteam\u00e9rica.As\u00ed evolucion\u00f3 el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446545","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446545"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446545\/revisions"}],"predecessor-version":[{"id":1446576,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446545\/revisions\/1446576"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446545"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446545"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446545"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}