{"id":1446559,"date":"2024-03-06T12:37:40","date_gmt":"2024-03-06T20:37:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/"},"modified":"2024-03-07T04:45:10","modified_gmt":"2024-03-07T12:45:10","slug":"exembajado-peru-oea-presidente-consejo-ministros-peru-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","title":{"rendered":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Gustavo Adrianz\u00e9n es el nuevo presidente del Consejo de Ministros tras la renuncia de Alberto Ot\u00e1rola. Adrianz\u00e9n jur\u00f3 su cargo este mi\u00e9rcoles ante la presidenta Dina Boluarte. Hasta ahora era el embajador de Per\u00fa en la Organizaci\u00f3n de los Estados Americanos (OEA). Tambi\u00e9n fue ministro de Justicia y Derechos Humanos durante el Gobierno de Ollanta Humala y es experto en administraci\u00f3n p\u00fablica.<\/p>\n<p>La renuncia de Ot\u00e1rola como presidente del Consejo de Ministros de Per\u00fa lleg\u00f3 el martes, dos d\u00edas despu\u00e9s de que un programa de televisi\u00f3n peruano publicara un audio en el que presuntamente se le escucha solicitarle su curriculum vitae a una mujer con la que habr\u00eda tenido una relaci\u00f3n sentimental y que, posteriormente, fue contratada en el Ministerio de Defensa.<\/p>\n<p>Renuncia el presidente del Consejo de Ministros de Per\u00fa, Alberto Ot\u00e1rola, tras esc\u00e1ndalo por presunta contrataci\u00f3n irregular de una mujer<\/p>\n<p>La acusaci\u00f3n fue difundida el domingo por el programa de televisi\u00f3n Panorama, transmitido por Panamericana TV.<\/p>\n<p>Tras la difusi\u00f3n del audio, Ot\u00e1rola afirm\u00f3 a trav\u00e9s de X, antes Twitter, que no hab\u00eda cometido \u201cning\u00fan acto ilegal\u201d y atribuy\u00f3 el caso a una \u201cinfamia\u201d y a \u201coscuros intereses\u201d. La mujer presuntamente beneficiada, Yazir\u00e9 Pinedo, confirm\u00f3 en una entrevista con el medio local Canal N que la voz del audio era suya y afirm\u00f3 que hab\u00eda tenido una relaci\u00f3n sentimental con Ot\u00e1rola, pero neg\u00f3 haber obtenido contratos con el Estado por ello.<\/p>\n<p>La noche del lunes, la Fiscal\u00eda de Per\u00fa inform\u00f3 en X que abri\u00f3 una investigaci\u00f3n contra Ot\u00e1rola y otros dos funcionarios del Consejo de Ministros por la presunta contrataci\u00f3n irregular de Pinedo.<\/p>\n<p>CNN est\u00e1 buscando la respuesta del ahora expremier al anuncio de la Fiscal\u00eda.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; Gustavo Adrianz\u00e9n es el nuevo presidente del Consejo de Ministros tras la renuncia de Alberto Ot\u00e1rola. Adrianz\u00e9n jur\u00f3 su cargo este mi\u00e9rcoles ante la presidenta Dina Boluarte. Hasta ahora era el embajador de Per\u00fa en la Organizaci\u00f3n de los Estados Americanos (OEA). Tambi\u00e9n fue ministro de Justicia y Derechos Humanos durante el [&hellip;]<\/p>\n","protected":false},"author":186172566,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446559","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; Gustavo Adrianz\u00e9n es el nuevo presidente del Consejo de Ministros tras la renuncia de Alberto Ot\u00e1rola. Adrianz\u00e9n jur\u00f3 su cargo este mi\u00e9rcoles ante la presidenta Dina Boluarte. Hasta ahora era el embajador de Per\u00fa en la Organizaci\u00f3n de los Estados Americanos (OEA). Tambi\u00e9n fue ministro de Justicia y Derechos Humanos durante el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-06T20:37:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-07T12:45:10+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa\",\"datePublished\":\"2024-03-06T20:37:40+00:00\",\"dateModified\":\"2024-03-07T12:45:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\"},\"wordCount\":344,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\",\"url\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\",\"name\":\"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-06T20:37:40+00:00\",\"dateModified\":\"2024-03-07T12:45:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"\",\"url\":\"https:\/\/noticiasya.com\/costa-central\/author\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; Gustavo Adrianz\u00e9n es el nuevo presidente del Consejo de Ministros tras la renuncia de Alberto Ot\u00e1rola. Adrianz\u00e9n jur\u00f3 su cargo este mi\u00e9rcoles ante la presidenta Dina Boluarte. Hasta ahora era el embajador de Per\u00fa en la Organizaci\u00f3n de los Estados Americanos (OEA). Tambi\u00e9n fue ministro de Justicia y Derechos Humanos durante el [&hellip;]","og_url":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","og_site_name":"Noticias","article_published_time":"2024-03-06T20:37:40+00:00","article_modified_time":"2024-03-07T12:45:10+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"","Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/"},"author":{"name":"","@id":""},"headline":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa","datePublished":"2024-03-06T20:37:40+00:00","dateModified":"2024-03-07T12:45:10+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/"},"wordCount":344,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","url":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","name":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-06T20:37:40+00:00","dateModified":"2024-03-07T12:45:10+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/hartford\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"","url":"https:\/\/noticiasya.com\/costa-central\/author"}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Exembajador de Per\u00fa en la OEA es el presidente del Consejo de Ministros de Per\u00fa","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/06\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-06T20:37:40Z","datePublished":"2024-03-06T20:37:40Z","dateModified":"2024-03-07T12:45:10Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Exembajador de Per\\u00fa en la OEA es el presidente del Consejo de Ministros de Per\\u00fa\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/06\\\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/06\\\/exembajado-peru-oea-presidente-consejo-ministros-peru-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-06T20:37:40Z\",\"datePublished\":\"2024-03-06T20:37:40Z\",\"dateModified\":\"2024-03-07T12:45:10Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446543,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/presidente-consejo-ministros-peru-renuncia-orix\/","url_meta":{"origin":1446559,"position":0},"title":"Renuncia el presidente del Consejo de Ministros de Per\u00fa, Alberto Ot\u00e1rola, tras esc\u00e1ndalo por presunta contrataci\u00f3n irregular de una mujer","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- Alberto Ot\u00e1rola renunci\u00f3 este martes como presidente del Consejo de Ministros de Per\u00fa, seg\u00fan anunci\u00f3 el ahora exfuncionario en un mensaje en su cuenta de X, antes Twitter. Su dimisi\u00f3n ocurre dos d\u00edas despu\u00e9s de que un programa de televisi\u00f3n peruano publicara un audio en el que presuntamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462318,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/13\/presidente-del-consejo-de-ministros-de-peru-renuncia-orix\/","url_meta":{"origin":1446559,"position":1},"title":"Presidente del Consejo de Ministros de Per\u00fa renuncia un d\u00eda antes del paro nacional convocado contra la inseguridad p\u00fablica","author":"","date":"mayo 13, 2025","format":false,"excerpt":"El presidente del Consejo de Ministros de Per\u00fa, Gustavo Adrianz\u00e9n, renunci\u00f3 este martes a su cargo en el Gobierno de Dina Boluarte, un d\u00eda antes de las protestas previstas en el pa\u00eds debido a los problemas de inseguridad p\u00fablica.Adrianz\u00e9n anunci\u00f3 su dimisi\u00f3n en un breve mensaje a los medios, acompa\u00f1ado\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452457,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/05\/presidente-consejo-ministros-peru-edmundo-gonzalez-venezuela-orix\/","url_meta":{"origin":1446559,"position":2},"title":"Presidente del Consejo de Ministros de Per\u00fa afirma que Edmundo Gonz\u00e1lez no es el presidente electo de Venezuela","author":"","date":"septiembre 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El presidente del Consejo de Ministros de Per\u00fa, Gustavo Adrianz\u00e9n, neg\u00f3 este jueves que su pa\u00eds haya reconocido a Edmundo Gonz\u00e1lez Urrutia como presidente electo de Venezuela y desautoriz\u00f3 lo que hab\u00eda dicho el entonces canciller Javier Gonz\u00e1lez-Olaechea tras las elecciones.En declaraciones al medio local RPP, Adrianz\u00e9n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446538,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/martin-vizcarra-niega-complot-otarola-orix\/","url_meta":{"origin":1446559,"position":3},"title":"Expresidente Mart\u00edn Vizcarra niega acusaciones de \u201ccomplot\u201d contra premier Ot\u00e1rola para sacarlo del cargo","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN) -- El expresidente de Per\u00fa, Mart\u00edn Vizcarra, neg\u00f3 \u201crotundamente\u201d que \u00e9l o su partido pol\u00edtico, Per\u00fa Primero, hayan organizado un complot contra el presidente del Consejo de Ministros, Alberto Ot\u00e1rola. \u201cNo conozco y menos he hablado con Nicanor Boluarte ni nadie de este gobierno\u201d, dijo en X, antes Twitter.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450460,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/17\/presidente-consejo-ministros-peru-irresponsable-ministerio-publico-llamado-movilizacion-social-orix\/","url_meta":{"origin":1446559,"position":4},"title":"Presidente del Consejo de Ministros de Per\u00fa dice que es \u201cirresponsable\u201d que el Ministerio P\u00fablico promueva un \u201cllamado a la movilizaci\u00f3n social\u201d","author":"","date":"junio 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente del Consejo de Ministros de Per\u00fa, Gustavo Adrianz\u00e9n, calific\u00f3 de \u201cirresponsable\u201d que el Ministerio P\u00fablico est\u00e9 \u201cpromoviendo un llamado a la movilizaci\u00f3n social\u201d en respuesta los proyectos de ley que impulsa el Congreso de Per\u00fa, dijo este lunes el funcionario en conferencia con la prensa\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446535,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/05\/peru-investiga-alberto-otarola-favorecer-vinculo-sentimental-orix\/","url_meta":{"origin":1446559,"position":5},"title":"Fiscal\u00eda peruana investiga al presidente del Consejo de Ministros por presuntamente favorecer a una persona con la que habr\u00eda tenido v\u00ednculo sentimental","author":"","date":"marzo 5, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 El Ministerio P\u00fablico peruano inform\u00f3 este lunes en X, antes Twitter, que \"inici\u00f3 diligencias preliminares\" contra el primer ministro Alberto Ot\u00e1rola, como \"presunto instigador del delito contra la administraci\u00f3n p\u00fablica y como presunto autor del delito contra la administraci\u00f3n p\u00fablica-patrocinio ilegal\", ambos en agravio del Estado. La\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446559","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/users\/186172566"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446559"}],"version-history":[{"count":1,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446559\/revisions"}],"predecessor-version":[{"id":1446562,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446559\/revisions\/1446562"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446559"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446559"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446559"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}