{"id":1446745,"date":"2024-03-09T07:47:04","date_gmt":"2024-03-09T15:47:04","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/"},"modified":"2024-03-09T07:47:04","modified_gmt":"2024-03-09T15:47:04","slug":"estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","title":{"rendered":"Exclusiva: Estados Unidos se prepar\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022"},"content":{"rendered":"<p>(CNN) &#8212; A finales de 2022, Estados Unidos comenz\u00f3 a &#171;prepararse rigurosamente&#187; para un potencial ataque con armas nucleares de Rusia en Ucrania, en lo que habr\u00eda sido el primer ataque nuclear en guerra desde que Estados Unidos lanz\u00f3 bombas at\u00f3micas sobre Hiroshima y Nagasaki casi ochenta a\u00f1os antes, dijeron dos altos funcionarios de la administraci\u00f3n a CNN.<\/p>\n<p>A la administraci\u00f3n Biden le preocupaba espec\u00edficamente que Rusia pudiera utilizar un arma nuclear t\u00e1ctica o de campo de batalla, dijeron los funcionarios.<\/p>\n<p>Primero inform\u00e9 que los funcionarios estadounidenses estaban preocupados de que Rusia usara un arma nuclear t\u00e1ctica en 2022, pero en mi nuevo libro, &#171;El regreso de las grandes potencias&#187;, publicado el 12 de marzo, revelo detalles exclusivos sobre el nivel sin precedentes de planificaci\u00f3n de contingencia llevado a adelante en la medida en la que entre altos funcionarios de la administraci\u00f3n Biden crec\u00eda la alarma por la situaci\u00f3n.<\/p>\n<p>&#171;Ese fue el escenario que nos present\u00f3 el conflicto, as\u00ed lo cre\u00edmos y creo que ten\u00edamos derecho a prepararnos rigurosamente y hacer todo lo posible para evitar que eso suceda&#187;, me dijo el primer alto funcionario con el que habl\u00e9.<\/p>\n<p>Lo que llev\u00f3 a la administraci\u00f3n Biden a llegar a una evaluaci\u00f3n tan sorprendente no fue un indicador, sino un conjunto de acontecimientos, an\u00e1lisis y, fundamentalmente, nueva inteligencia altamente sensible.<\/p>\n<p>Putin advierte a Occidente que el env\u00edo de tropas a Ucrania podr\u00eda conducir a una guerra nuclear<\/p>\n<p>El temor de la administraci\u00f3n, me dijo un segundo alto funcionario, &#171;no era s\u00f3lo hipot\u00e9tico, sino que tambi\u00e9n se basaba en cierta informaci\u00f3n que recogimos&#187;.<\/p>\n<p>&#171;Tuvimos que planificar para estar en la mejor posici\u00f3n posible en caso de que este acontecimiento ya impensable realmente ocurriera&#187;, me dijo la misma fuente.<\/p>\n<p>Durante este per\u00edodo desde finales del verano hasta el oto\u00f1o de 2022, el Consejo de Seguridad Nacional convoc\u00f3 una serie de reuniones para implementar planes de contingencia &#171;para evaluar c\u00f3mo responder\u00edamos en caso de una indicaci\u00f3n muy clara de que estaban a punto de hacer algo, atacar con un arma nuclear, o en caso de que simplemente lo hicieran. Evaluamos c\u00f3mo intentar\u00edamos prevenirlo o disuadirlo&#187;, me dijo el primer alto funcionario de la administraci\u00f3n.<\/p>\n<p>&#171;Es probable que muchos de nosotros no estabamos listos para llegar a nuestros puestos de trabajo y dedicar cantidades significativas de tiempo a prepararnos para un escenario que hace unos a\u00f1os se cre\u00eda que pertenec\u00eda a una \u00e9poca pasada&#187;, me dijo el mismo funcionario.<\/p>\n<p>Los rusos rodeados<\/p>\n<p>El final del verano de 2022 estaba resultando devastador para las fuerzas rusas en Ucrania. Las fuerzas ucranianas avanzaban hacia Jers\u00f3n, ocupada por Rusia, en el sur. La ciudad hab\u00eda sido el premio mayor de Rusia desde la invasi\u00f3n. Ahora corr\u00eda el peligro de perderse ante la contraofensiva ucraniana. Fundamentalmente, a medida que avanzaban las fuerzas ucranianas, unidades rusas enteras corr\u00edan peligro de ser rodeadas. La opini\u00f3n dentro de la administraci\u00f3n era que una p\u00e9rdida tan catastr\u00f3fica podr\u00eda ser un &#171;potencial desencadenante&#187; para el uso de armas nucleares.<\/p>\n<p>El Presidente Vladimir Putin en julio de 2022, en el desfile del D\u00eda de la Marina en San Petersburgo. (Stringer\/Getty Images\/Archivo)<\/p>\n<p>&#171;Si un n\u00famero significativo de fuerzas rusas era derrotado, si sus vidas quedaban destrozadas, eso ser\u00eda una especie de precursor de una amenaza potencial directa al territorio ruso o al Estado ruso&#187;, dijo el primer alto funcionario de la administraci\u00f3n.<\/p>\n<p>&#171;En Jers\u00f3n en ese momento hab\u00eda cada vez m\u00e1s se\u00f1ales de que las l\u00edneas rusas podr\u00edan colapsar. Decenas de miles de tropas rusas eran potencialmente vulnerables&#187;, a\u00f1adi\u00f3.<\/p>\n<p>Rusia estaba perdiendo terreno dentro del territorio soberano de Ucrania, no dentro de Rusia. Pero a los funcionarios estadounidenses les preocupaba que el presidente Vladimir Putin lo viera de otra manera. Le hab\u00eda dicho al pueblo ruso que Jers\u00f3n ahora era parte de la propia Rusia y, por lo tanto, podr\u00eda percibir una p\u00e9rdida devastadora all\u00ed como una amenaza directa para \u00e9l y el Estado ruso.<\/p>\n<p>&#171;Nuestra evaluaci\u00f3n hab\u00eda sido durante alg\u00fan tiempo que uno de los escenarios en los que contemplar\u00edan el uso de armas nucleares [inclu\u00eda] cosas como amenazas existenciales al Estado ruso, amenazas directas al territorio ruso&#187;, dijo el primer alto funcionario de la administraci\u00f3n.<\/p>\n<p>En tal evaluaci\u00f3n, Rusia podr\u00eda considerar un ataque nuclear t\u00e1ctico como un elemento disuasorio contra mayores p\u00e9rdidas de territorio controlado por Rusia en Ucrania, as\u00ed como cualquier posible ataque contra la propia Rusia.<\/p>\n<p>Bandera falsa<\/p>\n<p>Al mismo tiempo, la maquinaria propagand\u00edstica de Rusia estaba haciendo circular una nueva historia de bandera falsa sobre una bomba sucia ucraniana, que los funcionarios estadounidenses tem\u00edan que pudiera servir de cobertura para un ataque nuclear ruso.<\/p>\n<p>En octubre de 2022, el ministro de Defensa de Rusia, Sergei Shoigu, hizo una serie de llamadas telef\u00f3nicas a funcionarios de defensa de Estados Unidos, Reino Unido, Francia y Turqu\u00eda, dici\u00e9ndoles que el Kremlin estaba &#171;preocupado por posibles provocaciones por parte de Kiev que implicaran el uso de una bomba sucia&#187;.<\/p>\n<p>Estados Unidos y otros funcionarios occidentales rechazaron las advertencias rusas. A\u00fan as\u00ed, el embajador de Rusia ante la ONU entreg\u00f3 una carta directamente a las Naciones Unidas detallando la misma supuesta amenaza. Los funcionarios rusos alegaron que Ucrania construir\u00eda y detonar\u00eda una bomba sucia contra las fuerzas rusas y luego culpar\u00eda del ataque a Rusia.<\/p>\n<p>Los funcionarios estadounidenses desestimaron las advertencias rusas pero temieron la motivaci\u00f3n detr\u00e1s de ellas. &#171;Los mensajes p\u00fablicos rusos salieron del campo de izquierdas sobre la posibilidad de que Ucrania use una bomba sucia, lo que consideramos que no se basaba en algo real&#187;, me dijo el primer alto funcionario de la administraci\u00f3n. &#171;M\u00e1s preocupante&#187; para este funcionario era que los rusos dir\u00edan estas cosas &#171;ya sea como pretexto para hacer alguna locura o como tapadera para algo que ellos mismos estaban pensando hacer. Eso era bastante alarmante&#187;.<\/p>\n<p>Pero hubo una pieza m\u00e1s que elev\u00f3 esas preocupaciones a un nuevo nivel. Las agencias de inteligencia occidentales hab\u00edan recibido informaci\u00f3n de que ahora hab\u00eda comunicaciones entre funcionarios rusos que discut\u00edan expl\u00edcitamente un ataque nuclear.<\/p>\n<p>Como me lo describi\u00f3 el primer alto funcionario de la administraci\u00f3n, hab\u00eda &#171;indicios que est\u00e1bamos detectando por otros medios de que esto era al menos algo que los niveles inferiores del sistema ruso estaban discutiendo&#187;.<\/p>\n<p>El acceso de Estados Unidos a las comunicaciones internas rusas ya hab\u00eda demostrado su capacidad en el pasado. En el per\u00edodo previo a la invasi\u00f3n de Ucrania, Estados Unidos hab\u00eda interceptado a comandantes militares rusos que discut\u00edan los preparativos para la invasi\u00f3n, comunicaciones que formaban parte de la evaluaci\u00f3n de la inteligencia estadounidense, que luego result\u00f3 precisa, de que una invasi\u00f3n era inminente.<\/p>\n<p>&#171;Nunca es una evaluaci\u00f3n tajante, blanco o negro&#187;, me dijo el primer alto funcionario de la administraci\u00f3n. &#171;Pero el nivel de riesgo parec\u00eda estar aumentando, incluso por encima de cualquier otro momento&#187;.<\/p>\n<p>\u00bfEstados Unidos lo sabr\u00eda?<\/p>\n<p>En ning\u00fan momento Estados Unidos detect\u00f3 informaci\u00f3n de inteligencia que indicara que Rusia estuviera tomando medidas para movilizar sus fuerzas nucleares para llevar a cabo tal ataque.<\/p>\n<p>&#171;Obviamente le dimos una alta prioridad al seguimiento y al menos ten\u00edamos cierta capacidad para rastrear tales movimientos de sus fuerzas nucleares&#187;, me dijo este alto funcionario de la administraci\u00f3n. &#171;Y en ning\u00fan momento vimos indicios de los tipos de medidas que hubi\u00e9ramos esperado que tomaran si estuvieran siguiendo el camino hacia el uso de armas nucleares&#187;.<\/p>\n<p>Una ojiva falsa imitando una parte nuclear de un misil de crucero estrat\u00e9gico Kh-55SM, que fue utilizado por las tropas rusas durante los ataques con misiles contra Ucrania, se ve durante una rueda de prensa en Kyiv, Ucrania, en diciembre de 2022. (NurPhoto\/Getty Images)<\/p>\n<p>Sin embargo, los funcionarios estadounidenses no estaban seguros de saber si Rusia estaba posicionando armas nucleares t\u00e1cticas. A diferencia de las armas nucleares estrat\u00e9gicas, capaces de destruir ciudades enteras, las armas nucleares t\u00e1cticas o de campo de batalla son lo suficientemente peque\u00f1as como para moverse silenciosamente y podr\u00edan dispararse desde sistemas convencionales ya desplegados en el campo de batalla ucraniano.<\/p>\n<p>&#171;Si lo que iban a hacer era usar un arma nuclear t\u00e1ctica, particularmente un arma nuclear t\u00e1ctica de muy bajo rendimiento y particularmente si solo iban a usar una o una cantidad muy peque\u00f1a, no seguro que si o si lo hubi\u00e9ramos sabido&#187;, continu\u00f3 este alto funcionario de la administraci\u00f3n.<\/p>\n<p>Varias fuentes dentro del Gobierno de Bien participaron en una campa\u00f1a de divulgaci\u00f3n urgente. El secretario de Estado, Antony Blinken, comunic\u00f3 las preocupaciones de Estados Unidos &#171;muy directamente&#187; al ministro de Asuntos Exteriores ruso, Sergey Lavrov, seg\u00fan altos funcionarios. El presidente del Estado Mayor Conjunto, el general Mark Milley, llam\u00f3 a su hom\u00f3logo ruso, el general Valery Gerasimov, jefe del Estado Mayor de las Fuerzas Armadas rusas. Seg\u00fan un alto funcionario estadounidense, el presidente Joe Biden envi\u00f3 al director de la CIA, Bill Burns, a hablar con Sergey Naryshkin, jefe del servicio de inteligencia exterior de Rusia, en Turqu\u00eda, para comunicarle las preocupaciones de Estados Unidos sobre un ataque nuclear y evaluar las intenciones rusas.<\/p>\n<p>Estados Unidos tambi\u00e9n trabaj\u00f3 estrechamente con sus aliados para desarrollar planes de contingencia ante un ataque nuclear ruso y para comunicar advertencias a la parte rusa sobre las consecuencias de tal ataque.<\/p>\n<p>&#171;Llevamos a cabo una serie de conversaciones silenciosas con aliados centrales para analizar nuestras ideas!, me dijo el primer alto funcionario de la administraci\u00f3n. &#171;Ese es un sello distintivo de todo nuestro enfoque: que somos mejores y m\u00e1s fuertes al hacer estas cosas cuando estamos totalmente alineados con nuestros aliados&#187;.<\/p>\n<p>India y China<\/p>\n<p>Adem\u00e1s, Estados Unidos intent\u00f3 conseguir la ayuda de pa\u00edses que no eran aliados, en particular China e India, para disuadir a Rusia de semejante ataque.<\/p>\n<p>&#171;Una de las cosas que hicimos fue no s\u00f3lo enviarles mensajes directamente, sino instar, presionar y animar fuertemente a otros pa\u00edses, a quienes podr\u00edan prestar m\u00e1s atenci\u00f3n, a que hiciesen lo mismo&#187;, me dijo el segundo alto funcionario de la administraci\u00f3n.<\/p>\n<p>Los funcionarios estadounidenses dicen que la divulgaci\u00f3n y las declaraciones p\u00fablicas del l\u00edder chino Xi Jinping y del primer ministro indio Narendra Modi ayudaron a evitar una crisis.<\/p>\n<p>&#171;Creo que mostrar a la comunidad internacional la preocupaci\u00f3n al respecto, particularmente la preocupaci\u00f3n de los pa\u00edses clave para Rusia y para el Sur Global, tambi\u00e9n fue un factor \u00fatil y persuasivo y les mostr\u00f3 cu\u00e1l podr\u00eda ser el costo de todo esto&#187;, dijo el primer alto funcionario.<\/p>\n<p>&#171;Creo que el hecho de que sepamos que China intervino, India intervino y otros intervinieron, puede haber tenido alg\u00fan efecto en su forma de pensar&#187;, me dijo el segundo alto funcionario de la administraci\u00f3n. &#171;No puedo demostrarlo con certezas, pero creo que esa es nuestra evaluaci\u00f3n&#187;.<\/p>\n<p>Desde el susto nuclear de finales de 2022, he preguntado a funcionarios estadounidenses y europeos si identificaron amenazas similares. El peligro disminuy\u00f3 cuando la guerra entr\u00f3 en un per\u00edodo de relativo estancamiento en el este. Sin embargo, Estados Unidos y sus aliados se mantienen alerta.<\/p>\n<p>&#171;Hemos estado menos preocupados por la perspectiva inminente desde ese per\u00edodo, pero no es algo que est\u00e9 totalmente fuera del radar&#187;, me dijo un alto funcionario estadounidense. &#171;Seguimos perfeccionando los planes y&#8230; no est\u00e1 m\u00e1s all\u00e1 de la posibilidad de que podamos enfrentar al menos el riesgo creciente de esto nuevamente en los pr\u00f3ximos meses&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; A finales de 2022, Estados Unidos comenz\u00f3 a &#171;prepararse rigurosamente&#187; para un potencial ataque con armas nucleares de Rusia en Ucrania, en lo que habr\u00eda sido el primer ataque nuclear en guerra desde que Estados Unidos lanz\u00f3 bombas at\u00f3micas sobre Hiroshima y Nagasaki casi ochenta a\u00f1os antes, dijeron dos altos funcionarios de la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1446745","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Exclusiva: Estados Unidos se prepar\u00f3 &quot;rigurosamente&quot; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Exclusiva: Estados Unidos se prepar\u00f3 &quot;rigurosamente&quot; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; A finales de 2022, Estados Unidos comenz\u00f3 a &#171;prepararse rigurosamente&#187; para un potencial ataque con armas nucleares de Rusia en Ucrania, en lo que habr\u00eda sido el primer ataque nuclear en guerra desde que Estados Unidos lanz\u00f3 bombas at\u00f3micas sobre Hiroshima y Nagasaki casi ochenta a\u00f1os antes, dijeron dos altos funcionarios de la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-09T15:47:04+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Exclusiva: Estados Unidos se prepar\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022\",\"datePublished\":\"2024-03-09T15:47:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\"},\"wordCount\":2037,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\",\"name\":\"Exclusiva: Estados Unidos se prepar\u00f3 \\\"rigurosamente\\\" para un posible ataque nuclear de Rusia en Ucrania a finales de 2022 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-03-09T15:47:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Exclusiva: Estados Unidos se prepar\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Exclusiva: Estados Unidos se prepar\u00f3 \"rigurosamente\" para un posible ataque nuclear de Rusia en Ucrania a finales de 2022 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Exclusiva: Estados Unidos se prepar\u00f3 \"rigurosamente\" para un posible ataque nuclear de Rusia en Ucrania a finales de 2022 - Noticias","og_description":"(CNN) &#8212; A finales de 2022, Estados Unidos comenz\u00f3 a &#171;prepararse rigurosamente&#187; para un potencial ataque con armas nucleares de Rusia en Ucrania, en lo que habr\u00eda sido el primer ataque nuclear en guerra desde que Estados Unidos lanz\u00f3 bombas at\u00f3micas sobre Hiroshima y Nagasaki casi ochenta a\u00f1os antes, dijeron dos altos funcionarios de la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","og_site_name":"Noticias","article_published_time":"2024-03-09T15:47:04+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"10 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/"},"author":{"name":"","@id":""},"headline":"Exclusiva: Estados Unidos se prepar\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022","datePublished":"2024-03-09T15:47:04+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/"},"wordCount":2037,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","url":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","name":"Exclusiva: Estados Unidos se prepar\u00f3 \"rigurosamente\" para un posible ataque nuclear de Rusia en Ucrania a finales de 2022 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-03-09T15:47:04+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Exclusiva: Estados Unidos se prepar\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Exclusiva: Estados Unidos se prepar\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022","url":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/03\/09\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-03-09T15:47:04Z","datePublished":"2024-03-09T15:47:04Z","dateModified":"2024-03-09T15:47:04Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Exclusiva: Estados Unidos se prepar\\u00f3 &#171;rigurosamente&#187; para un posible ataque nuclear de Rusia en Ucrania a finales de 2022\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/09\\\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/03\\\/09\\\/estados-unidos-ataque-nuclear-ruso-ucrania-2022-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-03-09T15:47:04Z\",\"datePublished\":\"2024-03-09T15:47:04Z\",\"dateModified\":\"2024-03-09T15:47:04Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack-related-posts":[{"id":1446913,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/13\/putin-rusia-uso-armas-nucleares-no-hay-necesidad-trax\/","url_meta":{"origin":1446745,"position":0},"title":"Putin dice que est\u00e1 listo para usar armas nucleares si el Estado ruso est\u00e1 en juego, pero &#171;nunca ha habido tal necesidad&#187;","author":"","date":"marzo 13, 2024","format":false,"excerpt":"(CNN) -- Mosc\u00fa est\u00e1 lista para usar armas nucleares si existiera una amenaza para la existencia del Estado ruso, pero \"nunca ha habido tal necesidad\", dijo el presidente Vladimir Putin en una entrevista con los medios estatales publicada este mi\u00e9rcoles.El l\u00edder ruso hizo estos comentarios a los medios estatales Rossiya\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469941,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/09\/que-es-el-misil-balistico-oreshnik-lanzado-rusia-ucrania-trax\/","url_meta":{"origin":1446745,"position":1},"title":"\u00bfQu\u00e9 es el misil bal\u00edstico Oreshnik lanzado por Rusia contra Ucrania?","author":"","date":"enero 9, 2026","format":false,"excerpt":"Rusia lanz\u00f3 un misil Oreshnik contra Ucrania en la noche del jueves al viernes, por segunda vez desde que comenz\u00f3 la guerra a gran escala en 2022, en un ataque que, seg\u00fan Kyiv y sus aliados, pretende ser una advertencia para Occidente.Aunque los funcionarios de defensa rusos no dijeron d\u00f3nde\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448500,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/25\/rusia-veta-resolucion-onu-respaldada-estados-unidos-para-prohibir-las-armas-nucleares-en-el-espacio-trax\/","url_meta":{"origin":1446745,"position":2},"title":"Rusia veta resoluci\u00f3n de la ONU respaldada por Estados Unidos para prohibir las armas nucleares en el espacio","author":"","date":"abril 25, 2024","format":false,"excerpt":"(CNN) -- Rusia vet\u00f3 este mi\u00e9rcoles una resoluci\u00f3n de las Naciones Unidas que propon\u00eda prohibir el uso de armas nucleares en el espacio exterior en medio de preocupaciones respaldadas por la inteligencia estadounidense de que Mosc\u00fa est\u00e9 tratando de desarrollar un dispositivo nuclear capaz de destruir sat\u00e9lites.El embajador ruso, Vassily\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448937,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/06\/armas-nucleares-tacticas-rusia-trax\/","url_meta":{"origin":1446745,"position":3},"title":"\u00bfQu\u00e9 son las armas nucleares t\u00e1cticas y qu\u00e9 pasar\u00eda si Rusia desplegara una?","author":"","date":"mayo 6, 2024","format":false,"excerpt":"(CNN) --\u00a0Rusia anunci\u00f3 este lunes que llevar\u00e1 a cabo \"en un futuro pr\u00f3ximo\" ejercicios con armas nucleares no estrat\u00e9gicas (tambi\u00e9n llamadas \"t\u00e1cticas\"), luego de que el Kremlin condenara lo que calific\u00f3 de escalada de tensi\u00f3n \"sin precedentes\" por parte de Occidente.El Estado Mayor ruso inici\u00f3 los preparativos para realizar los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455920,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/19\/ucrania-rusia-misiles-ee-uu-atacms-trax\/","url_meta":{"origin":1446745,"position":4},"title":"Ucrania dispara misiles fabricados en EE.UU. contra objetivos en Rusia, seg\u00fan medios estatales rusos","author":"","date":"noviembre 19, 2024","format":false,"excerpt":"(CNN) -- Ucrania dispar\u00f3\u00a0misiles ATACMS de fabricaci\u00f3n estadounidense contra la regi\u00f3n rusa de Bryansk, inform\u00f3 el Ministerio de Defensa de Rusia, en una escalada importante en el mil\u00e9simo d\u00eda de guerra.El ataque se produce solo dos d\u00edas despu\u00e9s de que la administraci\u00f3n Biden diera luz verde a Kyiv para utilizar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451927,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/16\/ee-uu-ucrania-avanza-rusia-armas-trax\/","url_meta":{"origin":1446745,"position":5},"title":"EE.UU. observa de cerca c\u00f3mo las fuerzas ucranianas avanzan hacia Rusia con armas estadounidenses","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN) -- Estados Unidos ha observado de cerca c\u00f3mo las fuerzas de Ucrania se adentraban m\u00e1s en territorio ruso, impulsadas en parte por armas y equipos proporcionados por Estados Unidos, lo que ha suscitado dudas sobre si Kyiv ha respetado las restricciones de la administraci\u00f3n Biden sobre el uso de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1446745"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1446745\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1446745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1446745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1446745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}