{"id":1449698,"date":"2024-05-22T22:03:45","date_gmt":"2024-05-23T05:03:45","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/"},"modified":"2024-05-22T22:03:45","modified_gmt":"2024-05-23T05:03:45","slug":"6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","title":{"rendered":"Al menos 6 muertos y 50  heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n"},"content":{"rendered":"<p>(CNN En Espa\u00f1ol) &#8212; Al menos seis personas murieron y decenas resultaron heridas este mi\u00e9rcoles durante un mitin de campa\u00f1a del candidato presidencial Jorge \u00c1lvarez M\u00e1ynez en el municipio de San Pedro Garza Garc\u00eda, Nuevo Le\u00f3n, de acuerdo con fuentes oficiales.<\/p>\n<p>En un audio compartido con CNN, el candidato \u00c1lvarez M\u00e1ynez asegur\u00f3 que se reportan 6 personas fallecidas. El candidato mencion\u00f3 como posible la causa &#171;las condiciones meteorol\u00f3gicas at\u00edpicas&#187;, y asegur\u00f3 tambi\u00e9n que convers\u00f3 con Protecci\u00f3n Civil Local, quienes se encuentran investigando a fondo las causas del posible accidente.<\/p>\n<p>La tarima que utilizaban colaps\u00f3 debido a fuertes vientos que se registraron en el estado, seg\u00fan el gobernador de Nuevo Le\u00f3n, Samuel Garc\u00eda.<\/p>\n<p>Lamento el accidente en San Pedro Garza Garc\u00eda, causado por un fuerte viento durante el acto al que asistieron Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia por Movimiento Ciudadano y otros militantes, dirigentes y candidatos de ese partido. Seg\u00fan me informa Samuel Garc\u00eda,\u2026<br \/>\n\u2014 Andr\u00e9s Manuel (@lopezobrador_) May 23, 2024<\/p>\n<p>M\u00e1ynez, candidato presidencial por Movimiento Ciudadano que se encontraba en el lugar fue trasladado brevemente al hospital despu\u00e9s del suceso. Inform\u00f3 a trav\u00e9s de su cuenta en X que integrantes de su equipo hab\u00edan resultado heridos y ya hab\u00edan sido trasladados al hospital donde estaban siendo atendidos. A\u00f1adi\u00f3 que se estaba movilizando al lugar donde ocurri\u00f3 el accidente para acompa\u00f1ar a las v\u00edctimas.<\/p>\n<p>&#171;Estoy bien y en comunicaci\u00f3n con las autoridades estatales para dar seguimiento a lo sucedido&#187;, dijo en X.<\/p>\n<p>El candidato dijo que suspende todas sus actividades de campa\u00f1a tras el mortal derrumbe del escenario este mi\u00e9rcoles. Agreg\u00f3 que permanecer\u00e1 en el estado para dar seguimiento a la situaci\u00f3n, as\u00ed como a las v\u00edctimas del derrumbe generado por una fuerte r\u00e1faga de viento.<\/p>\n<p>El gobernador de Nuevo Le\u00f3n, Samuel Garc\u00eda, inst\u00f3 a los habitantes de la zona a permanecer en interiores, advirtiendo de m\u00e1s vientos fuertes, tormentas el\u00e9ctricas y lluvias.<\/p>\n<p>Le he informado a mi equipo que mi vista a Tlaxcala e Hidalgo el d\u00eda de ma\u00f1ana queda suspendida, as\u00ed como todas las actividades de campa\u00f1a.<br \/>\nTambi\u00e9n he suspendido mi vuelo de regreso. Estar\u00e9 en Nuevo Le\u00f3n al pendiente de la situaci\u00f3n y de las victimas. <a href=\"https:\/\/t.co\/05TnvoeThU\" rel=\"nofollow\">https:\/\/t.co\/05TnvoeThU<\/a><br \/>\n\u2014 Jorge \u00c1lvarez M\u00e1ynez (@AlvarezMaynez) May 23, 2024<\/p>\n<p>Los integrantes de mi equipo que resultaron lesionados ya est\u00e1n siendo atendidos en el hospital.<br \/>\nMe dirijo nuevamente al lugar de los hechos para acompa\u00f1ar a las victimas. <a href=\"https:\/\/t.co\/nb9tHxADLp\" rel=\"nofollow\">https:\/\/t.co\/nb9tHxADLp<\/a><br \/>\n\u2014 Jorge \u00c1lvarez M\u00e1ynez (@AlvarezMaynez) May 23, 2024<\/p>\n<p>Los fuertes vientos azotaron el estado de Nuevo Le\u00f3n durante el acto de campa\u00f1a. El Servicio Meteorol\u00f3gico Nacional hab\u00eda emitido un pron\u00f3stico general del tiempo advirtiendo de la posibilidad de fuertes vientos en toda la regi\u00f3n, advirtiendo de rachas de 50-70 km\/h a partir de este mi\u00e9rcoles por la tarde. El pron\u00f3stico prev\u00e9 vientos racheados, as\u00ed como la posibilidad de tormentas fuertes que generen lluvias torrenciales, rayos, granizo e incluso la posibilidad de tornados, hasta principios del jueves.<\/p>\n<p>&#8212; Con informaci\u00f3n de Fidel Guti\u00e9rrez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN En Espa\u00f1ol) &#8212; Al menos seis personas murieron y decenas resultaron heridas este mi\u00e9rcoles durante un mitin de campa\u00f1a del candidato presidencial Jorge \u00c1lvarez M\u00e1ynez en el municipio de San Pedro Garza Garc\u00eda, Nuevo Le\u00f3n, de acuerdo con fuentes oficiales. En un audio compartido con CNN, el candidato \u00c1lvarez M\u00e1ynez asegur\u00f3 que se reportan [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449698","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN En Espa\u00f1ol) &#8212; Al menos seis personas murieron y decenas resultaron heridas este mi\u00e9rcoles durante un mitin de campa\u00f1a del candidato presidencial Jorge \u00c1lvarez M\u00e1ynez en el municipio de San Pedro Garza Garc\u00eda, Nuevo Le\u00f3n, de acuerdo con fuentes oficiales. En un audio compartido con CNN, el candidato \u00c1lvarez M\u00e1ynez asegur\u00f3 que se reportan [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T05:03:45+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n\",\"datePublished\":\"2024-05-23T05:03:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\"},\"wordCount\":581,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\",\"name\":\"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-23T05:03:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n - Noticias","og_description":"(CNN En Espa\u00f1ol) &#8212; Al menos seis personas murieron y decenas resultaron heridas este mi\u00e9rcoles durante un mitin de campa\u00f1a del candidato presidencial Jorge \u00c1lvarez M\u00e1ynez en el municipio de San Pedro Garza Garc\u00eda, Nuevo Le\u00f3n, de acuerdo con fuentes oficiales. En un audio compartido con CNN, el candidato \u00c1lvarez M\u00e1ynez asegur\u00f3 que se reportan [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-23T05:03:45+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/"},"author":{"name":"","@id":""},"headline":"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n","datePublished":"2024-05-23T05:03:45+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/"},"wordCount":581,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","name":"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-23T05:03:45+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Al menos 6 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Al menos 6 muertos y 50  heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/22\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-23T05:03:45Z","datePublished":"2024-05-23T05:03:45Z","dateModified":"2024-05-23T05:03:45Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Al menos 6 muertos y 50  heridos tras accidente en evento de campa\\u00f1a de \\u00c1lvarez M\\u00e1ynez en Nuevo Le\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/22\\\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/22\\\/6-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-23T05:03:45Z\",\"datePublished\":\"2024-05-23T05:03:45Z\",\"dateModified\":\"2024-05-23T05:03:45Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449699,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/22\/9-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","url_meta":{"origin":1449698,"position":0},"title":"Al menos 9 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN En Espa\u00f1ol) -- Al menos nueve personas murieron y decenas resultaron heridas este mi\u00e9rcoles durante un mitin de campa\u00f1a del candidato presidencial Jorge \u00c1lvarez M\u00e1ynez en el municipio de San Pedro Garza Garc\u00eda, Nuevo Le\u00f3n, de acuerdo con fuentes oficiales.A trav\u00e9s de su cuenta de X, el gobernador de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449730,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/24\/sube-numero-hospitalizados-accidente-mitin-nuevo-leon-jorge-alvarez-maynez-orix\/","url_meta":{"origin":1449698,"position":1},"title":"Sube a 36 el n\u00famero de personas hospitalizadas por accidente en mitin de Nuevo Le\u00f3n","author":"","date":"mayo 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El n\u00famero de personas hospitalizadas por el accidente en el mitin de campa\u00f1a del partido Movimiento Ciudadano en San Pedro, en el norte\u00f1o estado de Nuevo Le\u00f3n \u2015que dej\u00f3 nueve personas muertas\u2015, subi\u00f3 la tarde de este jueves de 27 a 36, inform\u00f3 el gobierno del estado mexicano.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448281,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/19\/alvarez-maynez-apuesta-jovenes-propuestas-convencion-bancaria-mexico-orix\/","url_meta":{"origin":1449698,"position":2},"title":"\u00c1lvarez M\u00e1ynez apuesta por los j\u00f3venes en sus propuestas ante la Convenci\u00f3n Bancaria de M\u00e9xico","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El candidato a la presidencia de M\u00e9xico por Movimiento Ciudadano, Jorge \u00c1lvarez M\u00e1ynez, se present\u00f3 en la Convenci\u00f3n Bancaria este viernes y sus principales propuestas incluyeron potenciar el \u201cnearshoring\u201d en M\u00e9xico \u2013como lo \"est\u00e1 capitalizando Nuevo Le\u00f3n\"\u2013 y vincular la educaci\u00f3n con el sector productivo.Con \"nearshoring\", el candidato\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445920,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/22\/quien-es-jorge-alvarez-maynez-candidato-mexico-orix\/","url_meta":{"origin":1449698,"position":3},"title":"\u00bfQui\u00e9n es Jorge \u00c1lvarez M\u00e1ynez, el joven candidato que va por la presidencia de M\u00e9xico?","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Jorge \u00c1lvarez M\u00e1ynez es un joven diputado federal del partido Movimiento Ciudadano. A sus 38 a\u00f1os competir\u00e1 por la presidencia de M\u00e9xico contra las candidatas del oficialismo, Claudia Sheinbaum, y la aspirante del frente opositor, X\u00f3chitl G\u00e1lvez.En diciembre de 2023, el legislador se desempe\u00f1\u00f3 como coordinador de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449925,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","url_meta":{"origin":1449698,"position":4},"title":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico","author":"","date":"junio 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico por el partido Movimiento Ciudadano, ha presentado m\u00e1s de 30 propuestas de gobierno divididas en tres ejes: justicia, prosperidad e igualdad.M\u00e1ynez, quien afirma ser el candidato de la \u201cnueva pol\u00edtica\u201d y critica a sus oponentes llam\u00e1ndolas \u201clas candidatas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450025,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/mexico-cuantos-votos-estado-partido-candidato-prep-orix\/","url_meta":{"origin":1449698,"position":5},"title":"As\u00ed fue la votaci\u00f3n en cada uno de los estados en las elecciones en M\u00e9xico 2024: cifras y porcentajes de las coaliciones de partidos","author":"","date":"junio 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pasado 2 de junio tuvieron lugar las elecciones presidenciales que posicionaron a Claudia Sheinbaum como la pr\u00f3xima presidenta del pa\u00eds, la primera mujer en ocupar el cargo. Con casi el 60% de los votos, la candidata super\u00f3 a su principal opositora, X\u00f3chitl G\u00e1lvez, con una diferencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449698"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449698\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}