{"id":1449721,"date":"2024-05-23T16:03:50","date_gmt":"2024-05-23T23:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/"},"modified":"2024-05-23T16:03:50","modified_gmt":"2024-05-23T23:03:50","slug":"cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","title":{"rendered":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &#171;Diddy&#187; Combs"},"content":{"rendered":"<p>(CNN) &#8212; Cassie Ventura comparti\u00f3 un comunicado en el que expresa su gratitud por el apoyo que ha recibido desde que CNN public\u00f3 un video de vigilancia de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por su entonces novio, Sean &#171;Diddy&#187; Combs.<\/p>\n<p>&#171;Gracias por todo el amor y el apoyo de mi familia, amigos, extra\u00f1os y aquellos que a\u00fan no he conocido&#187;, escribi\u00f3 Ventura en una publicaci\u00f3n compartida en Instagram. &#171;La efusi\u00f3n de amor ha creado un lugar para que mi yo m\u00e1s joven se establezca y se sienta seguro ahora, pero esto es solo el comienzo&#187;.<\/p>\n<p>De la negaci\u00f3n a la admisi\u00f3n: c\u00f3mo un video de vigilancia oblig\u00f3 a Sean &#171;Diddy&#187; Combs a rendir cuentas<\/p>\n<p>Ventura continu\u00f3: &#171;La violencia dom\u00e9stica es EL problema. Me convirti\u00f3 en alguien que nunca pens\u00e9 que llegar\u00eda a ser. Con mucho trabajo duro, hoy estoy mejor, pero siempre estar\u00e9 recuper\u00e1ndome de mi pasado&#187;.<\/p>\n<p>A continuaci\u00f3n se centr\u00f3 en buscar apoyo para los dem\u00e1s.<\/p>\n<p>&#171;Lo \u00fanico que pido es que TODOS abran su coraz\u00f3n para creer en las v\u00edctimas la primera vez. Se necesita mucho coraz\u00f3n para decir la verdad desde una situaci\u00f3n en la que no ten\u00edas poder&#187;, escribi\u00f3 Ventura. &#171;Ofrezco mi apoyo a aquellos que todav\u00eda viven con miedo. Apoyen a su gente, no la aislen. Nadie deber\u00eda cargar este peso solo&#187;.<\/p>\n<p>&#171;Este viaje de curaci\u00f3n nunca termina, pero este apoyo significa todo para m\u00ed&#187;, concluy\u00f3 su mensaje.<\/p>\n<p>Combs y Ventura salieron de forma intermitente entre 2007 y 2018. En su denuncia, que se resolvi\u00f3 un d\u00eda despu\u00e9s de su presentaci\u00f3n en noviembre de 2023, Ventura aleg\u00f3 que Combs la viol\u00f3 en 2018 y la someti\u00f3 a a\u00f1os de repetidos abusos f\u00edsicos y de otro tipo a lo largo de su relaci\u00f3n.<\/p>\n<p>Combs neg\u00f3 previamente las acusaciones.<\/p>\n<p>&#171;La decisi\u00f3n de llegar a un acuerdo en una demanda, especialmente en 2023, no es de ninguna manera una admisi\u00f3n de mala conducta&#187;, dijo Ben Brafman, abogado de Combs, a CNN en un comunicado en noviembre. &#171;La decisi\u00f3n del Sr. Combs de llegar a un acuerdo en la demanda no socava en modo alguno su rotunda negaci\u00f3n de las reclamaciones. Se alegra de que hayan llegado a un acuerdo mutuo y le desea lo mejor a la se\u00f1ora Ventura&#187;.<\/p>\n<p>Combs se disculp\u00f3 el domingo por sus acciones vistas en el video de vigilancia.<\/p>\n<p>La abogada de Ventura, Meredith Firetog, critic\u00f3 su respuesta.<\/p>\n<p>&#171;Cuando Cassie y otras m\u00faltiples mujeres se presentaron, \u00e9l neg\u00f3 todo y sugiri\u00f3 que sus v\u00edctimas estaban buscando un d\u00eda de pago&#187;, ella en un comunicado a CNN.<\/p>\n<p>Ventura y Combs no se nombraron mutuamente en sus respectivas declaraciones. Su acuerdo de noviembre establece que ninguno de los dos puede hablar del otro de ninguna manera, seg\u00fan m\u00faltiples fuentes familiarizadas con el acuerdo.<\/p>\n<p>Crecientes problemas legales para Combs<\/p>\n<p>Combs ha sido nombrado en siete demandas civiles en los \u00faltimos meses, incluyendo la de Ventura. Seis de esas demandas, incluida una presentada el martes, contienen acusaciones de agresi\u00f3n sexual. Una de las seis demandas nombra a Combs como acusado, pero fue presentada contra el hijo de Combs, Christian Combs. Solo se ha llegado a un acuerdo en el caso de Ventura.<\/p>\n<p>Las autoridades registraron los domicilios de &#171;Diddy&#187; el 25 de marzo de 2024 porque es objeto de una investigaci\u00f3n federal llevada a cabo por un equipo del Departamento de Seguridad Nacional que se ocupa de la trata de personas y otros delitos, seg\u00fan un alto funcionario de las fuerzas del orden federales con conocimiento de la investigaci\u00f3n.<\/p>\n<p>La investigaci\u00f3n se deriva de muchas de las mismas acusaciones de agresi\u00f3n sexual presentadas en las demandas civiles, seg\u00fan una segunda fuente policial familiarizada con las pesquisas.<\/p>\n<p>Combs y sus abogados han negado las acusaciones. Seis demandas siguen activas.<\/p>\n<p>&#8212; Sandra Gonz\u00e1lez, Alli Rosenbloom y Elizabeth Wagmeister de CNN contribuyeron con este reportaje.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Cassie Ventura comparti\u00f3 un comunicado en el que expresa su gratitud por el apoyo que ha recibido desde que CNN public\u00f3 un video de vigilancia de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por su entonces novio, Sean &#171;Diddy&#187; Combs. &#171;Gracias por todo el amor y el apoyo de mi familia, amigos, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449721","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &quot;Diddy&quot; Combs - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &quot;Diddy&quot; Combs - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Cassie Ventura comparti\u00f3 un comunicado en el que expresa su gratitud por el apoyo que ha recibido desde que CNN public\u00f3 un video de vigilancia de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por su entonces novio, Sean &#171;Diddy&#187; Combs. &#171;Gracias por todo el amor y el apoyo de mi familia, amigos, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-23T23:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &#171;Diddy&#187; Combs\",\"datePublished\":\"2024-05-23T23:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\"},\"wordCount\":714,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\",\"name\":\"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean \\\"Diddy\\\" Combs - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-23T23:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &#171;Diddy&#187; Combs\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean \"Diddy\" Combs - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean \"Diddy\" Combs - Noticias","og_description":"(CNN) &#8212; Cassie Ventura comparti\u00f3 un comunicado en el que expresa su gratitud por el apoyo que ha recibido desde que CNN public\u00f3 un video de vigilancia de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por su entonces novio, Sean &#171;Diddy&#187; Combs. &#171;Gracias por todo el amor y el apoyo de mi familia, amigos, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-23T23:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/"},"author":{"name":"","@id":""},"headline":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &#171;Diddy&#187; Combs","datePublished":"2024-05-23T23:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/"},"wordCount":714,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","name":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean \"Diddy\" Combs - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-23T23:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &#171;Diddy&#187; Combs"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\u00eda siendo agredida f\u00edsicamente por Sean &#171;Diddy&#187; Combs","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/23\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-23T23:03:50Z","datePublished":"2024-05-23T23:03:50Z","dateModified":"2024-05-23T23:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Cassie Ventura rompe su silencio sobre el video de 2016 en el que aparec\\u00eda siendo agredida f\\u00edsicamente por Sean &#171;Diddy&#187; Combs\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/23\\\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/23\\\/cassie-ventura-rompe-silencio-video-sean-diddy-combs-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-23T23:03:50Z\",\"datePublished\":\"2024-05-23T23:03:50Z\",\"dateModified\":\"2024-05-23T23:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452802,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/18\/valentia-cassie-ventura-acusacion-sean-diddy-combs-trax\/","url_meta":{"origin":1449721,"position":0},"title":"C\u00f3mo la valent\u00eda de Cassie Ventura condujo a la acusaci\u00f3n de Sean &#171;Diddy&#187; Combs","author":"","date":"septiembre 18, 2024","format":false,"excerpt":"(CNN) -- Cassie Ventura est\u00e1 componiendo ahora su propia canci\u00f3n.La cantante de \"Me & U\" recuper\u00f3 el control de su historia cuando detall\u00f3 por primera vez a\u00f1os de inquietantes acusaciones de abuso en una demanda presentada contra su exnovio y exproductor Sean \"Diddy\" Combs en noviembre pasado.Aunque su demanda se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462629,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/21\/quien-es-cassie-ventura-sean-diddy-combs-abuso-orix\/","url_meta":{"origin":1449721,"position":1},"title":"Qui\u00e9n es Cassie Ventura, la cantante que demand\u00f3 a Sean &#8216;Diddy&#8217; Combs por abuso y ahora es testigo en el caso penal","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Casandra Ventura, m\u00e1s conocida como Cassie Ventura, es una figura destacada del R&B que pas\u00f3 de los escenarios a ser parte del escrutinio medi\u00e1tico, al convertirse en la primera mujer en denunciar a Sean \u201cDiddy\u201d Combs por abuso f\u00edsico y sexual, un hecho que desat\u00f3 una serie de acusaciones que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449595,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/20\/sean-diddy-combs-arrepentido-agredido-fisicamente-cassie-ventura-2016-trax\/","url_meta":{"origin":1449721,"position":2},"title":"Sean &#171;Diddy&#187; Combs dice estar &#171;verdaderamente arrepentido&#187; de haber agredido f\u00edsicamente a Cassie Ventura en 2016","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- Sean \"Diddy\" Combs se disculp\u00f3 este domingo por agredir f\u00edsicamente a su entonces novia Cassie Ventura, dos d\u00edas despu\u00e9s de que CNN publicara en exclusiva un video de vigilancia de un hotel de 2016 en el que Combs aparece agarr\u00e1ndola, empuj\u00e1ndola, arrastr\u00e1ndola y d\u00e1ndole patadas.\"Mi comportamiento en ese\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449661,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/21\/acusan-sean-diddy-combs-agresion-sexual-nueva-demanda-crystal-mckinney-mtv-trax\/","url_meta":{"origin":1449721,"position":3},"title":"Acusan a Sean &#8216;Diddy&#8217; Combs de agresi\u00f3n sexual en una nueva demanda de la exganadora de Misi\u00f3n Modelo de MTV","author":"","date":"mayo 21, 2024","format":false,"excerpt":"(CNN) -- Sean \"Diddy\" Combs fue acusado de agresi\u00f3n sexual en una nueva demanda presentada este martes por Crystal McKinney, una exmodelo y ganadora del programa de concursos Misi\u00f3n Modelo de MTV en 1998.Seg\u00fan la demanda, presentada en Nueva York y obtenida por CNN, McKinney afirma que fue \"drogada y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449553,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/17\/exclusiva-sean-diddy-combs-video-agresion-cassie-ventura-trax\/","url_meta":{"origin":1449721,"position":4},"title":"EXCLUSIVA | Sean &#171;Diddy&#187; Combs aparece agrediendo f\u00edsicamente a Cassie Ventura en un video de vigilancia de 2016 obtenido por CNN","author":"","date":"mayo 17, 2024","format":false,"excerpt":"(CNN) -- Un video de vigilancia de 2016 obtenido en exclusiva por CNN muestra a Sean \"Diddy\" Combs agarrando, empujando, arrastrando y pateando a su entonces novia Cassie Ventura durante un altercado que coincide con las acusaciones en una demanda federal ahora resuelta presentada por Ventura en noviembre.Las im\u00e1genes, recopiladas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449605,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/20\/video-vigilancia-obligo-sean-diddy-combs-trax\/","url_meta":{"origin":1449721,"position":5},"title":"De la negaci\u00f3n a la admisi\u00f3n: c\u00f3mo un video de vigilancia oblig\u00f3 a Sean &#171;Diddy&#187; Combs a rendir cuentas","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN) -- Casi 48 horas despu\u00e9s de publicarse un video de vigilancia obtenido en exclusiva por CNN en el que se ve a Sean \"Diddy\" Combs agrediendo f\u00edsicamente a su entonces novia Cassie Ventura en 2016, el cantante pidi\u00f3 disculpas.Justo antes de la 1 pm ET del viernes, CNN public\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449721"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449721\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}