{"id":1449835,"date":"2024-05-29T13:03:38","date_gmt":"2024-05-29T20:03:38","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/"},"modified":"2024-05-29T13:03:38","modified_gmt":"2024-05-29T20:03:38","slug":"brasil-retira-embajador-tel-aviv-guerra-gaza-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","title":{"rendered":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza"},"content":{"rendered":"<p>(CNN) &#8212; Brasil retir\u00f3 a su embajador en Israel de la embajada de Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza, seg\u00fan un decreto publicado este mi\u00e9rcoles en el diario oficial brasile\u00f1o.<\/p>\n<p>El embajador Frederico Meyer se incorporar\u00e1 a la misi\u00f3n permanente de Brasil ante la Organizaci\u00f3n de las Naciones Unidas (ONU) y otras organizaciones internacionales en Ginebra, indica el decreto, que no menciona un sustituto para Meyer.<\/p>\n<p>El Ministerio de Asuntos Exteriores de Israel dijo a CNN que no han recibido un &#171;mensaje oficial&#187; del Gobierno brasile\u00f1o sobre el asunto. Sin embargo, Israel dice que como &#171;respuesta al informe, el encargado de negocios brasile\u00f1o ha sido convocado al Ministerio de Asuntos Exteriores para una reuni\u00f3n sobre el tema ma\u00f1ana jueves&#187;.<\/p>\n<p>El pasado mes de febrero, Brasil convoc\u00f3 a Meyer despu\u00e9s de que el ministro de Asuntos Exteriores de Israel, Israel Katz, declarara al presidente Luiz In\u00e1cio Lula da Silva persona non grata en Israel por comparar la operaci\u00f3n israel\u00ed en Gaza con el Holocausto.<\/p>\n<p>Qu\u00e9 est\u00e1 pasando en Rafah, la ciudad del sur de Gaza donde ocurri\u00f3 el mort\u00edfero ataque a un campo de refugiados<\/p>\n<p>En un acto, Lula dijo que &#171;lo que est\u00e1 ocurriendo en Gaza con el pueblo palestino no tiene parang\u00f3n en la historia. De hecho, ocurri\u00f3 cuando Hitler decidi\u00f3 matar a los jud\u00edos&#187;.<\/p>\n<p>En aquel momento, Katz dijo que Lula no ser\u00eda bienvenido en Israel hasta que pidiera disculpas y se retractara de sus comentarios.<\/p>\n<p>En otras ocasiones, Lula se ha pronunciado en contra de las acciones de Israel en Gaza.<\/p>\n<p>Meyer hab\u00eda regresado recientemente a Tel Aviv tras ser llamado a filas en febrero, inform\u00f3 CNN Brasil.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Brasil retir\u00f3 a su embajador en Israel de la embajada de Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza, seg\u00fan un decreto publicado este mi\u00e9rcoles en el diario oficial brasile\u00f1o. El embajador Frederico Meyer se incorporar\u00e1 a la misi\u00f3n permanente de Brasil ante la Organizaci\u00f3n de las Naciones Unidas (ONU) [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449835","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Brasil retir\u00f3 a su embajador en Israel de la embajada de Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza, seg\u00fan un decreto publicado este mi\u00e9rcoles en el diario oficial brasile\u00f1o. El embajador Frederico Meyer se incorporar\u00e1 a la misi\u00f3n permanente de Brasil ante la Organizaci\u00f3n de las Naciones Unidas (ONU) [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-29T20:03:38+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza\",\"datePublished\":\"2024-05-29T20:03:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\"},\"wordCount\":328,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\",\"name\":\"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-29T20:03:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza - Noticias","og_description":"(CNN) &#8212; Brasil retir\u00f3 a su embajador en Israel de la embajada de Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza, seg\u00fan un decreto publicado este mi\u00e9rcoles en el diario oficial brasile\u00f1o. El embajador Frederico Meyer se incorporar\u00e1 a la misi\u00f3n permanente de Brasil ante la Organizaci\u00f3n de las Naciones Unidas (ONU) [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-29T20:03:38+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/"},"author":{"name":"","@id":""},"headline":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza","datePublished":"2024-05-29T20:03:38+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/"},"wordCount":328,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","name":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-29T20:03:38+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Brasil retira a su embajador en Tel Aviv tras meses de tensi\u00f3n por la guerra en Gaza","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-29T20:03:38Z","datePublished":"2024-05-29T20:03:38Z","dateModified":"2024-05-29T20:03:38Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Brasil retira a su embajador en Tel Aviv tras meses de tensi\\u00f3n por la guerra en Gaza\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/29\\\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/29\\\/brasil-retira-embajador-tel-aviv-guerra-gaza-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-29T20:03:38Z\",\"datePublished\":\"2024-05-29T20:03:38Z\",\"dateModified\":\"2024-05-29T20:03:38Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457246,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/05\/soldados-israelies-riesgo-detencion-extranjero-gaza-trax\/","url_meta":{"origin":1449835,"position":0},"title":"Soldados israel\u00edes se enfrentan a un creciente riesgo de detenci\u00f3n en el extranjero tras su servicio en Gaza","author":"","date":"enero 5, 2025","format":false,"excerpt":"Un exsoldado israel\u00ed que se encontraba de vacaciones en Brasil huy\u00f3 repentinamente del pa\u00eds despu\u00e9s de que se iniciara all\u00ed un proceso contra \u00e9l por su presunta responsabilidad en cr\u00edmenes de guerra durante su servicio en Gaza.El caso es el m\u00e1s reciente de una serie de demandas interpuestas por la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462567,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/20\/reino-unido-pausa-negociaciones-comerciales-israel-convoca-embajador-trax\/","url_meta":{"origin":1449835,"position":1},"title":"Reino Unido pausa las negociaciones comerciales con Israel y convoca al embajador israel\u00ed por la violencia en Gaza","author":"","date":"mayo 20, 2025","format":false,"excerpt":"El Reino Unido ha suspendido las negociaciones comerciales con Israel, ha sancionado a los colonos en la Ribera Occidental y ha convocado al embajador israel\u00ed debido a la operaci\u00f3n militar israel\u00ed en Gaza y la violencia de los colonos, anunci\u00f3 el martes el Ministerio de Asuntos Exteriores brit\u00e1nico.Las negociaciones del\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447637,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/02\/iran-venganza-ataque-israel-consulado-siria-trax\/","url_meta":{"origin":1449835,"position":2},"title":"Ir\u00e1n promete vengarse tras acusar a Israel del mort\u00edfero ataque contra su consulado en Siria","author":"","date":"abril 2, 2024","format":false,"excerpt":"(CNN) -- Ir\u00e1n prometi\u00f3 tomar represalias tras acusar a Israel de bombardear el lunes el complejo de su embajada en Siria, en una mort\u00edfera escalada de las tensiones regionales por la guerra de Gaza que, una vez m\u00e1s, pareci\u00f3 aumentar el riesgo de un conflicto m\u00e1s amplio en Medio Oriente.El\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445008,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/06\/milei-reitera-su-intencion-de-mudar-la-embajada-de-argentina-en-israel-de-tel-aviv-a-jerusalen-que-paises-tienen-su-embajada-en-cada-ciudad\/","url_meta":{"origin":1449835,"position":3},"title":"Milei reitera su intenci\u00f3n de mudar la embajada de Argentina en Israel de Tel Aviv a Jerusal\u00e9n: \u00bfqu\u00e9 pa\u00edses tienen su embajada en cada ciudad?","author":"","date":"febrero 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En Jerusal\u00e9n, que israel\u00edes y palestinos buscan que sea reconocida como su capital, no es com\u00fan encontrar embajadas de otros pa\u00edses, aunque s\u00ed las hay. El presidente de Argentina, Javier Milei, reiter\u00f3 este martes al arribar al pa\u00eds que tiene la intenci\u00f3n de trasladar la embajada de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462056,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/06\/cierra-oficina-asuntos-palestinos-embajada-jerusalen-trax\/","url_meta":{"origin":1449835,"position":4},"title":"Estados Unidos cierra la Oficina de Asuntos Palestinos y la fusiona con su embajada en Jerusal\u00e9n","author":"","date":"mayo 6, 2025","format":false,"excerpt":"El secretario de Estado de EE.UU., Marco Rubio, cerrar\u00e1 la Oficina de Asuntos Palestinos y la fusionar\u00e1 con la embajada de Estados Unidos en Jerusal\u00e9n, dijo este martes la portavoz del Departamento de Estado, Tammy Bruce.\u201cEsta decisi\u00f3n restablecer\u00e1 el marco del primer mandato de Trump de una misi\u00f3n diplom\u00e1tica unificada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462632,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/21\/diplomaticos-fuego-israeli-palestinos-ribera-occidental-trax\/","url_meta":{"origin":1449835,"position":5},"title":"Diplom\u00e1ticos extranjeros quedan bajo fuego israel\u00ed durante una visita oficial a un campo de refugiados palestino","author":"","date":"mayo 21, 2025","format":false,"excerpt":"Las fuerzas de Israel dispararon tiros de advertencia contra una numerosa delegaci\u00f3n de diplom\u00e1ticos europeos y \u00e1rabes que realizaban una visita oficial al campo de refugiados de Yen\u00edn, en la Ribera Occidental ocupada, lo que gener\u00f3 una r\u00e1pida condena.Delegaciones de m\u00e1s de 20 pa\u00edses, incluidos el Reino Unido, Francia, Canad\u00e1\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449835"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449835\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449835"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449835"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}