{"id":1449849,"date":"2024-05-29T18:03:47","date_gmt":"2024-05-30T01:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/"},"modified":"2024-05-29T18:03:47","modified_gmt":"2024-05-30T01:03:47","slug":"jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","title":{"rendered":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan?"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; A pesar de representar el 22% de la poblaci\u00f3n mexicana que puede votar, los j\u00f3venes entre 20 y 29 a\u00f1os muestran una notable tendencia al abstencionismo en los procesos electorales, de acuerdo con datos del Instituto Nacional Electoral (INE).<\/p>\n<p>Para la elecci\u00f3n de este 2 de junio, en M\u00e9xico hay m\u00e1s de 99 millones de ciudadanos inscritos en la lista nominal, son los que cuentan con una credencial vigente para poder votar. Los j\u00f3venes de 20 a 29 a\u00f1os son m\u00e1s de 22,5 millones de ese total, un 22% del total.<\/p>\n<p>El desencanto de los j\u00f3venes viene despu\u00e9s de votar por primera vez. En 2018, 53% de los ciudadanos de entre 18 y 19 a\u00f1os votaron, pero en las elecciones intermedias de 2021, ya con 21 y 22 a\u00f1os, la participaci\u00f3n fue de 41%. Un factor no considerado en esta comparaci\u00f3n es que la de 2018 fue una elecci\u00f3n presidencial y la de 2021 fue una elecci\u00f3n intermedia que solo incluy\u00f3 legisladores y gobernadores, entre otros cargos.<\/p>\n<p>CNN consult\u00f3 a especialistas sobre los motivos de este desencanto de muchos j\u00f3venes mexicanos con el ejercicio del voto.<br \/>\n\u201cEn la etapa de edad en la cual se incentiva m\u00e1s el voto es en entre 18 y 19 a\u00f1os, los j\u00f3venes est\u00e1n emocionados. Est\u00e1n invitados incluso est\u00e1n demandados a participar en el nuevo derecho que acaban de adquirir y por tanto entonces s\u00ed se vuelcan a las urnas\u201d, se\u00f1al\u00f3 Enrique Cuna, profesor e investigador de la Universidad Aut\u00f3noma Metropolitana de M\u00e9xico (UAM).<\/p>\n<p>Violencia repunta a horas de que concluyan las campa\u00f1a electorales en M\u00e9xico<\/p>\n<p>Pero luego la participaci\u00f3n baja. Desde 2009, el INE ha documentado una participaci\u00f3n menor en los j\u00f3venes de 20 a 29 a\u00f1os. De acuerdo con el \u00f3rgano electoral, el promedio de participaci\u00f3n de los mexicanos en la elecci\u00f3n de 2018 fue de 63%, sin embargo, en los j\u00f3venes de este grupo de edad penas lleg\u00f3 al 53% en esa elecci\u00f3n.<\/p>\n<p>\u201cS\u00ed hay un inter\u00e9s cuando eres primer votante, pero despu\u00e9s los j\u00f3venes tienden a desencantarse y esto es un fen\u00f3meno mundial, hay mucho desencanto en la pol\u00edtica\u201d, se\u00f1al\u00f3 Alejandra L\u00f3pez Mart\u00ednez, consultora especializada en el an\u00e1lisis, dise\u00f1o y evaluaci\u00f3n de pol\u00edticas p\u00fablicas con perspectiva de g\u00e9nero.<\/p>\n<p>Los especialistas consultados coincidieron en destacar varios factores que contribuyen a esta apat\u00eda electoral, entre ellos la desconfianza en el sistema pol\u00edtico, la falta de identificaci\u00f3n con los candidatos, las promesas incumplidas de los pol\u00edticos y la desigualdad econ\u00f3mica.<\/p>\n<p>Las elecciones generales 2024 en M\u00e9xico se llevan a cabo el domingo 2 de junio. (Cr\u00e9dito: YURI CORTEZ\/AFP v\u00eda Getty Images)<\/p>\n<p>La desconfianza en la pol\u00edtica<\/p>\n<p>La desconfianza en el sistema pol\u00edtico y ver que las promesas de candidatos y pol\u00edticos no se cumplen son algunas de las principales causas del abstencionismo juvenil en M\u00e9xico, consider\u00f3 Juan Carlos Villarreal Mart\u00ednez, profesor y consejero del Instituto Electoral del Estado de M\u00e9xico (IEEM).<\/p>\n<p>\u201cHemos invertido una gran cantidad de recursos a los \u00f3rganos electorales, pero no al tema central, que es el que provoca el abstencionismo, que es la calidad en el gobierno y los mecanismos de participaci\u00f3n y rendici\u00f3n de cuentas. Cuando hablamos de estos procesos de abstencionismo, la principal causa suele ser la desconfianza\u201d, explic\u00f3 Villarreal Mart\u00ednez.<\/p>\n<p>El consejero consider\u00f3 que el mejor mecanismo para estimular la participaci\u00f3n de los j\u00f3venes es \u201cel cumplimiento de las pol\u00edticas de campa\u00f1a y el ejercicio del gobierno; si esto no lo ven los j\u00f3venes en su corta vida es muy dif\u00edcil que volteen a ver con confianza los procesos electorales\u201d.<\/p>\n<p>\u201cEn 20 a\u00f1os se han visto transitar (por el poder) a tres partidos pol\u00edticos distintos, \u00bfpor qu\u00e9 son reacios entonces a participar? Porque en su corta vida no han visto el cumplimiento de las ofertas, ni de gobierno ni de los partidos pol\u00edticos, porque los j\u00f3venes ven cotidianamente actos de corrupci\u00f3n en los partidos, ven candidatos endebles sin propuestas, todo esto impacta en el elector\u201d, agreg\u00f3 Villarreal.<\/p>\n<p>Los j\u00f3venes que han participado en elecciones anteriores y no han visto mejoras tangibles en su vida cotidiana o en la sociedad en general tienden a volverse ap\u00e1ticos. Para Valeriano Ram\u00edrez Medina, doctor en estudios pol\u00edticos y profesor de la UNAM, el desencanto de los j\u00f3venes por el proceso electoral es porque luego de votar por un candidato o partido no ven un cambio o soluciones a sus problemas.<\/p>\n<p>\u201cAl final del d\u00eda no hay una respuesta y los chavos quieren respuestas inmediatas, quieren soluciones r\u00e1pidas, cuando no se dan entonces se da el desencanto, se da el desenganche y por lo tanto no hay una consecuencia y un seguimiento pol\u00edtico y eso nos lleva a un mayor acto de abstencionismo entre los 25 y los 39 a\u00f1os\u201d, expuso Ram\u00edrez.<\/p>\n<p>Seg\u00fan cifras del INE, en la elecci\u00f3n de 2018, vot\u00f3 57,1% de los j\u00f3venes de 19 a\u00f1os; 52,8% de los de 20 a 29 a\u00f1os, y 58,1% de los que tienen entre 30 y 34 a\u00f1os. En el grupo de 35 a 39 a\u00f1os vot\u00f3 61,9%. Todos estuvieron por debajo del promedio nacional de 63% de participaci\u00f3n.<\/p>\n<p>J\u00f3venes con una bandera mexicana mientras simpatizantes de la candidata presidencial opositora Xochitl G\u00e1lvez, del partido de coalici\u00f3n Fuerza y Coraz\u00f3n por M\u00e9xico, marchan hacia la Plaza del Z\u00f3calo el 19 de mayo de 2024. (Foto de CARL DE SOUZA\/AFP v\u00eda Getty Images)<\/p>\n<p>J\u00f3venes que no se sienten representados<\/p>\n<p>Los j\u00f3venes a menudo no se sienten representados por los candidatos y sus propuestas.<\/p>\n<p>Para L\u00f3pez Mart\u00ednez, una raz\u00f3n de esta falta de empat\u00eda de los j\u00f3venes es que los pol\u00edticos \u201ctienden a ser mucho mayores que ellos. En promedio los pol\u00edticos en M\u00e9xico tienen 60 o 61 a\u00f1os, que es la edad de las dos candidatas\u201d, la oficialista Claudia Sheinbaum y la opositora X\u00f3chitl G\u00e1lvez. El candidato de Movimiento Ciudadano, Jorge \u00c1lvarez M\u00e1ynez tiene 38 a\u00f1os.<\/p>\n<p>\u201cS\u00ed hay una brecha generacional importante, adem\u00e1s la participaci\u00f3n de los j\u00f3venes en pol\u00edtica no es en toma de decisiones, sino como carne de ca\u00f1\u00f3n, de avanzada\u201d, dijo la polit\u00f3loga , pues \u201clos j\u00f3venes no tienen experiencia, no saben lo que est\u00e1n haciendo y eso va generando desencanto en ellos porque no hay nadie que les hable de sus problemas de lo que les interesa a ellos de los retos que les vienen\u201d.<\/p>\n<p>AN\u00c1LISIS | \u00bfQu\u00e9 hay detr\u00e1s del aumento en el consumo de drogas en M\u00e9xico?<\/p>\n<p>Esa falta de identidad, pues las nuevas generaciones tienen m\u00faltiples identidades y formas de pensar, explic\u00f3 el doctor en estudios pol\u00edticos Valeriano Ram\u00edrez, provoca que muchos j\u00f3venes en lugar de basar su voto en propuestas concretas, lo hagan en razones superficiales, como la apariencia o el carisma del candidato, mientras que muchos simplemente optan por no votar.<\/p>\n<p>\u201cLas identidades pol\u00edticas se ven iguales para un joven que no distingue entre izquierda y derecha, no sabe cu\u00e1l es la propuesta de cada una, pero lo que s\u00ed tiene es afinidades, identidades con alg\u00fan candidato o candidata con la cual se identifica, con la cual dice \u2018\u00e9l me cae bien porque es guapo, porque es importante, porque es inteligente, porque me gusta su discurso\u2019, o simplemente hay una identidad. Pero si no existe esa identidad, si no existe esa afinidad, simplemente no entra en su esquema el voto, porque no es para ellos importante, porque ya piensan que las cosas est\u00e1n dadas y que es m\u00e1s f\u00e1cil adaptarse que transformar\u201d, explic\u00f3 el acad\u00e9mico de la UNAM.<\/p>\n<p>Otro tropiezo de los pol\u00edticos y sus partidos, seg\u00fan Alejandra L\u00f3pez, es la estrategia de comunicaci\u00f3n con la que tratan de llegar a los j\u00f3venes.<\/p>\n<p>\u201cHa habido una estrategia fallida al tratar de hablarle a los j\u00f3venes solamente utilizando los medios que utilizan los j\u00f3venes, es decir si los partidos pol\u00edticos y los candidatos y las autoridades solamente utilizan las redes sociales para llegar a los j\u00f3venes, pero el mensaje sigue siendo un mensaje para gente adulta, no van a llegar a los j\u00f3venes, entonces no es solamente hablarles a trav\u00e9s de los medios que ellos utilizan sino tambi\u00e9n con el lenguaje que ellos utilizan\u201d, expuso la polit\u00f3loga.<\/p>\n<p>Cr\u00e9dito: Getty Images<\/p>\n<p>Agendas que no atienden sus problemas<\/p>\n<p>Enrique Cuna, de la UAM, se\u00f1al\u00f3 que son tres los temas que importan e impactan a los j\u00f3venes: seguridad, empleo y educaci\u00f3n. Argument\u00f3 que en las agendas de los candidatos a la presidencia de M\u00e9xico hay propuestas que afectan a los j\u00f3venes, \u201cpero no por su condici\u00f3n de juventud, sino por su condici\u00f3n de madres, por su condici\u00f3n de v\u00edctimas de la violencia\u201d, entre otras cosas.<\/p>\n<p>L\u00f3pez y Villareal coincidieron en que no se debe pensar que a los j\u00f3venes solo hay que darles actividades deportivas y becas.<br \/>\n\u201cTenemos una Comisi\u00f3n de Juventud y Deporte como si los j\u00f3venes fueran deportistas y no les interesaran otras cosas o solamente pensar en becas para los j\u00f3venes, creo que hablar de una forma mucho m\u00e1s integral de las juventudes, de lo que ellos necesitan, que no todos est\u00e1n estudiando, no todos est\u00e1n trabajando, hay muchas circunstancias, dentro de las juventudes\u201d, puntualiz\u00f3 Lopez.<\/p>\n<p>\u201cAh\u00ed est\u00e1n los de 20 a 29 a\u00f1os. Ah\u00ed es donde menos participan los j\u00f3venes, ah\u00ed donde tenemos muchos problemas y creo yo que buena parte del des\u00e1nimo del desinter\u00e9s proviene de que no hay pol\u00edticas p\u00fablicas para los j\u00f3venes m\u00e1s all\u00e1 de estos programas de becas\u201d, destac\u00f3 Villarreal.<\/p>\n<p>El consejero del IEEM agreg\u00f3 que, en estas campa\u00f1as, \u201clejos de ofrecer cosas que transformen al pa\u00eds (los candidatos) est\u00e1n en una competencia rid\u00edcula, a ver qui\u00e9n regala m\u00e1s dinero, los j\u00f3venes no son tontos, los j\u00f3venes, lo entienden perfectamente bien y saben que las expectativas no van a cambiar\u201d.<\/p>\n<p>Villarreal a\u00f1adi\u00f3 que el problema de la desigualdad tambi\u00e9n afecta la participaci\u00f3n juvenil. &#171;Tenemos un problema terrible de desigualdad, y de fondo en la participaci\u00f3n ciudadana hay una argumentaci\u00f3n de car\u00e1cter emocional&#187;, afirm\u00f3.<\/p>\n<p>&#171;Si mi abuelo fue carpintero, mi padre fue carpintero y a m\u00ed como futuro me ponen ser carpintero, entonces \u00bfqu\u00e9 tipo de est\u00edmulo tengo yo para creer que la democracia va a resolver problemas de desigualdad?&#187;, se\u00f1al\u00f3.<\/p>\n<p>El acad\u00e9mico cuestion\u00f3 la motivaci\u00f3n que pueden tener los j\u00f3venes que viven en situaci\u00f3n vulnerable para confiar en que la democracia solucionar\u00e1 sus problemas. &#171;\u00bfQu\u00e9 tipo de est\u00edmulo tengo yo para pensar que un joven que vive en condiciones precarias va a ir a la universidad, un joven que gasta buena parte de sus recursos y tiempo en los trayectos tiene ganas de participar, cuando ha visto sistem\u00e1ticamente a lo largo de su vida, el fracaso del gobierno y los partidos?&#187;.<\/p>\n<p>Boleta de muestra para la elecci\u00f3n 2024 de la Presidencia de la Rep\u00fablica en M\u00e9xico. (Cr\u00e9dito: INE)<\/p>\n<p>Abstencionismo, una forma de participar<\/p>\n<p>Cuna sugiri\u00f3 entender el abstencionismo juvenil desde una perspectiva diferente: en lugar de verlo como un acto negativo, se deben comprender las razones que llevan a muchos j\u00f3venes a no participar en las elecciones.<\/p>\n<p>&#171;Se nos invita a pensar el abstencionismo como algo negativo, pero en realidad lo que tendr\u00edamos que hacer es entender por qu\u00e9 la gente no participa&#187;, afirma.<\/p>\n<p>Voto nulo en M\u00e9xico: \u00bfqu\u00e9 es y a qui\u00e9n beneficia?<\/p>\n<p>Cuna explic\u00f3 que, a nivel mundial, el abstencionismo puede ser una forma de rechazo hacia el sistema electoral, y de expresar que ninguna opci\u00f3n pol\u00edtica refleja sus intereses o inquietudes.<\/p>\n<p>El profesor de la UAM llam\u00f3 a eliminar el estigma asociado con el abstencionismo. &#171;(El abstencionista) no es simplemente alguien ap\u00e1tico y sin voluntad. Al contrario, tambi\u00e9n puede ser una forma de participaci\u00f3n activa fuera de las instituciones y partidos pol\u00edticos&#187;, destaco.<\/p>\n<p>Una de las razones principales para el abstencionismo, seg\u00fan Cuna, es la falta de representatividad. Los j\u00f3venes pueden sentir que ninguna candidatura les representa adecuadamente y por ello &#171;decidieron que ninguna de las opciones les manifiesta un inter\u00e9s o inquietud, o una representatividad, por tanto tambi\u00e9n puede ser v\u00e1lido el abstencionismo&#187;, explic\u00f3.<\/p>\n<p>\u00bfQu\u00e9 es y c\u00f3mo funciona la veda electoral en M\u00e9xico?<\/p>\n<p>Alejandra L\u00f3pez coincidi\u00f3 en que el abstencionismo y el voto nulo tambi\u00e9n son formas leg\u00edtimas de hacer pol\u00edtica. &#171;Definitivamente, no votar tambi\u00e9n es una forma de hacer pol\u00edtica y eso pues s\u00ed hay que tenerlo claro&#187;, afirm\u00f3.<\/p>\n<p>Concuerda con Cuna en que la falta de representaci\u00f3n es una de las principales razones para el abstencionismo, pues \u201clas personas no se sienten representadas por las opciones que hay&#187;.<\/p>\n<p>La polit\u00f3loga consider\u00f3 que anular el voto es otra manera v\u00e1lida de expresar descontento. &#171;Anular el voto tambi\u00e9n es una forma de hacer pol\u00edtica, pero yo en lo personal creo que la democracia es la elecci\u00f3n&#187;, subray\u00f3. Por ello destac\u00f3 la importancia de participar en el proceso electoral: &#171;Hay que escoger lo que est\u00e9 m\u00e1s cercano, aunque no te represente al 100%&#187;.<\/p>\n<p>(Foto: ULISES RUIZ\/AFP via Getty Images).<\/p>\n<p>Qu\u00e9 hacer para llegar a los j\u00f3venes<\/p>\n<p>Pese a todos estos obst\u00e1culos, los especialistas se\u00f1alan que existen m\u00faltiples estrategias que las autoridades y los partidos pol\u00edticos pueden implementar para revertir esta tendencia.<\/p>\n<p>Cuna propuso reconocer la heterogeneidad juvenil y conocer sus necesidades: \u201cNo es lo mismo hablarle a un a un joven de una universidad que a un joven que desgraciadamente no tuvo acceso a la educaci\u00f3n\u201d.<\/p>\n<p>\u201cHabr\u00eda que hacer un an\u00e1lisis serio, profundo de la gran heterogeneidad juvenil, segundo de sus necesidades, tercero un modelo de comunicaciones y acercamiento diferente y cuarto una construcci\u00f3n m\u00e1s \u00e9tica en la cuesti\u00f3n pol\u00edtica, un cambio de esencia de la pol\u00edtica y dejar de lado el caos y el enfrentamiento\u201d, sostuvo Cuna.<\/p>\n<p>Por su parte, Villarreal propuso que el \u00f3rgano electoral se centre m\u00e1s en actividades con los j\u00f3venes y que los partidos pol\u00edticos \u201csean m\u00e1s inteligentes para dirigirse a los j\u00f3venes, pues esta generaci\u00f3n tiene la mayor cantidad de datos disponibles al alcance de la mano con un tel\u00e9fono celular\u201d.<\/p>\n<p>Agreg\u00f3 que antes los partidos buscaban a los l\u00edderes juveniles y los incorporaban a tareas del partido. \u201cEn la medida que los j\u00f3venes se involucran en pol\u00edtica, digamos, una edad en donde pueden participar activamente, en esa medida se fortalece el sistema democr\u00e1tico\u201d, destac\u00f3 el consejero electoral.<\/p>\n<p>Como tercer punto, Villarreal propuso que el d\u00eda de la elecci\u00f3n se le regale un libro a los j\u00f3venes que voten. \u201cEso lo puede hacer la autoridad electoral, los libros pueden contribuir a la educaci\u00f3n de los chicos y puede ser un est\u00edmulo\u201d, aunque remarc\u00f3 que ning\u00fan est\u00edmulo es comparable a que los pol\u00edticos cumplan con sus propuestas y generen cambios reales.<\/p>\n<p>Valeriano Ram\u00edrez coincidi\u00f3 con Villarreal en que uno de los problemas es que los partidos ya no generan bases sociales que incluyan a los j\u00f3venes. Tambi\u00e9n consider\u00f3 que se debe incluir a las juventudes en actividades culturales, laborales, acad\u00e9micas que sean parte de un proyecto de vida pol\u00edtico en la sociedad.<\/p>\n<p>\u201cSi impulsamos eso atraemos a los j\u00f3venes a una participaci\u00f3n pol\u00edtica permanente y eso a informaci\u00f3n y a generar identidades, si no existen esto sin nada m\u00e1s se busca cada tres a\u00f1os a la gente para el voto, pues van a decir \u2018s\u00ed, muchas gracias, no voto o si voto\u2019, pero no hay una permanencia.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; A pesar de representar el 22% de la poblaci\u00f3n mexicana que puede votar, los j\u00f3venes entre 20 y 29 a\u00f1os muestran una notable tendencia al abstencionismo en los procesos electorales, de acuerdo con datos del Instituto Nacional Electoral (INE). Para la elecci\u00f3n de este 2 de junio, en M\u00e9xico hay m\u00e1s de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449849","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan? - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan? - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; A pesar de representar el 22% de la poblaci\u00f3n mexicana que puede votar, los j\u00f3venes entre 20 y 29 a\u00f1os muestran una notable tendencia al abstencionismo en los procesos electorales, de acuerdo con datos del Instituto Nacional Electoral (INE). Para la elecci\u00f3n de este 2 de junio, en M\u00e9xico hay m\u00e1s de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-30T01:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan?\",\"datePublished\":\"2024-05-30T01:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\"},\"wordCount\":2744,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\",\"name\":\"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan? - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-30T01:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan? - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan? - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; A pesar de representar el 22% de la poblaci\u00f3n mexicana que puede votar, los j\u00f3venes entre 20 y 29 a\u00f1os muestran una notable tendencia al abstencionismo en los procesos electorales, de acuerdo con datos del Instituto Nacional Electoral (INE). Para la elecci\u00f3n de este 2 de junio, en M\u00e9xico hay m\u00e1s de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-30T01:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"14 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan?","datePublished":"2024-05-30T01:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/"},"wordCount":2744,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","name":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan? - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-30T01:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan?"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Abstencionismo en M\u00e9xico: \u00bfpor qu\u00e9 muchos j\u00f3venes no votan?","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/29\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-30T01:03:47Z","datePublished":"2024-05-30T01:03:47Z","dateModified":"2024-05-30T01:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Abstencionismo en M\\u00e9xico: \\u00bfpor qu\\u00e9 muchos j\\u00f3venes no votan?\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/29\\\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/29\\\/jovenes-abstencionismo-desafio-democracia-elecciones-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-30T01:03:47Z\",\"datePublished\":\"2024-05-30T01:03:47Z\",\"dateModified\":\"2024-05-30T01:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448674,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/29\/venezolanos-argentina-votar-elecciones-orix\/","url_meta":{"origin":1449849,"position":0},"title":"Venezolanos en Argentina: son m\u00e1s de 200.000 y solo un peque\u00f1o porcentaje podr\u00e1 votar en las elecciones","author":"","date":"abril 29, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En Argentina viven alrededor de 220.000 venezolanos, seg\u00fan las estimaciones m\u00e1s recientes publicadas por el ministerio del Interior a 2023 y al menos el 70% est\u00e1 en edad de votar.Un venezolano que lleg\u00f3 al pa\u00eds en los \u00faltimos dos a\u00f1os no cumple los requisitos para empadronarse y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446036,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/27\/voto-extranjero-mexico-2024-orix\/","url_meta":{"origin":1449849,"position":1},"title":"C\u00f3mo votar en las elecciones de M\u00e9xico 2024 desde el extranjero y por internet","author":"","date":"febrero 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El 2 de junio de 2024, m\u00e1s de 100 millones de mexicanos est\u00e1n llamados a las elecciones generales donde se elegir\u00e1n 20.375 cargos, de los cuales 19.746 son locales y 629 son federales, incluida la renovaci\u00f3n de la Presidencia de la Rep\u00fablica.En las elecciones generales no solo podr\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444169,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/20\/como-votar-en-las-elecciones-de-mexico-2024-desde-el-extranjero-y-por-internet\/","url_meta":{"origin":1449849,"position":2},"title":"C\u00f3mo votar en las elecciones de M\u00e9xico 2024 desde el extranjero y por internet","author":"","date":"enero 20, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El 2 de junio de 2024, m\u00e1s de 97 millones de mexicanos est\u00e1n llamados a las elecciones generales donde se elegir\u00e1n 20.375 cargos, de los cuales 19.746 son locales y 629 son federales, incluida la renovaci\u00f3n de la Presidencia de la Rep\u00fablica.En las elecciones generales no solo podr\u00e1n\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469456,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/12\/20\/turning-point-jovenes-conservadores-expresan-preocupacion-trax\/","url_meta":{"origin":1449849,"position":3},"title":"En la reuni\u00f3n anual de Turning Point, j\u00f3venes conservadores expresan preocupaci\u00f3n por el futuro","author":"","date":"diciembre 20, 2025","format":false,"excerpt":"A sus 23 a\u00f1os, Caleb Gasca ya ha cumplido varios de los hitos tradicionales de la adultez. Se gradu\u00f3 de la universidad, consigui\u00f3 trabajo en una oficina de construcci\u00f3n y se cas\u00f3.No obstante, al vivir con los padres de su esposa en el Condado de San Bernardino, California, todav\u00eda siente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452617,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/12\/datos-votacion-elecciones-eeuu-inmigrantes-indocumentados-trax\/","url_meta":{"origin":1449849,"position":4},"title":"Lo que muestran los datos sobre si los inmigrantes indocumentados votan en las elecciones de EE.UU.","author":"","date":"septiembre 12, 2024","format":false,"excerpt":"(CNN) -- Los republicanos de la C\u00e1mara de Representantes consideran la idea de forzar un cierre del gobierno por el tema de los no ciudadanos que votan en las elecciones de EE.UU.La autoridad de financiaci\u00f3n del gobierno vence el 30 de septiembre, y el presidente de la C\u00e1mara de Representantes,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1444119,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/19\/como-tramitar-la-credencial-para-votar-en-las-elecciones-de-mexico-y-cual-es-la-fecha-limite\/","url_meta":{"origin":1449849,"position":5},"title":"\u00bfC\u00f3mo tramitar la credencial para votar en las elecciones de M\u00e9xico y cu\u00e1l es la fecha l\u00edmite?","author":"","date":"enero 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- En M\u00e9xico, es necesario que todos los ciudadanos mayores de 18 a\u00f1os cuenten con la credencial del Instituto Nacional Electoral (INE) para poder votar en las pr\u00f3ximas elecciones generales del 2 de junio, en donde se elegir\u00e1 presidente, diputados, senadores y autoridades locales.En total, se votar\u00e1 para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449849"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449849\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}