{"id":1449856,"date":"2024-05-30T03:03:48","date_gmt":"2024-05-30T10:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/"},"modified":"2024-05-30T03:03:48","modified_gmt":"2024-05-30T10:03:48","slug":"parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","title":{"rendered":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes"},"content":{"rendered":"<p>(CNN) &#8212; El parlamento espa\u00f1ol aprob\u00f3 este jueves una controvertida ley de amnist\u00eda que podr\u00eda beneficiar a cientos de personas que enfrentan procesamiento por su papel en el fallido intento de independencia en Catalu\u00f1a, en Barcelona y sus alrededores, en 2017.<\/p>\n<p>La votaci\u00f3n a favor del proyecto de ley, presentado el a\u00f1o pasado por el gobernante Partido Socialista del presidente Pedro S\u00e1nchez, fue de 177 a 172, anunci\u00f3 el presidente de la c\u00e1mara baja del parlamento espa\u00f1ol.<\/p>\n<p>El apoyo crucial provino de dos partidos separatistas catalanes, Junts (Juntos) y Esquerra Republicana (Izquierda Republicana), cada uno con siete esca\u00f1os en el parlamento espa\u00f1ol.<\/p>\n<p>El principal partido conservador de oposici\u00f3n de Espa\u00f1a, el Partido Popular, y el partido de extrema derecha Vox votaron en contra de la medida. Justo antes de la votaci\u00f3n, la presidenta del gobierno regional de Madrid, Isabel D\u00edaz Ayuso, del Partido Popular, prometi\u00f3 apelar la nueva ley ante el Tribunal Constitucional de Espa\u00f1a, el m\u00e1s alto del pa\u00eds.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El parlamento espa\u00f1ol aprob\u00f3 este jueves una controvertida ley de amnist\u00eda que podr\u00eda beneficiar a cientos de personas que enfrentan procesamiento por su papel en el fallido intento de independencia en Catalu\u00f1a, en Barcelona y sus alrededores, en 2017. La votaci\u00f3n a favor del proyecto de ley, presentado el a\u00f1o pasado por el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449856","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El parlamento espa\u00f1ol aprob\u00f3 este jueves una controvertida ley de amnist\u00eda que podr\u00eda beneficiar a cientos de personas que enfrentan procesamiento por su papel en el fallido intento de independencia en Catalu\u00f1a, en Barcelona y sus alrededores, en 2017. La votaci\u00f3n a favor del proyecto de ley, presentado el a\u00f1o pasado por el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-30T10:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes\",\"datePublished\":\"2024-05-30T10:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\"},\"wordCount\":206,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\",\"name\":\"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-30T10:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes - Noticias","og_description":"(CNN) &#8212; El parlamento espa\u00f1ol aprob\u00f3 este jueves una controvertida ley de amnist\u00eda que podr\u00eda beneficiar a cientos de personas que enfrentan procesamiento por su papel en el fallido intento de independencia en Catalu\u00f1a, en Barcelona y sus alrededores, en 2017. La votaci\u00f3n a favor del proyecto de ley, presentado el a\u00f1o pasado por el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-30T10:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/"},"author":{"name":"","@id":""},"headline":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes","datePublished":"2024-05-30T10:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/"},"wordCount":206,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","name":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-30T10:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El Parlamento espa\u00f1ol aprueba una controvertida ley de amnist\u00eda para los separatistas catalanes","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/30\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-30T10:03:48Z","datePublished":"2024-05-30T10:03:48Z","dateModified":"2024-05-30T10:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El Parlamento espa\\u00f1ol aprueba una controvertida ley de amnist\\u00eda para los separatistas catalanes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/30\\\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/30\\\/parlamento-espanol-aprueba-una-controvertida-ley-de-amnistia-para-los-separatistas-catalanes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-30T10:03:48Z\",\"datePublished\":\"2024-05-30T10:03:48Z\",\"dateModified\":\"2024-05-30T10:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1449406,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/11\/perfil-carles-puigdemont-quien-es-cargos-investigaciones-presidencia-cataluna-exterior-orix\/","url_meta":{"origin":1449856,"position":0},"title":"\u00bfQui\u00e9n es Carles Puigdemont y qu\u00e9 hizo el l\u00edder independentista que busca la presidencia de Catalu\u00f1a desde el exterior?","author":"","date":"mayo 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Carles Puigdemont es una figura pol\u00e9mica y divisiva en la pol\u00edtica de Espa\u00f1a. De la l\u00ednea m\u00e1s independentista catalana, busca desde el exterior llegar otra vez a la presidencia de la Generalitat de Catalu\u00f1a a pesar de tener un proceso en contra por sus acciones separatistas.El regreso\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447255,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/22\/carles-puigdemont-elecciones-cataluna-parlamento-orix\/","url_meta":{"origin":1449856,"position":1},"title":"Carles Puigdemont se presentar\u00e1 a las elecciones al Parlamento de Catalu\u00f1a del 12 de mayo","author":"","date":"marzo 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013\u2013 El expresidente de la Generalitat de Catalu\u00f1a Carles Puigdemont anunci\u00f3 este jueves que se presentar\u00e1 a las elecciones al Parlamento de Catalu\u00f1a del pr\u00f3ximo 12 de mayo.\u201cNo solo se trata de optar a las elecciones. Se trata de proponer mi candidatura a la restituci\u00f3n de la presidencia\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445567,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/17\/que-importancia-tienen-las-elecciones-de-galicia-2024-en-espana\/","url_meta":{"origin":1449856,"position":2},"title":"\u00bfQu\u00e9 importancia tienen las elecciones de Galicia 2024 en Espa\u00f1a?","author":"","date":"febrero 17, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Cerca de 2,7 millones de electores est\u00e1n llamados a participar este domingo 18 de febrero en las elecciones al Parlamento de Galicia, en las que se elegir\u00e1 a los 75 diputados que compondr\u00e1n esta asamblea en la pr\u00f3xima legislatura y que, dependiendo de la representaci\u00f3n que obtenga cada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449380,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/10\/salvador-illa-candidato-elecciones-cataluna-orix\/","url_meta":{"origin":1449856,"position":3},"title":"\u00bfQui\u00e9n es Salvador Illa? Perfil del candidato que lidera las encuestas en Catalu\u00f1a","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Salvador Illa, el candidato a la presidencia de la Generalitat de Catalu\u00f1a por el Partido Socialista, es una figura central de la pol\u00edtica de Espa\u00f1a.Illa propone dejar atr\u00e1s los a\u00f1os del proceso que cobr\u00f3 relevancia en 2010, cuando el Tribunal Supremo de Espa\u00f1a anul\u00f3 o reinterpret\u00f3 varios\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449437,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/13\/analisis-quien-podria-gobernar-cataluna-claves-que-arrojan-resultados-elecciones-parlamento-autonomico-orix\/","url_meta":{"origin":1449856,"position":4},"title":"AN\u00c1LISIS | \u00bfQui\u00e9n podr\u00eda gobernar en Catalu\u00f1a? Estas son las claves que arrojan los resultados de las elecciones al Parlamento auton\u00f3mico","author":"","date":"mayo 13, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Partido de los Socialistas de Catalu\u00f1a, asociado al Partido Socialista Obrero Espa\u00f1ol, fue la fuerza m\u00e1s votada este domingo en las elecciones parlamentarias. Con 42 esca\u00f1os, el candidato de esta formaci\u00f3n para presidir la Generalitat, Salvador Illa, parte con una posici\u00f3n aventajada para intentar hacerse con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449421,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/12\/partido-socialista-cataluna-vence-elecciones-parlamento-autonomico-orix\/","url_meta":{"origin":1449856,"position":5},"title":"Partido Socialista de Catalu\u00f1a vence en elecciones del Parlamento auton\u00f3mico","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El Partido Socialista de Catalu\u00f1a (PSC), liderado por Salvador Illa, ha quedado como la fuerza m\u00e1s votada en las elecciones al Parlamento de la comunidad aut\u00f3noma realizadas este domingo, seg\u00fan datos facilitados por la Generalitat de Catalunya.Con un 99,48% de los votos escrutados, el PSC logr\u00f3 sacar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449856"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449856\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}