{"id":1449895,"date":"2024-05-31T12:03:49","date_gmt":"2024-05-31T19:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/"},"modified":"2024-05-31T12:03:49","modified_gmt":"2024-05-31T19:03:49","slug":"messi-ultimo-partido-seleccion-argentina-copa-america-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","title":{"rendered":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 El capit\u00e1n de la selecci\u00f3n argentina de f\u00fatbol, Lionel Messi, est\u00e1 en la recta final de su participaci\u00f3n en la primera parte del a\u00f1o con el Inter Miami, antes de sumarse al combinado nacional para disputar la Copa Am\u00e9rica en Estados Unidos. Despu\u00e9s de ausentarse en el \u00faltimo encuentro que Inter gan\u00f3 en Canad\u00e1 frente a Vancouver Whitecaps por 2 a 1 el pasado s\u00e1bado, y ser parte del equipo que cay\u00f3 ante Atlanta en Miami (donde marc\u00f3 un gol), el \u201810\u2019 argentino est\u00e1 listo para jugar el \u00faltimo partido con el Inter antes de sumarse al equipo de Lionel Scaloni.<\/p>\n<p>Noventa minutos para volver a ponerse la 10 de la selecci\u00f3n<\/p>\n<p>Desde que volvi\u00f3 de la lesi\u00f3n que lo margin\u00f3 de la gira de amistosos con la selecci\u00f3n en marzo, Messi jug\u00f3 nueve de los \u00faltimos once partidos que disput\u00f3 Inter Miami y mostr\u00f3 un estado de forma fant\u00e1stico desde lo estad\u00edstico y tambi\u00e9n desde lo f\u00edsico. El astro volvi\u00f3 a jugar frente a Colorado el 13 de abril y convirti\u00f3 un gol en los 45 minutos que disput\u00f3.<\/p>\n<p>Lionel Messi marca dos goles ante una actuaci\u00f3n virtuosa en la MLS asiste a la victoria del Inter Miami de 3-1 sobre Nashville SC<\/p>\n<p>Desde su regreso marc\u00f3 ocho goles y adem\u00e1s entreg\u00f3 nueve asistencias en un total de nueve partidos, en los que sum\u00f3 765 minutos. Esto quiere decir que particip\u00f3 en una acci\u00f3n que deriv\u00f3 en gol cada 45 minutos. No solo sus n\u00fameros llaman a ilusionar a los hinchas argentinos, tambi\u00e9n desde lo f\u00edsico, ya que en los \u00faltimos ocho partidos que jug\u00f3 disput\u00f3 la totalidad de los minutos en juego.<\/p>\n<p>El delantero argentino del Inter Miami, Lionel Messi, durante el partido de f\u00fatbol de la Major League Soccer (MLS) entre el Inter Miami CF y el Atlanta United FC el 29 de mayo de 2024. (Foto de CHANDAN KHANNA\/AFP v\u00eda Getty Images)<\/p>\n<p>Si bien el director t\u00e9cnico Gerardo Martino decidi\u00f3 que no viaje a Vancouver para el encuentro del 25 de junio, el entrenador aclar\u00f3 que fue por una cuesti\u00f3n de calendario. Ya en el partido de entresemana frente a Atlanta, Messi volvi\u00f3 a la titularidad y complet\u00f3 el encuentro.<\/p>\n<p>El s\u00e1bado ser\u00e1 su \u00faltimo partido antes de sumarse a los entrenamientos de la selecci\u00f3n, cuando el Inter Miami reciba al St. Louis City.<\/p>\n<p>Con la selecci\u00f3n, como en casa<\/p>\n<p>Cuando el lunes 3 de junio comiencen los entrenamientos de la selecci\u00f3n argentina de cara a la Copa Am\u00e9rica, lo que cambiar\u00e1 para Messi ser\u00e1n sus compa\u00f1eros, pero no el escenario. El equipo campe\u00f3n del mundo en Qatar 2022 har\u00e1 su preparaci\u00f3n en Miami, en el predio de Inter con la vista puesta en los dos partidos amistosos previos a la copa.<\/p>\n<p>El 9 de junio, el equipo de Scaloni jugar\u00e1 su primer amistoso ante Ecuador en el Soldier Field de la ciudad de Chicago. Mientras que el 14, en el estadio Fedex en Washington DC, disputar\u00e1 el \u00faltimo encuentro amistoso frente a Guatemala previo al certamen continental.<\/p>\n<p>Lionel Scaloni convoc\u00f3 a un total de 29 jugadores para la gira previa. Despu\u00e9s del segundo amistoso, el entrenador deber\u00e1 entregar la n\u00f3mina con los 26 nombres definitivos para afrontar la Copa Am\u00e9rica. El 20 de junio marcar\u00e1 el comienzo de la defensa del t\u00edtulo para la selecci\u00f3n argentina cuando enfrente a Canad\u00e1 en la ciudad de Atlanta, en el estadio Mercedes Benz.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212;\u00a0 El capit\u00e1n de la selecci\u00f3n argentina de f\u00fatbol, Lionel Messi, est\u00e1 en la recta final de su participaci\u00f3n en la primera parte del a\u00f1o con el Inter Miami, antes de sumarse al combinado nacional para disputar la Copa Am\u00e9rica en Estados Unidos. Despu\u00e9s de ausentarse en el \u00faltimo encuentro que Inter gan\u00f3 [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449895","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212;\u00a0 El capit\u00e1n de la selecci\u00f3n argentina de f\u00fatbol, Lionel Messi, est\u00e1 en la recta final de su participaci\u00f3n en la primera parte del a\u00f1o con el Inter Miami, antes de sumarse al combinado nacional para disputar la Copa Am\u00e9rica en Estados Unidos. Despu\u00e9s de ausentarse en el \u00faltimo encuentro que Inter gan\u00f3 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T19:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica\",\"datePublished\":\"2024-05-31T19:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\"},\"wordCount\":625,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\",\"name\":\"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-31T19:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212;\u00a0 El capit\u00e1n de la selecci\u00f3n argentina de f\u00fatbol, Lionel Messi, est\u00e1 en la recta final de su participaci\u00f3n en la primera parte del a\u00f1o con el Inter Miami, antes de sumarse al combinado nacional para disputar la Copa Am\u00e9rica en Estados Unidos. Despu\u00e9s de ausentarse en el \u00faltimo encuentro que Inter gan\u00f3 [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","og_site_name":"Noticias","article_published_time":"2024-05-31T19:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/"},"author":{"name":"","@id":""},"headline":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica","datePublished":"2024-05-31T19:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/"},"wordCount":625,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","url":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","name":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-31T19:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Messi juega su \u00faltimo partido antes de sumarse a la selecci\u00f3n argentina para la Copa Am\u00e9rica","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-31T19:03:49Z","datePublished":"2024-05-31T19:03:49Z","dateModified":"2024-05-31T19:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Messi juega su \\u00faltimo partido antes de sumarse a la selecci\\u00f3n argentina para la Copa Am\\u00e9rica\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/31\\\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/31\\\/messi-ultimo-partido-seleccion-argentina-copa-america-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-31T19:03:49Z\",\"datePublished\":\"2024-05-31T19:03:49Z\",\"dateModified\":\"2024-05-31T19:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1445449,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/15\/messi-y-su-frenetica-agenda-le-permitira-estar-presente-en-los-juegos-olimpicos\/","url_meta":{"origin":1449895,"position":0},"title":"Messi y su fren\u00e9tica agenda, \u00bfle permitir\u00e1 estar presente en los Juegos Ol\u00edmpicos?","author":"","date":"febrero 15, 2024","format":false,"excerpt":"(CNN) -- \"Vamos\", suscribi\u00f3 Lionel Messi en el posteo que la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) realiz\u00f3 a los pocos minutos que la Albiceleste consigui\u00f3 el boleto a Par\u00eds 2024.El s\u00edmbolo m\u00e1ximo de la Albiceleste se sum\u00f3 al festejo de la selecci\u00f3n de Argentina sub-23, que este domingo venci\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445451,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/15\/messi-y-su-frenetica-agenda-le-permitira-estar-presente-en-los-juegos-olimpicos-2\/","url_meta":{"origin":1449895,"position":1},"title":"Messi y su fren\u00e9tica agenda, \u00bfle permitir\u00e1 estar presente en los Juegos Ol\u00edmpicos?","author":"","date":"febrero 15, 2024","format":false,"excerpt":"(CNN) -- \"Vamos\", suscribi\u00f3 Lionel Messi en el posteo que la Asociaci\u00f3n del F\u00fatbol Argentino (AFA) realiz\u00f3 a los pocos minutos que la Albiceleste consigui\u00f3 el boleto a Par\u00eds 2024.El s\u00edmbolo m\u00e1ximo de la Albiceleste se sum\u00f3 al festejo de la selecci\u00f3n de Argentina sub-23, que este domingo venci\u00f3 en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456044,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/23\/lionel-messi-2024-dos-titulos-lesiones-deuda-pendiente-orix\/","url_meta":{"origin":1449895,"position":2},"title":"El 2024 de Lionel Messi: dos t\u00edtulos, varias lesiones y una deuda pendiente","author":"","date":"noviembre 23, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El pitazo final del \u00e1rbitro Wilmar Rold\u00e1n en el partido en que la selecci\u00f3n argentina derrot\u00f3 a Per\u00fa el pasado martes, marc\u00f3 no solo el final del encuentro, sino tambi\u00e9n el de la temporada de Lionel Messi. Tras una eliminaci\u00f3n temprana en los playoffs de la Major\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457614,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/18\/desafios-messi-2025-orix\/","url_meta":{"origin":1449895,"position":3},"title":"Los desaf\u00edos de Lionel Messi para el a\u00f1o 2025","author":"","date":"enero 18, 2025","format":false,"excerpt":"Este s\u00e1bado comienza la pretemporada de Inter Miami, con el enfrentamiento con el Club Am\u00e9rica de M\u00e9xico en Las Vegas, y empieza tambi\u00e9n el a\u00f1o futbol\u00edstico n\u00famero 21 para Lionel Messi.En su tercera temporada como jugador de la Major League Soccer (MLS), el 10 argentino todav\u00eda tiene nuevos retos por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456104,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/26\/javier-mascherano-messi-nuevo-entrenador-inter-miami-trax\/","url_meta":{"origin":1449895,"position":4},"title":"Javier Mascherano, excompa\u00f1ero de Lionel Messi, es el nuevo entrenador del Inter Miami","author":"","date":"noviembre 26, 2024","format":false,"excerpt":"(CNN) \u2014 Javier Mascherano, excapit\u00e1n de la selecci\u00f3n de Argentina, ser\u00e1 el nuevo entrenador del Inter Miami, seg\u00fan anunci\u00f3 este martes el club.Mascherano se reencontrar\u00e1 con el legendario delantero Lionel Messi, con quien jug\u00f3 en la selecci\u00f3n nacional y pas\u00f3 casi ocho a\u00f1os en el Barcelona.Este ser\u00e1 el primer cargo\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445829,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/21\/inter-miami-real-salt-lake-messi-mls-previa-orix\/","url_meta":{"origin":1449895,"position":5},"title":"\u00bfC\u00f3mo llega Messi a su debut en la nueva temporada MLS?","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La MLS levanta el tel\u00f3n de la temporada 2024 y no hay mejor acto que tener al \u00faltimo ganador del Bal\u00f3n de Oro y campe\u00f3n del mundo Lionel Messi como atracci\u00f3n principal. Este mi\u00e9rcoles a las 8 p.m., hora de Miami, Inter recibe a Real Salt Lake\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449895","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449895"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449895\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449895"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449895"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449895"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}