{"id":1449904,"date":"2024-05-31T15:03:40","date_gmt":"2024-05-31T22:03:40","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/"},"modified":"2024-05-31T15:03:40","modified_gmt":"2024-05-31T22:03:40","slug":"onu-pondra-fin-mision-asistencia-iraq-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","title":{"rendered":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003"},"content":{"rendered":"<p>(CNN) &#8212;\u00a0El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas adopt\u00f3 por unanimidad el viernes una resoluci\u00f3n que pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq despu\u00e9s de m\u00e1s de dos d\u00e9cadas de la invasi\u00f3n liderada por Estados Unidos en 2003.<\/p>\n<p>La resoluci\u00f3n acuerda que la Misi\u00f3n de Asistencia de las Naciones Unidas para Iraq (UNAMI, por sus siglas en ingl\u00e9s) se encuentra en sus \u00faltimos 19 meses y cesar\u00e1 sus operaciones el 31 de diciembre de 2025.<\/p>\n<p>Despu\u00e9s de esta fecha, la UNAMI cesar\u00e1 todas sus operaciones y pasar\u00e1 a una fase de liquidaci\u00f3n para poner fin a sus actividades en Iraq.<\/p>\n<p>20 a\u00f1os de la guerra en Iraq: \u00bfqui\u00e9nes apoyaron la invasi\u00f3n y qui\u00e9nes no?<\/p>\n<p>La misi\u00f3n fue establecida por una resoluci\u00f3n del Consejo de Seguridad de la ONU en 2003 a petici\u00f3n del Gobierno de Iraq despu\u00e9s de la invasi\u00f3n encabezada por Estados Unidos y la ca\u00edda de Saddam Hussein.<\/p>\n<p>La resoluci\u00f3n solicita al Secretario General de la ONU, en colaboraci\u00f3n con el Gobierno de Iraq, desarrollar un plan de transici\u00f3n y liquidaci\u00f3n para fines de 2024. Este plan guiar\u00e1 la transferencia de las tareas de la UNAMI, garantizar\u00e1 una retirada segura y ordenada de personal y activos, y fij\u00f3 una fecha de finalizaci\u00f3n para las actividades de liquidaci\u00f3n, seg\u00fan un comunicado de la ONU.<\/p>\n<p>El Gobierno de Iraq emiti\u00f3 una declaraci\u00f3n expresando su agradecimiento por la resoluci\u00f3n y reiter\u00f3 que esta decisi\u00f3n sigue la solicitud formal del primer ministro Mohammed al-Sudani al secretario general de la ONU, Antonio Guterres, y al Consejo de Seguridad de la ONU en mayo.<\/p>\n<p>El Gobierno de Iraq destac\u00f3 en su declaraci\u00f3n las capacidades mejoradas de las fuerzas armadas iraqu\u00edes, los r\u00e1pidos avances econ\u00f3micos y de desarrollo del pa\u00eds y los avances en reforma, gobernanza, servicios y bienestar social.<\/p>\n<p>La declaraci\u00f3n del Gobierno dice que el Gobierno reafirma su compromiso con la cooperaci\u00f3n continua, as\u00ed como la asociaci\u00f3n sostenible con las ONU y sus programas de desarrollo en Iraq.<\/p>\n<p>El representante de Estados Unidos ante la ONU, Robert Wood, elogi\u00f3 el papel de la UNAMI en el apoyo a las elecciones, los derechos humanos y el compromiso entre Iraq y Kuwait.<\/p>\n<p>\u201cTodos reconocemos que Iraq ha cambiado dram\u00e1ticamente en los \u00faltimos a\u00f1os y que la misi\u00f3n de la UNAMI necesitaba ser realineada como parte de nuestro compromiso de fomentar un Iraq seguro, estable y soberano. Iraq y la UNAMI tienen mucho de qu\u00e9 enorgullecerse\u201d, dijo Wood.<\/p>\n<p>El Consejo de Seguridad enfatiz\u00f3 la importancia de la cooperaci\u00f3n del Gobierno de Iraq durante esta transici\u00f3n.<\/p>\n<p>El Consejo tambi\u00e9n elogi\u00f3 los esfuerzos de Ira1 para abordar cuestiones internas y avanzar hacia hitos cr\u00edticos, incluidas las pr\u00f3ximas elecciones parlamentarias.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212;\u00a0El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas adopt\u00f3 por unanimidad el viernes una resoluci\u00f3n que pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq despu\u00e9s de m\u00e1s de dos d\u00e9cadas de la invasi\u00f3n liderada por Estados Unidos en 2003. La resoluci\u00f3n acuerda que la Misi\u00f3n de Asistencia de las Naciones [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449904","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003 - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003 - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212;\u00a0El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas adopt\u00f3 por unanimidad el viernes una resoluci\u00f3n que pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq despu\u00e9s de m\u00e1s de dos d\u00e9cadas de la invasi\u00f3n liderada por Estados Unidos en 2003. La resoluci\u00f3n acuerda que la Misi\u00f3n de Asistencia de las Naciones [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-05-31T22:03:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003\",\"datePublished\":\"2024-05-31T22:03:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\"},\"wordCount\":533,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\",\"name\":\"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003 - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-05-31T22:03:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003 - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003 - Noticias","og_description":"(CNN) &#8212;\u00a0El Consejo de Seguridad de la Organizaci\u00f3n de las Naciones Unidas adopt\u00f3 por unanimidad el viernes una resoluci\u00f3n que pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq despu\u00e9s de m\u00e1s de dos d\u00e9cadas de la invasi\u00f3n liderada por Estados Unidos en 2003. La resoluci\u00f3n acuerda que la Misi\u00f3n de Asistencia de las Naciones [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","og_site_name":"Noticias","article_published_time":"2024-05-31T22:03:40+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/"},"author":{"name":"","@id":""},"headline":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003","datePublished":"2024-05-31T22:03:40+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/"},"wordCount":533,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","url":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","name":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003 - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-05-31T22:03:40+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La ONU pondr\u00e1 fin a su misi\u00f3n de asistencia en Iraq m\u00e1s de 20 a\u00f1os despu\u00e9s de la invasi\u00f3n liderada por EE.UU. en 2003","url":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/05\/31\/onu-pondra-fin-mision-asistencia-iraq-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-05-31T22:03:40Z","datePublished":"2024-05-31T22:03:40Z","dateModified":"2024-05-31T22:03:40Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La ONU pondr\\u00e1 fin a su misi\\u00f3n de asistencia en Iraq m\\u00e1s de 20 a\\u00f1os despu\\u00e9s de la invasi\\u00f3n liderada por EE.UU. en 2003\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/31\\\/onu-pondra-fin-mision-asistencia-iraq-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/05\\\/31\\\/onu-pondra-fin-mision-asistencia-iraq-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-05-31T22:03:40Z\",\"datePublished\":\"2024-05-31T22:03:40Z\",\"dateModified\":\"2024-05-31T22:03:40Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459131,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/24\/eeuu-usia-resolucion-onu-ucrania-trax\/","url_meta":{"origin":1449904,"position":0},"title":"Estados Unidos se suma a Rusia para votar en contra de resoluci\u00f3n de la ONU que condena la guerra en Ucrania","author":"","date":"febrero 24, 2025","format":false,"excerpt":"Estados Unidos se uni\u00f3 este lunes a Rusia para votar en contra de una resoluci\u00f3n de la Asamblea General de la ONU que condena la guerra de Rusia contra Ucrania, en un sorprendente cambio con respecto a a\u00f1os de pol\u00edtica estadounidense.El voto en contra de la resoluci\u00f3n respaldada por Ucrania\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470222,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/19\/iraq-retirada-total-fuerzas-estadounidenses-trax\/","url_meta":{"origin":1449904,"position":1},"title":"Iraq anuncia la retirada total de las fuerzas estadounidenses de su territorio federal","author":"","date":"enero 19, 2026","format":false,"excerpt":"El Gobierno de Iraq anunci\u00f3 el domingo que las fuerzas estadounidenses hab\u00edan completado una \u201cretirada total\u201d de las instalaciones militares dentro del territorio federal del pa\u00eds, lo que excluye la regi\u00f3n semiaut\u00f3noma del Kurdist\u00e1n, donde las tropas estadounidenses permanecen.El Ministerio de Defensa de Iraq inform\u00f3 que el \u00faltimo contingente de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449391,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/10\/asamblea-general-onu-vota-reconsiderar-membresia-palestina-trax\/","url_meta":{"origin":1449904,"position":2},"title":"La Asamblea General de la ONU vota pedir al Consejo de Seguridad reconsiderar la membres\u00eda palestina","author":"","date":"mayo 10, 2024","format":false,"excerpt":"(CNN) -- Una resoluci\u00f3n de la Asamblea General de la Organizaci\u00f3n de las Naciones Unidas, que pide al Consejo de Seguridad de la ONU reconsiderar la membres\u00eda palestina en la ONU, fue aprobada este viernes con 143 votos a favor, nueve votos en contra y 25 abstenciones.La resoluci\u00f3n pide al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459089,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/22\/resolucion-onu-guerra-ucrania-trax\/","url_meta":{"origin":1449904,"position":3},"title":"EE.UU. propone su propia resoluci\u00f3n en la ONU por aniversario de la guerra en Ucrania tras no respaldar declaraci\u00f3n europea","author":"","date":"febrero 22, 2025","format":false,"excerpt":"Estados Unidos propuso su propia resoluci\u00f3n de las Naciones Unidas para conmemorar el tercer aniversario de la guerra de Rusia en Ucrania, tras negarse a respaldar una resoluci\u00f3n redactada por Kyiv y apoyada por Europa.El secretario de Estado, Marco Rubio, la describi\u00f3 como \u201cuna resoluci\u00f3n sencilla e hist\u00f3rica (\u2026) que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452916,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/21\/argentina-seis-paises-gobierno-venezolano-fin-represion-onu-orix\/","url_meta":{"origin":1449904,"position":4},"title":"Argentina y otros seis pa\u00edses instan al gobierno venezolano a poner fin a la represi\u00f3n ante el Consejo de DD.HH. de la ONU","author":"","date":"septiembre 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El representante de Argentina ante las Naciones Unidas en Ginebra, Carlos Foradori, inst\u00f3 a Venezuela en el Consejo de Derechos Humanos a liberar a quienes han sido detenidos arbitrariamente y a poner fin a la represi\u00f3n y persecuci\u00f3n por cuestiones pol\u00edticas, inform\u00f3 la Canciller\u00eda argentina este viernes.Ecuador\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1468655,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/11\/24\/gaza-humanitarian-foundation-cerrara-trax\/","url_meta":{"origin":1449904,"position":5},"title":"La controvertida Fundaci\u00f3n Humanitaria de Gaza pondr\u00e1 fin a sus operaciones en el enclave palestino","author":"","date":"noviembre 24, 2025","format":false,"excerpt":"La controvertida Fundaci\u00f3n Humanitaria de Gaza oficialmente pondr\u00e1 fin a sus operaciones en el territorio palestino, seg\u00fan dos fuentes israel\u00edes, despu\u00e9s de haber suspendido su labor en el enclave el mes pasado tras el inicio del alto el fuego.\u201cEstamos poniendo fin a nuestras operaciones porque hemos cumplido nuestra misi\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449904"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449904\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}