{"id":1449925,"date":"2024-06-01T19:03:50","date_gmt":"2024-06-02T02:03:50","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/"},"modified":"2024-06-01T19:03:50","modified_gmt":"2024-06-02T02:03:50","slug":"5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","title":{"rendered":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013 Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico por el partido Movimiento Ciudadano, ha presentado m\u00e1s de 30 propuestas de gobierno divididas en tres ejes: justicia, prosperidad e igualdad.<\/p>\n<p>M\u00e1ynez, quien afirma ser el candidato de la \u201cnueva pol\u00edtica\u201d y critica a sus oponentes llam\u00e1ndolas \u201clas candidatas de la vieja pol\u00edtica\u201d, ha enfocado su campa\u00f1a principalmente en la poblaci\u00f3n joven y promete trabajar en unidad por el pa\u00eds. Estas son sus cinco propuestas clave:<\/p>\n<p>Regulaci\u00f3n de las drogas<\/p>\n<p>El excoordinador de diputados de la bancada naranja, color con el que de identifica su partido, promete implementar un Plan Nacional de Pacificaci\u00f3n que incluye regular el mercado de drogas, seg\u00fan consta en su plan &#171;M\u00e9xico con justicia&#187; que plantea cuatro medidas:<\/p>\n<p>Pasar de un modelo prohibicionista de las drogas a uno de regulaci\u00f3n.<br \/>\nEliminar el delito de posesi\u00f3n simple de drogas, para dejar de criminalizar la pobreza.<br \/>\nQue las comunidades y pueblos hist\u00f3ricamente afectados por el prohibicionismo sean part\u00edcipes de los beneficios de la regulaci\u00f3n.<br \/>\nAmnist\u00eda a personas en prisi\u00f3n por delitos relacionados con la portaci\u00f3n y consumo de cannabis.<\/p>\n<p>Un estudio de la Consultora AC afirma que en M\u00e9xico\u00a0operan al menos 175 grupos criminales\u00a0que cubren hasta el 80 % del territorio nacional, algo que \u2013seg\u00fan expertos\u2013 refleja el fracaso en las estrategias de seguridad por parte de diversos gobiernos desde 2006.<\/p>\n<p>\u00bfQui\u00e9n es Jorge \u00c1lvarez M\u00e1ynez, el candidato de Movimiento Ciudadano que va por la presidencia de M\u00e9xico?<\/p>\n<p>Otro\u00a0informe\u00a0del Observatorio Mexicano de Salud Mental y Adicciones se\u00f1ala que el n\u00famero de consumidores de anfetaminas, metanfetaminas, \u00e9xtasis y otros estimulantes de uso m\u00e9dico creci\u00f3 218 %, de 2017 a 2022.<\/p>\n<p>V\u00eda civil para la paz y la seguridad<\/p>\n<p>M\u00e1ynez ha insistido en poner fin a la militarizaci\u00f3n del pa\u00eds que inici\u00f3 a finales de 2006 con la llamada guerra contra las drogas del expresidente Felipe Calder\u00f3n. Para lograrlo propone crear la Academia de Alta Formaci\u00f3n Policial, fortalecer a los polic\u00edas con salarios y condiciones dignas, as\u00ed como cambiar el modelo de Ministerio P\u00fablico a polic\u00eda investigadora.<\/p>\n<p>El plan tambi\u00e9n contempla la creaci\u00f3n de una polic\u00eda de Caminos Federal y convenios con los estados, polic\u00edas y estatales de caminos, as\u00ed como delimitar las tareas del ej\u00e9rcito y la Guardia Nacional a territorios de altos \u00edndices de violencia y el regreso gradual de las Fuerzas Armadas a sus cuarteles.<\/p>\n<p>El Inventario Nacional de lo Militarizado \u2013una base de datos que documenta la militarizaci\u00f3n en M\u00e9xico publicada a finales de abril\u2013 se\u00f1ala que entre 2006 y 2023 los tres niveles de gobierno transfirieron funciones y presupuesto civiles a las fuerzas armadas en al menos 291 ocasiones a trav\u00e9s distintas reformas, acuerdos presidenciales y convenios particulares.<\/p>\n<p>En el actual gobierno, la militarizaci\u00f3n no s\u00f3lo ocurri\u00f3 con la seguridad p\u00fablica, las fuerzas armadas tambi\u00e9n tuvieron tareas civiles como la protecci\u00f3n al medio ambiente, la pol\u00edtica social, la salud y las obras p\u00fablica, se\u00f1ala el informe realizado por organizaciones de la sociedad civil.<\/p>\n<p>Las 5 propuestas clave de X\u00f3chitl G\u00e1lvez para ser presidenta de M\u00e9xico<\/p>\n<p>Reforma Econ\u00f3mica<\/p>\n<p>En su programa \u201cUn buen gobierno para M\u00e9xico\u201d M\u00e1ynez propone una reforma econ\u00f3mica gradual para financiar gastos en educaci\u00f3n, salud y otros rubros, a trav\u00e9s de 8 puntos clave:<\/p>\n<p>Sistema universal de pensiones con perspectiva de g\u00e9nero<br \/>\nDerechos e ingresos laborales garantizados<br \/>\nSeguro de desempleo temporal<br \/>\nIngreso vital de emergencia<br \/>\nDignificaci\u00f3n del trabajo agrario y campesino<br \/>\nReforma fiscal progresiva<br \/>\nCreaci\u00f3n de un organismo aut\u00f3nomo que dise\u00f1e la Ley de Ingresos y el Presupuesto de Egresos<br \/>\nProfesionalizaci\u00f3n de las Micro, Peque\u00f1as y Medianas Empresas (MIPyMES)<\/p>\n<p>Programa para la transici\u00f3n energ\u00e9tica<\/p>\n<p>Contemplado en el eje de prosperidad, propone incrementar las metas para la generaci\u00f3n de energ\u00edas por medio de fuentes renovables que sean, a su vez, vinculantes. Tambi\u00e9n propone reducir de manera gradual los subsidios a los combustibles f\u00f3siles para orientarlos en el aprovechamiento de energ\u00edas renovables.<\/p>\n<p>El proyecto de M\u00e1ynez plantea transformar gradualmente a la Comisi\u00f3n Federal de Electricidad (CFE) y a Pemex en empresas de energ\u00eda renovable y limpia y plantea el cierre de las refiner\u00edas de Tula, en Hidalgo, y Cadereyta, en Nuevo Le\u00f3n.<\/p>\n<p>Las 5 propuestas clave de Claudia Sheinbaum para ser presidenta de M\u00e9xico<\/p>\n<p>M\u00e9xico sigue dependiendo en gran medida del petr\u00f3leo, el gas y el carb\u00f3n y los combustibles f\u00f3siles representan el 86% del suministro total de energ\u00eda, mientras que las energ\u00edas renovables solo suponen el 8%, seg\u00fan Carbon Brief.<\/p>\n<p>Plan Educativo<\/p>\n<p>En materia educativa, el abanderado de Movimiento Ciudadano promete incrementar la oferta educativa para llevar a un mill\u00f3n de j\u00f3venes a las universidades, duplicar el total de becas en educaci\u00f3n superior y tejer alianzas con universidades privadas para ampliar la cobertura.<\/p>\n<p>Para las escuelas de educaci\u00f3n b\u00e1sica, propone ampliar la cobertura escolar con incentivos para evitar la deserci\u00f3n antes de concluir la secundaria, que todos los planteles ofrezcan comidas completas y nutritivas y horario extendido con clases de arte y deportes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2013 Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico por el partido Movimiento Ciudadano, ha presentado m\u00e1s de 30 propuestas de gobierno divididas en tres ejes: justicia, prosperidad e igualdad. M\u00e1ynez, quien afirma ser el candidato de la \u201cnueva pol\u00edtica\u201d y critica a sus oponentes llam\u00e1ndolas \u201clas candidatas de la vieja pol\u00edtica\u201d, [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449925","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2013 Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico por el partido Movimiento Ciudadano, ha presentado m\u00e1s de 30 propuestas de gobierno divididas en tres ejes: justicia, prosperidad e igualdad. M\u00e1ynez, quien afirma ser el candidato de la \u201cnueva pol\u00edtica\u201d y critica a sus oponentes llam\u00e1ndolas \u201clas candidatas de la vieja pol\u00edtica\u201d, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-02T02:03:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico\",\"datePublished\":\"2024-06-02T02:03:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\"},\"wordCount\":926,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\",\"name\":\"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-02T02:03:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico - Noticias","og_description":"(CNN Espa\u00f1ol) \u2013 Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico por el partido Movimiento Ciudadano, ha presentado m\u00e1s de 30 propuestas de gobierno divididas en tres ejes: justicia, prosperidad e igualdad. M\u00e1ynez, quien afirma ser el candidato de la \u201cnueva pol\u00edtica\u201d y critica a sus oponentes llam\u00e1ndolas \u201clas candidatas de la vieja pol\u00edtica\u201d, [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-02T02:03:50+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/"},"author":{"name":"","@id":""},"headline":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico","datePublished":"2024-06-02T02:03:50+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/"},"wordCount":926,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","name":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-02T02:03:50+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Las 5 propuestas clave de Jorge \u00c1lvarez M\u00e1ynez, candidato a la presidencia de M\u00e9xico","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/01\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-02T02:03:50Z","datePublished":"2024-06-02T02:03:50Z","dateModified":"2024-06-02T02:03:50Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Las 5 propuestas clave de Jorge \\u00c1lvarez M\\u00e1ynez, candidato a la presidencia de M\\u00e9xico\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/01\\\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/01\\\/5-propuestas-clave-jorge-alvarez-maynez-candidato-presidencia-mexico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-02T02:03:50Z\",\"datePublished\":\"2024-06-02T02:03:50Z\",\"dateModified\":\"2024-06-02T02:03:50Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448281,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/19\/alvarez-maynez-apuesta-jovenes-propuestas-convencion-bancaria-mexico-orix\/","url_meta":{"origin":1449925,"position":0},"title":"\u00c1lvarez M\u00e1ynez apuesta por los j\u00f3venes en sus propuestas ante la Convenci\u00f3n Bancaria de M\u00e9xico","author":"","date":"abril 19, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El candidato a la presidencia de M\u00e9xico por Movimiento Ciudadano, Jorge \u00c1lvarez M\u00e1ynez, se present\u00f3 en la Convenci\u00f3n Bancaria este viernes y sus principales propuestas incluyeron potenciar el \u201cnearshoring\u201d en M\u00e9xico \u2013como lo \"est\u00e1 capitalizando Nuevo Le\u00f3n\"\u2013 y vincular la educaci\u00f3n con el sector productivo.Con \"nearshoring\", el candidato\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445920,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/22\/quien-es-jorge-alvarez-maynez-candidato-mexico-orix\/","url_meta":{"origin":1449925,"position":1},"title":"\u00bfQui\u00e9n es Jorge \u00c1lvarez M\u00e1ynez, el joven candidato que va por la presidencia de M\u00e9xico?","author":"","date":"febrero 22, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Jorge \u00c1lvarez M\u00e1ynez es un joven diputado federal del partido Movimiento Ciudadano. A sus 38 a\u00f1os competir\u00e1 por la presidencia de M\u00e9xico contra las candidatas del oficialismo, Claudia Sheinbaum, y la aspirante del frente opositor, X\u00f3chitl G\u00e1lvez.En diciembre de 2023, el legislador se desempe\u00f1\u00f3 como coordinador de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449591,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/20\/tercer-debate-presidencial-mexico-lo-mejor-del-ultimo-cara-a-cara-entre-sheinbaum-galvez-y-maynez-trax\/","url_meta":{"origin":1449925,"position":2},"title":"Tercer debate presidencial en M\u00e9xico: lo mejor del \u00faltimo cara a cara entre Sheinbaum, G\u00e1lvez y M\u00e1ynez","author":"","date":"mayo 20, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) --\u00a0 Este domingo se realiz\u00f3 el tercer y \u00faltimo debate presidencial rumbo a las elecciones generales del 2 de junio en M\u00e9xico. En el encuentro se discuti\u00f3, entre otros temas, el problema de la inseguridad, uno de los asuntos m\u00e1s preocupantes para los electores.El debate cont\u00f3 con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446160,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/01\/elecciones-presidenciales-mexico-2024-candidatos-presidenciales-orix\/","url_meta":{"origin":1449925,"position":3},"title":"Elecciones presidenciales de M\u00e9xico 2024: estos son los candidatos","author":"","date":"marzo 1, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Las elecciones generales del 2 de junio de 2024 en M\u00e9xico ser\u00e1n las m\u00e1s grandes de la historia, seg\u00fan el Instituto Nacional Electoral (INE), debido a que se espera la afluencia de unos 98 millones de posibles votantes, lo que representa entre 8 y 9 millones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1446463,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/03\/04\/elecciones-presidenciales-mexico-2024-candidatos-presidenciales-orix-2\/","url_meta":{"origin":1449925,"position":4},"title":"Elecciones presidenciales de M\u00e9xico 2024: estos son los candidatos","author":"","date":"marzo 4, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Las elecciones generales del 2 de junio de 2024 en M\u00e9xico ser\u00e1n las m\u00e1s grandes de la historia, seg\u00fan el Instituto Nacional Electoral (INE), debido a que se espera la afluencia de unos 98 millones de posibles votantes, lo que representa entre 8 y 9 millones de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449699,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/22\/9-muertos-decenas-heridos-cierre-de-campana-movimiento-ciudadano-orix\/","url_meta":{"origin":1449925,"position":5},"title":"Al menos 9 muertos y 50 heridos tras accidente en evento de campa\u00f1a de \u00c1lvarez M\u00e1ynez en Nuevo Le\u00f3n","author":"","date":"mayo 22, 2024","format":false,"excerpt":"(CNN En Espa\u00f1ol) -- Al menos nueve personas murieron y decenas resultaron heridas este mi\u00e9rcoles durante un mitin de campa\u00f1a del candidato presidencial Jorge \u00c1lvarez M\u00e1ynez en el municipio de San Pedro Garza Garc\u00eda, Nuevo Le\u00f3n, de acuerdo con fuentes oficiales.A trav\u00e9s de su cuenta de X, el gobernador de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449925","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449925"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449925\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449925"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449925"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449925"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}