{"id":1449930,"date":"2024-06-02T02:03:47","date_gmt":"2024-06-02T09:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/"},"modified":"2024-06-02T02:03:47","modified_gmt":"2024-06-02T09:03:47","slug":"guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","title":{"rendered":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos"},"content":{"rendered":"<p>(CNN) &#8212; La brutal invasi\u00f3n rusa de Ucrania brind\u00f3 a los servicios de inteligencia estadounidenses una rara oportunidad para reclutar a miembros del Kremlin furiosos con el manejo de la guerra.<\/p>\n<p>\u201cEl descontento crea para nosotros una oportunidad \u00fanica en una generaci\u00f3n\u201d, dijo el a\u00f1o pasado el director de la CIA, Bill Burns, durante un discurso en el Reino Unido. &#171;Estamos muy abiertos a los negocios&#187;.<\/p>\n<p>&#171;Ese negocio es el intercambio de informaci\u00f3n que el activo o agente proporcionar\u00eda para algo que desean&#187;, dijo David McCloskey, exoficial de la CIA y autor de Mosc\u00fa X. &#171;Queremos personas que tengan alguna idea de cu\u00e1les son las prioridades de los l\u00edderes [rusos], de lo que est\u00e1n tratando de lograr&#187;.<\/p>\n<p>El esfuerzo de reclutamiento en curso est\u00e1 lejos de ser un secreto de estado. La CIA ha publicado videos en ruso en las redes sociales apelando al patriotismo de los rusos descontentos con acceso a informaci\u00f3n que podr\u00eda ser \u00fatil para Estados Unidos.<\/p>\n<p>El esfuerzo destaca la evoluci\u00f3n de un servicio de inteligencia que hist\u00f3ricamente ha llevado a cabo su misi\u00f3n esencial de contrarrestar las amenazas a la seguridad nacional e informar a los responsables pol\u00edticos bajo un manto de secreto.<\/p>\n<p>El edificio del Ministerio de Relaciones Exteriores de Rusia se ve detr\u00e1s de un cartel que muestra la Z, una insignia t\u00e1ctica de las tropas rusas en Ucrania, el 13 de octubre de 2022. (Cr\u00e9dito: Alexander Nemenov\/AFP\/Getty Images)<\/p>\n<p>De hecho, hasta que el impopular interno y ef\u00edmero director de la CIA, James Schlesinger, finalmente coloc\u00f3 un letrero en una carretera que marcaba el sitio de la sede de la organizaci\u00f3n ultrasecreta en Virginia en 1973, su misma ubicaci\u00f3n hab\u00eda estado protegida del p\u00fablico.<\/p>\n<p>Un avance r\u00e1pido hasta el d\u00eda de hoy, cuando la agencia de espionaje no solo es omnipresente en las plataformas de redes sociales, sino que est\u00e1 utilizando activamente su nueva presencia p\u00fablica para lograr uno de los objetivos principales de la CIA: reclutar esp\u00edas extranjeros para robar secretos.<\/p>\n<p>Las publicaciones han incluido instrucciones paso a paso para los posibles informantes rusos sobre c\u00f3mo evitar la detecci\u00f3n por parte de los servicios de seguridad de Rusia mediante el uso de redes privadas virtuales, o VPN, y el navegador web Tor para comunicarse de forma an\u00f3nima y mediante cifrado con la agencia de la siguiente manera. llamada Red Oscura.<\/p>\n<p>El FBI lanz\u00f3 un esfuerzo similar destinado a reclutar fuentes del gobierno ruso en Estados Unidos, incluyendo anuncios de redes sociales dirigidos geogr\u00e1ficamente a tel\u00e9fonos ubicados cerca de la embajada de Rusia en Washington.<\/p>\n<p>&#171;Este llamamiento directo es un enfoque inusual, pero podr\u00eda resultar eficaz para llegar a una poblaci\u00f3n rusa con pocas opciones para expresar su descontento&#187;, dijo Douglas London, ex jefe de estaci\u00f3n de la CIA destinado en el extranjero. &#171;A los rusos enojados con la corrupci\u00f3n y los abusos sancionados por el Estado por parte del Kremlin, sin forma de actuar abiertamente, les quedan pocas alternativas adem\u00e1s de encontrar apoyo externo&#187;.<\/p>\n<p>Pero si bien la tecnolog\u00eda es nueva, el espionaje ha apuntalado, y a menudo socavado, las relaciones entre Estados Unidos y Rusia durante d\u00e9cadas.<\/p>\n<p>Esa batalla secreta entre los servicios de inteligencia es el tema central de un nuevo documental de CNN-BBC \u2013 \u201c Secretos y esp\u00edas \u201d \u2013 que se estrena el domingo a las 10 p.m., hora del Este.<\/p>\n<p>Con entrevistas nunca antes escuchadas de esp\u00edas de la Guerra Fr\u00eda y de los traidores que sellaron su destino, \u201cSecretos y esp\u00edas\u201d rastrea a los agentes que trabajaron detr\u00e1s de escena para robar y compartir inteligencia vital mientras el mundo estaba al borde de una guerra nuclear.<\/p>\n<p>Se muestra un sello del FBI en el edificio del FBI J. Edgar Hoover en Washington, DC, el 9 de agosto de 2022. (Cr\u00e9dito: Stefani Reynolds\/AFP\/Getty Images)<\/p>\n<p>M\u00e1s de 30 a\u00f1os despu\u00e9s de la disoluci\u00f3n de la Uni\u00f3n Sovi\u00e9tica, el mundo regres\u00f3 a un per\u00edodo de conflicto entre grandes potencias. En su \u00faltimo libro , Jim Sciutto, analista jefe de seguridad nacional de CNN, lo describe como \u201cuna ruptura definitiva entre la era posterior a la Guerra Fr\u00eda y una era completamente nueva e incierta\u201d.<\/p>\n<p>Al igual que la Guerra Fr\u00eda del pasado, el espionaje sigue siendo una herramienta vital para ambos lados del \u00faltimo conflicto, como lo demuestran los oficiales de inteligencia estadounidenses expertos en tecnolog\u00eda que intentan reclutar nuevos activos a plena vista, y los agentes vinculados a Rusia que, seg\u00fan se informa, aumentan sus operaciones en toda Europa.<\/p>\n<p>Si bien el espionaje es ilegal en todas las naciones del mundo, y los agentes encubiertos ciertamente han sido utilizados con prop\u00f3sitos nefastos como sabotaje, asesinato e interferencia electoral, \u201cSecretos y esp\u00edas\u201d revela una funci\u00f3n menos conocida e hist\u00f3ricamente cr\u00edtica de Espionaje: para reducir la incertidumbre y los errores de c\u00e1lculo entre adversarios con armas nucleares.<\/p>\n<p>Como subraya el documental, las lecciones de espionaje de la Guerra Fr\u00eda bien podr\u00edan determinar la futura estabilidad global.<\/p>\n<p>&#171;Tienes que conocer a tu enemigo&#187;, dijo el historiador presidencial de CNN, Tim Naftali. &#171;Si no lo haces, puedes asustar a tu enemigo para que haga algo que ninguno de los dos quiere que suceda&#187;.<\/p>\n<p>\u2013Sarah Moon, Alex Marquardt y Donie O&#8217;Sullivan de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; La brutal invasi\u00f3n rusa de Ucrania brind\u00f3 a los servicios de inteligencia estadounidenses una rara oportunidad para reclutar a miembros del Kremlin furiosos con el manejo de la guerra. \u201cEl descontento crea para nosotros una oportunidad \u00fanica en una generaci\u00f3n\u201d, dijo el a\u00f1o pasado el director de la CIA, Bill Burns, durante un [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1449930","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; La brutal invasi\u00f3n rusa de Ucrania brind\u00f3 a los servicios de inteligencia estadounidenses una rara oportunidad para reclutar a miembros del Kremlin furiosos con el manejo de la guerra. \u201cEl descontento crea para nosotros una oportunidad \u00fanica en una generaci\u00f3n\u201d, dijo el a\u00f1o pasado el director de la CIA, Bill Burns, durante un [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-02T09:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos\",\"datePublished\":\"2024-06-02T09:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\"},\"wordCount\":954,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\",\"name\":\"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-02T09:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","og_locale":"es_ES","og_type":"article","og_title":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos - Noticias","og_description":"(CNN) &#8212; La brutal invasi\u00f3n rusa de Ucrania brind\u00f3 a los servicios de inteligencia estadounidenses una rara oportunidad para reclutar a miembros del Kremlin furiosos con el manejo de la guerra. \u201cEl descontento crea para nosotros una oportunidad \u00fanica en una generaci\u00f3n\u201d, dijo el a\u00f1o pasado el director de la CIA, Bill Burns, durante un [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-02T09:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/"},"author":{"name":"","@id":""},"headline":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos","datePublished":"2024-06-02T09:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/"},"wordCount":954,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","name":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-02T09:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\u00edas rusos","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/02\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-02T09:03:47Z","datePublished":"2024-06-02T09:03:47Z","dateModified":"2024-06-02T09:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La guerra de Ucrania es una gran oportunidad para que la inteligencia estadounidense reclute esp\\u00edas rusos\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/02\\\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/02\\\/guerra-ucrania-oportunidad-inteligencia-estadounidense-reclute-espias-rusos-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-02T09:03:47Z\",\"datePublished\":\"2024-06-02T09:03:47Z\",\"dateModified\":\"2024-06-02T09:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1459521,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/05\/director-cia-suspendio-apoyo-inteligencia-ucrania-trax\/","url_meta":{"origin":1449930,"position":0},"title":"El director de la CIA afirma que EE.UU. suspendi\u00f3 el apoyo de inteligencia a Ucrania","author":"","date":"marzo 5, 2025","format":false,"excerpt":"El director de la CIA, John Ratcliffe, dijo este mi\u00e9rcoles que Estados Unidos suspendi\u00f3 el apoyo de inteligencia y los env\u00edos de armas a Ucrania tras el enfrentamiento en la Oficina Oval entre el presidente Volodymyr Zelensky y el presidente de Estados Unidos, Donald Trump, el viernes pasado.\u201cTrump ten\u00eda una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445727,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/20\/muere-en-espana-el-piloto-ruso-que-deserto-ante-ucrania-en-septiembre-pasado-segun-la-direccion-de-inteligencia-de-defensa-de-ucrania\/","url_meta":{"origin":1449930,"position":1},"title":"Muere en Espa\u00f1a el piloto ruso que desert\u00f3 ante Ucrania en septiembre pasado, seg\u00fan la Direcci\u00f3n de Inteligencia de Defensa de Ucrania","author":"","date":"febrero 20, 2024","format":false,"excerpt":"(CNN) -- Muri\u00f3 el piloto de helic\u00f3ptero ruso Maxim Kuzminov, que desert\u00f3 en Ucrania en septiembre pasado en lo que fue una operaci\u00f3n dram\u00e1tica, le dijo a CNN la Direcci\u00f3n de Inteligencia de Defensa (GUR) de Ucrania.La declaraci\u00f3n se produce mientras las autoridades espa\u00f1olas investigan la muerte de un hombre\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445834,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/21\/piloto-ruso-espana-kuzminov-deserto-muerto-ucrania-trax\/","url_meta":{"origin":1449930,"position":2},"title":"Muere en Espa\u00f1a el piloto ruso que desert\u00f3 ante Ucrania en septiembre pasado, seg\u00fan la Direcci\u00f3n de Inteligencia de Defensa de Ucrania","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN) -- Muri\u00f3 el piloto de helic\u00f3ptero ruso Maxim Kuzminov, que desert\u00f3 en Ucrania en septiembre pasado en lo que fue una operaci\u00f3n dram\u00e1tica, le dijo a CNN la Direcci\u00f3n de Inteligencia de Defensa (GUR) de Ucrania.La noticia llega despu\u00e9s de que la Guardia Civil espa\u00f1ola en la provincia de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452510,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/07\/cia-y-mi6-aparicion-publica-sin-precedentes-londres-trax\/","url_meta":{"origin":1449930,"position":3},"title":"Los jefes de la CIA y del MI6 hacen una aparici\u00f3n p\u00fablica conjunta sin precedentes en Londres","author":"","date":"septiembre 7, 2024","format":false,"excerpt":"(CNN) -- Los jefes de la CIA de Estados Unidos y del servicio de inteligencia exterior del Reino Unido, conocido como MI6, destacaron la importancia de la colaboraci\u00f3n de inteligencia entre sus pa\u00edses en una aparici\u00f3n p\u00fablica conjunta sin precedentes este s\u00e1bado en Londres.El evento, un debate en el Financial\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458787,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/15\/funcionarios-trump-reunion-rusos-ucrania-trax\/","url_meta":{"origin":1449930,"position":4},"title":"Altos cargos del Gobierno de Trump se reunir\u00e1n con importantes funcionarios rusos para iniciar conversaciones sobre Ucrania","author":"","date":"febrero 15, 2025","format":false,"excerpt":"Altos funcionarios de la administraci\u00f3n Trump est\u00e1n listos para reunirse con importantes cargos rusos para iniciar conversaciones destinadas a poner fin a la guerra en Ucrania, seg\u00fan m\u00faltiples fuentes.Se espera que el asesor de Seguridad Nacional, Mike Waltz, el secretario de Estado, Marco Rubio, y el enviado a Medio Oriente,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1445818,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/02\/21\/quien-era-maxim-kuzminov-piloto-ruso-deserto-asesinado-en-espana\/","url_meta":{"origin":1449930,"position":5},"title":"\u00bfQui\u00e9n era Maxim Kuzminov, el piloto ruso que desert\u00f3 y que fue asesinado en Espa\u00f1a?","author":"","date":"febrero 21, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Este martes, el piloto de helic\u00f3ptero ruso Maxim Kuzminov \u2014quien hab\u00eda desertado en Ucrania en septiembre pasado en lo que fue una operaci\u00f3n dram\u00e1tica\u2014 fue asesinado en Espa\u00f1a, seg\u00fan autoridades ucranianas y espa\u00f1olas.Kuzminov fue asesinado a tiros el 13 de febrero dentro del estacionamiento de un edificio\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1449930"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1449930\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1449930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1449930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1449930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}