{"id":1450036,"date":"2024-06-04T16:03:46","date_gmt":"2024-06-04T23:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/"},"modified":"2024-06-04T16:03:46","modified_gmt":"2024-06-04T23:03:46","slug":"pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","title":{"rendered":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, mostr\u00f3 sorpresa este martes, despu\u00e9s de que el Juzgado de Instrucci\u00f3n n\u00famero 41 de Madrid citara a declarar a su esposa, Bego\u00f1a G\u00f3mez, el pr\u00f3ximo 5 de julio, en el marco de la causa que la investiga por la presunta comisi\u00f3n de los delitos de corrupci\u00f3n en los negocios y tr\u00e1fico de influencias.<\/p>\n<p>\u201cEsta decisi\u00f3n se anuncia s\u00f3lo cinco d\u00edas antes de que se celebren elecciones al Parlamento Europeo, lo cual resulta extra\u00f1o\u201d, se\u00f1al\u00f3 S\u00e1nchez en una nueva carta dirigida a la ciudadan\u00eda que comparti\u00f3 en sus redes sociales.<\/p>\n<p>Justicia de Espa\u00f1a cita a declarar a Bego\u00f1a G\u00f3mez, esposa de Pedro S\u00e1nchez, como investigada<\/p>\n<p>\u201cHabitualmente, se ha seguido la regla no escrita de no dictar resoluciones susceptibles de condicionar el desarrollo normal de una campa\u00f1a electoral y, por tanto, el voto de los ciudadanos. En este caso, resulta evidente que esta pr\u00e1ctica no se ha respetado. Dejo al lector extraer sus propias conclusiones\u201d, a\u00f1adi\u00f3 S\u00e1nchez.<\/p>\n<p>Como ha hecho en ocasiones anteriores, el l\u00edder del Ejecutivo espa\u00f1ol se\u00f1al\u00f3 que esta situaci\u00f3n responde a una campa\u00f1a promovida por los l\u00edderes de la oposici\u00f3n \u201ccon el fin de quebrarme en el plano pol\u00edtico y personal\u201d.<\/p>\n<p>S\u00e1nchez defendi\u00f3 a su esposa, de quien dijo \u201ces una mujer trabajadora y honesta que reivindica su derecho a trabajar\u201d, agregando que \u201cno hay nada detr\u00e1s de esta acusaci\u00f3n\u201d promovida por la organizaci\u00f3n de ultraderecha Manos Limpias.<\/p>\n<p>\u201cMi decisi\u00f3n de continuar al frente de la Presidencia del Gobierno es m\u00e1s firme que nunca\u201d, se\u00f1al\u00f3 S\u00e1nchez en la misiva, recordando su decisi\u00f3n de mantenerse en el cargo tras haber anunciado un per\u00edodo de reflexi\u00f3n a finales de abril, cuando se dio a conocer la investigaci\u00f3n contra su mujer.<\/p>\n<p>\u00bfQu\u00e9 se sabe de la investigaci\u00f3n?<\/p>\n<p>Bego\u00f1a G\u00f3mez ha sido llamada a declarar en calidad de investigada el pr\u00f3ximo 5 de julio a las 10 a.m., hora local, en el marco de la pesquisa que lidera el Juzgado de Instrucci\u00f3n 41 de Madrid por los presuntos delitos de corrupci\u00f3n en los negocios y tr\u00e1fico de influencias, inform\u00f3 el Tribunal Superior de Justicia de Madrid (TSJM).<\/p>\n<p>\u00bfQu\u00e9 se sabe sobre la investigaci\u00f3n judicial contra Bego\u00f1a G\u00f3mez, esposa de Pedro S\u00e1nchez?<\/p>\n<p>El TSJM detall\u00f3 que este juzgado comenz\u00f3 diligencias de investigaci\u00f3n el 16 de abril por la presunta comisi\u00f3n de los delitos de tr\u00e1fico de influencias y corrupci\u00f3n en los negocios contra Bego\u00f1a G\u00f3mez, tras recibir por reparto ordinario una denuncia de Manos Limpias. Miguel Bernard, secretario general de la organizaci\u00f3n, admiti\u00f3 a fines de abril en un comunicado que su denuncia se bas\u00f3 en informaci\u00f3n posiblemente falsa publicada en medios digitales.<\/p>\n<p>La Fiscal\u00eda Provincial de Madrid apel\u00f3 la decisi\u00f3n del juzgado y solicit\u00f3 que se archive la investigaci\u00f3n, dijeron desde la Fiscal\u00eda General del Estado a CNN. Incluso, una fuente del servicio de fiscales agreg\u00f3 que no hay indicios de delito alguno en el contenido de la denuncia.<\/p>\n<p>Sin embargo, el juzgado decidi\u00f3 seguir adelante con la instrucci\u00f3n de la causa, debido a que, si bien exist\u00eda informaci\u00f3n \u201cinveros\u00edmil o con datos err\u00f3neos\u201d en la denuncia, existen otros \u201cdatos objetivos suficientes\u201d que legitimaban el inicio de una investigaci\u00f3n.<\/p>\n<p>Por su parte, S\u00e1nchez afirm\u00f3 en ocasiones anteriores que la denuncia se sostiene en &#171;falsedades&#187; e &#171;informaciones espurias&#187;, sobre las que su esposa ha impulsado acciones legales para que esos medios se rectifiquen, calific\u00f3 a Manos Limpias de organizaci\u00f3n ultraderechista y dijo que el objetivo de la denuncia es hacerlo &#171;desfallecer en lo pol\u00edtico y en lo personal&#187;.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, mostr\u00f3 sorpresa este martes, despu\u00e9s de que el Juzgado de Instrucci\u00f3n n\u00famero 41 de Madrid citara a declarar a su esposa, Bego\u00f1a G\u00f3mez, el pr\u00f3ximo 5 de julio, en el marco de la causa que la investiga por la presunta comisi\u00f3n de los delitos [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450036","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, mostr\u00f3 sorpresa este martes, despu\u00e9s de que el Juzgado de Instrucci\u00f3n n\u00famero 41 de Madrid citara a declarar a su esposa, Bego\u00f1a G\u00f3mez, el pr\u00f3ximo 5 de julio, en el marco de la causa que la investiga por la presunta comisi\u00f3n de los delitos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-04T23:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo\",\"datePublished\":\"2024-06-04T23:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\"},\"wordCount\":698,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\",\"name\":\"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-04T23:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, mostr\u00f3 sorpresa este martes, despu\u00e9s de que el Juzgado de Instrucci\u00f3n n\u00famero 41 de Madrid citara a declarar a su esposa, Bego\u00f1a G\u00f3mez, el pr\u00f3ximo 5 de julio, en el marco de la causa que la investiga por la presunta comisi\u00f3n de los delitos [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-04T23:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/"},"author":{"name":"","@id":""},"headline":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo","datePublished":"2024-06-04T23:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/"},"wordCount":698,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","name":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-04T23:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Pedro S\u00e1nchez, \u201cextra\u00f1ado\u201d por la citaci\u00f3n a declarar de su esposa en plena campa\u00f1a electoral para el Parlamento Europeo","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-04T23:03:46Z","datePublished":"2024-06-04T23:03:46Z","dateModified":"2024-06-04T23:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Pedro S\\u00e1nchez, \\u201cextra\\u00f1ado\\u201d por la citaci\\u00f3n a declarar de su esposa en plena campa\\u00f1a electoral para el Parlamento Europeo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/04\\\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/04\\\/pedro-sanchez-extranado-citacion-esposa-begona-gomez-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-04T23:03:46Z\",\"datePublished\":\"2024-06-04T23:03:46Z\",\"dateModified\":\"2024-06-04T23:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1448478,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/24\/carta-pedro-sanchez-investigacion-esposa-begona-gomez-orix\/","url_meta":{"origin":1450036,"position":0},"title":"Pedro S\u00e1nchez cancela su agenda y dice que el pr\u00f3ximo lunes informar\u00e1 si contin\u00faa como presidente del Gobierno de Espa\u00f1a","author":"","date":"abril 24, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, anunci\u00f3 que har\u00e1 una pausa en sus compromisos p\u00fablicos para \u201cpoder reflexionar\u201d y decidir si contin\u00faa al frente de sus responsabilidades, de acuerdo con una carta que public\u00f3 en sus redes sociales.S\u00e1nchez adelant\u00f3 que comparecer\u00e1 antes los medios de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450904,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/05\/justicia-espanola-aplaza-declaracion-begona-gomez-investigada-julio-orix\/","url_meta":{"origin":1450036,"position":1},"title":"La justicia espa\u00f1ola aplaza la declaraci\u00f3n de Bego\u00f1a G\u00f3mez en calidad de investigada para el 19 de julio","author":"","date":"julio 5, 2024","format":false,"excerpt":"(CNN) -- Bego\u00f1a G\u00f3mez, esposa del presidente\u00a0del Gobierno\u00a0de\u00a0Espa\u00f1a, Pedro S\u00e1nchez, estaba llamada a\u00a0declarar este viernes ante\u00a0el\u00a0Juzgado\u00a0de\u00a0Instrucci\u00f3n n\u00famero 41\u00a0de\u00a0Madrid por\u00a0la\u00a0presunta comisi\u00f3n\u00a0de\u00a0los\u00a0delitos\u00a0de\u00a0corrupci\u00f3n\u00a0en\u00a0los negocios y tr\u00e1fico\u00a0de\u00a0influencias.Son posibles delitos que esta sala empez\u00f3 a investigar el pasado 16 de abril y sobre los que G\u00f3mez no se ha pronunciado p\u00fablicamente. S\u00ed lo ha hecho\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448553,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/26\/begona-gomez-esposa-pedro-sanchez-investigada-orix\/","url_meta":{"origin":1450036,"position":2},"title":"Qui\u00e9n es Bego\u00f1a G\u00f3mez, esposa de Pedro S\u00e1nchez, investigada por la Justicia Espa\u00f1ola","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La investigaci\u00f3n abierta por un juzgado de Madrid contra Bego\u00f1a G\u00f3mez, esposa del presidente del Gobierno de Espa\u00f1a, Pedro S\u00e1nchez, tiene un futuro incierto, luego de la apelaci\u00f3n de fiscales que, seg\u00fan pudo conocer este jueves CNN, solicitaron que se archive la pesquisa.Miguel Bernard, secretario general de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448655,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/29\/pedro-sanchez-anuncio-posible-renuncia-presidente-espana-orix\/","url_meta":{"origin":1450036,"position":3},"title":"\u00daltima hora de Pedro S\u00e1nchez y su decisi\u00f3n, en vivo: noticias y reacciones a su posible renuncia","author":"","date":"abril 29, 2024","format":false,"excerpt":"Haz clic aqu\u00ed para ver las actualizaciones m\u00e1s recientesPedro S\u00e1nchez y su esposa Bego\u00f1a G\u00f3mez en el Palacio de Carlos V en Granada, Espa\u00f1a, el 5 de octubre de 2023. (JORGE GUERRERO\/AFP v\u00eda Getty Images)The-CNN-Wire\u2122 & \u00a9 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448551,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/26\/manos-limpias-organizacion-detras-denuncia-begona-gomez-esposa-pedro-sanchez-orix\/","url_meta":{"origin":1450036,"position":4},"title":"Qu\u00e9 es Manos Limpias, la organizaci\u00f3n detr\u00e1s de la denuncia contra Bego\u00f1a G\u00f3mez, esposa de Pedro S\u00e1nchez","author":"","date":"abril 26, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Bego\u00f1a G\u00f3mez, esposa de Pedro S\u00e1nchez, presidente del Gobierno de Espa\u00f1a, enfrenta una investigaci\u00f3n judicial por supuestos delitos de tr\u00e1fico de influencias y corrupci\u00f3n, lo que llev\u00f3 al mandatario a cancelar su agenda p\u00fablica para \"reflexionar\" si debe continuar en su cargo.S\u00e1nchez consider\u00f3 en una carta, publicada\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448615,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/27\/concentracion-apoyo-pedro-sanchez-12500-personas-orix\/","url_meta":{"origin":1450036,"position":5},"title":"Una concentraci\u00f3n en apoyo a Pedro S\u00e1nchez re\u00fane a 12.500 personas, seg\u00fan datos oficiales","author":"","date":"abril 27, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La madrile\u00f1a Calle de Ferraz, donde se sit\u00faa la sede del Partido Socialista Obrero Espa\u00f1ol, luc\u00eda abarrotada este s\u00e1bado por la ma\u00f1ana. Alrededor de 12.500 personas, seg\u00fan datos de la Delegaci\u00f3n del Gobierno en Madrid, tomaron un tramo\u00a0de la calle para mostrar su apoyo al presidente del Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450036","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1450036"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450036\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1450036"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1450036"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1450036"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}