{"id":1450042,"date":"2024-06-04T20:03:51","date_gmt":"2024-06-05T03:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/"},"modified":"2024-06-04T20:03:51","modified_gmt":"2024-06-05T03:03:51","slug":"justicia-suspendio-juicio-muerte-diego-maradona-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","title":{"rendered":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Tribunal oral en lo criminal N\u00b03 de San Isidro, Buenos Aires, decidi\u00f3 suspender la audiencia de debate en el juicio por la muerte de Diego Maradona, que estaba prevista para el 4 de junio, y la reprogram\u00f3 para el 1 de octubre de 2024.<\/p>\n<p>El fallo al que tuvo acceso CNN firmado por los jueces Ver\u00f3nica Di Tomasso, Maximiliano Savarino y Julieta Miktach sostiene que el Tribunal dispuso la realizaci\u00f3n de la audiencia lo antes posible, pero que debe suspenderla por una \u201cpluralidad de cuestiones que se han ido suscitando por las distintas pretensiones de las partes\u201d.<\/p>\n<p>La suspensi\u00f3n hab\u00eda sido pedida por la representaci\u00f3n legal de Dalma y Gianina Maradona, dos de las hijas del futbolista, en un escrito al Tribunal por existir &#171;planteos inconclusos de naturaleza t\u00e9cnica&#187; y con el objeto de evitar \u201cfuturos planteos nulificantes\u201d. El mismo pide la reprogramaci\u00f3n para cuando el pedido de juicio por jurado de parte de uno de los acusados se encuentre resuelto.<\/p>\n<p>Los hijos de Diego Maradona piden traslado del cuerpo a un mausoleo por motivos de seguridad y para poder rendir homenaje<\/p>\n<p>El planteo de juicio por jurado al que se refiere el escrito presentado por Fernando Burlando y Fabi\u00e1n Am\u00e9ndola, letrados de dos de las hijas de Maradona, es una de la \u201cpluralidad de cuestiones\u201d que marca el fallo. El Tribunal en su momento no hizo lugar al pedido de la enfermera Dahiana Madrid, una de las imputadas, a ser juzgada por parte de un Tribunal de jurados, pero en mayo se dict\u00f3 un pronunciamiento que revoc\u00f3 esa decisi\u00f3n del Tribunal N\u00b03. Por lo que se debe resolver si hay un proceso judicial \u00fanico para los ocho imputados, o se autoriza la realizaci\u00f3n con esta modalidad para Madrid. En Argentina se denomina juicio por jurados a la participaci\u00f3n de ciudadanos comunes, no t\u00e9cnicos, como miembros del jurado.<\/p>\n<p>El proceso busca definir si el equipo m\u00e9dico puso en riesgo a y ocasion\u00f3 la muerte de Maradona, que paraliz\u00f3 a Argentina el 25 de noviembre de 2020. Los ocho acusados ser\u00e1n juzgados por cargos de homicidio simple por dolo eventual, un delito que prev\u00e9 penas de entre 8 y 25 a\u00f1os de prisi\u00f3n.<\/p>\n<p>Entre los principales acusados se encuentran el neurocirujano Leopoldo Luque, m\u00e9dico personal del exfutbolista en sus \u00faltimos a\u00f1os de vida, Agustina Cosachov, que era psiquiatra de Maradona. El abogado de Luque ha dicho a CNN en el pasado que el m\u00e9dico rechaza los cargos en su contra y que analizan si apelar\u00e1n la medida en la siguiente instancia. Mientras que Cosachov se declara inocente, seg\u00fan su abogado.<\/p>\n<p>Denegaron el traslado del cuerpo de Maradona<\/p>\n<p>El fallo, adem\u00e1s, no hacer lugar por el momento al pedido del traslado de los restos de Maradona, aunque no incluye los fundamentos de esta medida. Los hijos del exjugador hicieron una solicitud a la justicia en mayo para trasladar el cuerpo de su padre desde el cementerio privado Jard\u00edn de Bella Vista, ubicado en la provincia de Buenos Aires, hacia el barrio Puerto Madero, en la capital argentina. La petici\u00f3n se hizo para llevar el cuerpo del astro a un lugar de acceso p\u00fablico y gratuito denominado Memorial del Diez.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; El Tribunal oral en lo criminal N\u00b03 de San Isidro, Buenos Aires, decidi\u00f3 suspender la audiencia de debate en el juicio por la muerte de Diego Maradona, que estaba prevista para el 4 de junio, y la reprogram\u00f3 para el 1 de octubre de 2024. El fallo al que tuvo acceso CNN [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450042","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; El Tribunal oral en lo criminal N\u00b03 de San Isidro, Buenos Aires, decidi\u00f3 suspender la audiencia de debate en el juicio por la muerte de Diego Maradona, que estaba prevista para el 4 de junio, y la reprogram\u00f3 para el 1 de octubre de 2024. El fallo al que tuvo acceso CNN [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-05T03:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona\",\"datePublished\":\"2024-06-05T03:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\"},\"wordCount\":580,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\",\"name\":\"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-05T03:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","og_locale":"es_ES","og_type":"article","og_title":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; El Tribunal oral en lo criminal N\u00b03 de San Isidro, Buenos Aires, decidi\u00f3 suspender la audiencia de debate en el juicio por la muerte de Diego Maradona, que estaba prevista para el 4 de junio, y la reprogram\u00f3 para el 1 de octubre de 2024. El fallo al que tuvo acceso CNN [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-05T03:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/"},"author":{"name":"","@id":""},"headline":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona","datePublished":"2024-06-05T03:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/"},"wordCount":580,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","name":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-05T03:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"La justicia suspendi\u00f3 el inicio del juicio por la muerte de Diego Maradona","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/04\/justicia-suspendio-juicio-muerte-diego-maradona-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-05T03:03:51Z","datePublished":"2024-06-05T03:03:51Z","dateModified":"2024-06-05T03:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"La justicia suspendi\\u00f3 el inicio del juicio por la muerte de Diego Maradona\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/04\\\/justicia-suspendio-juicio-muerte-diego-maradona-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/04\\\/justicia-suspendio-juicio-muerte-diego-maradona-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-05T03:03:51Z\",\"datePublished\":\"2024-06-05T03:03:51Z\",\"dateModified\":\"2024-06-05T03:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463025,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/30\/cronologia-escandalo-anulacion-juicio-muerte-diego-maradona-orix\/","url_meta":{"origin":1450042,"position":0},"title":"&#171;Justicia Divina&#187;: cronolog\u00eda del esc\u00e1ndalo que llev\u00f3 a la anulaci\u00f3n del juicio por la muerte de Diego Maradona","author":"","date":"mayo 30, 2025","format":false,"excerpt":"Podr\u00eda haber sido un d\u00eda m\u00e1s del debate que hab\u00eda iniciado dos meses antes y en el que ya hab\u00edan declarado alrededor de 40 testigos. Pero la audiencia del 15 de mayo del juicio por la muerte de Diego Armando Maradona se transform\u00f3 en un punto de quiebre y llev\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460408,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/25\/detienen-falso-testimonio-testigo-juicio-maradona-orix\/","url_meta":{"origin":1450042,"position":1},"title":"Detienen por falso testimonio a un testigo en el juicio por la muerte de Maradona","author":"","date":"marzo 25, 2025","format":false,"excerpt":"Uno de los testigos que declar\u00f3 en el juicio por la muerte del exfutbolista Diego Armando Maradona, el custodio Julio C\u00e9sar Coria, qued\u00f3 detenido este martes por falso testimonio, determin\u00f3 el Tribunal que lleva el proceso en Buenos Aires.El abogado de dos de las hijas de Maradona, Fernando Burlando, solicit\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1459895,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/13\/juicio-muerte-maradona-testigos-declarar-orix\/","url_meta":{"origin":1450042,"position":2},"title":"Juicio por la muerte de Maradona: los testigos comenzar\u00e1n a declarar el martes","author":"","date":"marzo 13, 2025","format":false,"excerpt":"El juicio por la muerte del ex astro argentino del f\u00fatbol Diego Armando Maradona tuvo su segunda audiencia este jueves en Buenos Aires. Durante esta jornada, se cerraron los aspectos preliminares y, con ello, los testigos comenzar\u00e1n a declarar el martes pr\u00f3ximo ante el tribunal.Se espera que declaren m\u00e1s de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462863,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/27\/apartan-jueza-juicio-muerte-diego-armando-maradona-orix\/","url_meta":{"origin":1450042,"position":3},"title":"Apartan a jueza del juicio por la muerte de Diego Armando Maradona","author":"","date":"mayo 27, 2025","format":false,"excerpt":"Un tribunal argentino apart\u00f3 a la jueza Julieta Makintach del proceso penal por la muerte del futbolista argentino Diego Armando Maradona.El abogado de uno de los acusados hab\u00eda pedido la recusaci\u00f3n por posible falta de imparcialidad y por presunta autorizaci\u00f3n de Makintach para la filmaci\u00f3n de un documental en las\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1462643,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/05\/21\/suspenden-juicio-de-maradona-por-siete-dias-orix\/","url_meta":{"origin":1450042,"position":4},"title":"Suspenden juicio de Maradona por siete d\u00edas, dice el abogado de las hijas","author":"","date":"mayo 21, 2025","format":false,"excerpt":"El juicio sobre las circunstancias que rodearon la muerte del exfutbolista argentino Diego Armando Maradona (1960 \u2013 2020) fue suspendido este martes por decisi\u00f3n del Tribunal Oral en lo Criminal N\u00b03 de San Isidro, inform\u00f3 Fernando Burlando, abogado de las hijas del astro, Dalma y Giannina Maradona.\u201cMe parece prudente y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460113,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/19\/juicio-muerte-maradona-declaraciones-orix\/","url_meta":{"origin":1450042,"position":5},"title":"Con una lista de m\u00e1s de 100 testigos, comienzan las declaraciones en el juicio por la muerte de Maradona","author":"","date":"marzo 19, 2025","format":false,"excerpt":"Mientras habla el abogado de una de las personas acusadas por la muerte del futbolista argentino Diego Maradona, se escucha un grito con una frase de dif\u00edcil traducci\u00f3n, pero que en la voz de cualquier argentino tiene un solo significado, y es el apoyo incondicional a Maradona: \u201c\u00a1Aguante el Diego!\u201d.En\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450042","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1450042"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450042\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1450042"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1450042"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1450042"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}