{"id":1450079,"date":"2024-06-05T22:03:46","date_gmt":"2024-06-06T05:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/"},"modified":"2024-06-05T22:03:46","modified_gmt":"2024-06-06T05:03:46","slug":"onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","title":{"rendered":"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes"},"content":{"rendered":"<p>(CNN) &#8212; El planeta acaba de marcar un nuevo hito &#171;impactante&#187;, al soportar 12 meses consecutivos de calor sin precedentes, seg\u00fan los nuevos datos de Copernicus, el servicio de vigilancia clim\u00e1tica de la Uni\u00f3n Europea.<\/p>\n<p>Seg\u00fan los datos de Copernicus, todos los meses comprendidos entre junio de 2023 y mayo de 2024 han sido los m\u00e1s calurosos de la historia.<\/p>\n<p>La racha de 12 meses de calor fue &#171;chocante, pero no sorprendente&#187;, dado el cambio clim\u00e1tico provocado por el hombre, dijo Carlo Buontempo, director de Copernicus, quien advirti\u00f3 de lo peor que est\u00e1 por venir. A menos que se reduzca dr\u00e1sticamente la contaminaci\u00f3n por combustibles f\u00f3siles que calienta el planeta, &#171;esta serie de meses m\u00e1s calurosos ser\u00e1 recordada como comparativamente fr\u00eda&#187;, afirm\u00f3.<\/p>\n<p>Copernicus dio a conocer sus datos el mismo d\u00eda en que el secretario general de las Naciones Unidas, Ant\u00f3nio Guterres, pronunci\u00f3 en Nueva York un apasionado discurso sobre el cambio clim\u00e1tico, en el que tach\u00f3 a las empresas de combustibles f\u00f3siles de &#171;padrinos del caos clim\u00e1tico&#187; y, por primera vez, pidi\u00f3 expl\u00edcitamente a todos los pa\u00edses que prohibieran la publicidad de sus productos derivados de combustibles f\u00f3siles.<\/p>\n<p>Guterres inst\u00f3 a los l\u00edderes mundiales a tomar r\u00e1pidamente el control de la espiral de la crisis clim\u00e1tica o enfrentarse a peligrosos puntos de inflexi\u00f3n. &#171;Estamos jugando a la ruleta rusa con nuestro planeta&#187;, afirm\u00f3 este mi\u00e9rcoles. &#171;Necesitamos una rampa de salida de la autopista hacia el infierno clim\u00e1tico&#187;.<\/p>\n<p>La agobiante c\u00fapula de calor en Estados Unidos no har\u00e1 m\u00e1s que empeorar. \u00bfCu\u00e1ndo podr\u00edan alcanzar las temperaturas m\u00e1ximas?<\/p>\n<p>\u00bfQu\u00e9 es un domo de calor y por qu\u00e9 es tan peligroso? 1:33<\/p>\n<p>A medida que aumentan las temperaturas, los compromisos clim\u00e1ticos mundiales &#171;penden de un hilo&#187;, advirti\u00f3.<\/p>\n<p>Los datos de Copernicus mostraron que cada mes desde julio de 2023 ha sido al menos 1,5 grados m\u00e1s c\u00e1lido que las temperaturas anteriores a la industrializaci\u00f3n, cuando los humanos empezaron a quemar grandes cantidades de combustibles f\u00f3siles que calientan el planeta.<\/p>\n<p>La temperatura media global en los \u00faltimos 12 meses fue de 1,63 cent\u00edgrados grados por encima de estos niveles preindustriales.<\/p>\n<p>En virtud del Acuerdo de Par\u00eds de 2015, los pa\u00edses acordaron limitar el calentamiento global a 1,5 grados por encima de los niveles preindustriales. Aunque este objetivo se refiere al calentamiento a lo largo de d\u00e9cadas, y no de un solo mes o a\u00f1o, los cient\u00edficos afirman que este incumplimiento es una se\u00f1al alarmante.<\/p>\n<p>&#171;Es un presagio de que se avecinan efectos clim\u00e1ticos cada vez m\u00e1s peligrosos&#187;, declar\u00f3 Richard Allan, catedr\u00e1tico de clima de la Universidad de Reading (Reino Unido).<\/p>\n<p>La noticia llega cuando el oeste de Estados Unidos est\u00e1 sufriendo su primera ola de calor en lo que va de verano, con temperaturas que superan los 37 grados cent\u00edgrados. Pero el calor sin precedentes ya ha dejado un rastro de muerte y destrucci\u00f3n en todo el planeta esta primavera.<\/p>\n<p>Decenas de personas han muerto en la India en las \u00faltimas semanas a medida que las temperaturas se acercaban a los 50 grados cent\u00edgrados; las brutales temperaturas en el sudeste asi\u00e1tico han causado muertes, el cierre de escuelas y el marchitamiento de las cosechas; y a medida que el calor aumentaba en M\u00e9xico, monos aulladores ca\u00edan muertos de los \u00e1rboles.<\/p>\n<p>Monos aulladores sucumben ante ola de calor en M\u00e9xico 3:02<\/p>\n<p>El aumento de la temperatura del aire y de los oc\u00e9anos tambi\u00e9n provoca lluvias m\u00e1s intensas y tormentas destructivas como las que han azotado este a\u00f1o Estados Unidos, Brasil, Kenya y Emiratos \u00c1rabes Unidos, entre otros pa\u00edses.<\/p>\n<p>El reciente calor ofrece &#171;una ventana al futuro con un calor extremo que desaf\u00eda los l\u00edmites de la supervivencia humana&#187;, afirm\u00f3 Ben Clarke, investigador del Instituto Grantham del Imperial College de Londres. &#171;Es vital que la gente entienda que cada d\u00e9cima de grado de calentamiento expone a m\u00e1s personas a un calor peligroso y potencialmente mortal&#187;, declar\u00f3 a CNN.<\/p>\n<p>\u00bfNo puedes dormir con las altas temperaturas de este verano? Mira estos 10 consejos<\/p>\n<p>Un cami\u00f3n cisterna llena de agua a la gente durante una ola de calor en Nueva Delhi, India, el 3 de junio de 2024. Bajo un calor abrasador, la gente espera en largas colas, con la esperanza de llenar al menos un cubo. (Cr\u00e9dito: Raj K Raj\/Hindustan Times\/Getty Images)<\/p>\n<p>&#171;Los fen\u00f3menos extremos acelerados por el caos clim\u00e1tico se acumulan, destruyen vidas, golpean las econom\u00edas y afectan a la salud&#187;, afirm\u00f3 Gutteres.<\/p>\n<p>La humanidad est\u00e1 teniendo un impacto desmesurado en el mundo, dijo, compar\u00e1ndolo con el meteorito que inici\u00f3 el proceso de exterminio de los dinosaurios hace 66 millones de a\u00f1os.<\/p>\n<p>&#171;En el caso del clima, no somos los dinosaurios&#187;, dijo Guterres. &#171;Somos el meteorito. No s\u00f3lo estamos en peligro. Somos el peligro&#187;.<\/p>\n<p>Una zona inundada en el barrio de Cavalhada tras las fuertes lluvias en Porto Alegre, Brasil, el 23 de mayo de 2024. (Cr\u00e9dito: Diego Vara\/Reuters)<\/p>\n<p>Un futuro a\u00fan m\u00e1s caluroso<\/p>\n<p>Se espera que las temperaturas mundiales empiecen a descender por debajo de los niveles r\u00e9cord en los pr\u00f3ximos meses a medida que El Ni\u00f1o \u2014un fen\u00f3meno clim\u00e1tico natural que tiende a aumentar la temperatura media del planeta\u2014 se debilite.<\/p>\n<p>Pero eso no significar\u00e1 el fin de la tendencia a largo plazo al aumento de las temperaturas, ya que los seres humanos siguen quemando combustibles f\u00f3siles que calientan el planeta. &#171;Aunque esta secuencia de meses r\u00e9cord acabar\u00e1 interrumpi\u00e9ndose, la firma general del cambio clim\u00e1tico se mantiene y no hay se\u00f1ales a la vista de un cambio en dicha tendencia&#187;, afirm\u00f3 Buontempo.<\/p>\n<p>El discurso de Guterres tambi\u00e9n hizo referencia a los nuevos datos publicados por la Organizaci\u00f3n Meteorol\u00f3gica Mundial (OMM), seg\u00fan los cuales hay casi un 86% de probabilidades de que al menos uno de los a\u00f1os comprendidos entre 2024 y 2028 bata el r\u00e9cord del a\u00f1o m\u00e1s caluroso, establecido en 2023.<\/p>\n<p>La OMM tambi\u00e9n calcul\u00f3 en casi un 50% la probabilidad de que la temperatura media mundial durante todo el quinquenio comprendido entre 2024 y 2028 supere en m\u00e1s de 1,5 grados cent\u00edgrados los niveles preindustriales. Ello acercar\u00eda al mundo a incumplir el l\u00edmite de 1,5 grados a largo plazo que constituye el n\u00facleo del Acuerdo de Par\u00eds.<\/p>\n<p>Los hogares de las abejas en Arizona se est\u00e1n derritiendo por las altas temperaturas<\/p>\n<p>Caroline Street bajo el calor de la tarde del s\u00e1bado 25 de mayo en Houston. (Cr\u00e9dito: Jon Shapley\/Houston Chronicle\/Getty Images)<\/p>\n<p>Guterres culp\u00f3 firmemente de la crisis clim\u00e1tica a las empresas de combustibles f\u00f3siles que &#171;obtienen beneficios r\u00e9cord y disfrutan de billones en subvenciones financiadas por los contribuyentes&#187;, afirm\u00f3.<\/p>\n<p>Estas empresas han gastado miles de millones de d\u00f3lares durante d\u00e9cadas &#171;distorsionando la verdad, enga\u00f1ando al p\u00fablico y sembrando la duda&#187;, a\u00f1adi\u00f3. Hizo un llamamiento a todos los pa\u00edses para que proh\u00edban los anuncios de combustibles f\u00f3siles, de forma similar a las prohibiciones publicitarias implantadas en todo el mundo para otros productos nocivos para la salud humana, como el tabaco.<\/p>\n<p>&#171;Estamos en el momento de la verdad&#187;, afirm\u00f3, a\u00f1adiendo que la batalla por un planeta habitable se ganar\u00e1 o se perder\u00e1 en esta d\u00e9cada.<\/p>\n<p>Hizo un llamamiento a los l\u00edderes mundiales para que tomen medidas inmediatas, incluyendo grandes recortes en la contaminaci\u00f3n que calienta el planeta y el fin inmediato de cualquier nuevo proyecto de carb\u00f3n. Inst\u00f3 a los pa\u00edses ricos a comprometerse a abandonar el carb\u00f3n para 2030, reducir el petr\u00f3leo y el gas en un 60% para 2035 y aumentar el flujo de financiaci\u00f3n a las naciones m\u00e1s pobres y vulnerables al cambio clim\u00e1tico.<\/p>\n<p>&#171;No podemos aceptar un futuro en el que los ricos est\u00e9n protegidos en burbujas con aire acondicionado, mientras el resto de la humanidad es azotada por un clima letal en tierras invivibles&#187;, afirm\u00f3 Guterres.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El planeta acaba de marcar un nuevo hito &#171;impactante&#187;, al soportar 12 meses consecutivos de calor sin precedentes, seg\u00fan los nuevos datos de Copernicus, el servicio de vigilancia clim\u00e1tica de la Uni\u00f3n Europea. Seg\u00fan los datos de Copernicus, todos los meses comprendidos entre junio de 2023 y mayo de 2024 han sido los [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450079","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El jefe de la ONU dice que el mundo est\u00e1 en la &quot;autopista hacia el infierno clim\u00e1tico&quot;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El jefe de la ONU dice que el mundo est\u00e1 en la &quot;autopista hacia el infierno clim\u00e1tico&quot;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El planeta acaba de marcar un nuevo hito &#171;impactante&#187;, al soportar 12 meses consecutivos de calor sin precedentes, seg\u00fan los nuevos datos de Copernicus, el servicio de vigilancia clim\u00e1tica de la Uni\u00f3n Europea. Seg\u00fan los datos de Copernicus, todos los meses comprendidos entre junio de 2023 y mayo de 2024 han sido los [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T05:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes\",\"datePublished\":\"2024-06-06T05:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\"},\"wordCount\":1406,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\",\"name\":\"El jefe de la ONU dice que el mundo est\u00e1 en la \\\"autopista hacia el infierno clim\u00e1tico\\\": el planeta soport\u00f3 12 meses seguidos de calor sin precedentes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-06T05:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El jefe de la ONU dice que el mundo est\u00e1 en la \"autopista hacia el infierno clim\u00e1tico\": el planeta soport\u00f3 12 meses seguidos de calor sin precedentes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","og_locale":"es_ES","og_type":"article","og_title":"El jefe de la ONU dice que el mundo est\u00e1 en la \"autopista hacia el infierno clim\u00e1tico\": el planeta soport\u00f3 12 meses seguidos de calor sin precedentes - Noticias","og_description":"(CNN) &#8212; El planeta acaba de marcar un nuevo hito &#171;impactante&#187;, al soportar 12 meses consecutivos de calor sin precedentes, seg\u00fan los nuevos datos de Copernicus, el servicio de vigilancia clim\u00e1tica de la Uni\u00f3n Europea. Seg\u00fan los datos de Copernicus, todos los meses comprendidos entre junio de 2023 y mayo de 2024 han sido los [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-06T05:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/"},"author":{"name":"","@id":""},"headline":"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes","datePublished":"2024-06-06T05:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/"},"wordCount":1406,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","name":"El jefe de la ONU dice que el mundo est\u00e1 en la \"autopista hacia el infierno clim\u00e1tico\": el planeta soport\u00f3 12 meses seguidos de calor sin precedentes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-06T05:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"El jefe de la ONU dice que el mundo est\u00e1 en la &#171;autopista hacia el infierno clim\u00e1tico&#187;: el planeta soport\u00f3 12 meses seguidos de calor sin precedentes","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/05\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-06T05:03:46Z","datePublished":"2024-06-06T05:03:46Z","dateModified":"2024-06-06T05:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"El jefe de la ONU dice que el mundo est\\u00e1 en la &#171;autopista hacia el infierno clim\\u00e1tico&#187;: el planeta soport\\u00f3 12 meses seguidos de calor sin precedentes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/05\\\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/05\\\/onu-planeta-12-meses-calor-sin-precedentes-cambio-climatico-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-06T05:03:46Z\",\"datePublished\":\"2024-06-06T05:03:46Z\",\"dateModified\":\"2024-06-06T05:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452496,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/06\/verano-mas-caluroso-jamas-registrado-trax\/","url_meta":{"origin":1450079,"position":0},"title":"El planeta vive el verano m\u00e1s caluroso jam\u00e1s registrado por segundo a\u00f1o consecutivo","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN) -- El verano rompi\u00f3 r\u00e9cords globales de calor por segundo a\u00f1o consecutivo, confirmaron los cient\u00edficos, lo que pone a 2024 firmemente en camino de ser el a\u00f1o m\u00e1s caluroso en la historia registrada.El per\u00edodo entre junio y agosto, verano en el hemisferio norte, fue el m\u00e1s caluroso desde que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457442,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/10\/2024-ano-mas-caluroso-objetivo-climatico-trax\/","url_meta":{"origin":1450079,"position":1},"title":"2024 fue el a\u00f1o m\u00e1s caluroso registrado, superando un objetivo clim\u00e1tico y culminando 10 a\u00f1os de calor sin precedentes","author":"","date":"enero 10, 2025","format":false,"excerpt":"Es oficial: 2024 fue el a\u00f1o m\u00e1s caluroso registrado, rompiendo el r\u00e9cord anterior establecido en 2023 y empujando al mundo por encima de un umbral clim\u00e1tico cr\u00edtico, de acuerdo con nuevos datos de la agencia de monitoreo clim\u00e1tico de Europa, Copernicus.El a\u00f1o pasado fue 1,6 grados m\u00e1s caliente que el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449245,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/07\/calentamiento-global-abril-calor-record-copernicus-trax\/","url_meta":{"origin":1450079,"position":2},"title":"El planeta alcanz\u00f3 en abril un calor r\u00e9cord, mientras los cient\u00edficos advierten que 2024 podr\u00eda batir r\u00e9cords de altas temperaturas por segundo a\u00f1o consecutivo","author":"","date":"mayo 7, 2024","format":false,"excerpt":"(CNN) -- El extraordinario calor global contin\u00faa su racha. El mes pasado, el mundo soport\u00f3 el abril m\u00e1s caluroso jam\u00e1s registrado, seg\u00fan los nuevos datos de Copernicus, el servicio de vigilancia clim\u00e1tica de la Uni\u00f3n Europea.Son ya 11 meses consecutivos de temperaturas globales sin precedentes. Con este nuevo dato, algunos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443423,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/09\/el-calentamiento-global-en-2023-se-acerco-al-limite-que-el-mundo-esta-tratando-de-evitar\/","url_meta":{"origin":1450079,"position":3},"title":"El calentamiento global en 2023 se acerc\u00f3 al l\u00edmite que el mundo est\u00e1 tratando de evitar","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) -- El calentamiento global en 2023 alcanz\u00f3 los 1,48 grados Celsius, seg\u00fan muestran los datos publicados este martes, mientras el a\u00f1o m\u00e1s caluroso registrado impuls\u00f3 al mundo a solo cent\u00e9simas de grado de un umbral clim\u00e1tico cr\u00edtico.Los an\u00e1lisis del a\u00f1o pasado ya hab\u00edan confirmado que 2023 fue el m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443438,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/09\/el-calentamiento-global-en-2023-se-acerco-al-limite-que-el-mundo-esta-tratando-de-evitar-2\/","url_meta":{"origin":1450079,"position":4},"title":"El calentamiento global en 2023 se acerc\u00f3 al l\u00edmite que el mundo est\u00e1 tratando de evitar","author":"","date":"enero 9, 2024","format":false,"excerpt":"(CNN) -- El calentamiento global en 2023 alcanz\u00f3 los 1,48 grados Celsius, seg\u00fan muestran los datos publicados este martes, mientras el a\u00f1o m\u00e1s caluroso registrado impuls\u00f3 al mundo a solo cent\u00e9simas de grado de un umbral clim\u00e1tico cr\u00edtico.Los an\u00e1lisis del a\u00f1o pasado ya hab\u00edan confirmado que 2023 fue el m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448123,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/15\/calor-oceanico-blanqueamiento-mundial-corales-trax\/","url_meta":{"origin":1450079,"position":5},"title":"Los corales del mundo registran uno de los peores eventos de blanqueamiento registrado","author":"","date":"abril 15, 2024","format":false,"excerpt":"(CNN) -- Los arrecifes de coral de todo el mundo est\u00e1n experimentando un blanqueamiento masivo a medida que la crisis clim\u00e1tica impulsa un calor oce\u00e1nico r\u00e9cord, seg\u00fan anunciaron el lunes dos organismos cient\u00edficos, y algunos expertos advierten de que \u00e9ste podr\u00eda convertirse en el peor periodo de blanqueamiento de la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1450079"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450079\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1450079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1450079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1450079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}