{"id":1450104,"date":"2024-06-06T14:03:52","date_gmt":"2024-06-06T21:03:52","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/"},"modified":"2024-06-06T14:03:52","modified_gmt":"2024-06-06T21:03:52","slug":"lula-da-silva-observadores-elecciones-venezuela-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","title":{"rendered":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; A menos de dos meses para las elecciones presidenciales en Venezuela, la observaci\u00f3n internacional en esos comicios es uno de los temas que marca el camino rumbo al 28 de julio, d\u00eda para el que est\u00e1 pautada la cita con las urnas.<\/p>\n<p>El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, mantuvo este mi\u00e9rcoles una llamada con su hom\u00f3logo venezolano, Nicol\u00e1s Maduro. Lula da Silva insisti\u00f3 en la conversaci\u00f3n sobre \u201cla importancia de contar con amplia participaci\u00f3n de observadores internacionales\u201d, inform\u00f3 el Gobierno de Brasil.<\/p>\n<p>El presidente de Brasil, adem\u00e1s, resalt\u00f3 la necesidad de cumplir el acuerdo de Barbados suscrito entre el Gobierno y la oposici\u00f3n de Venezuela en octubre pasado para celebrar unos comicios con garant\u00edas democr\u00e1ticas.<\/p>\n<p>Venezuela revoca invitaci\u00f3n a observadores de la Uni\u00f3n Europea para las elecciones de julio<\/p>\n<p>La llamada entre los mandatarios se da una semana despu\u00e9s de que Venezuela revocara la invitaci\u00f3n a la misi\u00f3n de observaci\u00f3n de la Uni\u00f3n Europea (UE). El presidente del Consejo Nacional Electoral (CNE), Elvis Amoroso, anunci\u00f3 la decisi\u00f3n con la lectura de un comunicado en el que aleg\u00f3 que \u201cser\u00eda inmoral permitir la participaci\u00f3n europea conociendo sus pr\u00e1cticas neocoloniales e intervencionismo contra Venezuela, no siendo, en consecuencia, su presencia grata en un proceso electoral tan importante para la democracia\u201d.<\/p>\n<p>La petici\u00f3n para dejar sin efecto la observaci\u00f3n la realiz\u00f3 el presidente de la Asamblea Nacional, Jorge Rodr\u00edguez, luego de que UE anunciara el levantamiento de las sanciones que impuso a Amoroso, y otros tres funcionarios mientras manten\u00eda las medidas contra 50 personas relacionadas con el gobierno de Maduro. Rodr\u00edguez tild\u00f3 a los dirigentes de la UE como \u201cgroseros, bastardos, canallas, ilegales e ileg\u00edtimos\u201d.<\/p>\n<p>La UE, por su parte, difundi\u00f3 a trav\u00e9s de sus redes sociales su reacci\u00f3n ante la decisi\u00f3n de Caracas. \u201cLa Uni\u00f3n Europea lamenta profundamente la decisi\u00f3n unilateral del Consejo Nacional Electoral de Venezuela de retirar su invitaci\u00f3n a observar las elecciones presidenciales del 28 de julio\u201d, dice el texto publicado en la cuenta de X de la UE en Venezuela.<\/p>\n<p>La l\u00edder opositora y ganadora de las primarias opositoras venezolanas, Mar\u00eda Corina Machado, se refiri\u00f3 este martes al asunto afirmado durante un breve encuentro con periodistas. Machado afirm\u00f3 que \u201cel Consejo Nacional Electoral ya hab\u00eda emitido invitaciones, incluyendo a la Uni\u00f3n Europea, realmente para nosotros es una se\u00f1al de miedo, ellos est\u00e1n reconociendo que no quieren ser observados, creo que es un gran error, creo que deber\u00eda reconsiderarse\u201d.<\/p>\n<p>Corina Machado denuncia un &#171;terreno totalmente inclinado&#187; para las elecciones en Venezuela<\/p>\n<p>La Plataforma Unitaria Democr\u00e1tica (PUD) de Venezuela, la coalici\u00f3n que re\u00fane a la mayor\u00eda de los partidos opositores y que respaldan la candidatura de Edmundo Gonz\u00e1lez Urrutia, rechaz\u00f3 la postura de las autoridades electorales e indic\u00f3 en un comunicado que \u201cno evitar\u00e1 lo que todos sabemos que ocurrir\u00e1 el pr\u00f3ximo 28 de julio, que es la contundente victoria que representa el candidato de la Unidad\u201d.<\/p>\n<p>Brasil y Colombia recientemente anunciaron que no enviar\u00e1n misiones de observaci\u00f3n electoral a Venezuela. El CNE tambi\u00e9n curs\u00f3 invitaciones al Centro Carter, a las Naciones Unidas (ONU), a la Uni\u00f3n Africana y a la Comunidad de Estados Latinoamericanos y Caribe\u00f1os (Celac).<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) &#8212; A menos de dos meses para las elecciones presidenciales en Venezuela, la observaci\u00f3n internacional en esos comicios es uno de los temas que marca el camino rumbo al 28 de julio, d\u00eda para el que est\u00e1 pautada la cita con las urnas. El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, mantuvo [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450104","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) &#8212; A menos de dos meses para las elecciones presidenciales en Venezuela, la observaci\u00f3n internacional en esos comicios es uno de los temas que marca el camino rumbo al 28 de julio, d\u00eda para el que est\u00e1 pautada la cita con las urnas. El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, mantuvo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-06T21:03:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela\",\"datePublished\":\"2024-06-06T21:03:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\"},\"wordCount\":606,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\",\"name\":\"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-06T21:03:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela - Noticias","og_description":"(CNN Espa\u00f1ol) &#8212; A menos de dos meses para las elecciones presidenciales en Venezuela, la observaci\u00f3n internacional en esos comicios es uno de los temas que marca el camino rumbo al 28 de julio, d\u00eda para el que est\u00e1 pautada la cita con las urnas. El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, mantuvo [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","og_site_name":"Noticias","article_published_time":"2024-06-06T21:03:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/"},"author":{"name":"","@id":""},"headline":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela","datePublished":"2024-06-06T21:03:52+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/"},"wordCount":606,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","url":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","name":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-06T21:03:52+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/06\/lula-da-silva-observadores-elecciones-venezuela-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-06T21:03:52Z","datePublished":"2024-06-06T21:03:52Z","dateModified":"2024-06-06T21:03:52Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Lula da Silva insiste en la importancia de los observadores internacionales en las elecciones en Venezuela\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/06\\\/lula-da-silva-observadores-elecciones-venezuela-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/06\\\/lula-da-silva-observadores-elecciones-venezuela-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-06T21:03:52Z\",\"datePublished\":\"2024-06-06T21:03:52Z\",\"dateModified\":\"2024-06-06T21:03:52Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1451926,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/16\/lula-da-silva-gobierno-maduro-venezuela-regimen-desagradable-sesgo-autoritario-orix\/","url_meta":{"origin":1450104,"position":0},"title":"Lula da Silva dice que el Gobierno de Maduro en Venezuela es un r\u00e9gimen con un &#171;sesgo autoritario&#187;, pero &#171;no es una dictadura&#187;","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Brasil, Luiz In\u00e1cio Lula da Silva, calific\u00f3 este viernes al Gobierno de Nicol\u00e1s Maduro en Venezuela como un r\u00e9gimen \"muy desagradable\" con un \"sesgo autoritario\", aunque aclar\u00f3 que no lo considera una dictadura.\"Creo\u00a0que\u00a0Venezuela\u00a0vive\u00a0en\u00a0un r\u00e9gimen muy\u00a0desagradable. No creo\u00a0que sea una dictadura, es diferente a una\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451919,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/16\/maduro-machado-rechazan-propuesta-repetir-elecciones-venezuela-orix\/","url_meta":{"origin":1450104,"position":1},"title":"Tanto Nicol\u00e1s Maduro como Mar\u00eda Corina Machado rechazan la propuesta de nuevas elecciones en Venezuela","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Una propuesta para celebrar nuevas elecciones en Venezuela, originalmente planteada por el principal asesor de pol\u00edtica internacional de Lula da Silva y posteriormente respaldada por Colombia, parece ser rechazada en el pa\u00eds, tanto por el Gobierno de Nicolc\u00e1s Maduro como por la oposici\u00f3n, encabezada por Mar\u00eda Corina\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451872,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/14\/nuevas-elecciones-venezuela-propuesta-celso-amorim-asesor-lula-da-silva-orix\/","url_meta":{"origin":1450104,"position":2},"title":"Nuevas elecciones en Venezuela: la propuesta de Celso Amorim, asesor de Lula da Silva","author":"","date":"agosto 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Celso Amorim, el principal asesor de pol\u00edtica internacional del presidente de Brasil, Luiz In\u00e1cio Lula da Silva, propuso celebrar nuevas elecciones para contrarrestar la crisis generada en el pa\u00eds por la controversia sobre el ganador de los comicios del 28 de julio.La idea fue sugerida al presidente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451401,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/25\/alberto-fernandez-maduro-elecciones-orix\/","url_meta":{"origin":1450104,"position":3},"title":"Alberto Fern\u00e1ndez: &#171;Si Maduro pierde las elecciones lo tiene que aceptar&#187;","author":"","date":"julio 25, 2024","format":false,"excerpt":"(CNN en Espa\u00f1ol) -- El expresidente de Argentina, Alberto Fern\u00e1ndez, afirm\u00f3 este martes que si Nicol\u00e1s Maduro pierde las elecciones de Venezuela debe aceptar el resultado.Fern\u00e1ndez se refiri\u00f3 durante una entrevista con Radio Con Vos a los comicios del domingo, en los que iba a participar como veedor de los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451914,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/16\/maduro-rechaza-propuesta-repetir-elecciones-venezuela-orix\/","url_meta":{"origin":1450104,"position":4},"title":"Maduro rechaza propuesta de repetir elecciones en Venezuela","author":"","date":"agosto 16, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El presidente de Venezuela, Nicol\u00e1s Maduro, rechaz\u00f3 la propuesta que sugirieron Brasil y Colombia de repetir las elecciones en el pa\u00eds y dijo que los conflictos que hay en Venezuela se deben resolver entre los venezolanos con sus instituciones y su ley.\"Yo no practico la diplomacia de micr\u00f3fono\",\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455448,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/30\/venezuela-brasil-asesor-lula-da-silva-agresion-elecciones-orix\/","url_meta":{"origin":1450104,"position":5},"title":"Venezuela llama a consultas a su embajador en Brasil; se\u00f1ala a asesor de Lula da Silva de \u201cagresi\u00f3n\u201d por declaraciones sobre elecciones","author":"","date":"octubre 30, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0El Gobierno de Venezuela convoc\u00f3 este mi\u00e9rcoles al encargado de negocios de Brasil y a su embajador, Manuel Vadell, para manifestar el rechazo a las declaraciones del asesor especial de asuntos exteriores brasile\u00f1o Celso Amorim, inform\u00f3 la Canciller\u00eda venezolana en un comunicado.\"Se ha dedicado de manera impertinente a\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1450104"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450104\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1450104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1450104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1450104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}