{"id":1450144,"date":"2024-06-07T13:03:43","date_gmt":"2024-06-07T20:03:43","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/"},"modified":"2024-06-07T13:03:43","modified_gmt":"2024-06-07T20:03:43","slug":"blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","title":{"rendered":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes"},"content":{"rendered":"<p>(CNN) &#8212; El secretario de Estado de EE.UU., Antony Blinken, viajar\u00e1 a Medio Oriente la pr\u00f3xima semana para aumentar la presi\u00f3n sobre un acuerdo de alto el fuego y liberaci\u00f3n de rehenes que, seg\u00fan el Gobierno, podr\u00eda poner fin a la guerra en Gaza.<\/p>\n<p>Blinken viajar\u00e1 a Egipto, Israel, Jordania y Qatar para &#171;debatir con sus socios la necesidad de alcanzar un acuerdo de alto el fuego que garantice la liberaci\u00f3n de todos los rehenes&#187;, anunci\u00f3 este viernes el portavoz del Departamento de Estado, Matthew Miller.<\/p>\n<p>El m\u00e1ximo diplom\u00e1tico estadounidense &#171;har\u00e1 hincapi\u00e9 en la importancia de que Hamas acepte la propuesta que est\u00e1 sobre la mesa, que es casi id\u00e9ntica a la que el grupo respald\u00f3 el mes pasado&#187;, dijo Miller.<\/p>\n<p>Estados Unidos y otros 16 pa\u00edses cuyos ciudadanos fueron tomados como rehenes instan a Hamas e Israel a &#171;cerrar el trato&#187;<\/p>\n<p>Hamas a\u00fan no ha presentado una respuesta formal a la propuesta, que fue transmitida al ala pol\u00edtica de Hamas por los qatar\u00edes el pasado jueves.<\/p>\n<p>&#171;Esperamos una respuesta de Hamas lo antes posible, y seguimos esperando&#187;, declar\u00f3 Miller en una rueda de prensa celebrada el jueves.<\/p>\n<p>Una fuente familiarizada con la informaci\u00f3n dijo este jueves que esperaban una respuesta en los pr\u00f3ximos d\u00edas.<\/p>\n<p>En sus reuniones, Blinken &#171;discutir\u00e1 c\u00f3mo la propuesta de alto el fuego beneficiar\u00eda tanto a israel\u00edes como a palestinos&#187; y &#171;subrayar\u00e1 que aliviar\u00eda el sufrimiento en Gaza, permitir\u00eda un aumento masivo de la ayuda humanitaria y permitir\u00eda a los palestinos regresar a sus barrios&#187;, dijo Miller.<\/p>\n<p>&#171;Desbloquear\u00eda la posibilidad de lograr la calma a lo largo de la frontera septentrional de Israel, para que tanto las familias israel\u00edes desplazadas como las libanesas puedan regresar a sus hogares, y establecer\u00eda las condiciones para una mayor integraci\u00f3n entre Israel y sus vecinos \u00e1rabes, reforzando la seguridad a largo plazo de Israel y mejorando la estabilidad en toda la regi\u00f3n. El secretario tambi\u00e9n seguir\u00e1 reiterando la necesidad de evitar que el conflicto siga escalando&#187;, declar\u00f3.<\/p>\n<p>Blinken es el \u00faltimo funcionario estadounidense que viaja a la regi\u00f3n despu\u00e9s de que el presidente Joe Biden esbozara el acuerdo propuesto el pasado viernes, tras las visitas del director de la CIA Bill Burns y el funcionario del Consejo de Seguridad Nacional, Brett McGurk. El jefe de la diplomacia estadounidense ha mantenido una serie de conversaciones telef\u00f3nicas con los socios regionales para debatir la propuesta.<\/p>\n<p>Las FDI notifican a las familias de cuatro rehenes israel\u00edes retenidos en Gaza que &#171;ya no est\u00e1n vivos&#187;<\/p>\n<p>Como inform\u00f3 CNN el jueves, el Gobierno de Biden ha pasado la \u00faltima semana presionando a los pa\u00edses, en particular Egipto, Qatar y Turqu\u00eda, que tienen relaciones con Hamas para que hagan amenazas espec\u00edficas para presionar al grupo para que acepte el acuerdo.<\/p>\n<p>El Gobierno ha pedido a varios pa\u00edses que amenacen con congelar las cuentas bancarias de los miembros de Hamas y restringir su capacidad para viajar libremente por la regi\u00f3n, seg\u00fan dos funcionarios estadounidenses. En muchos casos, los miembros de Hamas han podido operar libremente durante mucho tiempo a pesar de pertenecer al grupo terrorista.<\/p>\n<p>Estados Unidos ha instado a Qatar, que permite a Hamas tener una oficina pol\u00edtica en su capital, a que declare que expulsar\u00e1 al grupo terrorista si no acepta el acuerdo, seg\u00fan uno de esos funcionarios estadounidenses. Despu\u00e9s de meses diciendo a Hamas que se arriesgaba a ser expulsado, Qatar hizo realmente esa amenaza, dijo ese funcionario.<\/p>\n<p>Miller afirm\u00f3 el mi\u00e9rcoles que Estados Unidos ha visto c\u00f3mo tanto Egipto como Qatar &#171;ejerc\u00edan una presi\u00f3n significativa sobre Hamas&#187;, pero se neg\u00f3 a entrar en los detalles de esas campa\u00f1as de presi\u00f3n por separado.<\/p>\n<p>Adem\u00e1s de las reuniones para impulsar el acuerdo, Blinken asistir\u00e1 en Jordania a &#171;una conferencia sobre la respuesta humanitaria urgente a Gaza, copatrocinada por Jordania, Egipto y las Naciones Unidas&#187;, dijo Miller en su anuncio del viernes.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El secretario de Estado de EE.UU., Antony Blinken, viajar\u00e1 a Medio Oriente la pr\u00f3xima semana para aumentar la presi\u00f3n sobre un acuerdo de alto el fuego y liberaci\u00f3n de rehenes que, seg\u00fan el Gobierno, podr\u00eda poner fin a la guerra en Gaza. Blinken viajar\u00e1 a Egipto, Israel, Jordania y Qatar para &#171;debatir con [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450144","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El secretario de Estado de EE.UU., Antony Blinken, viajar\u00e1 a Medio Oriente la pr\u00f3xima semana para aumentar la presi\u00f3n sobre un acuerdo de alto el fuego y liberaci\u00f3n de rehenes que, seg\u00fan el Gobierno, podr\u00eda poner fin a la guerra en Gaza. Blinken viajar\u00e1 a Egipto, Israel, Jordania y Qatar para &#171;debatir con [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-07T20:03:43+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes\",\"datePublished\":\"2024-06-07T20:03:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\"},\"wordCount\":724,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\",\"name\":\"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-07T20:03:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes - Noticias","og_description":"(CNN) &#8212; El secretario de Estado de EE.UU., Antony Blinken, viajar\u00e1 a Medio Oriente la pr\u00f3xima semana para aumentar la presi\u00f3n sobre un acuerdo de alto el fuego y liberaci\u00f3n de rehenes que, seg\u00fan el Gobierno, podr\u00eda poner fin a la guerra en Gaza. Blinken viajar\u00e1 a Egipto, Israel, Jordania y Qatar para &#171;debatir con [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-07T20:03:43+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/"},"author":{"name":"","@id":""},"headline":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes","datePublished":"2024-06-07T20:03:43+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/"},"wordCount":724,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","name":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-07T20:03:43+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Blinken viajar\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/07\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-07T20:03:43Z","datePublished":"2024-06-07T20:03:43Z","dateModified":"2024-06-07T20:03:43Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Blinken viajar\\u00e1 a Medio Oriente mientras Estados Unidos aumenta la presi\\u00f3n sobre la propuesta de alto el fuego y entrega de rehenes\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/07\\\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/07\\\/blinken-medio-oriente-presion-propuesta-alto-fuego-rehenes-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-07T20:03:43Z\",\"datePublished\":\"2024-06-07T20:03:43Z\",\"dateModified\":\"2024-06-07T20:03:43Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450260,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/12\/blinken-expresa-frustracion-cambios-acuerdo-alto-fuego-gaza-trax\/","url_meta":{"origin":1450144,"position":0},"title":"Blinken expresa su frustraci\u00f3n por los cambios en el acuerdo de alto el fuego en Gaza solicitados por Hamas","author":"","date":"junio 12, 2024","format":false,"excerpt":"(CNN) -- El secretario de Estado de EE.UU., Antony Blinken, expres\u00f3 este mi\u00e9rcoles su frustraci\u00f3n porque Hamas present\u00f3 \"numerosos cambios\" a una propuesta respaldada por EE.UU. para un alto el fuego y la liberaci\u00f3n de rehenes en Gaza, un hecho que arroja m\u00e1s dudas sobre las perspectivas de asegurar r\u00e1pidamente\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448730,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/01\/blinken-reunion-israel-presion-hamas-alto-el-fuego-trax\/","url_meta":{"origin":1450144,"position":1},"title":"Blinken celebra reuniones de alto nivel en Israel mientras aumenta la presi\u00f3n sobre Hamas para que acepte el acuerdo de alto el fuego","author":"","date":"mayo 1, 2024","format":false,"excerpt":"(CNN) -- El secretario de Estado de Estados Unidos, Antony Blinken, se prepara para una nueva ronda de conversaciones de alto nivel en Israel este mi\u00e9rcoles, en la que Estados Unidos pretende aumentar la presi\u00f3n sobre Hamas para que acepte un alto el fuego y un acuerdo de liberaci\u00f3n de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451957,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/18\/ataque-israel-palestinos-muertos-familia-centro-gaza-trax\/","url_meta":{"origin":1450144,"position":2},"title":"Mueren siete miembros de una misma familia tras ataque de Israel en el centro de Gaza","author":"","date":"agosto 18, 2024","format":false,"excerpt":"(CNN) -- Siete miembros de una misma familia murieron el domingo en un ataque a\u00e9reo israel\u00ed en el centro de Gaza, seg\u00fan informaron fuentes m\u00e9dicas, mientras el secretario de Estado Antony Blinken aterrizaba en Israel para impulsar un cese del fuego y un acuerdo sobre los rehenes.Seis ni\u00f1os y su\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466235,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/09\/07\/propuesta-alto-fuego-liberacion-rehenes-israel-hamas-trax\/","url_meta":{"origin":1450144,"position":3},"title":"Estados Unidos presenta nuevos puntos para el alto el fuego en Medio Oriente que exigen la liberaci\u00f3n de todos los rehenes","author":"","date":"septiembre 7, 2025","format":false,"excerpt":"Estados Unidos present\u00f3 nuevos principios para el alto el fuego en Medio Oriente que exigen la liberaci\u00f3n inmediata de todos los rehenes y el comeinzo de las negociaciones para un fin integral de la guerra, seg\u00fan dos funcionarios israel\u00edes familiarizados con las discusiones.Los principios fueron transmitidos a Hamas, seg\u00fan los\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451969,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/19\/blinken-reune-presidente-israel-insta-alto-el-fuego-acuerdo-rehenes-trax\/","url_meta":{"origin":1450144,"position":4},"title":"Blinken destaca el &#171;momento decisivo&#187; para el alto el fuego y el acuerdo sobre los rehenes en su reuni\u00f3n con el presidente de Israel","author":"","date":"agosto 19, 2024","format":false,"excerpt":"(CNN) --\u00a0 El impulso para finalizar un alto el fuego y un acuerdo sobre rehenes en Gaza ha llegado a un \u201cmomento decisivo\u201d, dijo este lunes el principal diplom\u00e1tico de Estados Unidos despu\u00e9s de reunirse con el presidente de Israel en su \u00faltimo viaje a la regi\u00f3n.Esta es \u201cprobablemente la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451737,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/08\/12\/francia-alemania-reino-unido-respaldan-llamamientos-mediadores-israel-y-hamas-acuerdo-alto-el-fuego\/","url_meta":{"origin":1450144,"position":5},"title":"Francia, Alemania y Reino Unido respaldan los llamamientos de los mediadores para que Israel y Hamas acepten el acuerdo de un alto el fuego","author":"","date":"agosto 12, 2024","format":false,"excerpt":"(CNN) -- Francia, Alemania y Reino Unido respaldaron este lunes los llamamientos de los mediadores que instan a Israel y Hamas a aceptar la propuesta de un alto el fuego y el acuerdo sobre los rehenes, mientras crece el temor ante la posibilidad de un ataque iran\u00ed que podr\u00eda derivar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1450144"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450144\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1450144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1450144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1450144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}