{"id":1450179,"date":"2024-06-09T21:03:49","date_gmt":"2024-06-10T04:03:49","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/"},"modified":"2024-06-09T21:03:49","modified_gmt":"2024-06-10T04:03:49","slug":"julia-louis-dreyfus-politicamente-correcto-comedia-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","title":{"rendered":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;"},"content":{"rendered":"<p>(CNN) &#8212; Hazte a un lado, Jerry. Julia Louis-Dreyfus ingres\u00f3 a la conversaci\u00f3n.<\/p>\n<p>El mes pasado, el comediante Jerry Seinfeld provoc\u00f3 un debate en internet cuando le dijo al New Yorker en una entrevista que sent\u00eda que ya no hab\u00eda &#171;cosas divertidas&#187; para ver en la televisi\u00f3n, y se quej\u00f3 de que era &#171;el resultado de la basura de la extrema izquierda y de la correci\u00f3n pol\u00edtica, y gente que se preocupa mucho por las ofensas a otras personas&#187;.<\/p>\n<p>Cuando se le pidi\u00f3 que respondiera a los tan comentados dichos de su excoprotagonista de \u201cSeinfeld\u201d durante una entrevista reciente con el New York Times, Louis-Dreyfus respondi\u00f3 pensativamente y dijo: \u201cCreo que ser consciente de ciertas sensibilidades no es algo malo\u201d.<\/p>\n<p>\u201cSi miras retrospectivamente la comedia y el drama, digamos hace 30 a\u00f1os, a trav\u00e9s de la lente de hoy, puedes encontrar fragmentos que no envejecen bien\u201d, dijo.<\/p>\n<p>&#171;Al diablo con la pasi\u00f3n&#187;: el consejo de Jerry Seinfeld para los graduados de 2024<\/p>\n<p>Sin mencionar el nombre de su excoprotagonista, Louis-Dreyfus a\u00f1adi\u00f3: &#171;Cuando escucho a la gente empezar a quejarse de lo pol\u00edticamente correcto &#8211;y entiendo por qu\u00e9 la gente podr\u00eda rechazarlo&#8211;, pero para m\u00ed eso es una se\u00f1al de alerta, porque a veces significa algo m\u00e1s&#187;.<\/p>\n<p>La estrella de \u201cVeep\u201d ampli\u00f3 con sus pensamientos iniciales en una segunda llamada con el periodista, seg\u00fan el Times.<\/p>\n<p>La correcci\u00f3n pol\u00edtica, dijo m\u00e1s tarde, \u201cen la medida en que equivale a tolerancia, es obviamente fant\u00e1stica\u201d. A\u00f1adi\u00f3 que todav\u00eda se reserva el derecho de \u201cabuchear a cualquiera que diga algo que me ofenda, y respetar al mismo tiempo su derecho a la libertad de expresi\u00f3n\u201d.<\/p>\n<p>&#171;Creo que es bueno estar alerta&#187;, a\u00f1adi\u00f3.<\/p>\n<p>El mayor problema, se\u00f1al\u00f3, es la \u201cconsolidaci\u00f3n del dinero y el poder\u201d en lo que respecta al \u201caislamiento\u201d de los estudios, transmisores y distribuidores de Hollywood, que ella considera la verdadera \u201camenaza al arte\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Hazte a un lado, Jerry. Julia Louis-Dreyfus ingres\u00f3 a la conversaci\u00f3n. El mes pasado, el comediante Jerry Seinfeld provoc\u00f3 un debate en internet cuando le dijo al New Yorker en una entrevista que sent\u00eda que ya no hab\u00eda &#171;cosas divertidas&#187; para ver en la televisi\u00f3n, y se quej\u00f3 de que era &#171;el resultado [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1450179","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &quot;Es bueno estar alerta&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &quot;Es bueno estar alerta&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Hazte a un lado, Jerry. Julia Louis-Dreyfus ingres\u00f3 a la conversaci\u00f3n. El mes pasado, el comediante Jerry Seinfeld provoc\u00f3 un debate en internet cuando le dijo al New Yorker en una entrevista que sent\u00eda que ya no hab\u00eda &#171;cosas divertidas&#187; para ver en la televisi\u00f3n, y se quej\u00f3 de que era &#171;el resultado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-10T04:03:49+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;\",\"datePublished\":\"2024-06-10T04:03:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\"},\"wordCount\":369,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\",\"name\":\"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: \\\"Es bueno estar alerta\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-06-10T04:03:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: \"Es bueno estar alerta\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: \"Es bueno estar alerta\" - Noticias","og_description":"(CNN) &#8212; Hazte a un lado, Jerry. Julia Louis-Dreyfus ingres\u00f3 a la conversaci\u00f3n. El mes pasado, el comediante Jerry Seinfeld provoc\u00f3 un debate en internet cuando le dijo al New Yorker en una entrevista que sent\u00eda que ya no hab\u00eda &#171;cosas divertidas&#187; para ver en la televisi\u00f3n, y se quej\u00f3 de que era &#171;el resultado [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","og_site_name":"Noticias","article_published_time":"2024-06-10T04:03:49+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/"},"author":{"name":"","@id":""},"headline":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;","datePublished":"2024-06-10T04:03:49+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/"},"wordCount":369,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","url":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","name":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: \"Es bueno estar alerta\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-06-10T04:03:49+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Julia Louis-Dreyfus se suma al debate sobre ser pol\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;","url":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/06\/09\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-06-10T04:03:49Z","datePublished":"2024-06-10T04:03:49Z","dateModified":"2024-06-10T04:03:49Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Julia Louis-Dreyfus se suma al debate sobre ser pol\\u00edticamente correcto en la comedia: &#171;Es bueno estar alerta&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/09\\\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/06\\\/09\\\/julia-louis-dreyfus-politicamente-correcto-comedia-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-06-10T04:03:49Z\",\"datePublished\":\"2024-06-10T04:03:49Z\",\"dateModified\":\"2024-06-10T04:03:49Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450330,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/13\/papa-francisco-conclave-comediantes-jimmy-fallon-chumel-torres-liss-pereira-malena-guinzburg-trax\/","url_meta":{"origin":1450179,"position":0},"title":"El papa Francisco organiza un &#171;c\u00f3nclave de comediantes&#187;: invita a Jimmy Fallon, &#8216;do\u00f1a Florinda&#8217;, Chumel Torres, Liss Pereira y Malena Guinzburg","author":"","date":"junio 13, 2024","format":false,"excerpt":"(CNN) -- Este viernes se celebrar\u00e1 una reuni\u00f3n mundial de comediantes en un lugar un poco inusual: el Vaticano.El papa Francisco organiza el equivalente a un \u201cc\u00f3nclave de comediantes\u201d al invitar a Roma a nombres destacados de la comedia de todo el mundo como Whoopi Goldberg, Jimmy Fallon, Chris Rock,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469681,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/12\/31\/actor-the-wire-isiah-whitlock-jr-muere-71-anos-trax\/","url_meta":{"origin":1450179,"position":1},"title":"El actor de &#8216;The Wire&#8217; Isiah Whitlock Jr. muere a los 71 a\u00f1os","author":"","date":"diciembre 31, 2025","format":false,"excerpt":"Isiah Whitlock Jr., cuya singular forma de pronunciar un eslogan en \u201cThe Wire\u201d le dio al mundo una de las frases m\u00e1s ic\u00f3nicas del siglo, muri\u00f3 a la edad de 71 a\u00f1os.Whitlock falleci\u00f3 hoy en paz en Nueva York tras una valiente batalla contra una breve enfermedad, declar\u00f3 su representante,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456875,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/12\/23\/extraditaran-expiloto-estadounidense-acusado-entrenar-militares-chinos-ap\/","url_meta":{"origin":1450179,"position":2},"title":"Extraditar\u00e1n a Estados Unidos a expiloto de combate estadounidense acusado de entrenar a militares chinos","author":"","date":"diciembre 23, 2024","format":false,"excerpt":"Un exmarine estadounidense acusado de entrenar a pilotos militares chinos ser\u00e1 extraditado para enfrentar cargos en Estados Unidos, confirm\u00f3 este lunes el fiscal general de Australia, lo que supone un golpe para sus partidarios que han montado una campa\u00f1a p\u00fablica por su libertad.Daniel Duggan, un australiano naturalizado, fue arrestado en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467352,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/10\/14\/expresidente-frances-sarkozy-carcel-trax\/","url_meta":{"origin":1450179,"position":3},"title":"Esto es lo que le espera al expresidente de Francia Nicolas Sarkozy tras las rejas","author":"","date":"octubre 14, 2025","format":false,"excerpt":"Como expresidente de Francia, Nicolas Sarkozy ha estado tras muchas puertas cerradas para el ciudadano franc\u00e9s medio.El 21 de octubre, cuando el fr\u00edo acero de la puerta de su celda resuene tras \u00e9l, estar\u00e1 en una habitaci\u00f3n a la que pocos desear\u00edan entrar.El exl\u00edder franc\u00e9s fue condenado en septiembre por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443574,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/12\/sonrisas-proposito-y-encurtidos-julia-roberts-habla-sobre-su-belleza-atemporal-en-una-entrevista-para-british-vogue\/","url_meta":{"origin":1450179,"position":4},"title":"Sonrisas, prop\u00f3sito y &#171;encurtidos&#187;: Julia Roberts habla sobre su belleza atemporal en una entrevista para British Vogue","author":"","date":"enero 12, 2024","format":false,"excerpt":"(CNN) -- Con su caracter\u00edstica sonrisa y su estilo atemporal, Julia Roberts puede ser un \u00edcono de la belleza, pero no se toma a s\u00ed misma demasiado en serio.Cuando se le pregunt\u00f3 en una nueva entrevista con British Vogue qu\u00e9 es lo que la mantiene joven a sus 56 a\u00f1os,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466701,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/09\/22\/400-artistas-carta-apoyo-jimmy-kimmel-trax\/","url_meta":{"origin":1450179,"position":5},"title":"400 artistas firmaron carta en apoyo a Jimmy Kimmel contra &#171;amenazas gubernamentales&#187;","author":"","date":"septiembre 22, 2025","format":false,"excerpt":"M\u00e1s de 400 celebridades apoyaron a Jimmy Kimmel y alzaron la voz contra \u201clas amenazas gubernamentales a nuestra libertad de expresi\u00f3n\u201d en una carta abierta organizada por la Uni\u00f3n Estadounidense por las Libertades Civiles (ACLU, por sus siglas en ingl\u00e9s).Jennifer Aniston, Meryl Streep, Tom Hanks, Selena Gomez, Billy Crystal, Robert\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450179","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1450179"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1450179\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1450179"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1450179"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1450179"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}