{"id":1452688,"date":"2024-09-14T17:03:47","date_gmt":"2024-09-15T00:03:47","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/"},"modified":"2024-09-14T17:03:47","modified_gmt":"2024-09-15T00:03:47","slug":"pilotos-fedex-cuentan-como-evitaron-desastre-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","title":{"rendered":"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre"},"content":{"rendered":"<p>(CNN) &#8212; El clima no pod\u00eda ser peor, en t\u00e9rminos de niebla densa. Los pilotos de un avi\u00f3n de carga de FedEx no pod\u00edan ver la pista ni el aer\u00f3dromo en el Aeropuerto Internacional Austin-Bergstrom, en Texas. Pero est\u00e1n entrenados para tales aproximaciones de \u201cCategor\u00eda III\u201d, una aproximaci\u00f3n automatizada cuando los pilotos no necesitan ver para aterrizar, siempre y cuando todo en la aeronave funcione correctamente. Y lo estaba.<\/p>\n<p>Sin embargo, un error humano en la torre de control de tr\u00e1fico a\u00e9reo y la falta de tecnolog\u00eda de seguridad cr\u00edtica llevaron al avi\u00f3n a unos 150 pies (casi 50 metros) de un avi\u00f3n de Southwest Airlines que transportaba a 128 personas, seg\u00fan un informe de la Junta Nacional de Seguridad en el Transporte de EE.UU. (NTSB, por sus siglas en ingl\u00e9s) sobre el incidente del 4 de febrero de 2023.<\/p>\n<p>As\u00ed es viajar en el avi\u00f3n del papa<\/p>\n<p>\u201cVi la silueta del otro avi\u00f3n, fue all\u00ed cuando llam\u00e9&#8230; \u2018Da la vuelta. Da la vuelta. Da la vuelta\u2019\u201d, dijo el primer oficial Robert Bradeen a Pete Muntean de CNN, en la primera entrevista televisiva sobre el incidente.<\/p>\n<p>\u201cDefinitivamente fue un momento impactante. No esperas ver un avi\u00f3n tan, tan cerca. Y esperas nunca verlos tan cerca\u201d, dijo Bradeen.<\/p>\n<p>El capit\u00e1n Hugo Carvajal inici\u00f3 el procedimiento de giro y su avi\u00f3n alcanz\u00f3 un lugar seguro.<\/p>\n<p>\u201cSab\u00eda que estaba bastante cerca porque reconoc\u00ed el tono de voz de Rob cuando dijo: \u2018da la vuelta\u2019\u201d, asegur\u00f3 Carvajal a CNN. \u201cY luego el enfoque en ese momento es simplemente alejarse del suelo, alejarse del avi\u00f3n\u201d.<\/p>\n<p>El incidente en Austin ahora se conoce como la &#171;casi colisi\u00f3n&#187; m\u00e1s cercana durante un tiempo en que segu\u00edan ocurriendo en aeropuertos de costa a costa. La Junta Nacional de Seguridad en el Transporte ha investigado m\u00e1s de una decena de casos similares desde el comienzo del a\u00f1o pasado.<\/p>\n<p>El jueves, se agreg\u00f3 otro casi accidente a la lista cuando un avi\u00f3n de Alaska Airlines y un avi\u00f3n de Southwest casi colisionaron en Nashville.<\/p>\n<p>En algunos casos, pilotos h\u00e9roes como Bradeen y Carvajal han evitado que cursos de colisi\u00f3n se conviertan en mortales. El jueves, la pareja recibi\u00f3 el Premio a la Superioridad en la Aviaci\u00f3n de su sindicato por el trabajo en equipo y la vigilancia que evitaron lo que habr\u00eda sido el peor desastre a\u00e9reo en d\u00e9cadas.<\/p>\n<p>\u2018Muy rutinario justo hasta el final\u2019<\/p>\n<p>El d\u00fao atribuye su r\u00e1pida respuesta al entrenamiento y la experiencia. Carvajal ha estado con FedEx durante 22 a\u00f1os; Bradeen ha estado volando para la compa\u00f1\u00eda durante unos cinco a\u00f1os y medio.<\/p>\n<p>El vuelo fue como de costumbre, hasta que no lo fue. Los dos informaron sobre la aproximaci\u00f3n antes de subir al avi\u00f3n en Memphis y la informaron en vuelo. Y han entrenado repetidamente para la aproximaci\u00f3n de Categor\u00eda III.<\/p>\n<p>\u201cFue muy rutinario justo hasta el final\u201d, dijo Bradeen.<\/p>\n<p>El crucero viral de nueve meses llega a su fin. As\u00ed fue realmente la experiencia a bordo<\/p>\n<p>Pero a unos cinco kil\u00f3metros de aterrizar, se inquietaron cuando un controlador de tr\u00e1fico a\u00e9reo autoriz\u00f3 el despegue del vuelo de Southwest frente a ellos.<\/p>\n<p>\u201cEscuchamos a Southwest registrarse y luego la torre los autoriz\u00f3, lo que nos sorprendi\u00f3 a ambos. Nos miramos y expresamos un poco de escepticismo al respecto. Y Hugo me pidi\u00f3 que confirmara que todav\u00eda est\u00e1bamos autorizados para aterrizar, lo cual hice\u201d, dijo Bradeen.<\/p>\n<p>El Boeing 737 de Southwest estuvo sentado en el centro de la pista durante 19 segundos, de acuerdo con el informe de la NTSB, mientras el Boeing 767 de FedEx se dirig\u00eda hacia \u00e9l en la niebla. La conciencia de los pilotos estaba elevada, pero Bradeen dijo que no se dio cuenta de que una colisi\u00f3n era inminente hasta estar a unos 30 o 50 metros de distancia.<\/p>\n<p>\u201cEstaba mirando afuera porque est\u00e1bamos preocupados. As\u00ed que estaba mirando entre los sistemas de monitoreo internos y sobre el escudo de deslumbramiento, tratando de ver la pista y nuestra zona de aterrizaje. Y vi una luz de posici\u00f3n en la silueta del avi\u00f3n de Southwest justo sobre el escudo de deslumbramiento con cierre\u201d.<\/p>\n<p>Y pidi\u00f3 dar el giro. Mirar fuera de la aeronave durante una aproximaci\u00f3n de este tipo no es lo habitual, dijo Bradeen, pero debido a que no estaba seguro de la ubicaci\u00f3n del avi\u00f3n de Southwest, estaba mirando entre los sistemas interiores y el exterior.<\/p>\n<p>\u201cY afortunadamente pude mirar en el momento adecuado y verlo\u201d.<\/p>\n<p>Suerte, m\u00e1s a\u00f1os de experiencia.<\/p>\n<p>\u2018Esto podr\u00eda haber sido una tragedia\u2019<\/p>\n<p>\u201cEsto podr\u00eda haber sido una tragedia. Si no hubiera habido dos pilotos bien entrenados y calificados en la cabina de vuelo ese d\u00eda, ciertamente podr\u00edamos estar contando una historia muy diferente en este momento\u201d, dijo el capit\u00e1n Jason Ambrosi, presidente de la Asociaci\u00f3n de Pilotos de L\u00edneas A\u00e9reas.<\/p>\n<p>La NTSB emiti\u00f3 siete recomendaciones en junio basadas en el incidente de Austin, incluida la instalaci\u00f3n de tecnolog\u00eda en todos los aeropuertos comerciales para detectar el movimiento de aviones y veh\u00edculos en el suelo. La Administraci\u00f3n Federal de Aviaci\u00f3n ha dicho que instalar\u00eda un sistema de detecci\u00f3n de superficie en algunos aeropuertos para fines de 2025. Austin estar\u00eda entre esos aeropuertos.<\/p>\n<p>Carvajal dijo que \u201cconseguir los d\u00f3lares para apoyar ese tipo de equipo en cada aer\u00f3dromo\u201d es importante. Subray\u00f3 que tener dos pilotos en cada cabina es fundamental para la seguridad.<\/p>\n<p>\u201cEste incidente podr\u00eda haber sido catastr\u00f3fico. Si no fuera por las acciones heroicas de la tripulaci\u00f3n de FedEx\u201d, dijo Jennifer Homendy, presidenta de la NTSB, durante una audiencia hace unos meses. Agradeci\u00f3 a los pilotos por salvar vidas.<\/p>\n<p>Pero, \u00bfellos se ven a s\u00ed mismos como h\u00e9roes?<\/p>\n<p>\u201cDepende de tu perspectiva\u201d, dijo Bradeen. \u201cPara nosotros, hicimos nuestro trabajo. Es para lo que estamos entrenados\u201d.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; El clima no pod\u00eda ser peor, en t\u00e9rminos de niebla densa. Los pilotos de un avi\u00f3n de carga de FedEx no pod\u00edan ver la pista ni el aer\u00f3dromo en el Aeropuerto Internacional Austin-Bergstrom, en Texas. Pero est\u00e1n entrenados para tales aproximaciones de \u201cCategor\u00eda III\u201d, una aproximaci\u00f3n automatizada cuando los pilotos no necesitan ver [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452688","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Da la vuelta. Da la vuelta. Da la vuelta&quot;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Da la vuelta. Da la vuelta. Da la vuelta&quot;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; El clima no pod\u00eda ser peor, en t\u00e9rminos de niebla densa. Los pilotos de un avi\u00f3n de carga de FedEx no pod\u00edan ver la pista ni el aer\u00f3dromo en el Aeropuerto Internacional Austin-Bergstrom, en Texas. Pero est\u00e1n entrenados para tales aproximaciones de \u201cCategor\u00eda III\u201d, una aproximaci\u00f3n automatizada cuando los pilotos no necesitan ver [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-15T00:03:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre\",\"datePublished\":\"2024-09-15T00:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\"},\"wordCount\":1062,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\",\"name\":\"\\\"Da la vuelta. Da la vuelta. Da la vuelta\\\": los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-15T00:03:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Da la vuelta. Da la vuelta. Da la vuelta\": los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","og_locale":"es_ES","og_type":"article","og_title":"\"Da la vuelta. Da la vuelta. Da la vuelta\": los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre - Noticias","og_description":"(CNN) &#8212; El clima no pod\u00eda ser peor, en t\u00e9rminos de niebla densa. Los pilotos de un avi\u00f3n de carga de FedEx no pod\u00edan ver la pista ni el aer\u00f3dromo en el Aeropuerto Internacional Austin-Bergstrom, en Texas. Pero est\u00e1n entrenados para tales aproximaciones de \u201cCategor\u00eda III\u201d, una aproximaci\u00f3n automatizada cuando los pilotos no necesitan ver [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","og_site_name":"Noticias","article_published_time":"2024-09-15T00:03:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/"},"author":{"name":"","@id":""},"headline":"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre","datePublished":"2024-09-15T00:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/"},"wordCount":1062,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","url":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","name":"\"Da la vuelta. Da la vuelta. Da la vuelta\": los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-15T00:03:47+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\u00f3mo evitaron h\u00e1bilmente el desastre","url":"http:\/\/noticiasya.com\/costa-central\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/09\/14\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-15T00:03:47Z","datePublished":"2024-09-15T00:03:47Z","dateModified":"2024-09-15T00:03:47Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"&#171;Da la vuelta. Da la vuelta. Da la vuelta&#187;: los pilotos que estuvieron a 50 metros de estrellarse cuentan c\\u00f3mo evitaron h\\u00e1bilmente el desastre\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/09\\\/14\\\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/09\\\/14\\\/pilotos-fedex-cuentan-como-evitaron-desastre-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-15T00:03:47Z\",\"datePublished\":\"2024-09-15T00:03:47Z\",\"dateModified\":\"2024-09-15T00:03:47Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1467555,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/10\/21\/avion-aterrizaje-emergencia-pilotos-trax\/","url_meta":{"origin":1452688,"position":0},"title":"Avi\u00f3n aterriza de emergencia luego de perder contacto con auxiliares de vuelo y de que se escuchen golpes en puerta de cabina","author":"","date":"octubre 21, 2025","format":false,"excerpt":"Un vuelo de American Airlines, operado por SkyWest Airlines, realiz\u00f3 un aterrizaje de emergencia en Nebraska el lunes por la noche despu\u00e9s de que los pilotos no pudieron comunicarse con los asistentes de vuelo y escucharon a alguien afuera de la puerta de la cabina, seg\u00fan la Administraci\u00f3n Federal de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464766,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/07\/22\/incidente-avion-aeromexico-delta-trax\/","url_meta":{"origin":1452688,"position":1},"title":"Un avi\u00f3n de Aerom\u00e9xico casi aterriza encima de un 737 de Delta Air Lines que despegaba","author":"","date":"julio 22, 2025","format":false,"excerpt":"Dos aviones estuvieron a punto de colisionar en la pista en Ciudad de M\u00e9xico este lunes, cuando un jet regional de Aerom\u00e9xico que se aproximaba para aterrizar vol\u00f3 por encima y aterriz\u00f3 delante de un Boeing 737 de Delta Air Lines que ya comenzaba su despegue.El vuelo 590 de Delta\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472600,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/26\/faa-investiga-incidente-california-avion-helicoptero-trax\/","url_meta":{"origin":1452688,"position":2},"title":"La FAA investiga un incidente en California en el que un avi\u00f3n de United Airlines casi choca con un helic\u00f3ptero Black Hawk","author":"","date":"marzo 26, 2026","format":false,"excerpt":"La Administraci\u00f3n Federal de Aviaci\u00f3n (FAA, por sus siglas en ingl\u00e9s) est\u00e1 investigando un incidente en el que un helic\u00f3ptero de la Guardia Nacional del Ej\u00e9rcito de Estados Unidos cruz\u00f3 por delante de un avi\u00f3n de pasajeros que aterrizaba en el Aeropuerto John Wayne, en Santa Ana, California, inform\u00f3 la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458754,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/14\/altimetro-helicoptero-black-hawk-choco-avion-washington-trax\/","url_meta":{"origin":1452688,"position":3},"title":"Es posible que el alt\u00edmetro del helic\u00f3ptero Black Hawk que choc\u00f3 con un avi\u00f3n en Washington haya sido inexacto","author":"","date":"febrero 14, 2025","format":false,"excerpt":"Un an\u00e1lisis preliminar de los datos de vuelo y la grabadora de voz a bordo de un helic\u00f3ptero Black Hawk antes de la colisi\u00f3n con un vuelo comercial sobre Washington el 29 de enero indic\u00f3 que el alt\u00edmetro del helic\u00f3ptero puede haber sido inexacto y que los pilotos pueden no\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458054,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/30\/pilotos-informes-situaciones-riesgo-helicopteros-aeropuerto-raegan-choque-washington-trax\/","url_meta":{"origin":1452688,"position":4},"title":"Pilotos hab\u00edan reportado situaciones de riesgo con helic\u00f3pteros en el Aeropuerto Nacional Reagan antes del mortal choque","author":"","date":"enero 30, 2025","format":false,"excerpt":"Al menos dos pilotos informaron de situaciones peligrosas con helic\u00f3pteros mientras intentaban aterrizar en el aeropuerto en los tres a\u00f1os previos a la colisi\u00f3n letal entre el helic\u00f3ptero del Ej\u00e9rcito y un avi\u00f3n de American Airlines cerca del Aeropuerto Nacional Reagan (DCA), seg\u00fan una revisi\u00f3n de CNN de informes de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460603,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/30\/parte-mas-arriesgada-vuelo-trax\/","url_meta":{"origin":1452688,"position":5},"title":"\u00bfCu\u00e1l es la parte m\u00e1s arriesgada de tu vuelo? No es volar a 40.000 pies","author":"","date":"marzo 30, 2025","format":false,"excerpt":"Viajar por el cielo sin nada debajo, excepto 40.000 pies de aire enrarecido, puede parecer un lugar peligroso, pero cuando se trata de viajar en un avi\u00f3n comercial, de ninguna manera es la parte m\u00e1s riesgosa del vuelo.La seguridad de la aviaci\u00f3n ha sido sometida a un renovado escrutinio tras\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1452688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1452688"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1452688\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1452688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1452688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1452688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}