{"id":1452753,"date":"2024-09-17T01:03:48","date_gmt":"2024-09-17T08:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/"},"modified":"2024-09-17T01:03:48","modified_gmt":"2024-09-17T08:03:48","slug":"ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","title":{"rendered":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;"},"content":{"rendered":"<p>(CNN)\u00a0 &#8212; El hombre sospechoso del aparente intento de magnicidio contra el expresidente Donald Trump se describi\u00f3 el domingo en las redes sociales como un luchador trotamundos por la libertad: tuiteaba a los l\u00edderes mundiales, viajaba a Ucrania para apoyar su esfuerzo b\u00e9lico y profesaba su voluntad de morir por las causas en las que cre\u00eda.<\/p>\n<p>Ryan Wesley Routh, un constructor de viviendas de 58 a\u00f1os que vive en Hawai, dijo a los medios de comunicaci\u00f3n que hab\u00eda pasado meses en Ucrania trabajando para traer combatientes extranjeros al pa\u00eds desde Afganist\u00e1n. En Twitter, ahora conocida como X, implor\u00f3 al presidente Joe Biden que \u201cenv\u00ede todas las armas que tenemos a Ucrania\u201d y ofreci\u00f3 consejos al presidente de Ucrania, Volodymyr Zelensky, sobre estrategia militar.<\/p>\n<p>Pero la grandiosa imagen que Routh pint\u00f3 en Internet no parec\u00eda coincidir con su realidad. En una entrevista del a\u00f1o pasado, reconoci\u00f3 que no hab\u00eda conseguido ni una sola visa para los combatientes afganos que dec\u00eda estar dispuesto a enviar al pa\u00eds, y un funcionario militar ucraniano le dijo a CNN que las ideas de Routh parec\u00edan \u201cdelirantes\u201d.<\/p>\n<p>\u00bfQui\u00e9n es Ryan Wesley Routh, el hombre detenido en relaci\u00f3n al aparente segundo intento de magnicidio contra Trump?<\/p>\n<p>Lejos de su teclado, Routh dirig\u00eda una peque\u00f1a empresa que constru\u00eda peque\u00f1as casas en un suburbio de Honolulu, y pasaba su tiempo escribiendo cartas a su peri\u00f3dico local sobre campamentos de personas sin hogar, grafitis en un t\u00fanel de una autopista de Oahu y una disputa sobre una ruta de senderismo.<\/p>\n<p>Y los tuits de Routh a Biden, Zelensky y otras figuras famosas parecen haber sido ignorados, hasta que fue arrestado en Florida esta semana, despu\u00e9s de supuestamente esperar a Trump con un rifle de asalto afuera del campo de golf del expresidente en Palm Beach.<\/p>\n<p>La Oficina del sheriff del condado de Martin public\u00f3 el domingo un video de la c\u00e1mara corporal del arresto de Ryan Routh en una carretera interestatal de Florida. (Cr\u00e9dito: Oficina del sheriff del condado de Marti\/Facebook)<\/p>\n<p>En lo que parece ser el segundo intento de magnicidio contra Trump en unos dos meses, las autoridades dijeron que un agente del Servicio Secreto vio el ca\u00f1\u00f3n de un fusil con una mira telesc\u00f3pica que sobresal\u00eda de una valla mientras el candidato republicano jugaba una partida de golf. El agente abri\u00f3 fuego y Routh supuestamente huy\u00f3 del lugar en autom\u00f3vil sin disparar ning\u00fan tiro. Routh fue detenido m\u00e1s tarde y ha sido acusado de dos cargos, entre ellos posesi\u00f3n de un arma de fuego mientras era un delincuente convicto y posesi\u00f3n de un arma de fuego con un n\u00famero de serie borrado.<\/p>\n<p>Guerrero del teclado<\/p>\n<p>En los a\u00f1os previos al supuesto intento de magnicidio de Routh, \u00e9ste public\u00f3 mensajes en l\u00ednea criticando a Trump y mostr\u00f3 un profundo inter\u00e9s en apoyar a Ucrania en su guerra con Rusia.<\/p>\n<p>Routh se uni\u00f3 a X, entonces conocida como Twitter, en enero de 2020, e inmediatamente comenz\u00f3 a publicar sobre pol\u00edtica, seg\u00fan tuits guardados por Wayback Machine de Internet Archive. Routh afirm\u00f3 en una publicaci\u00f3n de 2020 que apoy\u00f3 a Trump en 2016, pero que hab\u00eda cambiado su tono sobre el expresidente: escribi\u00f3 que &#171;yo y el mundo esper\u00e1bamos que el presidente Trump fuera diferente y mejor que el candidato, pero todos est\u00e1bamos muy decepcionados y parece que est\u00e1s empeorando y degenerando&#187;. M\u00e1s recientemente, sugiri\u00f3 que el eslogan de la campa\u00f1a de Trump deber\u00eda ser &#171;convertir a los estadounidenses en esclavos de nuevo&#187;.<\/p>\n<p>En 2019 y 2020, seg\u00fan los registros de la Comisi\u00f3n Federal Electoral, Routh don\u00f3 peque\u00f1as cantidades a las campa\u00f1as de los candidatos presidenciales dem\u00f3cratas Tulsi Gabbard, Beto O&#8217;Rourke, Tom Steyer, Elizabeth Warren y Andrew Yang. Entre sus tuits de esa \u00e9poca, Routh llama al entonces candidato Joe Biden &#171;Joe el so\u00f1oliento&#187; y lo critica por ser alguien que &#171;no defiende nada; no tiene planes, no tiene ideas, es tan d\u00e9bil como Hillary&#187;.<\/p>\n<p>El detenido en aparente intento de magnicidio contra Trump critic\u00f3 al expresidente en redes sociales<\/p>\n<p>Routh tambi\u00e9n mostr\u00f3 un sentido de importancia personal en mensajes a l\u00edderes mundiales ya en 2020, cuando tuite\u00f3 repetidamente al dictador norcoreano Kim Jong Un. En un tuit , Routh escribi\u00f3: \u201cMe gustar\u00eda invitarlo a Hawai de vacaciones. Nos encantar\u00eda tenerlo aqu\u00ed y entretenerlo&#8230; Soy un l\u00edder aqu\u00ed y puedo organizar todo el viaje. Por favor, venga\u201d.<\/p>\n<p>En los d\u00edas previos y posteriores a la invasi\u00f3n rusa de Ucrania en febrero de 2022, Routh tuite\u00f3 decenas de veces sobre el conflicto. \u201cEstoy listo para ir a Ucrania, luchar y morir\u201d, escribi\u00f3 en una publicaci\u00f3n.<\/p>\n<p>Y tuite\u00f3 directamente a Zelensky, diciendo: \u201cPODEMOS CONSEGUIR QUE MILES DE CIVILES SE UNAN A SU LUCHA. Estoy dispuesto a ser el ejemplo. VOLAR\u00c9 DESDE ESTADOS UNIDOS Y LUCHAR\u00c9 CON USTEDES&#8230; POR FAVOR, T\u00d3MESE EL TIEMPO PARA RESPONDER\u201d. Zelensky no pareci\u00f3 responder.<\/p>\n<p>Un estadounidense en Kyiv<\/p>\n<p>Routh cumpli\u00f3 su promesa de viajar a Ucrania, seg\u00fan entrevistas con varias personas que lo conocieron all\u00ed, as\u00ed como fotograf\u00edas en las redes sociales. Pero sus esfuerzos por apoyar al pa\u00eds no parecieron llegar muy lejos.<\/p>\n<p>Seg\u00fan una p\u00e1gina de GoFundMe publicada por la prometida de Routh, Kathleen Shaffer, el hombre viaj\u00f3 al pa\u00eds en abril de 2022. Las fotos geolocalizadas por CNN muestran a Routh posando con carteles proucranianos, as\u00ed como una gran cantidad de drones, en la plaza Maidan de Kyiv. La p\u00e1gina de GoFundMe, que ya fue eliminada, recaud\u00f3 US$ 1.865 de su objetivo de US$ 2.500, que seg\u00fan Shaffer se destinar\u00edan a equipo t\u00e1ctico, alojamiento y suministros necesarios para los voluntarios. Shaffer escribi\u00f3 que Routh ya hab\u00eda &#171;organizado la entrega de 120 drones a las l\u00edneas del frente&#187;, aunque CNN no pudo verificar esas afirmaciones.<\/p>\n<p>En esta fotograf\u00eda de abril de 2022, Ryan Wesley Routh rinde homenaje a los ciudadanos extranjeros muertos durante la guerra entre Rusia y Ucrania en una plaza central de Kyiv. (Cr\u00e9dito: Efrem Lukatsky\/AP\/Archivo)<\/p>\n<p>En entrevistas con The New York Times y Semafor el a\u00f1o pasado, Routh describi\u00f3 sus esfuerzos por apoyar a Ucrania, incluso tratando de llevar combatientes de Afganist\u00e1n al pa\u00eds. Se mostr\u00f3 frustrado por la falta de progreso en su trabajo: el a\u00f1o pasado le dijo a Semafor que en sus reuniones con funcionarios ucranianos, \u201ccasi todos le hab\u00edan gritado\u201d.<\/p>\n<p>Un representante de la legi\u00f3n extranjera del Comando de Fuerzas Terrestres de Ucrania dijo a CNN que Routh se hab\u00eda comunicado con el comando varias veces, pero que nunca fue parte de la unidad militar en la que luchan los voluntarios en el extranjero.<\/p>\n<p>\u201cPodemos confirmar que esta persona se puso en contacto con nosotros en varias ocasiones a trav\u00e9s de Internet. La mejor manera de describir sus mensajes es como ideas delirantes\u201d, dijo el oficial Oleksandr Shaguri. \u201cNos ofrec\u00eda un gran n\u00famero de reclutas de diferentes pa\u00edses, pero para nosotros era obvio que sus ofertas no eran realistas. Ni siquiera respondimos, no hab\u00eda nada que responder. Nunca form\u00f3 parte de la Legi\u00f3n y no colabor\u00f3 \u200b\u200bcon nosotros de ninguna manera\u201d.<\/p>\n<p>Vance culpa a la ret\u00f3rica progresista del aparente intento de magnicidio contra Trump<\/p>\n<p>Ryan Wesley Routh participa en una manifestaci\u00f3n en el centro de Kyiv, Ucrania, el s\u00e1bado 30 de abril de 2022. (Cr\u00e9dito: Efrem Lukatsky\/AP)<\/p>\n<p>Michael Wasiura, un periodista que conoci\u00f3 y entrevist\u00f3 a Routh en Ucrania en 2022, dijo que despu\u00e9s de que los esfuerzos de Routh para unirse a la Legi\u00f3n Internacional del pa\u00eds fueran rechazados, instal\u00f3 un monumento improvisado en Kyiv para los soldados extranjeros que hab\u00edan muerto en la guerra.<\/p>\n<p>\u201cEstaba all\u00ed todos los d\u00edas\u201d, dijo Wasiura. \u201cAl hablar con \u00e9l, estaba claro que no estaba hablando con una persona normal. Era\u2026 quiz\u00e1s man\u00edaco sea la palabra correcta. Era extremadamente devoto. Hac\u00eda todo esto por iniciativa propia porque le importaba la causa y estaba tan extremadamente devoto de ella que, en esencia, estaba acampando en un pa\u00eds extranjero\u201d.<\/p>\n<p>Evelyn Aschenbrenner, ciudadana estadounidense que sirvi\u00f3 en la Legi\u00f3n Internacional de Ucrania durante dos a\u00f1os, dijo a CNN que le advirtieron a Routh varias veces que utilizara las v\u00edas oficiales para reclutar gente para luchar en Ucrania, pero \u00e9l simplemente no les hizo caso. Aschenbrenner le mostr\u00f3 a CNN varios mensajes que intercambiaron con Routh, en los que Routh expres\u00f3 su enojo por lo que \u00e9l ve\u00eda como la falta de voluntad de Ucrania para aceptar su ayuda.<\/p>\n<p>Servicio Secreto asegura que Donald Trump nunca estuvo en riesgo tras segundo intento de asesinato<\/p>\n<p>\u201cParec\u00eda tener una especie de delirio de grandeza\u201d, dijo Aschenbrenner. \u201cYo pensaba: \u2018Lo \u00fanico que est\u00e1s haciendo es causar dolores de cabeza a todo el mundo\u2026 la legi\u00f3n ya tiene un sitio web de reclutamiento, no hay necesidad de que hagas esto\u2019\u201d.<\/p>\n<p>El estadounidense Ryan O&#8217;Leary, un veterano de la Guardia Nacional de Estados Unidos que est\u00e1 luchando en Ucrania y se encontr\u00f3 con Routh en 2022, lo describi\u00f3 como &#171;extra\u00f1o&#187;.<\/p>\n<p>&#171;Lo encontr\u00e9 inofensivo, pero no era una persona que deber\u00eda estar en una zona de guerra, ya que estaba mentalmente desequilibrado&#187;, dijo O&#8217;Leary.<\/p>\n<p>El a\u00f1o pasado, Routh aparentemente hab\u00eda escrito un libro sobre la guerra \u2013\u201cUkraine&#8217;s Unwinnable War: The Fatal Flaw of Democracy, World Abandonment and the Global Citizen-Taiwan, Afghanistan, North Korea and the end of Humanity\u201d\u2013 y vend\u00eda una versi\u00f3n digital en Amazon por US$ 2,99. En el libro, criticaba a Trump como un \u201cidiota\u201d, un \u201cbuf\u00f3n\u201d y un \u201ctonto\u201d, y parec\u00eda hacer referencia a su apoyo anterior a Trump al escribir: \u201cSoy lo suficientemente hombre para decir que juzgu\u00e9 mal y comet\u00ed un terrible error\u201d.<\/p>\n<p>AN\u00c1LISIS | Trump pasa del aparente segundo intento de magnicidio a afirmaciones m\u00e1s incendiarias<\/p>\n<p>Al mismo tiempo, Routh tambi\u00e9n mostr\u00f3 su apoyo a Taiw\u00e1n. En publicaciones en l\u00ednea, Routh afirm\u00f3 estar involucrado en la \u201cLegi\u00f3n Extranjera de Taiw\u00e1n\u201d, un grupo que supuestamente recluta personal militar extranjero para luchar por Taiw\u00e1n en caso de una guerra con China. Pero varias personas que figuran como simpatizantes en el sitio web del grupo dijeron a CNN que no ten\u00edan conocimiento de la legi\u00f3n ni de sus actividades, y algunos nunca hab\u00edan o\u00eddo hablar de Routh antes.<\/p>\n<p>El periodista de la revista Newsweek Romania Remus Cernea, una de las personas que figuran en el sitio web, dijo a CNN que conoci\u00f3 a Routh en la plaza Maidan de Kyiv en junio de 2022. Cernea entrevist\u00f3 a Routh sobre sus esfuerzos por apoyar a Ucrania, y Routh dijo que \u201cpara m\u00ed, muchos otros conflictos son grises, pero este conflicto es definitivamente blanco y negro. Se trata del bien contra el mal\u201d.<\/p>\n<p>Musk publica y borra\u00a0su\u00a0fuerte mensaje sobre intentos de atentados contra Trump<\/p>\n<p>Cernea dijo que aproximadamente un a\u00f1o despu\u00e9s se encontr\u00f3 con Routh nuevamente y record\u00f3 que estaba visiblemente frustrado porque no hab\u00edan llegado m\u00e1s extranjeros para ayudar a Ucrania. Cernea dijo que se sorprendi\u00f3 al enterarse de que Routh hab\u00eda sido arrestado en relaci\u00f3n con el intento de magnicidio contra Trump.<\/p>\n<p>\u201cPara m\u00ed es una sorpresa, porque lo ve\u00eda como una persona idealista, inocente, genuina, sin ning\u00fan instinto asesino\u201d, dijo Cernea.<\/p>\n<p>Historia de volatilidad<\/p>\n<p>Sin embargo, en los a\u00f1os previos a sus esfuerzos internacionales, Routh tuvo antecedentes de problemas con la ley en su natal Carolina del Norte.<\/p>\n<p>En 2002, el peri\u00f3dico Greensboro News and Record inform\u00f3 que hab\u00eda sido arrestado despu\u00e9s de atrincherarse dentro de un negocio local con una ametralladora.<\/p>\n<p>Los registros judiciales muestran que fue acusado de posesi\u00f3n ilegal de un arma de destrucci\u00f3n masiva, entre otros cargos, y se declar\u00f3 culpable.<\/p>\n<p>Tracy Fulk, una agente de Polic\u00eda de Greensboro en ese momento, dijo a CNN que el incidente comenz\u00f3 cuando detuvo a Routh para detenerlo en una parada de tr\u00e1fico. Dijo que vio un arma en su auto y, despu\u00e9s de sacar su arma, el hombre se alej\u00f3 y corri\u00f3 hacia su negocio. Eso llev\u00f3 a un enfrentamiento con un equipo de respuesta especial de la Polic\u00eda y Routh luego se entreg\u00f3, dijo Fulk.<\/p>\n<p>Mira las entrevistas anteriores con el sospechoso del aparente intento de magnicidio contra Donald Trump<\/p>\n<p>\u201cEra una persona peligrosa\u201d, dijo Fulk, y agreg\u00f3 que la Polic\u00eda local lo conoc\u00eda. Pero cuando lo arrestaron, record\u00f3, \u201cestaba muy callado y no dijo mucho durante el tiempo que estuve con \u00e9l\u201d.<\/p>\n<p>En los a\u00f1os siguientes, seg\u00fan los registros judiciales, Routh se enfrent\u00f3 a una letan\u00eda de acusaciones penales menos graves, algunas de las cuales fueron posteriormente desestimadas. Fue acusado en m\u00faltiples casos de emitir cheques sin fondos y se declar\u00f3 culpable de uno de esos cargos en 2003. En 2009 y 2010, fue acusado de posesi\u00f3n de una sustancia controlada y posesi\u00f3n de un veh\u00edculo robado, delitos menores que fueron desestimados, y fue declarado culpable de posesi\u00f3n de bienes robados, por lo que recibi\u00f3 tres a\u00f1os de libertad condicional.<\/p>\n<p>El presunto magnicida tambi\u00e9n parec\u00eda tener algunos problemas de dinero: los jueces le ordenaron pagar decenas de miles de d\u00f3lares a los demandantes en varias demandas civiles presentadas en su contra, y las autoridades estatales y federales lo han\u202f acusado repetidamente \u202fde no pagar sus impuestos a tiempo.<\/p>\n<p>Presentan cargos relacionados con armas contra el sospechoso del supuesto intento de magnicidio contra Trump<\/p>\n<p>Los problemas legales de Routh contrastan marcadamente con lo que parece ser su primera aparici\u00f3n en las noticias: un joven de 25 a\u00f1os fue descrito como un h\u00e9roe local en un art\u00edculo del Greensboro News and Record de 1991 despu\u00e9s de que, seg\u00fan se informa, persigui\u00f3 y luch\u00f3 contra un presunto violador. Routh recibi\u00f3 un premio de la Polic\u00eda local por sus acciones y el peri\u00f3dico se refiri\u00f3 a \u00e9l como un &#171;superciudadano, si no un superh\u00e9roe&#187;.<\/p>\n<p>M\u00e1s recientemente, se mud\u00f3 a Hawai y vive cerca del oc\u00e9ano en Ka\u02bba\u02bbawa, un pueblo de aproximadamente 1.200 habitantes en la costa norte de la isla de Oahu, seg\u00fan muestran registros p\u00fablicos.<\/p>\n<p>Routh, que anteriormente hab\u00eda trabajado en instalaci\u00f3n y reparaci\u00f3n de techos de casas, inici\u00f3 un negocio de construcci\u00f3n en el que erig\u00eda casas diminutas. Apareci\u00f3 en el Honolulu Star-Advertiser en 2019 por sus esfuerzos para albergar a la poblaci\u00f3n sin techo de Hawai. El sitio web de su empresa, que incluye fotos y videos de Routh construyendo casas sencillas con lo que parece ser madera contrachapada, dice que su misi\u00f3n era &#171;producir soluciones a nuestros propios problemas aqu\u00ed mismo en la isla&#187;.<\/p>\n<p>La casa de Ryan Routh en Ka\u02bba\u02bbawa, Hawai, el 15 de septiembre. (Cr\u00e9dito: Audrey McAvoy\/AP)<\/p>\n<p>Un hombre hawaiano que dio una mala cr\u00edtica a la empresa de Routh en Facebook le dijo a CNN que estaba desconcertado por la respuesta de Routh a la cr\u00edtica. Saili Levi, propietario de una empresa de comercializaci\u00f3n de vainilla, dijo que pag\u00f3 a Routh US$ 3.800 por adelantado para construir un remolque para su negocio, pero cuando Levi fue al taller de Routh para evaluar su trabajo, era de mala calidad. Cuando le pidi\u00f3 a Routh que mejorara el trabajo, dijo Levi, Routh se enoj\u00f3.<\/p>\n<p>\u201cEmpez\u00f3 a despotricar, ya sabes, \u2018\u00bfCrees que porque tienes dinero eres mejor que yo?\u2019\u201d, dijo Levi. \u201cDecid\u00ed que tal vez deber\u00eda dejarlo pasar por el bien de mi familia\u201d.<\/p>\n<p>Routh tambi\u00e9n escribi\u00f3 varias cartas al editor que fueron publicadas en el peri\u00f3dico Star-Advertiser, prometiendo donar mano de obra para construir casas para personas sin techo, criticando un plan para demoler un viejo estadio deportivo como una &#171;cat\u00e1strofe inminente&#187; y denunciando a los trabajadores de la construcci\u00f3n por no rellenar los baches.<\/p>\n<p>As\u00ed actu\u00f3 Ryan Wesley Routh en el supuesto ataque a Trump 3:09<\/p>\n<p>Incluso pareci\u00f3 haber considerado postularse a la alcald\u00eda de Honolulu este a\u00f1o. Un sitio web improvisado, \u201cVote Ryan Routh\u201d, que incluye informaci\u00f3n de contacto que coincide con la de Routh, contiene casi 70 publicaciones que abordan las opiniones de Routh sobre el acceso a los sitios hist\u00f3ricos, la crisis de vivienda de la isla, su propuesta de \u201cguerra contra las termitas\u201d y la molestia que suponen los gallos. En las publicaciones, la mayor\u00eda de las cuales se subieron este verano, Routh se describi\u00f3 a s\u00ed mismo como alguien sobrio durante toda su vida y escribi\u00f3 que hab\u00eda pasado ocho meses en Ucrania.<\/p>\n<p>\u201cDebemos seguir adelante con un liderazgo l\u00f3gico que apoye a quienes desean lograr grandes cosas\u201d, escribi\u00f3 Routh en una publicaci\u00f3n. No apareci\u00f3 en la boleta electoral durante las elecciones primarias para alcalde del mes pasado.<\/p>\n<p>El hijo mayor de Routh, Oran, le dijo a CNN v\u00eda mensaje de texto que Routh era \u201cun padre amoroso y afectuoso, y un hombre honesto y trabajador\u201d.<\/p>\n<p>\u201cNo s\u00e9 qu\u00e9 ha pasado en Florida y espero que las cosas se hayan exagerado\u201d, escribi\u00f3 el joven Routh. \u201cNo parece que el hombre que conozco haga algo loco, mucho menos violento\u201d.<\/p>\n<p>&#8211;Paradise Afshar, Nelli Black, Benjamin Brown, Scott Glover, Lex Harvey, Winter Hawk, Rob Kuznia, Kyung Lah, Daniel Medina, Gianluca Mezzofiore, Rob Picheta, Majlie de Puy Kamp, Sabrina Shulman, Teele Rebane, Adam Renton y Jessie Yeung de CNN contribuyeron a este informe.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN)\u00a0 &#8212; El hombre sospechoso del aparente intento de magnicidio contra el expresidente Donald Trump se describi\u00f3 el domingo en las redes sociales como un luchador trotamundos por la libertad: tuiteaba a los l\u00edderes mundiales, viajaba a Ucrania para apoyar su esfuerzo b\u00e9lico y profesaba su voluntad de morir por las causas en las que [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1452753","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &quot;delirio de grandeza&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &quot;delirio de grandeza&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN)\u00a0 &#8212; El hombre sospechoso del aparente intento de magnicidio contra el expresidente Donald Trump se describi\u00f3 el domingo en las redes sociales como un luchador trotamundos por la libertad: tuiteaba a los l\u00edderes mundiales, viajaba a Ucrania para apoyar su esfuerzo b\u00e9lico y profesaba su voluntad de morir por las causas en las que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-17T08:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;\",\"datePublished\":\"2024-09-17T08:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\"},\"wordCount\":3001,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\",\"name\":\"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un \\\"delirio de grandeza\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-09-17T08:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un \"delirio de grandeza\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un \"delirio de grandeza\" - Noticias","og_description":"(CNN)\u00a0 &#8212; El hombre sospechoso del aparente intento de magnicidio contra el expresidente Donald Trump se describi\u00f3 el domingo en las redes sociales como un luchador trotamundos por la libertad: tuiteaba a los l\u00edderes mundiales, viajaba a Ucrania para apoyar su esfuerzo b\u00e9lico y profesaba su voluntad de morir por las causas en las que [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","og_site_name":"Noticias","article_published_time":"2024-09-17T08:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/"},"author":{"name":"","@id":""},"headline":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;","datePublished":"2024-09-17T08:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/"},"wordCount":3001,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","url":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","name":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un \"delirio de grandeza\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-09-17T08:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"De Ucrania a Hawai: el extra\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;","url":"http:\/\/noticiasya.com\/costa-central\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/09\/17\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-09-17T08:03:48Z","datePublished":"2024-09-17T08:03:48Z","dateModified":"2024-09-17T08:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"De Ucrania a Hawai: el extra\\u00f1o comportamiento del sospechoso del intento de magnicidio de Trump sugiere un &#171;delirio de grandeza&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/09\\\/17\\\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/09\\\/17\\\/ucrania-hawai-comportamiento-sospechoso-intento-magnicidio-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-09-17T08:03:48Z\",\"datePublished\":\"2024-09-17T08:03:48Z\",\"dateModified\":\"2024-09-17T08:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1452714,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/15\/detenido-aparente-intento-magnicidio-trump-critico-expresidente-redes-sociales-trax\/","url_meta":{"origin":1452753,"position":0},"title":"El detenido en aparente intento de magnicidio contra Trump critic\u00f3 al expresidente en redes sociales","author":"","date":"septiembre 15, 2024","format":false,"excerpt":"(CNN) -- Un hombre de 58 a\u00f1os detenido este domingo en relaci\u00f3n con un aparente intento de magnicidio contra Donald Trump en Florida es un constructor de viviendas asequibles aut\u00f3nomo en Hawai que recurri\u00f3 a las redes sociales para opinar sobre pol\u00edtica y acontecimientos actuales, a veces criticando al expresidente.Ryan\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456145,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/28\/putin-elogia-trump-inteligente-experimentada-trax\/","url_meta":{"origin":1452753,"position":1},"title":"Putin dice que Trump es una persona &#171;inteligente y experimentada&#187; que &#171;encontrar\u00e1 una soluci\u00f3n&#187;","author":"","date":"noviembre 28, 2024","format":false,"excerpt":"(CNN) \u2014\u00a0El presidente de Rusia, Vladimir Putin, elogi\u00f3 el jueves al presidente electo de Estados Unidos, Donald Trump, como un pol\u00edtico \u201cinteligente y experimentado\u201d capaz de encontrar \u201csoluciones\u201d, en un momento en que aumentan las tensiones entre Mosc\u00fa y Occidente por la guerra en Ucrania.En declaraciones a los periodistas en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460288,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/22\/enviado-eeuu-ucrania-regiones-ocupadas-trax\/","url_meta":{"origin":1452753,"position":2},"title":"El enviado de EE.UU. dice que el &#171;elefante en el cuarto&#187; en las conversaciones de paz es si Ucrania ceder\u00e1 regiones ocupadas","author":"","date":"marzo 22, 2025","format":false,"excerpt":"El mayor obst\u00e1culo para resolver la guerra de Rusia en Ucrania es el estatus de Crimea y las cuatro regiones ucranianas continentales ocupadas por Rusia, dijo el enviado especial de EE.UU. Steve Witkoff, llamando a ese tema \u201cel elefante en el cuarto\u201d en las conversaciones de paz.En una larga entrevista\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451154,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/15\/trump-vance-vicepresidente-heredero-politico-maga-analisis-trax\/","url_meta":{"origin":1452753,"position":3},"title":"AN\u00c1LISIS | Dos d\u00edas despu\u00e9s de sobrevivir a un intento de magnicidio, Trump elige a su heredero MAGA","author":"","date":"julio 15, 2024","format":false,"excerpt":"(CNN) -- J.D. Vance es la encarnaci\u00f3n de la transformaci\u00f3n populista, nacionalista y obrera del viejo Partido Republicano del establishment.Por eso el expresidente Donald Trump \u2013que nunca olvida los entusiasmos de su base\u2013 eligi\u00f3 al senador de Ohio como compa\u00f1ero de f\u00f3rmula para la vicepresidencia y lo nombr\u00f3 de hecho\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467483,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/10\/17\/cnn-verifica-trump-ningun-presidente-terminado-guerra-trax\/","url_meta":{"origin":1452753,"position":4},"title":"CNN verifica: Trump afirma falsamente que ning\u00fan otro presidente de EE.UU. ha terminado una guerra","author":"","date":"octubre 17, 2025","format":false,"excerpt":"El presidente de Estados Unidos, Donald Trump, hizo m\u00faltiples afirmaciones falsas a la prensa durante una reuni\u00f3n este viernes con el presidente de Ucrania, Volodymyr Zelensky, en la Casa Blanca, incluida una afirmaci\u00f3n largamente desacreditada sobre la guerra en Ucrania.Trump repiti\u00f3 su versi\u00f3n falsa sobre la invasi\u00f3n a gran escala\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458895,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/19\/analisis-donald-trump-putin-ucrania-trax\/","url_meta":{"origin":1452753,"position":5},"title":"AN\u00c1LISIS | Trump asesta otro golpe a Ucrania y refuerza a\u00fan m\u00e1s a Putin","author":"","date":"febrero 19, 2025","format":false,"excerpt":"Parec\u00eda que las cosas no pod\u00edan ponerse m\u00e1s negras para Ucrania. Entonces, el presidente Donald Trump tom\u00f3 la palabra.Tras excluir al presidente Volodymyr Zelensky de las primeras conversaciones de Estados Unidos con Rusia para poner fin a la guerra, Trump acus\u00f3 falsamente este martes a Ucrania de iniciar un conflicto\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1452753","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1452753"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1452753\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1452753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1452753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1452753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}