{"id":1455412,"date":"2024-10-28T17:03:48","date_gmt":"2024-10-29T00:03:48","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/"},"modified":"2024-10-28T17:03:48","modified_gmt":"2024-10-29T00:03:48","slug":"antartida-convirtio-lugares-vacaciones-populares-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","title":{"rendered":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo"},"content":{"rendered":"<p>(CNN) &#8212; Era una tarde brillante y soleada durante la reciente temporada de verano en la Ant\u00e1rtida cuando el crucero Seabourn Pursuit choc\u00f3 contra una capa de hielo marino en la bah\u00eda Hanusse. El barco avanz\u00f3 a toda velocidad, con el hielo desmoron\u00e1ndose bajo su proa, hasta quedar incrustado varios cientos de metros en el agua helada del mar.<\/p>\n<p>Los 250 pasajeros a bordo del Pursuit salieron a sus balcones y se asomaron a los laterales de las cubiertas para ver qu\u00e9 ocurr\u00eda.<br \/>\nPero no hubo una carrera como en el Titanic hacia los botes salvavidas. En su lugar, los pasajeros bajaron a la pasarela y empezaron a salir del barco para dar un paseo por el hielo. Esto no fue un accidente. Fue una experiencia planificada, completada con una mesa con copas de champ\u00e1n para brindar por su llegada a la Ant\u00e1rtida.<\/p>\n<p>Sin duchas, sin intimidad, sin remordimientos: as\u00ed es vivir realmente en la Ant\u00e1rtida<\/p>\n<p>Entre los pasajeros que paseaban por la capa de hielo se encontraban Greg y Susana McCurdy, una pareja de polic\u00edas jubilados de Las Vegas. Susana es ahora agente de viajes a tiempo parcial, y los McCurdy est\u00e1n pasando su jubilaci\u00f3n visitando tantos lugares ex\u00f3ticos como pueden.<\/p>\n<p>Susana y Greg McCurdy celebran un paseo sobre una capa de hielo ant\u00e1rtica flotante. Cr\u00e9dito: Jason Evans<\/p>\n<p>Tras tomar sus copas de champ\u00e1n, los McCurdy desplegaron una peque\u00f1a pancarta en la que se le\u00eda &#171;7\u00b0 Continente Ant\u00e1rtico 2024&#187; y posaron para una foto. Con este viaje, se hab\u00edan unido a un peque\u00f1o pero creciente grupo de personas que han pisado todos los continentes del planeta.<\/p>\n<p>Susana dice que \u00faltimamente ha observado un cambio entre sus clientes. &#171;Quieren m\u00e1s autenticidad, m\u00e1s cosas de la lista de cosas que hacer antes de morir, sobre todo despu\u00e9s del covid. Simplemente ya no esperan m\u00e1s&#8230; Y la Ant\u00e1rtida est\u00e1 casi al principio de la lista de todos&#187;.<\/p>\n<p>Destino para lista de deseos<\/p>\n<p>Las cr\u00edas de ping\u00fcino son un elemento b\u00e1sico de los viajes a la Ant\u00e1rtida a finales de verano. Cr\u00e9dito: Jason Evans<\/p>\n<p>El auge de los viajes a la Ant\u00e1rtida comenz\u00f3 mucho antes del boom de los viajes despu\u00e9s de la pandemia de covid.<\/p>\n<p>La Asociaci\u00f3n Internacional de Operadores Tur\u00edsticos de la Ant\u00e1rtida (IAATO, por sus siglas en ingl\u00e9s) lleva haciendo un seguimiento del n\u00famero de turistas que visitan el continente blanco desde principios de los a\u00f1os noventa. Por aquel entonces, unas 7.000 personas lo visitaban cada a\u00f1o.<\/p>\n<p>Las cifras se han disparado realmente en la \u00faltima media d\u00e9cada aproximadamente. En el invierno de 2017, algo menos de 44.000 turistas visitaron la Ant\u00e1rtida. Este a\u00f1o, esa cifra super\u00f3 los 122.000 visitantes. Y lleagn en tal n\u00famero porque viajar al continente m\u00e1s fr\u00edo de la Tierra nunca ha sido tan f\u00e1cil&#8230; ni tan lujoso.<\/p>\n<p>Los cient\u00edficos observaron im\u00e1genes del espacio para ver a qu\u00e9 velocidad reverdece la Ant\u00e1rtida. Esto es lo que descubrieron<\/p>\n<p>Hace un par de d\u00e9cadas, viajar a la Ant\u00e1rtida significaba hacerlo en barcos m\u00e1s peque\u00f1os, muchos de ellos antiguos &#171;cortadores de hielo&#187; de Rusia, Canad\u00e1 y otras naciones polares. Era cualquier cosa menos una experiencia de lujo.<\/p>\n<p>Robin West, vicepresidente y director general de expediciones de Seabourn, realiz\u00f3 su primer viaje a la regi\u00f3n en 2002. Dice que muchos de los barcos de entonces estaban equipados con literas y ba\u00f1os compartidos. &#171;Pon\u00edas tu nombre en una pizarra para comer espaguetis o lasa\u00f1a cada noche&#187;, dijo.<\/p>\n<p>El Seabourn Pursuit utiliza su proa para cortar hielo en la Ant\u00e1rtida. Cr\u00e9dito: Jason Evans<\/p>\n<p>Pocos de los barcos ten\u00edan siquiera ventanas para ver el exterior. La experiencia actual es muy diferente.<\/p>\n<p>Colleen McDaniel, redactora jefe de Cruise Critic, atribuye a las l\u00edneas de cruceros Lindblad y National Geographic el m\u00e9rito de haber abierto los viajes a la Ant\u00e1rtida a m\u00e1s visitantes hace aproximadamente una d\u00e9cada.<\/p>\n<p>&#171;Fueron realmente las pioneras en acercar la experiencia ant\u00e1rtica a un viajero m\u00e1s tradicional. Pero aquellas navegaciones iniciales eran menos lujosas de lo que vemos hoy en d\u00eda&#187;, dijo McDaniel.<\/p>\n<p>&#171;\u00daltimamente Ponant, Silversea, Seabourn y Scenic han dado pasos de gigante con esa experiencia de lujo de alta gama, ofreciendo incre\u00edbles suites a bordo, cenas excepcionales e incluso spas. L\u00edneas de cruceros como Quark est\u00e1n creando productos para los amantes de la aventura, ofreciendo cosas como esqu\u00ed de fondo y acampada&#187;.<\/p>\n<p>Estas son las mujeres que dirigen la &#171;oficina de correos de los ping\u00fcinos&#187; de la Ant\u00e1rtida<\/p>\n<p>Preocupaciones medioambientales<\/p>\n<p>Las crecientes cifras del turismo hacen que algunos expertos den la voz de alarma sobre los impactos medioambientales del repunte de visitantes.<\/p>\n<p>Un estudio de 2022 publicado en la revista acad\u00e9mica Nature descubri\u00f3 que la nieve de la Ant\u00e1rtida se derrite m\u00e1s deprisa debido a las visitas tur\u00edsticas al continente. El holl\u00edn negro que sale de las chimeneas de los cruceros se deposita en el hielo y atrae la luz solar, provocando que toneladas de nieve se derritan prematuramente. Los ecologistas tambi\u00e9n afirman que la creciente presencia humana en la Ant\u00e1rtida est\u00e1 provocando un aumento de los niveles de di\u00f3xido de carbono en una zona del planeta que no est\u00e1 acostumbrada a ello.<\/p>\n<p>Una foca leopardo levanta la vista tras echarse una siesta sobre un trozo de hielo flotante en la Ant\u00e1rtida. Cr\u00e9dito: Jason Evans<\/p>\n<p>Los operadores de cruceros dicen ser muy conscientes de su impacto medioambiental. Los pasajeros reciben instrucciones detalladas sobre no llevar consigo ning\u00fan alimento ajeno u otros contaminantes para los desembarcos en la Ant\u00e1rtida. Se les instruye para que nunca se tumben en la nieve y mantengan la distancia con los animales para evitar que las bacterias y los virus transmitidos por el ser humano infecten a la fauna salvaje.<\/p>\n<p>Los pa\u00edses que realizan turismo e investigaci\u00f3n en la Ant\u00e1rtida han firmado lo que se conoce como el Tratado Ant\u00e1rtico. En \u00e9l se establece que nadie debe construir estructuras permanentes en la zona para uso tur\u00edstico. Dicho de otro modo, no hay hoteles en la Ant\u00e1rtida. Recientemente, la IAATO comenz\u00f3 a llevar un registro del consumo de combustible de los cruceros en la regi\u00f3n ant\u00e1rtica y algunos operadores utilizan ahora la propulsi\u00f3n el\u00e9ctrica cuando pueden, en un esfuerzo por reducir las emisiones de holl\u00edn y CO2.<\/p>\n<p>El crucero viral de nueve meses llega a su fin. As\u00ed fue realmente la experiencia a bordo<\/p>\n<p>M\u00e1s formas que nunca de acceder al continente<\/p>\n<p>Mientras tanto, las compa\u00f1\u00edas de cruceros han invertido miles de millones de d\u00f3lares en los \u00faltimos a\u00f1os en buques de expedici\u00f3n de lujo especialmente construidos.<\/p>\n<p>Tanto el Seabourn Pursuit como su barco gemelo, el Venture, cuentan con un lujoso spa, nueve restaurantes y ocho salones y bares para los aproximadamente 250 pasajeros a bordo. Cada uno de los 132 camarotes tiene grandes puertas de cristal y un balc\u00f3n, lo que permite a los viajeros situarse f\u00e1cilmente en el exterior mientras flotan los majestuosos icebergs.<\/p>\n<p>Por un suplemento, los pasajeros pueden reservar una plaza en uno de los submarinos de a bordo o explorar las aguas ant\u00e1rticas en kayak. Y los pasajeros no deben preocuparse por las g\u00e9lidas temperaturas, ya que se les proporciona un equipo especialmente dise\u00f1ado para el fr\u00edo que garantiza que se mantengan calientes y secos mientras pasean entre los ping\u00fcinos y las focas.<\/p>\n<p>\u00daltimamente, incluso ha surgido una nueva categor\u00eda de viajes a la Ant\u00e1rtida.<\/p>\n<p>Operadores como Celebrity, Norwegian y Princess ofrecen ahora visitas &#171;s\u00f3lo en crucero&#187; que permiten a los pasajeros ver la Ant\u00e1rtida sin llegar a tocar tierra en la pr\u00edstina y fr\u00e1gil tundra.<\/p>\n<p>La fauna salvaje es un gran atractivo de los cruceros ant\u00e1rticos. Cr\u00e9dito: Jason Evans<\/p>\n<p>Estas visitas suelen contar con barcos m\u00e1s grandes y suelen ser m\u00e1s asequibles. La IAATO afirma que en 2017, unos 7.000 pasajeros visitaron la Ant\u00e1rtida en un viaje &#171;s\u00f3lo crucero&#187;. Esta \u00faltima temporada, esa cifra super\u00f3 los 43.000, un aumento de m\u00e1s del 500%.<\/p>\n<p>&#171;Estas l\u00edneas convencionales ofrecen una forma m\u00e1s econ\u00f3mica de viajar a la regi\u00f3n, aunque en realidad no desembarque en la Ant\u00e1rtida&#187;, afirma McDaniel, de Cruise Critic. &#171;Y aunque no podr\u00e1 ver ping\u00fcinos o focas tan de cerca como en un desembarco, seguir\u00e1 vi\u00e9ndolos. Tambi\u00e9n podr\u00e1 ver ballenas y muchas variedades de aves&#187;.<\/p>\n<p>Ya sea en uno de los nuevos barcos de lujo o en la experiencia de s\u00f3lo crucero, un viaje a la Ant\u00e1rtida es una oportunidad de ver otro mundo, desde la majestuosa belleza de los icebergs y glaciares hasta el juguet\u00f3n deambular de los ping\u00fcinos, y nunca ha sido tan f\u00e1cil visitarla.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) &#8212; Era una tarde brillante y soleada durante la reciente temporada de verano en la Ant\u00e1rtida cuando el crucero Seabourn Pursuit choc\u00f3 contra una capa de hielo marino en la bah\u00eda Hanusse. El barco avanz\u00f3 a toda velocidad, con el hielo desmoron\u00e1ndose bajo su proa, hasta quedar incrustado varios cientos de metros en el [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1455412","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) &#8212; Era una tarde brillante y soleada durante la reciente temporada de verano en la Ant\u00e1rtida cuando el crucero Seabourn Pursuit choc\u00f3 contra una capa de hielo marino en la bah\u00eda Hanusse. El barco avanz\u00f3 a toda velocidad, con el hielo desmoron\u00e1ndose bajo su proa, hasta quedar incrustado varios cientos de metros en el [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-29T00:03:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo\",\"datePublished\":\"2024-10-29T00:03:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\"},\"wordCount\":1556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\",\"name\":\"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-10-29T00:03:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","og_locale":"es_ES","og_type":"article","og_title":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo - Noticias","og_description":"(CNN) &#8212; Era una tarde brillante y soleada durante la reciente temporada de verano en la Ant\u00e1rtida cuando el crucero Seabourn Pursuit choc\u00f3 contra una capa de hielo marino en la bah\u00eda Hanusse. El barco avanz\u00f3 a toda velocidad, con el hielo desmoron\u00e1ndose bajo su proa, hasta quedar incrustado varios cientos de metros en el [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","og_site_name":"Noticias","article_published_time":"2024-10-29T00:03:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/"},"author":{"name":"","@id":""},"headline":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo","datePublished":"2024-10-29T00:03:48+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/"},"wordCount":1556,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","url":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","name":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-10-29T00:03:48+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"C\u00f3mo el lugar m\u00e1s fr\u00edo de la Tierra se convirti\u00f3 en uno de los lugares de vacaciones m\u00e1s populares del mundo","url":"http:\/\/noticiasya.com\/costa-central\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/10\/28\/antartida-convirtio-lugares-vacaciones-populares-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-10-29T00:03:48Z","datePublished":"2024-10-29T00:03:48Z","dateModified":"2024-10-29T00:03:48Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"C\\u00f3mo el lugar m\\u00e1s fr\\u00edo de la Tierra se convirti\\u00f3 en uno de los lugares de vacaciones m\\u00e1s populares del mundo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/10\\\/28\\\/antartida-convirtio-lugares-vacaciones-populares-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/10\\\/28\\\/antartida-convirtio-lugares-vacaciones-populares-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-10-29T00:03:48Z\",\"datePublished\":\"2024-10-29T00:03:48Z\",\"dateModified\":\"2024-10-29T00:03:48Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455026,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/10\/revelan-detalles-barco-hundido-endurance-escaneo-trax\/","url_meta":{"origin":1455412,"position":0},"title":"Revelan nuevos detalles impactantes del barco hundido Endurance de Shackleton con un escaneo 3D","author":"","date":"octubre 10, 2024","format":false,"excerpt":"(CNN) \u2013\u2013 Un nuevo escaneo 3D revel\u00f3 detalles nunca vistos del naufragio del HMS Endurance del explorador ant\u00e1rtico Ernest Shackleton, que fue encontrado en 2022, m\u00e1s de un siglo despu\u00e9s de que el barco se hundiera.La imagen, vista por CNN este jueves, muestra como si el barco, que se hundi\u00f3\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443152,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/04\/donde-esta-el-hielo-la-capa-de-hielo-de-los-grandes-lagos-es-casi-inexistente-y-alcanza-su-nivel-mas-bajo-en-50-anos\/","url_meta":{"origin":1455412,"position":1},"title":"\u00bfD\u00f3nde est\u00e1 el hielo? La capa de hielo de los Grandes Lagos es casi inexistente y alcanza su nivel m\u00e1s bajo en 50 a\u00f1os","author":"","date":"enero 4, 2024","format":false,"excerpt":"(CNN) -- Un comienzo c\u00e1lido de la temporada invernal ha dejado a los Grandes Lagos pr\u00e1cticamente sin hielo y con su capa de hielo m\u00e1s baja en un comienzo de a\u00f1o en al menos 50 a\u00f1os.El d\u00eda de A\u00f1o Nuevo, s\u00f3lo el 0,35% de los Grandes Lagos estaban cubiertos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1443154,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/01\/04\/donde-esta-el-hielo-la-capa-de-hielo-de-los-grandes-lagos-es-casi-inexistente-y-alcanza-su-nivel-mas-bajo-en-50-anos-2\/","url_meta":{"origin":1455412,"position":2},"title":"\u00bfD\u00f3nde est\u00e1 el hielo? La capa de hielo de los Grandes Lagos es casi inexistente y alcanza su nivel m\u00e1s bajo en 50 a\u00f1os","author":"","date":"enero 4, 2024","format":false,"excerpt":"(CNN) -- Un comienzo c\u00e1lido de la temporada invernal ha dejado a los Grandes Lagos pr\u00e1cticamente sin hielo y con su capa de hielo m\u00e1s baja en un comienzo de a\u00f1o en al menos 50 a\u00f1os.El d\u00eda de A\u00f1o Nuevo, s\u00f3lo el 0,35% de los Grandes Lagos estaban cubiertos de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1460030,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/03\/17\/medico-artico-guerra-fria-proposito-secreto-trax\/","url_meta":{"origin":1455412,"position":3},"title":"Un m\u00e9dico fue destinado al \u00c1rtico en plena Guerra Fr\u00eda. D\u00e9cadas despu\u00e9s, descubri\u00f3 su prop\u00f3sito secreto","author":"","date":"marzo 17, 2025","format":false,"excerpt":"Es 1962. Las tensiones de la Guerra Fr\u00eda se intensifican entre Washington y Mosc\u00fa. Obligado a alistarse en el ej\u00e9rcito de Estados Unidos, un joven m\u00e9dico interrumpe a rega\u00f1adientes su residencia m\u00e9dica en el Hospital Bellevue de Nueva York y se embarca hacia un remoto rinc\u00f3n de Groenlandia.\u00bfSus \u00f3rdenes? Servir\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469870,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/07\/visitar-groenlandia-turismo-trax\/","url_meta":{"origin":1455412,"position":4},"title":"Todo el mundo habla de Groenlandia. As\u00ed es visitarla","author":"","date":"enero 7, 2026","format":false,"excerpt":"Groenlandia se encuentra en pleno invierno, pero el presidente Donald Trump ha vuelto a sacar a esta isla \u00e1rtica de 56.000 habitantes, en su mayor\u00eda inuit, situada a medio camino entre Nueva York y Mosc\u00fa, de su anonimato helado, reavivando el debate sobre el control estadounidense.\u201cNecesitamos Groenlandia\u2026 Es muy estrat\u00e9gica\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470198,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/17\/mundo-habla-groenlandia-visitar-isla-trax\/","url_meta":{"origin":1455412,"position":5},"title":"Todo el mundo habla de Groenlandia. As\u00ed es visitar la isla","author":"","date":"enero 17, 2026","format":false,"excerpt":"Groenlandia puede estar sumida en la oscuridad del invierno, pero el presidente Donald Trump ha sacado una vez m\u00e1s a la isla \u00e1rtica de 56.000 habitantes, en su mayor\u00eda inuit \u2014situada a medio camino entre Nueva York y Mosc\u00fa\u2014 de su anonimato congelado, y ha reavivado el debate sobre el\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1455412"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455412\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1455412"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1455412"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1455412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}