{"id":1455558,"date":"2024-11-04T16:03:55","date_gmt":"2024-11-05T00:03:55","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/"},"modified":"2024-11-04T16:03:55","modified_gmt":"2024-11-05T00:03:55","slug":"cnn-verifica-trump-campana-mentiras-inmigracion-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","title":{"rendered":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo"},"content":{"rendered":"<p>Washington (CNN) &#8212; El expresidente Donald Trump comenz\u00f3 el \u00faltimo d\u00eda completo de la campa\u00f1a presidencial de 2024 como muchos de los d\u00edas anteriores: mintiendo sobre inmigraci\u00f3n, econom\u00eda y otros temas.<\/p>\n<p>En el primer mitin de campa\u00f1a de los cuatro planeados este d\u00eda, en Raleigh, Carolina del Norte, Trump repiti\u00f3 numerosas mentiras relacionadas con la inmigraci\u00f3n que ha dicho una y otra vez durante el \u00faltimo mes.<\/p>\n<p>Estas elecciones son tan divisivas que algunas empresas han guardado silencio incluso sobre cuestiones c\u00edvicas b\u00e1sicas<\/p>\n<p>Tambi\u00e9n revivi\u00f3 una teor\u00eda conspirativa infundada sobre la Oficina de Estad\u00edsticas Laborales, a\u00f1adiendo algunos nuevos detalles imaginarios, e hizo dos afirmaciones falsas sobre la expresidenta de la C\u00e1mara de Representantes Nancy Pelosi.<\/p>\n<p>He aqu\u00ed una comprobaci\u00f3n de algunos de los comentarios de Trump sobre Raleigh:<\/p>\n<p>Inmigraci\u00f3n<\/p>\n<p>La respuesta federal al hurac\u00e1n Helene: Trump repiti\u00f3 su falsa afirmaci\u00f3n de que la Agencia Federal de Gesti\u00f3n de Emergencias (FEMA, por sus siglas en ingl\u00e9s) &#171;todav\u00eda no est\u00e1 all\u00ed&#187; en Carolina del Norte respondiendo al hurac\u00e1n Helene, que golpe\u00f3 a finales de septiembre.<\/p>\n<p>Esto no es ni siquiera cerca de la verdad. La FEMA respondi\u00f3 inmediatamente a la cat\u00e1strofe en Carolina del Norte y dijo el 25 de octubre que ten\u00eda m\u00e1s de 1.700 personal desplegado en el estado. FEMA dijo el 16 de octubre que hab\u00eda aprobado m\u00e1s de US$ 100 millones en ayuda individual a los residentes de Carolina del Norte.<\/p>\n<p>En una sesi\u00f3n informativa a principios de octubre, el gobernador de Carolina del Norte, el dem\u00f3crata Roy Cooper, dijo: &#171;Estamos agradecidos por las r\u00e1pidas acciones y la estrecha comunicaci\u00f3n que hemos tenido con el presidente y con el equipo de FEMA&#187;. Will Ray, director de gesti\u00f3n de emergencias del estado, dijo en la sesi\u00f3n informativa: &#171;Estamos agradecidos por el apoyo no solo de los 22 estados que han enviado equipos para apoyarnos, sino tambi\u00e9n de nuestro equipo de FEMA y otros miembros de la familia federal&#187;.<\/p>\n<p>Una madre venezolana pidi\u00f3 ayuda en un grupo de Facebook de un barrio de Denver. Alguien inesperado respondi\u00f3<\/p>\n<p>FEMA y los migrantes<\/p>\n<p>Trump afirm\u00f3 falsamente que FEMA no respondi\u00f3 en Carolina del Norte porque la agencia &#171;gast\u00f3 todo su dinero en traer asesinos y mucha gente; gastaron todo su dinero en traer migrantes ilegales&#187;.<\/p>\n<p>FEMA no gast\u00f3 su dinero de ayuda en cat\u00e1strofes en personas indocumentadas. El Congreso asign\u00f3 a la agencia m\u00e1s de US$ 35.000 millones en fondos de alivio de desastres para el a\u00f1o fiscal 2024, seg\u00fan las estad\u00edsticas oficiales de FEMA, y tambi\u00e9n le dio a FEMA un fondo mucho m\u00e1s peque\u00f1o de dinero, US$ 650 millones en el a\u00f1o fiscal 2024, para un programa destinado a ayudar a las comunidades a albergar a los migrantes.<\/p>\n<p>Contrariamente a lo que afirma Trump, se trata de dos fondos distintos.<\/p>\n<p>El n\u00famero de inmigrantes<\/p>\n<p>Trump repiti\u00f3 su falsa afirmaci\u00f3n de que &#171;21 millones de personas&#187; cruzaron la frontera bajo la administraci\u00f3n de Biden.<\/p>\n<p>Hasta septiembre, el pa\u00eds hab\u00eda registrado menos de 11 millones de &#171;encuentros&#187; nacionales con migrantes durante el gobierno de Biden, incluidos millones que fueron expulsados r\u00e1pidamente del pa\u00eds.<\/p>\n<p>Incluso sumando a los llamados fugitivos que evadieron la detecci\u00f3n, estimados por los republicanos de la C\u00e1mara de Representantes en aproximadamente 2 millones, no hay forma de que el total sea de &#171;21 millones&#187;.<\/p>\n<p>Migrantes y homicidios<\/p>\n<p>Trump repiti\u00f3 una afirmaci\u00f3n falsa sobre las cifras publicadas en septiembre acerca de los inmigrantes y la delincuencia, diciendo err\u00f3neamente que las cifras mostraban que 13.099 asesinos cruzaron la frontera durante el gobierno de Biden.<\/p>\n<p>En realidad, el Departamento de Seguridad Nacional y expertos independientes han se\u00f1alado que esta cifra de inmigrantes que ahora tienen condenas por homicidio se refiere a personas que entraron al pa\u00eds durante d\u00e9cadas, incluso durante la propia administraci\u00f3n de Trump, no solo bajo Joe Biden y Kamala Harris &#8211; y que la cifra incluye a personas que actualmente est\u00e1n encarceladas en prisiones y c\u00e1rceles federales, estatales y locales.<\/p>\n<p>Estas son las propuestas que ha hecho Donald Trump para volver a la presidencia: inmigraci\u00f3n, justicia, crimen, aborto y m\u00e1s<\/p>\n<p>Prisiones y l\u00edderes extranjeros<\/p>\n<p>Trump repiti\u00f3 su falsa afirmaci\u00f3n de que los gobiernos extranjeros est\u00e1n &#171;liberando a todos sus presos de las c\u00e1rceles de todo el mundo, no de Sudam\u00e9rica, de todo el mundo&#187;. Luego sugiri\u00f3 que la poblaci\u00f3n carcelaria mundial ha disminuido como resultado de ello.<\/p>\n<p>No hay pruebas de estas afirmaciones, que la propia campa\u00f1a de Trump ha sido incapaz de defender. La poblaci\u00f3n carcelaria mundial registrada aument\u00f3 de octubre de 2021 a abril de 2024, de al menos unos 10,77 millones de personas a al menos unos 10,99 millones de personas, seg\u00fan la Lista Mundial de Poblaci\u00f3n Carcelaria elaborada por expertos del Reino Unido.<\/p>\n<p>&#171;Hago una b\u00fasqueda diaria de noticias para ver lo que est\u00e1 pasando en las c\u00e1rceles de todo el mundo y no he visto absolutamente ninguna evidencia de que alg\u00fan pa\u00eds est\u00e9 vaciando sus prisiones y envi\u00e1ndolas todas a Estados Unidos&#187;, dijo Helen Fair, coautora de la lista de poblaci\u00f3n carcelaria e investigadora del Instituto de Investigaci\u00f3n de Pol\u00edticas de Crimen y Justicia de Birkbeck, Universidad de Londres, en junio, cuando Trump hizo una afirmaci\u00f3n similar.<\/p>\n<p>El gr\u00e1fico favorito de Trump<\/p>\n<p>Trump repiti\u00f3 su falsa afirmaci\u00f3n, desmentida desde hace tiempo, de que su gr\u00e1fico favorito sobre las cifras de migraci\u00f3n en la frontera sur -que afortunadamente hab\u00eda girado la cabeza para mirar cuando un atacante intent\u00f3 matarlo en un mitin de campa\u00f1a en julio- tiene una flecha en la parte inferior que apunta &#171;al d\u00eda en que dej\u00e9 el cargo&#187;, cuando, dijo, EE.UU. ten\u00eda &#171;la inmigraci\u00f3n ilegal m\u00e1s baja&#187; de su historia.<\/p>\n<p>El gr\u00e1fico no lo muestra. De hecho, la flecha apunta en realidad a abril de 2020, cuando a Trump a\u00fan le quedaban m\u00e1s de ocho meses de mandato y cuando la migraci\u00f3n mundial se hab\u00eda reducido a un goteo debido a la pandemia del covid-19. Despu\u00e9s de alcanzar un m\u00ednimo de aproximadamente tres a\u00f1os (no un m\u00ednimo hist\u00f3rico) en abril de 2020, las cifras de migraci\u00f3n en la frontera sur aumentaron cada mes hasta el final del mandato de Trump.<\/p>\n<p>Construcci\u00f3n del muro<\/p>\n<p>Trump repiti\u00f3 su falsa afirmaci\u00f3n de que hab\u00eda construido &#171;571 millas de muro&#187; (918 kil\u00f3metros) en la frontera sur durante su administraci\u00f3n. Eso es una exageraci\u00f3n significativa. Los datos oficiales del gobierno muestran que se construyeron 458 millas o 737 kil\u00f3metros bajo el mandato de Trump, incluyendo tanto el muro construido donde antes no exist\u00edan barreras como el muro construido para reemplazar barreras anteriores.<\/p>\n<p>Migrantes en Springfield<\/p>\n<p>Trump repiti\u00f3 su falsa afirmaci\u00f3n de que &#171;liberaron 30.000 migrantes ilegales&#187; en Springfield, Ohio, diciendo que mientras otros usan &#171;un peque\u00f1o tecnicismo&#187; para decir que estos reci\u00e9n llegados de Hait\u00ed tienen permitido estar all\u00ed, son &#171;ilegales&#187; en su opini\u00f3n.<\/p>\n<p>Esto es falso en m\u00e1s de un sentido. Aunque no conocemos el estatus migratorio de cada inmigrante haitiano en Springfield, la comunidad est\u00e1, en general, en el pa\u00eds legalmente. El sitio web de la ciudad de Springfield dice: &#171;S\u00cd, los inmigrantes haitianos est\u00e1n aqu\u00ed legalmente, bajo el Programa de Permiso Humanitario de Inmigraci\u00f3n. Una vez aqu\u00ed, los inmigrantes pueden solicitar el Estatus de Protecci\u00f3n Temporal (TPS)&#187;.<\/p>\n<p>Trump dice que solo repiti\u00f3 &#171;lo que se inform\u00f3&#187;, al ser confrontado por sus afirmaciones falsas sobre los inmigrantes haitianos en Springfield<\/p>\n<p>El gobernador republicano de Ohio, Mike DeWine , escribi\u00f3 en un art\u00edculo de opini\u00f3n en The New York Times sobre Springfield en septiembre que los inmigrantes haitianos &#171;est\u00e1n all\u00ed legalmente&#187; y que, como partidario de Trump y J. D. Vance, est\u00e1 &#171;entristecido&#187; por el menosprecio de los candidatos a &#171;los inmigrantes legales que viven en Springfield&#187;.<\/p>\n<p>En segundo lugar, nadie &#171;liber\u00f3&#187; a los inmigrantes en Springfield; los residentes haitianos de la ciudad no fueron enviados all\u00ed por un programa de reasentamiento del gobierno. M\u00e1s bien, decidieron trasladarse a la ciudad de forma independiente debido a las oportunidades de empleo, la vivienda asequible y la presencia de una comunidad haitiana, entre otros factores.<\/p>\n<p>Y aunque no existe un recuento oficial del n\u00famero de inmigrantes en Springfield, la cifra de &#171;30.000&#187; de Trump supera las estimaciones locales. El sitio web de la ciudad de Springfield dice que se calcula que hay entre 12.000 y 15.000 inmigrantes en el condado que incluye a Springfield, donde la poblaci\u00f3n total es de unos 138.000 habitantes. Chris Cook, comisionado de salud del condado, dijo en julio que su equipo estimaba que la mejor cifra era de 10.000 a 12.000 residentes haitianos en el condado.<\/p>\n<p>Empleo<\/p>\n<p>La revisi\u00f3n del empleo en agosto: Trump repiti\u00f3 su falsa afirmaci\u00f3n de que un &#171;denunciante&#187; fue el responsable de una revisi\u00f3n a la baja de las cifras de empleo por parte de la Oficina Federal de Estad\u00edsticas Laborales (BLS, por sus siglas en ingl\u00e9s), que anunci\u00f3 en agosto que su revisi\u00f3n anual de los datos laborales encontr\u00f3 que la econom\u00eda a\u00f1adi\u00f3 alrededor de 818.000 puestos de trabajo menos de lo inicialmente reportado para los 12 meses que terminaron en marzo.<\/p>\n<p>&#171;Pensaron que podr\u00edan salirse con la suya durante las elecciones, pero hab\u00eda un denunciante, y el denunciante no pod\u00eda soportar lo que estaban haciendo, y los denunci\u00f3, y los atraparon&#187;, dijo Trump en Raleigh.<\/p>\n<p>Esto es ficci\u00f3n. La Oficina de Estad\u00edsticas Laborales publica regularmente los datos preliminares revisados en agosto, y hab\u00eda anunciado la fecha exacta de esta publicaci\u00f3n de datos en particular -el 21 de agosto- con semanas de antelaci\u00f3n.<\/p>\n<p>William Beach, un economista conservador que fue nombrado por Trump para dirigir la Oficina de Estad\u00edsticas Laborales, escribi\u00f3 en las redes sociales: &#171;Para aquellos que piensan que la gran revisi\u00f3n de las cifras de empleo de BLS se &#8216;filtr\u00f3&#8217; y estaba destinada a salir despu\u00e9s de las elecciones, recuerden que la BLS siempre anuncia sus borradores de revisi\u00f3n en agosto y anunci\u00f3 la fecha de este a\u00f1o, el 21 de agosto, hace muchos meses. Es importante comprobar los hechos&#187;.<\/p>\n<p>La \u00faltima revisi\u00f3n del empleo<\/p>\n<p>Trump afirm\u00f3 falsamente que hubo otra revisi\u00f3n a la baja de las cifras de empleo, la semana pasada, &#171;porque ten\u00edan otro denunciante, as\u00ed que tuvieron que hacerlo &#8211; quer\u00edan esperar hasta despu\u00e9s de las elecciones de nuevo&#187;. Esto tambi\u00e9n es una tonter\u00eda; se trat\u00f3 de otra revisi\u00f3n normal realizada y anunciada por la propia Oficina de Estad\u00edsticas Laborales, y no hay indicios de que hubiera ning\u00fan denunciante implicado.<\/p>\n<p>El informe de empleo de octubre<\/p>\n<p>Trump habl\u00f3 del informe de empleo de octubre, que mostr\u00f3 un aumento por debajo de las expectativas de 12.000 empleos en medio de grandes tormentas y huelgas laborales, y dijo que estaba agradecido de que se publicara &#8211; &#171;porque trataron de retenerlo; trataron de no publicar el informe. Kamala dijo: &#8216;No publiquen ese informe, me costar\u00e1 las elecciones'&#187;.<\/p>\n<p>Esto tambi\u00e9n es falso. El informe sali\u00f3 a la hora prevista p\u00fablicamente el viernes. No hay indicios de que Harris o cualquier otra persona tratara de impedir su publicaci\u00f3n.<\/p>\n<p>Nancy Pelosi<\/p>\n<p>Pelosi y las acciones<\/p>\n<p>Trump repiti\u00f3 una afirmaci\u00f3n falsa sobre la representante Nancy Pelosi, expresidenta de la C\u00e1mara de Representantes, diciendo que ella vendi\u00f3 acciones de Visa &#171;la semana pasada&#187; y luego &#171;al d\u00eda siguiente&#187; el gobierno federal anunci\u00f3 una &#171;importante investigaci\u00f3n&#187; de Visa.<\/p>\n<p>En realidad, las acciones de Visa fueron vendidas por el marido de Pelosi, m\u00e1s de dos meses y medio antes de que el Departamento de Justicia presentara una demanda contra la empresa. Y la demanda se present\u00f3 en septiembre, no la semana pasada.<\/p>\n<p>Pelosi y el discurso de Trump sobre el Estado de la Uni\u00f3n<\/p>\n<p>Trump revivi\u00f3 una afirmaci\u00f3n falsa de su presidencia, diciendo que Pelosi &#171;podr\u00eda haber ido a la c\u00e1rcel&#187; por romper una copia de su discurso del Estado de la Uni\u00f3n de 2020 despu\u00e9s de que \u00e9l lo terminara, porque ella &#171;no ten\u00eda permitido hacer eso&#187;.<\/p>\n<p>No era ilegal bajo las leyes de registros gubernamentales que Pelosi rasgara una copia del discurso de Trump. La copia del discurso de Pelosi no calific\u00f3 como un registro oficial del gobierno, seg\u00fan han afirmado expertos a los medios.<\/p>\n<p>Otros temas<\/p>\n<p>Trump y Nord Stream 2: Trump repiti\u00f3 una afirmaci\u00f3n falsa sobre el gasoducto Nord Stream 2, que era una preciada iniciativa del presidente de Rusia, Vladimir Putin, diciendo: &#171;Cerr\u00e9 su gasoducto, estaba muerto&#187;. Trump no acab\u00f3 con el gasoducto.<\/p>\n<p>Convirti\u00f3 en ley las sanciones relacionadas con el proyecto a los tres a\u00f1os de su presidencia, cuando el gasoducto ya estaba completado en un 90%, y la empresa estatal rusa detr\u00e1s del proyecto anunci\u00f3 en diciembre de 2020 que reanudaba la construcci\u00f3n.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Washington (CNN) &#8212; El expresidente Donald Trump comenz\u00f3 el \u00faltimo d\u00eda completo de la campa\u00f1a presidencial de 2024 como muchos de los d\u00edas anteriores: mintiendo sobre inmigraci\u00f3n, econom\u00eda y otros temas. En el primer mitin de campa\u00f1a de los cuatro planeados este d\u00eda, en Raleigh, Carolina del Norte, Trump repiti\u00f3 numerosas mentiras relacionadas con la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1455558","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo - Noticias\" \/>\n<meta property=\"og:description\" content=\"Washington (CNN) &#8212; El expresidente Donald Trump comenz\u00f3 el \u00faltimo d\u00eda completo de la campa\u00f1a presidencial de 2024 como muchos de los d\u00edas anteriores: mintiendo sobre inmigraci\u00f3n, econom\u00eda y otros temas. En el primer mitin de campa\u00f1a de los cuatro planeados este d\u00eda, en Raleigh, Carolina del Norte, Trump repiti\u00f3 numerosas mentiras relacionadas con la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T00:03:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo\",\"datePublished\":\"2024-11-05T00:03:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\"},\"wordCount\":2238,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\",\"name\":\"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-11-05T00:03:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","og_locale":"es_ES","og_type":"article","og_title":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo - Noticias","og_description":"Washington (CNN) &#8212; El expresidente Donald Trump comenz\u00f3 el \u00faltimo d\u00eda completo de la campa\u00f1a presidencial de 2024 como muchos de los d\u00edas anteriores: mintiendo sobre inmigraci\u00f3n, econom\u00eda y otros temas. En el primer mitin de campa\u00f1a de los cuatro planeados este d\u00eda, en Raleigh, Carolina del Norte, Trump repiti\u00f3 numerosas mentiras relacionadas con la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","og_site_name":"Noticias","article_published_time":"2024-11-05T00:03:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/"},"author":{"name":"","@id":""},"headline":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo","datePublished":"2024-11-05T00:03:55+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/"},"wordCount":2238,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","url":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","name":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-11-05T00:03:55+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"CNN verifica: Trump comienza el \u00faltimo d\u00eda completo de campa\u00f1a repitiendo mentiras sobre inmigraci\u00f3n y empleo","url":"http:\/\/noticiasya.com\/costa-central\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/11\/04\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-11-05T00:03:55Z","datePublished":"2024-11-05T00:03:55Z","dateModified":"2024-11-05T00:03:55Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"CNN verifica: Trump comienza el \\u00faltimo d\\u00eda completo de campa\\u00f1a repitiendo mentiras sobre inmigraci\\u00f3n y empleo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/11\\\/04\\\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/11\\\/04\\\/cnn-verifica-trump-campana-mentiras-inmigracion-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-11-05T00:03:55Z\",\"datePublished\":\"2024-11-05T00:03:55Z\",\"dateModified\":\"2024-11-05T00:03:55Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1457694,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/21\/decretos-inmigracion-trump-trax\/","url_meta":{"origin":1455558,"position":0},"title":"Las 7 medidas sobre inmigraci\u00f3n con las que Trump inaugur\u00f3 su segundo mandato","author":"","date":"enero 21, 2025","format":false,"excerpt":"El presidente Donald Trump comenz\u00f3 su mandato con una serie de amplios decretos sobre inmigraci\u00f3n, que incluyeron declarar una emergencia nacional en la frontera sur de EE.UU., poner fin de inmediato al uso de la aplicaci\u00f3n CBP One y dar inicio a un proceso para poner fin a la ciudadan\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455223,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/18\/cnn-verifica-desmintiendo-mentiras-trump-inmigracion-trax\/","url_meta":{"origin":1455558,"position":1},"title":"CNN verifica: desmintiendo las mentiras dichas por Trump en octubre sobre inmigraci\u00f3n","author":"","date":"octubre 18, 2024","format":false,"excerpt":"(CNN) --\u00a0El expresidente Donald Trump dijo una gran cantidad de mentiras sobre una gran cantidad de temas en el \u00faltimo mes de la elecci\u00f3n presidencial. Pero est\u00e1 mintiendo con m\u00e1s frecuencia, por mucha diferencia, sobre inmigraci\u00f3n.Los discursos y entrevistas de Trump en los mitines de octubre contuvieron una abrumadora serie\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452379,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/03\/analisis-trump-mentiras-ocho-anos-trax\/","url_meta":{"origin":1455558,"position":2},"title":"AN\u00c1LISIS | Trump sigue contando las mismas mentiras que dijo hace ocho a\u00f1os","author":"","date":"septiembre 3, 2024","format":false,"excerpt":"(CNN) -- En un discurso pronunciado la semana pasada ante la Asociaci\u00f3n de la Guardia Nacional de Estados Unidos, el expresidente Donald Trump afirm\u00f3 que \u00e9l fue el presidente que \"cre\u00f3\" el programa de atenci\u00f3n sanitaria Veterans Choice, y consigui\u00f3 que \"se aprobara en el Congreso\", despu\u00e9s de que otros\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451511,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/30\/harris-acusaciones-trump-inmigracion-trax\/","url_meta":{"origin":1455558,"position":3},"title":"La campa\u00f1a de Harris responde a las acusaciones de Trump en materia de inmigraci\u00f3n","author":"","date":"julio 30, 2024","format":false,"excerpt":"(CNN) -- Este martes, la campa\u00f1a de Harris mostr\u00f3 un primer vistazo sobre c\u00f3mo planea contrarrestar los ataques del expresidente Donald Trump, quien presenta falsamente a la vicepresidenta Kamala Harris como el \u201czar fronterizo\u201d de la administraci\u00f3n.El video de campa\u00f1a de 50 segundos, publicado por primera vez en CNN este\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1451191,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/17\/medidas-inmigracion-latinos-biden-ee-uu-trax\/","url_meta":{"origin":1455558,"position":4},"title":"Biden anunciar\u00e1 nuevas medidas sobre inmigraci\u00f3n y oportunidades educativas para los latinos en su discurso de este mi\u00e9rcoles ante Unidos","author":"","date":"julio 17, 2024","format":false,"excerpt":"(CNN) --\u00a0 El presidente Joe Biden reanuda su visita de tres d\u00edas a Las Vegas con un discurso este mi\u00e9rcoles ante la mayor organizaci\u00f3n latina de defensa de los derechos civiles y continuar\u00e1 su acercamiento a este grupo demogr\u00e1fico crucial dando a conocer nuevas medidas sobre inmigraci\u00f3n y sobre la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1457591,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/17\/trump-prepara-campana-agresiva-inmigracion-trax\/","url_meta":{"origin":1455558,"position":5},"title":"Trump prepara una agresiva campa\u00f1a sobre migraci\u00f3n para sus primeras horas de gobierno","author":"","date":"enero 17, 2025","format":false,"excerpt":"El equipo de Donald Trump est\u00e1 ultimando una agresiva serie de decretos en materia de inmigraci\u00f3n que se espera que se hagan p\u00fablicas solo unas horas despu\u00e9s de que el presidente electo jure el cargo, dando inicio a una campa\u00f1a de represi\u00f3n de la inmigraci\u00f3n que tendr\u00e1 implicaciones para la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455558","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1455558"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455558\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1455558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1455558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1455558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}