{"id":1455610,"date":"2024-11-06T11:03:39","date_gmt":"2024-11-06T19:03:39","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/"},"modified":"2024-11-06T11:03:39","modified_gmt":"2024-11-06T19:03:39","slug":"harris-gana-trump-puerto-rico-voto-simbolico-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","title":{"rendered":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n"},"content":{"rendered":"<p>(CNN Espa\u00f1ol) \u2014 La candidata presidencial dem\u00f3crata, la vicepresidenta Kamala Harris, fue la preferida de los puertorrique\u00f1os en una votaci\u00f3n simb\u00f3lica que tuvo lugar en la isla para la elecci\u00f3n presidencial de Estados Unidos, con 73,46% de los votos (709.902 personas) frente al 26,54% (256.505) del candidato presidencial republicano, el ahora presidente electo de EE.UU., Donald Trump, seg\u00fan los resultados preliminares de la Comisi\u00f3n Estatal de Elecciones (CEE) de Puerto Rico.<\/p>\n<p>La CEE de Puerto Rico dio a conocer este mi\u00e9rcoles los resultados preliminares con el 91,35% de los colegios reportados.<\/p>\n<p>De las 1.937.707 personas inscritas en los colegios reportados, la CEE dijo que se entregaron 1.114.471 para esta votaci\u00f3n simb\u00f3lica, por lo que la participaci\u00f3n preliminar fue de 57,51%.<\/p>\n<p>Adem\u00e1s de los votos por Harris y Trump, hubo 120.436 votos en blanco y 17.937 votos donde se nomin\u00f3 a alguien directamente.<\/p>\n<p>Donald Trump gana las elecciones en EE.UU. 2024 | Resultados, en vivo: noticias y reacciones<\/p>\n<p>Aunque es parte de EE.UU., los residentes de la isla no tienen voto en las elecciones federales y por lo tanto esos votos son un simulacro. Se trata de una consulta simb\u00f3lica para que los puertorrique\u00f1os emitan su preferencia para presidente y vicepresidente del pa\u00eds; incluso la boleta de votaci\u00f3n lleva el nombre de \u201cpapeleta de preferencia presidencial\u201d, seg\u00fan la Comisi\u00f3n Estatal de Elecciones (CEE) de Puerto Rico.<\/p>\n<p>Como ciudadanos estadounidenses, los residentes en Puerto Rico participan en las elecciones primarias presidenciales, eligen gobernador y legislatura local. El voto de preferencia presidencial de la isla no cuenta en los resultados oficiales de EE.UU. debido a que, en resumen, Puerto Rico es un \u201cterritorio no incorporado&#187; y no un &#171;estado&#187;, por lo que no tiene representaci\u00f3n en el Colegio Electoral estadounidense y no puede emitir votos para presidente, ni tampoco elegir senadores y representantes para el Congreso en Washington, seg\u00fan lo que establece la ley estadounidense.<\/p>\n<p>De acuerdo con la agencia EFE, el objetivo de esta votaci\u00f3n simb\u00f3lica es expresar el sentir de los puertorrique\u00f1os, que en las \u00faltimas semanas han estado en el centro de las noticias por un hecho relacionado con las elecciones (en espec\u00edfico, con un mitin de campa\u00f1a).<\/p>\n<p>Residentes de la isla dijeron sentirse indignados debido a los insultos vertidos en un mitin de Trump a finales de octubre en Nueva York por el comediante Tony Hinchcliffe, quien calific\u00f3 a Puerto Rico como &#171;una isla flotante de basura&#187;.<\/p>\n<p>Los comentarios ofensivos resonaron m\u00e1s all\u00e1 de la isla y llegaron a territorio continental de EE.UU.<br \/>\nMatthew Tuerk, alcalde de Allentown \u2013ciudad de Pensilvania donde viven aproximadamente 40.000 puertorrique\u00f1os; en ese estado, viven en total unos 500.000 boricuas\u2013, dijo a CNN que las palabras de Hinchcliffe ofendieron a la comunidad originaria de la isla.<\/p>\n<p>\u201cCuando hablan de otra persona de manera racista, eso no molesta. Pero atacando a la isla es un poco diferente, la gente sent\u00eda rabia. Ahora yo les estoy pidiendo que se convierta esa rabia en voto, en acci\u00f3n\u201d, coment\u00f3 Tuerk. Cabe recordar que los puertorrique\u00f1os que tienen una residencia permanente en alg\u00fan estado de EE.UU. s\u00ed pueden votar para presidente.<\/p>\n<p>Asimismo, pol\u00edticos dem\u00f3cratas, republicanos, puertorrique\u00f1os, figuras de la talla de Bad Bunny, Jennifer Lopez y Residente, entre otros grupos, reaccionaron al respecto y defendieron a la isla.<\/p>\n<p>En tanto, la campa\u00f1a de Trump se distanci\u00f3 de las palabras de Hinchcliffe y el propio Donald Trump dijo que nadie hizo m\u00e1s por Puerto Rico que \u00e9l.<\/p>\n<p>Pese a que los puertorrique\u00f1os pueden expresar su sentir al emitir su preferencia presidencial, algunos en la isla lo consideran una p\u00e9rdida de tiempo, como dijo Mar\u00eda Mercado, residente del municipio de Dorado, a CNN.<\/p>\n<p>&#171;Yo no perder\u00eda mi tiempo, hasta que se tome en cuenta, que se dijera que va a tener alg\u00fan tipo de efecto el voto. Si no, de verdad que yo por lo menos no voy a perder el tiempo votando por algo que no vale la pena&#187;, coment\u00f3 Mercado.<\/p>\n<p>&#171;Nosotros como ciudadanos americanos [estadounidenses] que somos, se debe dar la oportunidad para ejercer el voto en Estados Unidos, que sea v\u00e1lido&#187;, dijo Axel Maysonet, residente de Dorado.<\/p>\n<p>&#171;Nosotros no tenemos voz ni voto&#187; con la papeleta de preferencia presidencial, coment\u00f3 Ruth Robles, residente del municipio de Vega Alta.<\/p>\n<p>&#171;No s\u00e9 por qu\u00e9 est\u00e1 [el voto presidencial] en la papeleta, no es necesario, no sirve de nada nuestro voto. \u00bfPara qu\u00e9 vamos a votar por alguien que nuestro voto no va a servir? No entiendo&#187;, se\u00f1al\u00f3 Joseph Agosto, tambi\u00e9n residente de Vega Alta.<\/p>\n<p>&#8211;Con informaci\u00f3n de Rafy Rivera, Ver\u00f3nica Calder\u00f3n, Ray Sanchez, Veronica Stracqualursi, Kate Sullivan, Aaron Pellish, Priscilla Alvarez y Gregory Krieg, de CNN.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN Espa\u00f1ol) \u2014 La candidata presidencial dem\u00f3crata, la vicepresidenta Kamala Harris, fue la preferida de los puertorrique\u00f1os en una votaci\u00f3n simb\u00f3lica que tuvo lugar en la isla para la elecci\u00f3n presidencial de Estados Unidos, con 73,46% de los votos (709.902 personas) frente al 26,54% (256.505) del candidato presidencial republicano, el ahora presidente electo de EE.UU., [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1455610","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN Espa\u00f1ol) \u2014 La candidata presidencial dem\u00f3crata, la vicepresidenta Kamala Harris, fue la preferida de los puertorrique\u00f1os en una votaci\u00f3n simb\u00f3lica que tuvo lugar en la isla para la elecci\u00f3n presidencial de Estados Unidos, con 73,46% de los votos (709.902 personas) frente al 26,54% (256.505) del candidato presidencial republicano, el ahora presidente electo de EE.UU., [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-06T19:03:39+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n\",\"datePublished\":\"2024-11-06T19:03:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\"},\"wordCount\":840,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\",\"name\":\"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-11-06T19:03:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n - Noticias","og_description":"(CNN Espa\u00f1ol) \u2014 La candidata presidencial dem\u00f3crata, la vicepresidenta Kamala Harris, fue la preferida de los puertorrique\u00f1os en una votaci\u00f3n simb\u00f3lica que tuvo lugar en la isla para la elecci\u00f3n presidencial de Estados Unidos, con 73,46% de los votos (709.902 personas) frente al 26,54% (256.505) del candidato presidencial republicano, el ahora presidente electo de EE.UU., [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","og_site_name":"Noticias","article_published_time":"2024-11-06T19:03:39+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/"},"author":{"name":"","@id":""},"headline":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n","datePublished":"2024-11-06T19:03:39+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/"},"wordCount":840,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","url":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","name":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-11-06T19:03:39+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Harris le gana a Trump en Puerto Rico, pero el voto es simb\u00f3lico. As\u00ed qued\u00f3 la votaci\u00f3n","url":"http:\/\/noticiasya.com\/costa-central\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/11\/06\/harris-gana-trump-puerto-rico-voto-simbolico-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-11-06T19:03:39Z","datePublished":"2024-11-06T19:03:39Z","dateModified":"2024-11-06T19:03:39Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Harris le gana a Trump en Puerto Rico, pero el voto es simb\\u00f3lico. As\\u00ed qued\\u00f3 la votaci\\u00f3n\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/11\\\/06\\\/harris-gana-trump-puerto-rico-voto-simbolico-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/11\\\/06\\\/harris-gana-trump-puerto-rico-voto-simbolico-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-11-06T19:03:39Z\",\"datePublished\":\"2024-11-06T19:03:39Z\",\"dateModified\":\"2024-11-06T19:03:39Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1455620,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/06\/jenniffer-gonzalez-elecciones-puerto-rico-orix\/","url_meta":{"origin":1455610,"position":0},"title":"Jenniffer Gonz\u00e1lez gana las elecciones en Puerto Rico y el independentismo queda segundo, seg\u00fan resultados preliminares","author":"","date":"noviembre 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- Jenniffer Gonz\u00e1lez, del Partido Nuevo Progresista (PNP), fue la candidata ganadora este martes en las elecciones para gobernador en Puerto Rico, mientras que el independentista Juan Dalmau qued\u00f3 en segundo lugar, seg\u00fan los resultados preliminares.De acuerdo con la Comisi\u00f3n Estatal de Elecciones de Puerto Rico (CEEPR), con\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455753,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/11\/todo-listo-comenzar-escrutinio-electoral-puerto-rico-orix\/","url_meta":{"origin":1455610,"position":1},"title":"Todo listo para comenzar con el escrutinio electoral en Puerto Rico","author":"","date":"noviembre 11, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Comisi\u00f3n Estatal de Elecciones de Puerto Rico (CEEPR) inform\u00f3 que se iniciar\u00e1 este martes el escrutinio general de votos de las elecciones generales.Los comicios en la isla se llevaron a cabo el 5 de noviembre y la CEEPR dio los resultados preliminares con los cuales se\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1455611,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/06\/kamala-harris-los-angeles-votos-resultados-elecciones-ee-uu-2024-orix\/","url_meta":{"origin":1455610,"position":2},"title":"Kamala Harris gan\u00f3 en Los \u00c1ngeles con el 63% de los votos: resultados de las elecciones de EE.UU. 2024","author":"","date":"noviembre 6, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) \u2013 Kamala Harris fue la clara vencedora del voto popular en la elecci\u00f3n presidencial en el condado de Los \u00c1ngeles, California, seg\u00fan los datos publicados hasta la ma\u00f1ana de este mi\u00e9rcoles.La candidata dem\u00f3crata obtuvo 1.623.052 votos, que representan el 63,01% , mientras que su rival republicano, Donald Trump,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449958,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/03\/jenniffer-gonzalez-colon-comisionada-puerto-rico-resultados-elecciones-primarias-orix\/","url_meta":{"origin":1455610,"position":3},"title":"Jenniffer Gonz\u00e1lez-Col\u00f3n, comisionada de Puerto Rico ante la C\u00e1mara de Representantes de EE.UU., gana la primaria para la gobernaci\u00f3n de la isla, seg\u00fan resultados preliminares","author":"","date":"junio 3, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0Jenniffer Gonz\u00e1lez-Col\u00f3n fue la precandidata m\u00e1s votada en la elecci\u00f3n primaria para la gobernaci\u00f3n de Puerto Rico por el Partido Nuevo Progresista (PNP), seg\u00fan los resultados preliminares de la Comisi\u00f3n Estatal de Elecciones de Puerto Rico. La aspirante se impuso al actual gobernador de la isla, Pedro Pierluisi,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469253,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/12\/14\/abren-colegios-electorales-chile-balotaje-presidencial-efe\/","url_meta":{"origin":1455610,"position":4},"title":"Abren los colegios electorales en Chile para el balotaje presidencial entre Jara y Kast","author":"","date":"diciembre 14, 2025","format":false,"excerpt":"Un total de 3.379 locales de votaci\u00f3n con 40.473 mesas abrieron sus puertas este domingo para dar comienzo a las elecciones de la segunda vuelta presidencial en Chile, en las que se escoger\u00e1 al sucesor del progresista Gabriel Boric.M\u00e1s de 15,6 millones de personas est\u00e1n llamadas a las urnas para\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449948,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/02\/claudia-sheinbaum-proxima-presidenta-gana-presidencia-elecciones-mexico-orix\/","url_meta":{"origin":1455610,"position":5},"title":"Claudia Sheinbaum gana las elecciones a la Presidencia de M\u00e9xico, seg\u00fan resultados oficiales preliminares","author":"","date":"junio 2, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0La candidata oficialista Claudia Sheinbaum es la ganadora de las elecciones presidenciales de M\u00e9xico, de acuerdo con los resultados preliminares reportados este domingo por el Instituto Nacional Electoral (INE).Sheinbaum \u2014quien ser\u00e1 la primera mujer al frente del Gobierno de M\u00e9xico\u2014 tuvo entre 58,3% y 60,7% de la votaci\u00f3n,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1455610"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455610\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1455610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1455610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1455610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}