{"id":1455664,"date":"2024-11-08T03:03:44","date_gmt":"2024-11-08T11:03:44","guid":{"rendered":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/"},"modified":"2024-11-08T03:03:44","modified_gmt":"2024-11-08T11:03:44","slug":"ciudad-petrolera-flota-lago-grande-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","title":{"rendered":"Una alucinante ciudad petrolera de la era sovi\u00e9tica &#171;flota&#187; en el lago m\u00e1s grande del mundo"},"content":{"rendered":"<p>(CNN) \u2013\u2013 Cuando el cineasta Marc Wolfensberger se enter\u00f3 de la existencia de Neft Da\u015flar\u0131, pens\u00f3 que era un mito. No dejaba de escuchar hablar de esta ciudad secreta, que se extend\u00eda como tent\u00e1culos flotantes y oxidados sobre el mar Caspio, lejos de la costa m\u00e1s cercana. Pero muy pocos la hab\u00edan visto, dijo. \u201cEl grado de misterio era enormemente alto\u201d.<\/p>\n<p>No fue hasta que lo vio con sus propios ojos, cuando logr\u00f3 viajar all\u00ed en un barco de reparto de agua a finales de los a\u00f1os 90, que supo que era real. \u201cEra algo que no hab\u00eda visto antes\u201d, le dijo a CNN. Vigilado por buques militares, era como \u201cuna autopista en medio del mar\u201d, dijo, que se extend\u00eda \u201ccomo un pulpo\u201d.<\/p>\n<p>As\u00ed es Termeso, la ciudad oculta que Alejandro Magno no pudo conquistar<\/p>\n<p>Desesperado por documentar esta ciudad alucinante, pas\u00f3 ocho a\u00f1os convenciendo al gobierno de Azerbaiy\u00e1n para que le permitiera regresar, lo que finalmente hizo en 2008, cuando pas\u00f3 dos semanas all\u00ed para hacer su pel\u00edcula, \u201cOil Rocks: City Above the Sea\u201d.<\/p>\n<p>Puentes y plataformas de perforaci\u00f3n de Neft Da\u015flar\u0131 en 2011.<\/p>\n<p>Neft Da\u015flar\u0131, que se traduce como \u201crocas petrol\u00edferas\u201d, es una mara\u00f1a de pozos petrol\u00edferos y sitios de producci\u00f3n conectados por kil\u00f3metros de puentes en la inmensidad del mar Caspio, el lago m\u00e1s grande del mundo. Est\u00e1 a unos 96 kil\u00f3metros de la costa de Bak\u00fa, la capital de Azerbaiy\u00e1n, y a seis horas en barco desde el continente.<\/p>\n<p>Es la plataforma petrol\u00edfera marina m\u00e1s antigua del mundo, seg\u00fan el Libro de los r\u00e9cords Guinness, y en su apogeo lleg\u00f3 a albergar a m\u00e1s de 5.000 habitantes.<\/p>\n<p>Descubren una ciudad maya olvidada en la selva de M\u00e9xico gracias al mapeo l\u00e1ser<\/p>\n<p>Sin embargo, en las \u00faltimas d\u00e9cadas, su poblaci\u00f3n disminuy\u00f3, mientras que algunas zonas se deterioraron y fueron devoradas por el mar. Sin embargo, sigue en funcionamiento y es un s\u00edmbolo de la larga historia de Azerbaiy\u00e1n, rodeada por el petr\u00f3leo, en el Caspio, una vasta masa de agua rica en combustibles f\u00f3siles que calientan el planeta y que tambi\u00e9n se est\u00e1 reduciendo dr\u00e1sticamente debido a la crisis clim\u00e1tica que esos combustibles f\u00f3siles est\u00e1n impulsando.<\/p>\n<p>La historia de Oil Rocks se remonta a la era sovi\u00e9tica. A finales de la d\u00e9cada de 1940, los trabajadores petroleros desembarcaron en una peque\u00f1a isla y construyeron una plataforma de perforaci\u00f3n y una peque\u00f1a casa para alojarse. El primer pozo exploratorio se perfor\u00f3 en 1949 y de \u00e9l surgi\u00f3 una fuente de \u201coro negro\u201d.<\/p>\n<p>El yacimiento petrol\u00edfero envi\u00f3 su primer buque cisterna de petr\u00f3leo a tierra en 1951 y la construcci\u00f3n de la ciudad comenz\u00f3 en serio. Lo que vino despu\u00e9s fue un milagro arquitect\u00f3nico y t\u00e9cnico, dijo Wolfensberger.<\/p>\n<p>La ciudad fue creciendo lentamente, sostenida por postes de metal hundidos en el fondo marino y situada a varios metros sobre el nivel del mar como si flotara. Con el tiempo, estuvo formada por casi 2.000 pozos y alrededor de 320 sitios de producci\u00f3n, conectados por m\u00e1s de 160 kil\u00f3metros de puentes y m\u00e1s de 96 kil\u00f3metros de oleoductos y gasoductos.<\/p>\n<p>Producci\u00f3n de petr\u00f3leo en Neft Da\u015flar\u0131 en 2011.<\/p>\n<p>Siete barcos fuera de servicio fueron llevados a la zona y hundidos deliberadamente. Sus restos formaron una bah\u00eda artificial para proteger la ciudad del viento y las olas, aunque Neft Da\u015flar\u0131 sigue siendo vulnerable a las tormentas y las mareas turbulentas.<\/p>\n<p>\u201cAlgunos de esos barcos son visibles en la superficie del agua donde fueron enterrados\u201d, dijo Mirvari Gahramanli, directora de la Organizaci\u00f3n de Protecci\u00f3n de los Derechos de los Trabajadores Petroleros, que se centra en los derechos humanos en el sector del petr\u00f3leo y el gas de Azerbaiy\u00e1n.<\/p>\n<p>En las d\u00e9cadas siguientes, Neft Da\u015flar\u0131 fue adquiriendo edificios de viviendas para los trabajadores, una panader\u00eda, un teatro con capacidad para cientos de personas, tiendas, instalaciones m\u00e9dicas, un campo de f\u00fatbol y un helipuerto. Incluso hay \u00e1rboles y un parque plantados sobre las estructuras de acero.<\/p>\n<p>Algunos en Azerbaiy\u00e1n la llaman \u201cla octava maravilla del mundo\u201d, dijo Gahramanli. Otros la llaman \u201cla isla de los siete barcos\u201d, en honor a los barcos hundidos que la rodean.<\/p>\n<p>Seg\u00fan la petrolera estatal azerbaiyana SOCAR, propietaria y operadora de Neft Da\u015flar\u0131, fue una joya de la corona de la producci\u00f3n petrolera del Caspio y produjo casi 180 millones de toneladas de petr\u00f3leo en sus 75 a\u00f1os de existencia. En su apogeo en 1967, extrajo un r\u00e9cord de 7,6 millones de toneladas.<\/p>\n<p>Dormitorios del personal en Neft Da\u015flar\u0131 el 6 de septiembre de 2023. La construcci\u00f3n del asentamiento comenz\u00f3 durante la era sovi\u00e9tica en 1949. Ahora el asentamiento tiene un sistema de caminos y plataformas, y m\u00e1s de 160 kil\u00f3metros de calles y puentes que conectan las islas artificiales. (Cr\u00e9dito: Maxim Shipenkov\/EPA-EFE\/Shutterstock).<\/p>\n<p>Adem\u00e1s del alojamiento, la ciudad cuenta con un parque, un campo de f\u00fatbol y un gran teatro. (Cr\u00e9dito: Maxim Shipenkov\/EPA-EFE\/Shutterstock).<\/p>\n<p>Pero su importancia ha disminuido en las \u00faltimas d\u00e9cadas a medida que se abrieron yacimientos petrol\u00edferos m\u00e1s grandes y los precios del petr\u00f3leo fluctuaron. Los niveles de producci\u00f3n se redujeron a menos de 3.000 toneladas diarias (aproximadamente 1 mill\u00f3n de toneladas al a\u00f1o), seg\u00fan cifras de SOCAR de enero.<\/p>\n<p>\u201cLa producci\u00f3n en Neft Da\u015flar\u0131 abastece solo una peque\u00f1a parte de la producci\u00f3n petrolera de Azerbaiy\u00e1n, gran parte de la cual se suministra al mercado interno\u201d, dijo Brenda Shaffer, experta en energ\u00eda de la Escuela de Postgrado Naval de Estados Unidos, que ha asesorado a compa\u00f1\u00edas de petr\u00f3leo y gas en la regi\u00f3n del Caspio.<\/p>\n<p>Como la producci\u00f3n de petr\u00f3leo disminuy\u00f3, la poblaci\u00f3n de la ciudad se redujo a alrededor de 3.000 personas, dijo Gahramanli, y los trabajadores generalmente hacen turnos de 15 d\u00edas en el mar y luego 15 d\u00edas en casa en el continente terrestre.<\/p>\n<p>Por qu\u00e9 esta ciudad espa\u00f1ola se distingue de otros destinos populares del Mediterr\u00e1neo<\/p>\n<p>Algunas partes de la ciudad, vulnerables a las aguas salobres y tormentosas del Caspio, se est\u00e1n desmoronando. Incluso en 2008, grandes trozos de puentes se hab\u00edan derrumbado, dijo Wolfensberger. Hab\u00eda \u201ctodav\u00eda mucha vida, pero muchas cosas se estaban desmoronando al mismo tiempo\u201d.<\/p>\n<p>Tambi\u00e9n se recibieron informes sobre derrames de petr\u00f3leo. La organizaci\u00f3n de Gahramanli lleva a\u00f1os expresando su preocupaci\u00f3n por la contaminaci\u00f3n procedente de Neft Da\u015flar\u0131, incluidos informes sobre aguas residuales sin tratar que se vierten al mar Caspio.<\/p>\n<p>SOCAR no hab\u00eda respondido a las preguntas de CNN al momento de la publicaci\u00f3n, pero en un posteo de Facebook de 2019, la compa\u00f1\u00eda dijo que hab\u00eda identificado a trabajadores que hab\u00edan vertido petr\u00f3leo al mar. \u201cSOCAR tomar\u00e1 las medidas administrativas apropiadas sobre los empleados que contaminen el medio ambiente\u201d, dec\u00eda la publicaci\u00f3n.<\/p>\n<p>Gahramanli afirm\u00f3 que la situaci\u00f3n mejor\u00f3 en v\u00edsperas de la COP29, la conferencia sobre el clima respaldada por las Naciones Unidas que tendr\u00e1 lugar en Bak\u00fa la semana pr\u00f3xima. Los l\u00edderes mundiales se reunir\u00e1n para debatir la forma de abordar la crisis clim\u00e1tica, impulsada por la quema de combustibles f\u00f3siles por parte de los seres humanos, en salas de conferencias a solo unas decenas de kil\u00f3metros de Neft Da\u015flar\u0131.<\/p>\n<p>Plataforma petrolera y asentamiento industrial Neft Da\u015flar\u0131 en el mar Caspio el 6 de septiembre de 2023. Fue la primera plataforma petrolera offshore operativa del mundo. (Cr\u00e9dito: Maxim Shipenkov\/EPA-EFE\/Shutterstock).<\/p>\n<p>Una torre de perforaci\u00f3n petrol\u00edfera en Neft Da\u015flar\u0131. El mar est\u00e1 ganando terreno a algunas partes de la ciudad, pero a\u00fan sigue produciendo petr\u00f3leo. (Cr\u00e9dito: Maxim Shipenkov\/EPA-EFE\/Shutterstock).<\/p>\n<p>Desde hace tiempo se han planteado preguntas sobre qu\u00e9 pasar\u00e1 con esta enorme ciudad acu\u00e1tica cuando se acabe su petr\u00f3leo.<\/p>\n<p>Al final de su documental, Wolfensberger expone las dif\u00edciles decisiones que prev\u00e9 que deber\u00e1n tomar las autoridades: desmantelar la ciudad a un costo enorme, convertirla en un centro vacacional o simplemente abandonarla y \u201callanar el camino para un gran desastre ecol\u00f3gico\u201d.<\/p>\n<p>Algunos creen que se le dar\u00e1 un nuevo uso. \u201cCuando se agoten sus reservas de petr\u00f3leo, Neft Da\u015flar\u0131 probablemente se convertir\u00e1 en un im\u00e1n tur\u00edstico\u201d, dijo Shaffer. Wolfensberger cree que podr\u00eda convertirse en un museo. \u201cEs realmente la cuna de la exploraci\u00f3n petrolera en alta mar\u201d, dijo. \u201cEs parte del patrimonio\u201d.<\/p>\n<p>Pero, por ahora, la ciudad sigue en pie, sigue produciendo petr\u00f3leo, sigue pr\u00e1cticamente aislada de los forasteros, es un mosaico oxidado y s\u00edmbolo de una industria en lento declive.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2024 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>(CNN) \u2013\u2013 Cuando el cineasta Marc Wolfensberger se enter\u00f3 de la existencia de Neft Da\u015flar\u0131, pens\u00f3 que era un mito. No dejaba de escuchar hablar de esta ciudad secreta, que se extend\u00eda como tent\u00e1culos flotantes y oxidados sobre el mar Caspio, lejos de la costa m\u00e1s cercana. Pero muy pocos la hab\u00edan visto, dijo. \u201cEl [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1455664","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Una alucinante ciudad petrolera de la era sovi\u00e9tica &quot;flota&quot; en el lago m\u00e1s grande del mundo - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Una alucinante ciudad petrolera de la era sovi\u00e9tica &quot;flota&quot; en el lago m\u00e1s grande del mundo - Noticias\" \/>\n<meta property=\"og:description\" content=\"(CNN) \u2013\u2013 Cuando el cineasta Marc Wolfensberger se enter\u00f3 de la existencia de Neft Da\u015flar\u0131, pens\u00f3 que era un mito. No dejaba de escuchar hablar de esta ciudad secreta, que se extend\u00eda como tent\u00e1culos flotantes y oxidados sobre el mar Caspio, lejos de la costa m\u00e1s cercana. Pero muy pocos la hab\u00edan visto, dijo. \u201cEl [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-08T11:03:44+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Una alucinante ciudad petrolera de la era sovi\u00e9tica &#171;flota&#187; en el lago m\u00e1s grande del mundo\",\"datePublished\":\"2024-11-08T11:03:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\"},\"wordCount\":1532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\",\"name\":\"Una alucinante ciudad petrolera de la era sovi\u00e9tica \\\"flota\\\" en el lago m\u00e1s grande del mundo - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2024-11-08T11:03:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Una alucinante ciudad petrolera de la era sovi\u00e9tica &#171;flota&#187; en el lago m\u00e1s grande del mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Una alucinante ciudad petrolera de la era sovi\u00e9tica \"flota\" en el lago m\u00e1s grande del mundo - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Una alucinante ciudad petrolera de la era sovi\u00e9tica \"flota\" en el lago m\u00e1s grande del mundo - Noticias","og_description":"(CNN) \u2013\u2013 Cuando el cineasta Marc Wolfensberger se enter\u00f3 de la existencia de Neft Da\u015flar\u0131, pens\u00f3 que era un mito. No dejaba de escuchar hablar de esta ciudad secreta, que se extend\u00eda como tent\u00e1culos flotantes y oxidados sobre el mar Caspio, lejos de la costa m\u00e1s cercana. Pero muy pocos la hab\u00edan visto, dijo. \u201cEl [&hellip;]","og_url":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","og_site_name":"Noticias","article_published_time":"2024-11-08T11:03:44+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/"},"author":{"name":"","@id":""},"headline":"Una alucinante ciudad petrolera de la era sovi\u00e9tica &#171;flota&#187; en el lago m\u00e1s grande del mundo","datePublished":"2024-11-08T11:03:44+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/"},"wordCount":1532,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","url":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","name":"Una alucinante ciudad petrolera de la era sovi\u00e9tica \"flota\" en el lago m\u00e1s grande del mundo - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2024-11-08T11:03:44+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Una alucinante ciudad petrolera de la era sovi\u00e9tica &#171;flota&#187; en el lago m\u00e1s grande del mundo"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Una alucinante ciudad petrolera de la era sovi\u00e9tica &#171;flota&#187; en el lago m\u00e1s grande del mundo","url":"http:\/\/noticiasya.com\/costa-central\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2024\/11\/08\/ciudad-petrolera-flota-lago-grande-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2024-11-08T11:03:44Z","datePublished":"2024-11-08T11:03:44Z","dateModified":"2024-11-08T11:03:44Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Una alucinante ciudad petrolera de la era sovi\\u00e9tica &#171;flota&#187; en el lago m\\u00e1s grande del mundo\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/11\\\/08\\\/ciudad-petrolera-flota-lago-grande-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2024\\\/11\\\/08\\\/ciudad-petrolera-flota-lago-grande-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2024-11-08T11:03:44Z\",\"datePublished\":\"2024-11-08T11:03:44Z\",\"dateModified\":\"2024-11-08T11:03:44Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1464261,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/07\/06\/diogo-jota-jugador-perfecto-liverpool-trax\/","url_meta":{"origin":1455664,"position":0},"title":"El esp\u00edritu y la tenacidad de Diogo Jota lo hicieron el jugador perfecto para el Liverpool, una ciudad acostumbrada a luchar","author":"","date":"julio 6, 2025","format":false,"excerpt":"Hay una actuaci\u00f3n de Diogo Jota que muchos aficionados del Liverpool recordar\u00e1n por encima de todas las dem\u00e1s.En octubre de 2022, cuando los Reds estaban pasando por un mal momento de forma, Jota y compa\u00f1\u00eda se enfrentaron a un equipo del Manchester City que ganar\u00eda un triplete hist\u00f3rico esa temporada.Un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1452504,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/06\/trump-arremete-mujeres-acusado-agresion-sexual-jean-carroll-trax\/","url_meta":{"origin":1455664,"position":1},"title":"Trump arremete contra mujeres que lo han acusado de agresi\u00f3n sexual tras asistir a una audiencia para apelar veredicto en caso de Carroll","author":"","date":"septiembre 6, 2024","format":false,"excerpt":"(CNN) --\u00a0El expresidente de Estados Unidos Donald Trump arremeti\u00f3 este viernes contra varias mujeres que lo han acusado de agresi\u00f3n sexual despu\u00e9s de asistir a una audiencia judicial en Nueva York para intentar convencer a un tribunal de apelaciones federal de que deber\u00eda obtener un nuevo juicio despu\u00e9s de que\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456967,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/12\/25\/estatua-pie-grande-australia-kilcoy-trax\/","url_meta":{"origin":1455664,"position":2},"title":"El &#171;Pie Grande de Australia&#187; vigil\u00f3 la peque\u00f1a ciudad de Kilcoy durante d\u00e9cadas, pero un d\u00eda desapareci\u00f3","author":"","date":"diciembre 25, 2024","format":false,"excerpt":"La peque\u00f1a ciudad de Kilcoy no es donde tuvo lugar el primer ni el m\u00e1s reciente avistamiento de \u201cYowie\u201d. Y los cazadores de la versi\u00f3n australiana del Pie Grande tampoco tienen m\u00e1s probabilidades de verlo all\u00ed que en cualquier otro lugar de la vasta y accidentada selva del pa\u00eds.Sin embargo,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466321,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/09\/10\/sueno-americano-en-mexico-trax\/","url_meta":{"origin":1455664,"position":3},"title":"Fue deportada nueve veces. Luego, como otros, encontr\u00f3 su sue\u00f1o americano en M\u00e9xico","author":"","date":"septiembre 10, 2025","format":false,"excerpt":"Esther Morales vivi\u00f3 en Estados Unidos durante aproximadamente 20 a\u00f1os. A pesar de haber sido deportada varias veces, regres\u00f3 ilegalmente en repetidas ocasiones buscando la oportunidad de alcanzar el sue\u00f1o americano.Su novena deportaci\u00f3n, en 2009, ser\u00eda la \u00faltima. Incapaz de regresar a Estados Unidos debido a la aplicaci\u00f3n de medidas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1454941,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/10\/04\/muertos-israelies-frontera-libanesa-hostilidades-trax\/","url_meta":{"origin":1455664,"position":4},"title":"&#171;Habr\u00e1 muchos muertos&#187;: los israel\u00edes que viven cerca de la frontera libanesa temen una escalada de hostilidades","author":"","date":"octubre 4, 2024","format":false,"excerpt":"Kiryat Shmona, Israel (CNN) -- Yair Pinhas creci\u00f3 practicando senderismo en las colinas que rodean Kiryat Shmona, su ciudad natal en el norte de Israel, cerca de la frontera con el L\u00edbano.\"El r\u00edo Jord\u00e1n nace en la zona, y hay muchos lagos y arroyos preciosos, es incre\u00edble. Pero siempre admir\u00e1bamos\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458195,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/02\/04\/ellen-greenberg-actualizacion-caso-filadelfia-trax\/","url_meta":{"origin":1455664,"position":5},"title":"A pesar de 20 pu\u00f1aladas y 11 contusiones, la muerte de Ellen Greenberg fue declarada suicidio. El pat\u00f3logo cambi\u00f3 de opini\u00f3n","author":"","date":"febrero 4, 2025","format":false,"excerpt":"Hace 14 a\u00f1os, en una tarde nevada en Filadelfia, Ellen Greenberg fue encontrada muerta en el suelo de la cocina de su apartamento. Ten\u00eda 20 heridas de cuchillo y numerosas contusiones. Las autoridades dictaminaron que se hab\u00eda suicidado.Greenberg era una maestra de 27 a\u00f1os. Sus padres insistieron en que hab\u00eda\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455664","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1455664"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1455664\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1455664"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1455664"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1455664"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}