{"id":1463769,"date":"2025-06-20T06:03:51","date_gmt":"2025-06-20T13:03:51","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/"},"modified":"2025-06-20T06:03:51","modified_gmt":"2025-06-20T13:03:51","slug":"un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","title":{"rendered":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto"},"content":{"rendered":"<p>Gabriel Rosenstein, director de Hemodin\u00e1mica de Urgencias del Hospital Soroka de Beersheba, en Israel, se refiri\u00f3 al impacto de un misil iran\u00ed en el centro m\u00e9dico que caus\u00f3 da\u00f1os extensos en el pabell\u00f3n quir\u00fargico y dej\u00f3 al menos 40 heridos leves.<\/p>\n<p>En CNN Primera Ma\u00f1ana, el m\u00e9dico explic\u00f3 que la guerra no distingue entre civiles y soldados, entre m\u00e9dicos y pacientes.<\/p>\n<p>Afirm\u00f3 que \u201cviajaba en mi auto con mi mujer, que tambi\u00e9n es m\u00e9dica, y en el camino ya hab\u00edamos recibido unas alarmas en los tel\u00e9fonos. Es un sistema que se desarroll\u00f3 en los pa\u00edses que tienen tsunami, no importa a d\u00f3nde est\u00e9s conectado, al tel\u00e9fono llega al mensaje dici\u00e9ndonos que nos vayamos acercando a un lugar donde haya protecci\u00f3n, porque misiles ven\u00edan en nuestra direcci\u00f3n\u201d.<\/p>\n<p>Cont\u00f3 que la situaci\u00f3n era ca\u00f3tica, hab\u00eda niebla espesa, incertidumbre y explosiones cada vez m\u00e1s cercanas y asegur\u00f3 que se \u201crefugiaron debajo de un puente. Nos tiramos en el piso, tap\u00e1ndonos la cabeza, panza para abajo, y esperar que todo pase\u201d.<\/p>\n<p>Asegur\u00f3 que al saber que el Hospital Soroka hab\u00eda sido alcanzado, volvieron y all\u00ed vieron <strong>\u201cel caos total, donde un edificio estaba incendiado en el piso superior, y un mont\u00f3n de destrozos por todos lados, pero por suerte ese piso hab\u00eda sido evacuado un d\u00eda antes\u201d<\/strong>.<\/p>\n<p>El profesional explic\u00f3 que el hospital, que atiende a m\u00e1s de un mill\u00f3n de personas y cuenta con mil camas, qued\u00f3 pr\u00e1cticamente inoperable.<\/p>\n<p>Detall\u00f3 que <strong>\u201clas posibilidades hoy de trabajar en el Soroka casi no existen, no hay luz, hay falta de agua, destrozos por todos lados\u201d<\/strong> y cont\u00f3 que, sin embargo, apenas lleg\u00f3 al lugar, lo esperaba una urgencia porque \u201chab\u00eda un paciente con un infarto agudo de miocardio, tuve que pasar por encima de los destrozos. Fue dif\u00edcil transportar al paciente, pero por suerte sali\u00f3 bien\u201d.<\/p>\n<p>Gabriel Rosenstein insisti\u00f3 en que no hab\u00eda ning\u00fan objetivo militar en las cercan\u00edas y <strong>\u201cno hay ninguna raz\u00f3n por la que haya una base militar. Israel tiene sus bases, pero no est\u00e1n en esta zona\u201d<\/strong>.<\/p>\n<p>Subray\u00f3 que el hospital es un espacio de convivencia, donde \u201c<strong>alrededor del 40 por ciento de los m\u00e9dicos que trabajan en Soroka son beduinos<\/strong>. El jefe de la guardia de cirug\u00eda es beduino, y as\u00ed hay un mont\u00f3n.<br \/>Trabajamos juntos. Las enfermeras tambi\u00e9n\u201d.<\/p>\n<p>Y profundiz\u00f3 que la paciente a la que atendi\u00f3 tras el ataque era una mujer beduina: \u201cpobrecita no entend\u00eda lo que pasaba alrededor, pero por suerte sali\u00f3 bien. Y eso hay que entenderlo\u201d.<\/p>\n<p>Sobre el trasfondo del ataque, el m\u00e9dico asegur\u00f3 que <strong>\u201ccuando tu enemigo te dice que te quiere matar y tiene un cuchillo en la mano, una pistola o un Kalashnikov, cr\u00e9ele. Cuando Ir\u00e1n nos dice que nos quiere destruir, ac\u00e1 le creemos\u201d.<\/strong><\/p>\n<p>Y concluy\u00f3 que <strong>\u201ccuando te tiran un misil, el misil no sabe reconocer si sos jud\u00edo, sos musulmano o sos cristiano\u201d<\/strong>.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Gabriel Rosenstein, director de Hemodin\u00e1mica de Urgencias del Hospital Soroka de Beersheba, en Israel, se refiri\u00f3 al impacto de un misil iran\u00ed en el centro m\u00e9dico que caus\u00f3 da\u00f1os extensos en el pabell\u00f3n quir\u00fargico y dej\u00f3 al menos 40 heridos leves. En CNN Primera Ma\u00f1ana, el m\u00e9dico explic\u00f3 que la guerra no distingue entre civiles [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1463769","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto - Noticias\" \/>\n<meta property=\"og:description\" content=\"Gabriel Rosenstein, director de Hemodin\u00e1mica de Urgencias del Hospital Soroka de Beersheba, en Israel, se refiri\u00f3 al impacto de un misil iran\u00ed en el centro m\u00e9dico que caus\u00f3 da\u00f1os extensos en el pabell\u00f3n quir\u00fargico y dej\u00f3 al menos 40 heridos leves. En CNN Primera Ma\u00f1ana, el m\u00e9dico explic\u00f3 que la guerra no distingue entre civiles [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T13:03:51+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto\",\"datePublished\":\"2025-06-20T13:03:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\"},\"wordCount\":556,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\",\"name\":\"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-06-20T13:03:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","og_locale":"es_ES","og_type":"article","og_title":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto - Noticias","og_description":"Gabriel Rosenstein, director de Hemodin\u00e1mica de Urgencias del Hospital Soroka de Beersheba, en Israel, se refiri\u00f3 al impacto de un misil iran\u00ed en el centro m\u00e9dico que caus\u00f3 da\u00f1os extensos en el pabell\u00f3n quir\u00fargico y dej\u00f3 al menos 40 heridos leves. En CNN Primera Ma\u00f1ana, el m\u00e9dico explic\u00f3 que la guerra no distingue entre civiles [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","og_site_name":"Noticias","article_published_time":"2025-06-20T13:03:51+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/"},"author":{"name":"","@id":""},"headline":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto","datePublished":"2025-06-20T13:03:51+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/"},"wordCount":556,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","url":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","name":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-06-20T13:03:51+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Un misil sobre un hospital: la cr\u00f3nica de un m\u00e9dico argentino desde el coraz\u00f3n del conflicto","url":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-06-20T13:03:51Z","datePublished":"2025-06-20T13:03:51Z","dateModified":"2025-06-20T13:03:51Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Un misil sobre un hospital: la cr\\u00f3nica de un m\\u00e9dico argentino desde el coraz\\u00f3n del conflicto\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/un-misil-sobre-un-hospital-la-cronica-de-un-medico-argentino-desde-el-corazon-del-conflicto\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-06-20T13:03:51Z\",\"datePublished\":\"2025-06-20T13:03:51Z\",\"dateModified\":\"2025-06-20T13:03:51Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1450438,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/06\/17\/nina-9-anos-gravemente-quemada-misil-israel-pacientes-criticos-atrapados-gaza-trax\/","url_meta":{"origin":1463769,"position":0},"title":"Una ni\u00f1a de 9 a\u00f1os qued\u00f3 gravemente quemada por un misil de Israel, y no tiene escapatoria. Es solo uno de los miles de pacientes cr\u00edticos atrapados en Gaza","author":"","date":"junio 17, 2024","format":false,"excerpt":"Nota del editor: Este art\u00edculo contiene im\u00e1genes sensibles. La madre de la ni\u00f1a dio permiso para utilizarla y mostrar al mundo lo que su hija estaba pasando.(CNN) -- Hanan Aqel y su hermana ten\u00edan un shekel cada una en la mano, un regalo de su abuelo para ir a comprar\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450974,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/09\/ataque-rusia-ucrania-kyiv-hospital-infantil-bombardeos-trax\/","url_meta":{"origin":1463769,"position":1},"title":"Rusia ataca un hospital infantil en Kyiv y mata a decenas de personas en bombardeos a plena luz del d\u00eda","author":"","date":"julio 9, 2024","format":false,"excerpt":"(CNN) -- Un ataque ruso con misiles destruy\u00f3 parcialmente un hospital infantil en Kyiv este lunes, provocando que pacientes aterrorizados y sus familias huyeran para salvar sus vidas, mientras las autoridades temen que haya m\u00e1s personas atrapadas bajo los escombros.Mosc\u00fa lanz\u00f3 un descarado ataque a\u00e9reo diurno contra objetivos en ciudades\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1450999,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/07\/10\/onu-considera-muy-probable-misil-crucero-ruso-haya-alcanzado-principal-hospital-infantil-de-ucrania-trax\/","url_meta":{"origin":1463769,"position":2},"title":"La ONU considera &#171;muy probable&#187; que un misil de crucero ruso haya alcanzado el principal hospital infantil de Ucrania","author":"","date":"julio 10, 2024","format":false,"excerpt":"(CNN) -- El mayor hospital infantil de Ucrania recibi\u00f3 probablemente el impacto directo de un misil ruso este lunes, seg\u00fan una evaluaci\u00f3n de las Naciones Unidas, mientras la OTAN acordaba reforzar las defensas a\u00e9reas de Kyiv tras el ataque.Rusia ha negado reiteradamente haber atacado el hospital de Kyivy ha alegado,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1453039,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/09\/25\/israel-misil-balistico-hezbolla-tel-aviv-trax\/","url_meta":{"origin":1463769,"position":3},"title":"Israel intercepta un misil bal\u00edstico de Hezbollah cerca de Tel Aviv en el primer ataque de este tipo","author":"","date":"septiembre 25, 2024","format":false,"excerpt":"(CNN) -- Israel intercept\u00f3 un misil disparado por Hezbollah cerca de Tel Aviv este mi\u00e9rcoles, un ataque sin precedentes del grupo militante que lleg\u00f3 profundamente a los centros comerciales del pa\u00eds y marc\u00f3 un nuevo paso en la escalada del conflicto entre las dos partes.Los habitantes de Tel Aviv y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1465813,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/08\/24\/israel-ataca-yemen-huties-nuevo-misil-trax\/","url_meta":{"origin":1463769,"position":4},"title":"Israel ataca Yemen despu\u00e9s de que los hut\u00edes dispararan un nuevo tipo de misil","author":"","date":"agosto 24, 2025","format":false,"excerpt":"Israel atac\u00f3 a los hut\u00edes de Yemen el domingo despu\u00e9s de que los rebeldes respaldados por Ir\u00e1n dispararan un nuevo tipo de misil contra Israel.Las fuerzas israel\u00edes aseguran que atac\u00f3 un sitio militar donde se encuentra el palacio presidencial, as\u00ed como dos centrales el\u00e9ctricas y un lugar de almacenamiento de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1456167,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/11\/29\/camara-de-seguridad-muestra-hospital-de-alepo-durante-el-mortal-bombardeo\/","url_meta":{"origin":1463769,"position":5},"title":"C\u00e1mara de seguridad muestra hospital de Aleppo durante el mortal bombardeo","author":"","date":"noviembre 29, 2024","format":false,"excerpt":"(CNN) -- Un video de una c\u00e1mara de seguridad obtenido por el Canal 4 de Gran Breta\u00f1a muestra im\u00e1genes in\u00e9ditas del hospital pedi\u00e1trico de Aleppo, Siria, momentos antes \u2014y despu\u00e9s\u2014 de que fuera impactado con un misil a\u00e9reo la semana pasada.El hospital Al Quds estaba en un barrio controlado por\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1463769"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463769\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1463769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1463769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1463769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}