{"id":1463770,"date":"2025-06-20T08:03:58","date_gmt":"2025-06-20T15:03:58","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/"},"modified":"2025-06-20T08:03:58","modified_gmt":"2025-06-20T15:03:58","slug":"juez-limita-guardia-nacional-california-trump-trax","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","title":{"rendered":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump"},"content":{"rendered":"<p>Un juez federal escuchar\u00e1 el viernes los argumentos sobre la solicitud de California de una orden judicial que limitar\u00eda el uso de miembros del Ej\u00e9rcito estadounidense en Los \u00c1ngeles, incluyendo a miles de miembros federalizados de la Guardia Nacional estatal.<\/p>\n<p>La audiencia se llevar\u00e1 a cabo ante el juez federal de distrito Charles Breyer, de San Francisco, horas despu\u00e9s de que un tribunal de apelaciones<a href=\"https:\/\/cnnespanol.cnn.com\/2025\/06\/20\/eeuu\/trump-control-guardia-nacional-california-trax\"> revocara un fallo suyo<\/a> que exig\u00eda a Trump renunciar al control de 4.000 guardias federales.<\/p>\n<p>El Tribunal de Apelaciones del Noveno Circuito de EE.UU. rechaz\u00f3 el jueves por la noche la conclusi\u00f3n de Breyer de que Trump se hab\u00eda apoderado ilegalmente del control de las tropas estatales.<\/p>\n<p>Sin embargo, el gobernador dem\u00f3crata Gavin Newsom sigue buscando una orden judicial preliminar que prohibir\u00eda a Trump utilizar a los guardias, as\u00ed como a los infantes de Marina estadounidenses desplegados en el \u00e1rea de Los \u00c1ngeles, para cualquier fin que no sea la protecci\u00f3n de propiedad federal all\u00ed.<\/p>\n<p>Newsom afirma que Trump est\u00e1 violando la ley federal al permitir que los guardias federales protejan a los agentes federales que realizan actividades de control migratorio en Los \u00c1ngeles.<\/p>\n<p>La audiencia est\u00e1 programada para la 1 p. m., hora de Miami.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un juez federal escuchar\u00e1 el viernes los argumentos sobre la solicitud de California de una orden judicial que limitar\u00eda el uso de miembros del Ej\u00e9rcito estadounidense en Los \u00c1ngeles, incluyendo a miles de miembros federalizados de la Guardia Nacional estatal. La audiencia se llevar\u00e1 a cabo ante el juez federal de distrito Charles Breyer, de [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1463770","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump - Noticias\" \/>\n<meta property=\"og:description\" content=\"Un juez federal escuchar\u00e1 el viernes los argumentos sobre la solicitud de California de una orden judicial que limitar\u00eda el uso de miembros del Ej\u00e9rcito estadounidense en Los \u00c1ngeles, incluyendo a miles de miembros federalizados de la Guardia Nacional estatal. La audiencia se llevar\u00e1 a cabo ante el juez federal de distrito Charles Breyer, de [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T15:03:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump\",\"datePublished\":\"2025-06-20T15:03:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\",\"name\":\"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-06-20T15:03:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","og_locale":"es_ES","og_type":"article","og_title":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump - Noticias","og_description":"Un juez federal escuchar\u00e1 el viernes los argumentos sobre la solicitud de California de una orden judicial que limitar\u00eda el uso de miembros del Ej\u00e9rcito estadounidense en Los \u00c1ngeles, incluyendo a miles de miembros federalizados de la Guardia Nacional estatal. La audiencia se llevar\u00e1 a cabo ante el juez federal de distrito Charles Breyer, de [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","og_site_name":"Noticias","article_published_time":"2025-06-20T15:03:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/"},"author":{"name":"","@id":""},"headline":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump","datePublished":"2025-06-20T15:03:58+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","url":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","name":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-06-20T15:03:58+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Juez definir\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump","url":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/juez-limita-guardia-nacional-california-trump-trax\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-06-20T15:03:58Z","datePublished":"2025-06-20T15:03:58Z","dateModified":"2025-06-20T15:03:58Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Juez definir\\u00e1 si se limita el uso de la Guardia Nacional de California por parte de Trump\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/juez-limita-guardia-nacional-california-trump-trax\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/juez-limita-guardia-nacional-california-trump-trax\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-06-20T15:03:58Z\",\"datePublished\":\"2025-06-20T15:03:58Z\",\"dateModified\":\"2025-06-20T15:03:58Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1463672,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/17\/jueces-corte-apelaciones-debaten-trump-federalizo-ilegalmente-guardia-nacional-california-trax\/","url_meta":{"origin":1463770,"position":0},"title":"Jueces de la corte de apelaciones debaten si Trump federaliz\u00f3 ilegalmente a miembros de la Guardia Nacional de California","author":"","date":"junio 17, 2025","format":false,"excerpt":"Una corte federal de apelaciones pas\u00f3 m\u00e1s de una hora este martes debatiendo si el presidente Donald Trump federaliz\u00f3 de manera ilegal a miles de miembros de la Guardia Nacional de California para reforzar la seguridad en Los \u00c1ngeles en medio de disturbios por el control migratorio.Un panel de tres\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463761,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/19\/trump-control-guardia-nacional-california-trax\/","url_meta":{"origin":1463770,"position":1},"title":"Trump puede mantener el control de miles de guardias nacionales de California, dictamina un tribunal de apelaciones","author":"","date":"junio 19, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones permite al presidente Donald Trump mantener el control sobre miles de miembros de la Guardia Nacional de California.El Tribunal de Apelaciones del Noveno Circuito de EE.UU. accedi\u00f3 a la solicitud de Trump para levantar, por ahora, un fallo de un tribunal inferior que exig\u00eda al\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1467650,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/10\/22\/trump-enviar-guardia-nacional-cualquier-ciudad-batallas-legales-trax\/","url_meta":{"origin":1463770,"position":2},"title":"En medio de batallas legales, Trump dice que puede enviar a la Guardia Nacional a cualquier ciudad que considere necesario","author":"","date":"octubre 22, 2025","format":false,"excerpt":"Mientras una jueza federal dijo que extender\u00e1 una orden que bloquea el despliegue de tropas de la Guardia Nacional en Chicago, el presidente de Estados Unidos, Donald Trump, afirm\u00f3 que se siente facultado para enviar elementos a cualquier ciudad que considere necesario, despu\u00e9s de que una corte de apelaciones respaldara\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1466080,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/09\/02\/juez-trump-ley-federal-ejercito-los-angeles-trax\/","url_meta":{"origin":1463770,"position":3},"title":"Un juez dice que el Gobierno de Trump viol\u00f3 la ley federal al usar fuerzas militares en Los \u00c1ngeles","author":"","date":"septiembre 2, 2025","format":false,"excerpt":"Un juez federal dictamin\u00f3 este martes que el presidente de EE.UU., Donald Trump, y el secretario de Defensa, Pete Hegseth, violaron la ley federal al utilizar a las Fuerzas Armadas de Estados Unidos para ayudar a llevar a cabo actividades en Los \u00c1ngeles y sus alrededores este verano.El juez de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464805,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/07\/23\/corte-federal-golpe-trump-ciudadania-por-nacimiento-trax\/","url_meta":{"origin":1463770,"position":4},"title":"Corte federal de apelaciones da otro golpe al esfuerzo de Trump por terminar con la ciudadan\u00eda por nacimiento","author":"","date":"julio 23, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones emiti\u00f3 este mi\u00e9rcoles otro duro rev\u00e9s al decreto del presidente Donald Trump que buscaba poner fin a la ciudadan\u00eda por nacimiento, al dictaminar que es inconstitucional y mantener el bloqueo nacional contra esta controvertida pol\u00edtica.El fallo de 2-1 del 9\u00ba Tribunal de Apelaciones de EE.UU.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1469346,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/12\/17\/tribunal-apelaciones-trump-guardia-nacional-washington-trax\/","url_meta":{"origin":1463770,"position":5},"title":"Tribunal de apelaciones permite que Trump mantenga despliegue de la Guardia Nacional en Washington por ahora","author":"","date":"diciembre 17, 2025","format":false,"excerpt":"Un tribunal federal de apelaciones fall\u00f3 a favor de permitir que el presidente Donald Trump contin\u00fae con el despliegue de tropas de la Guardia Nacional en la ciudad de Washington.En una decisi\u00f3n un\u00e1nime emitida el mi\u00e9rcoles, el Tribunal de Apelaciones del Circuito de Washington suspendi\u00f3 indefinidamente una orden de un\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1463770"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463770\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1463770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1463770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1463770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}