{"id":1463771,"date":"2025-06-20T08:03:59","date_gmt":"2025-06-20T15:03:59","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/"},"modified":"2025-06-20T08:03:59","modified_gmt":"2025-06-20T15:03:59","slug":"mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","title":{"rendered":"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&#187;"},"content":{"rendered":"<p><strong>Mauro Berenstein, presidente de la DAIA<\/strong>, visit\u00f3 este viernes los estudios de CNN Radio para conversar con Nacho Gir\u00f3n sobre el conflicto de Israel con Ir\u00e1n, la visita del presidente Javier Milei a Israel d\u00edas antes eque comenzara la guerra y su preocupaci\u00f3n por \u201cel crecimiento del antisemitismo en Argentina\u201d.<\/p>\n<p>Berenstein, quien acompa\u00f1\u00f3 a Milei a Israel, confes\u00f3 en La Ma\u00f1ana de CNN: \u201c<strong>Fue traum\u00e1tica la salida y acompa\u00f1ando a las distintas familias que buscan que vuelvan sus familiares. Hab\u00edamos acompa\u00f1ado al presidente y cuando termin\u00f3 la gira al d\u00eda siguiente ten\u00eda el vuelo. Estuvimos cinco d\u00edas en los lugares de refugio\u201d.<\/strong><\/p>\n<p>\u201cIsrael es el \u00fanico pa\u00eds occidental democr\u00e1tico en la zona. Tuvo que intervenir porque hab\u00eda datos oficiales de que Ir\u00e1n estaba conformando un arma nuclear\u2026 En cinco meses iban a tener esa bomba at\u00f3mica\u201d, aclar\u00f3, y expres\u00f3: \u201cEst\u00e1 comprobado que en Ir\u00e1n financian al terrorismo. Ante este dato, el estado de Israel accion\u00f3 para desactivar, e Ir\u00e1n contest\u00f3 atacando a los civiles\u201d.<\/p>\n<p>En este sentido, dijo que \u201cel estado terrorista iran\u00ed busca da\u00f1ar a la poblaci\u00f3n da\u00f1ando indiscriminadamente\u201d. \u201cLo que defiende Israel es su derecho a existir y a la democracia\u201d, remarc\u00f3, y sostuvo que \u201calzamos la voz exigiendo que los secuestrados vuelvan a sus hogares\u201d.<\/p>\n<p><strong>El alineamiento de Milei con Israel<\/strong><\/p>\n<p>Seg\u00fan el titular de la DAIA, \u201ces la creencia del presidente Milei, que no es jud\u00edo y hace pocos a\u00f1os empez\u00f3 a conocer los valores y los acompa\u00f1a. Su pensamiento y su ideolog\u00eda de fe es propia\u2026. Cuando vemos su alineamiento con Israel y Estados Unidos es una cuesti\u00f3n de democracia y libertad\u201d.<\/p>\n<p>\u201cSu apoyo incondicional a Israel tiene que ver con sus valores democr\u00e1ticos\u201d, consider\u00f3, y asegur\u00f3 que aspiran a \u201cuna vida libre y con igualdad\u201d.<\/p>\n<p><strong>Informe sobre el antisemitismo en Argentina<\/strong><\/p>\n<p>En este sentido, Berenstein se refiri\u00f3 al <a href=\"https:\/\/daia.org.ar\">informe que refleja el crecimiento del antisemitismo en Argentina<\/a>: \u201cLa gran teor\u00eda que da vueltas es el proyecto de que iban a conquistar la Patagonia. Es muy gracioso: en mi vida particular me dedico a importar juguetes y trabaj\u00e9 muchos a\u00f1os en educaci\u00f3n. Me canso de escuchar o ver en redes sociales que soy el due\u00f1o de la Patagonia\u201d.<\/p>\n<p>\u201cEs un discurso de odio que cre\u00eda que la poblaci\u00f3n argentina hab\u00eda superado\u201d, asegur\u00f3.<\/p>\n<p><strong>Seguridad y control de la DAIA<\/strong><\/p>\n<p>\u201cHemos hablado con ministerios para que siga habiendo polic\u00edas en espacios jud\u00edos. No hay ninguna amenaza real. No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina. Tenemos nuestros protocolos y hacemos nuestro trabajo\u201d, cerr\u00f3.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mauro Berenstein, presidente de la DAIA, visit\u00f3 este viernes los estudios de CNN Radio para conversar con Nacho Gir\u00f3n sobre el conflicto de Israel con Ir\u00e1n, la visita del presidente Javier Milei a Israel d\u00edas antes eque comenzara la guerra y su preocupaci\u00f3n por \u201cel crecimiento del antisemitismo en Argentina\u201d. Berenstein, quien acompa\u00f1\u00f3 a Milei [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1463771","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mauro Berenstein, presidente de la DAIA: &quot;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&quot; - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mauro Berenstein, presidente de la DAIA: &quot;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&quot; - Noticias\" \/>\n<meta property=\"og:description\" content=\"Mauro Berenstein, presidente de la DAIA, visit\u00f3 este viernes los estudios de CNN Radio para conversar con Nacho Gir\u00f3n sobre el conflicto de Israel con Ir\u00e1n, la visita del presidente Javier Milei a Israel d\u00edas antes eque comenzara la guerra y su preocupaci\u00f3n por \u201cel crecimiento del antisemitismo en Argentina\u201d. Berenstein, quien acompa\u00f1\u00f3 a Milei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T15:03:59+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&#187;\",\"datePublished\":\"2025-06-20T15:03:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\"},\"wordCount\":496,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\",\"name\":\"Mauro Berenstein, presidente de la DAIA: \\\"No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina\\\" - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-06-20T15:03:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&#187;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mauro Berenstein, presidente de la DAIA: \"No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina\" - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","og_locale":"es_ES","og_type":"article","og_title":"Mauro Berenstein, presidente de la DAIA: \"No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina\" - Noticias","og_description":"Mauro Berenstein, presidente de la DAIA, visit\u00f3 este viernes los estudios de CNN Radio para conversar con Nacho Gir\u00f3n sobre el conflicto de Israel con Ir\u00e1n, la visita del presidente Javier Milei a Israel d\u00edas antes eque comenzara la guerra y su preocupaci\u00f3n por \u201cel crecimiento del antisemitismo en Argentina\u201d. Berenstein, quien acompa\u00f1\u00f3 a Milei [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","og_site_name":"Noticias","article_published_time":"2025-06-20T15:03:59+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/"},"author":{"name":"","@id":""},"headline":"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&#187;","datePublished":"2025-06-20T15:03:59+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/"},"wordCount":496,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","url":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","name":"Mauro Berenstein, presidente de la DAIA: \"No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina\" - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-06-20T15:03:59+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&#187;"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\u00f3n por un atentado en Argentina&#187;","url":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-06-20T15:03:59Z","datePublished":"2025-06-20T15:03:59Z","dateModified":"2025-06-20T15:03:59Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Mauro Berenstein, presidente de la DAIA: &#171;No hay motivos para que haya una preocupaci\\u00f3n por un atentado en Argentina&#187;\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/mauro-berenstein-presidente-de-la-daia-no-hay-motivos-para-que-haya-una-preocupacion-por-un-atentado-en-argentina\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-06-20T15:03:59Z\",\"datePublished\":\"2025-06-20T15:03:59Z\",\"dateModified\":\"2025-06-20T15:03:59Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1472056,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/10\/milei-sionista-discurso-nueva-york-iran-eeuu-israel-orix\/","url_meta":{"origin":1463771,"position":0},"title":"&#171;Me siento orgulloso de ser el presidente m\u00e1s sionista del mundo&#187;, dijo Milei desde Nueva York","author":"","date":"marzo 10, 2026","format":false,"excerpt":"Mientras el conflicto en Medio Oriente sigue avanzando y la geopol\u00edtica se sacude, el presidente de Argentina, Javier Milei, volvi\u00f3 a posicionarse como aliado fiel de Estados Unidos e Israel.En una disertaci\u00f3n en la Universidad Yeshiva en Nueva York, Milei dijo que se siente orgulloso de \u201cser el presidente m\u00e1s\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1463858,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/23\/ines-capdevila-el-alineamiento-de-milei-con-israel-no-favorece-a-la-argentina\/","url_meta":{"origin":1463771,"position":1},"title":"In\u00e9s Capdevila: &#171;El alineamiento de Milei con Israel no favorece a la Argentina&#187;","author":"","date":"junio 23, 2025","format":false,"excerpt":"In\u00e9s Capdevila, secretaria de redacci\u00f3n de La Naci\u00f3n, convers\u00f3 este lunes en La Ma\u00f1ana de CNN con Nacho Gir\u00f3n y expres\u00f3 que \u201cestamos lejos de un conflicto global\u201d a partir de la intervenci\u00f3n de Estados Unidos en la Guerra de Medio Oriente. Adem\u00e1s, se\u00f1al\u00f3 que \u201cel alineamiento total de Javier\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1448091,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/14\/paises-latinoamericanos-reaccionan-al-ataque-de-iran-a-israel-orix\/","url_meta":{"origin":1463771,"position":2},"title":"Pa\u00edses latinoamericanos expresan preocupaci\u00f3n tras ataque de Ir\u00e1n a Israel","author":"","date":"abril 14, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) --\u00a0 Tras el ataque con drones por parte de Ir\u00e1n a Israel e ls\u00e1bado, varios pa\u00edses latinoamericanos expresaron preocupaci\u00f3n por la situaci\u00f3n general en Medio Oriente. Estas son algunas reacciones.Chile: \u201cExpresamos nuestra preocupaci\u00f3n por la grave escalada de tensiones en Medio Oriente y los ataques iran\u00edes contra Israel.\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1471756,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/28\/reaccion-gobiernos-ataques-iran-seguridad-orix\/","url_meta":{"origin":1463771,"position":3},"title":"Gobiernos en Latinoam\u00e9rica expresan preocupaci\u00f3n por los ataques contra Ir\u00e1n y elevan la seguridad","author":"","date":"febrero 28, 2026","format":false,"excerpt":"Gobiernos y l\u00edderes de Am\u00e9rica Latina reaccionaron con preocupaci\u00f3n a los ataques de Estados Unidos e Israel contra Ir\u00e1n que comenzaron este s\u00e1bado. Algunos de ellos est\u00e1n en tensi\u00f3n con el Gobierno del presidente Donald Trump, como Cuba; otros se cuentan entre sus aliados, como Argentina, y otros se han\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472763,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/04\/01\/guardia-revolucionaria-irani-organizacion-terrorista-presion-trump-efe\/","url_meta":{"origin":1463771,"position":4},"title":"En l\u00ednea con la presi\u00f3n de Trump, Argentina designa a la Guardia Revolucionaria iran\u00ed como organizaci\u00f3n terrorista","author":"","date":"abril 1, 2026","format":false,"excerpt":"El Gobierno del presidente de Argentina, Javier Milei, declar\u00f3 el martes a la Guardia Revolucionaria de Ir\u00e1n como grupo terrorista, una decisi\u00f3n que, explic\u00f3, \u201cse fundamenta en informes oficiales que acreditan actividades il\u00edcitas de car\u00e1cter transnacional, incluyendo actos de terrorismo en suelo argentino\u201d.\u201cLa Oficina del presidente informa que el Gobierno\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1447932,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/04\/10\/javier-milei-embajador-de-la-luz-orix\/","url_meta":{"origin":1463771,"position":5},"title":"\u201cEmbajadores internacionales de la luz\u201d, \u00bfqu\u00e9 significa el reconocimiento a Javier Milei y su hermana Karina?","author":"","date":"abril 10, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- El presidente de Argentina, Javier Milei, y su hermana y secretaria general de la presidencia, Karina Milei, recibir\u00e1n este mi\u00e9rcoles la distinci\u00f3n \u201cEmbajadores Internacionales de la Luz\u201d. \u00bfDe qu\u00e9 se trata este reconocimiento?Los hermanos Milei viajaron el martes en la noche en la aerol\u00ednea de bandera Aerol\u00edneas\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463771","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1463771"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463771\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1463771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1463771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1463771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}