{"id":1463780,"date":"2025-06-20T10:03:46","date_gmt":"2025-06-20T17:03:46","guid":{"rendered":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/"},"modified":"2025-06-20T10:03:46","modified_gmt":"2025-06-20T17:03:46","slug":"panama-venezuela-restablecer-relaciones-consulares-orix","status":"publish","type":"post","link":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","title":{"rendered":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o"},"content":{"rendered":"<p>Los Gobiernos de Venezuela y Panam\u00e1 acordaron reactivar en los pr\u00f3ximos d\u00edas los servicios consulares en Caracas y en Ciudad de Panam\u00e1, que estaban suspendidos desde hace casi un a\u00f1o, informaron este jueves en un comunicado.<\/p>\n<p>En la nota de prensa difundida en la p\u00e1gina web de la Canciller\u00eda de Panam\u00e1, se explica que la decisi\u00f3n se tom\u00f3 \u201cante la imperiosa necesidad de atender los asuntos consulares de sus nacionales\u201d.<\/p>\n<p>Aunque no se especific\u00f3 la fecha de reanudaci\u00f3n de los servicios, el comunicado sostiene que \u201cesta medida tiene como objetivo prioritario brindar asistencia y protecci\u00f3n a las comunidades paname\u00f1as y venezolanas residentes en ambos pa\u00edses\u201d.<\/p>\n<p>CNN contact\u00f3 a la Canciller\u00eda de Panam\u00e1 para preguntarle si esta medida significa un probable restablecimiento de las relaciones diplom\u00e1ticas, pero aseguraron que solo implica a los servicios consulares. CNN tambi\u00e9n se comunic\u00f3 con la Canciller\u00eda de Venezuela para saber su posici\u00f3n sobre el mismo tema, pero hasta ahora no ha obtenido respuesta.<\/p>\n<p>El presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, anunci\u00f3 el 29 de julio de 2024 el retiro de su personal diplom\u00e1tico en Venezuela y que las relaciones con ese pa\u00eds quedaban en suspenso \u201chasta que se pusiera en marcha un sistema institucional, transparente y confiable\u201d.<\/p>\n<p>En ese momento, el reclamo era por el conteo de votos de las elecciones presidenciales en Venezuela, celebradas el domingo 28 de julio de 2024, y que dieron como ganador a Nicol\u00e1s Maduro en medio de cr\u00edticas de opositores y observadores y sin que hasta la fecha las autoridades den a conocer los n\u00fameros detallados de votos por centros y mesas de votaci\u00f3n.<\/p>\n<p>A fines de mayo, el presidente de Panam\u00e1, Jos\u00e9 Ra\u00fal Mulino, anunci\u00f3 en su conferencia de prensa semanal <a href=\"https:\/\/cnnespanol.cnn.com\/2025\/05\/22\/latinoamerica\/panama-reanudacion-vuelos-venezuela-orix\">el reinicio de las operaciones a\u00e9reas con Venezuela.<\/a><\/p>\n<p>\u201cLa reanudaci\u00f3n de los vuelos entre Panam\u00e1 y Venezuela se realizar\u00e1 bajo el principio de reciprocidad\u201d, se indic\u00f3 en aquella ocasi\u00f3n, en un comunicado la Autoridad Aeron\u00e1utica Civil de Panam\u00e1.<\/p>\n<p>The-CNN-Wire<br \/>&trade; &amp; &copy; 2025 Cable News Network, Inc., a Warner Bros. Discovery Company. All rights reserved.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los Gobiernos de Venezuela y Panam\u00e1 acordaron reactivar en los pr\u00f3ximos d\u00edas los servicios consulares en Caracas y en Ciudad de Panam\u00e1, que estaban suspendidos desde hace casi un a\u00f1o, informaron este jueves en un comunicado. En la nota de prensa difundida en la p\u00e1gina web de la Canciller\u00eda de Panam\u00e1, se explica que la [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[10],"tags":[],"class_list":["post-1463780","post","type-post","status-publish","format-standard","hentry","category-noticias-nacionales","market-global"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o - Noticias<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o - Noticias\" \/>\n<meta property=\"og:description\" content=\"Los Gobiernos de Venezuela y Panam\u00e1 acordaron reactivar en los pr\u00f3ximos d\u00edas los servicios consulares en Caracas y en Ciudad de Panam\u00e1, que estaban suspendidos desde hace casi un a\u00f1o, informaron este jueves en un comunicado. En la nota de prensa difundida en la p\u00e1gina web de la Canciller\u00eda de Panam\u00e1, se explica que la [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\" \/>\n<meta property=\"og:site_name\" content=\"Noticias\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-20T17:03:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\"},\"author\":{\"name\":\"\",\"@id\":\"\"},\"headline\":\"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o\",\"datePublished\":\"2025-06-20T17:03:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\"},\"wordCount\":375,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"articleSection\":[\"Noticias Nacionales\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\",\"url\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\",\"name\":\"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o - Noticias\",\"isPartOf\":{\"@id\":\"https:\/\/noticiasya.com\/#website\"},\"datePublished\":\"2025-06-20T17:03:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/noticiasya.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/noticiasya.com\/#website\",\"url\":\"https:\/\/noticiasya.com\/\",\"name\":\"Noticias\",\"description\":\"Lo que importa\",\"publisher\":{\"@id\":\"https:\/\/noticiasya.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/noticiasya.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/noticiasya.com\/#organization\",\"name\":\"Noticias\",\"url\":\"https:\/\/noticiasya.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"contentUrl\":\"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png\",\"width\":1801,\"height\":691,\"caption\":\"Noticias\"},\"image\":{\"@id\":\"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o - Noticias","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","og_locale":"es_ES","og_type":"article","og_title":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o - Noticias","og_description":"Los Gobiernos de Venezuela y Panam\u00e1 acordaron reactivar en los pr\u00f3ximos d\u00edas los servicios consulares en Caracas y en Ciudad de Panam\u00e1, que estaban suspendidos desde hace casi un a\u00f1o, informaron este jueves en un comunicado. En la nota de prensa difundida en la p\u00e1gina web de la Canciller\u00eda de Panam\u00e1, se explica que la [&hellip;]","og_url":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","og_site_name":"Noticias","article_published_time":"2025-06-20T17:03:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#article","isPartOf":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/"},"author":{"name":"","@id":""},"headline":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o","datePublished":"2025-06-20T17:03:46+00:00","mainEntityOfPage":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/"},"wordCount":375,"commentCount":0,"publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"articleSection":["Noticias Nacionales"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","url":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","name":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o - Noticias","isPartOf":{"@id":"https:\/\/noticiasya.com\/#website"},"datePublished":"2025-06-20T17:03:46+00:00","breadcrumb":{"@id":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/noticiasya.com\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/noticiasya.com\/"},{"@type":"ListItem","position":2,"name":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o"}]},{"@type":"WebSite","@id":"https:\/\/noticiasya.com\/#website","url":"https:\/\/noticiasya.com\/","name":"Noticias","description":"Lo que importa","publisher":{"@id":"https:\/\/noticiasya.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/noticiasya.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/noticiasya.com\/#organization","name":"Noticias","url":"https:\/\/noticiasya.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/","url":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","contentUrl":"https:\/\/noticiasya.com\/wp-content\/uploads\/sites\/22\/2023\/12\/logo-nacional.png","width":1801,"height":691,"caption":"Noticias"},"image":{"@id":"https:\/\/noticiasya.com\/#\/schema\/logo\/image\/"}}]}},"parsely":{"version":"1.1.0","canonical_url":"https:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","smart_links":{"inbound":0,"outbound":0},"traffic_boost_suggestions_count":0,"meta":{"@context":"https:\/\/schema.org","@type":"NewsArticle","headline":"Gobiernos de Panam\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\u00f1o","url":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/","mainEntityOfPage":{"@type":"WebPage","@id":"http:\/\/noticiasya.com\/costa-central\/2025\/06\/20\/panama-venezuela-restablecer-relaciones-consulares-orix\/"},"thumbnailUrl":"","image":{"@type":"ImageObject","url":""},"articleSection":"Noticias Nacionales","author":[],"creator":[],"publisher":{"@type":"Organization","name":"Noticias","logo":""},"keywords":[],"dateCreated":"2025-06-20T17:03:46Z","datePublished":"2025-06-20T17:03:46Z","dateModified":"2025-06-20T17:03:46Z"},"rendered":"<script type=\"application\/ld+json\" class=\"wp-parsely-metadata\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"NewsArticle\",\"headline\":\"Gobiernos de Panam\\u00e1 y Venezuela acuerdan reactivar relaciones consulares suspendidas hace casi un a\\u00f1o\",\"url\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/panama-venezuela-restablecer-relaciones-consulares-orix\\\/\",\"mainEntityOfPage\":{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/noticiasya.com\\\/costa-central\\\/2025\\\/06\\\/20\\\/panama-venezuela-restablecer-relaciones-consulares-orix\\\/\"},\"thumbnailUrl\":\"\",\"image\":{\"@type\":\"ImageObject\",\"url\":\"\"},\"articleSection\":\"Noticias Nacionales\",\"author\":[],\"creator\":[],\"publisher\":{\"@type\":\"Organization\",\"name\":\"Noticias\",\"logo\":\"\"},\"keywords\":[],\"dateCreated\":\"2025-06-20T17:03:46Z\",\"datePublished\":\"2025-06-20T17:03:46Z\",\"dateModified\":\"2025-06-20T17:03:46Z\"}<\/script>","tracker_url":"https:\/\/cdn.parsely.com\/keys\/noticiasya.com\/p.js"},"jetpack_featured_media_url":"","jetpack-related-posts":[{"id":1471614,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/02\/24\/denuncian-panama-presunta-apertura-valija-diplomatica-prix\/","url_meta":{"origin":1463780,"position":0},"title":"Venezuela denuncia que autoridades de Panam\u00e1 presuntamente forzaron la apertura de una valija diplom\u00e1tica","author":"","date":"febrero 24, 2026","format":false,"excerpt":"El gobierno de Venezuela denunci\u00f3 este martes que autoridades de Panam\u00e1 presuntamente forzaron la apertura de una valija diplom\u00e1tica, una situaci\u00f3n que Caracas describi\u00f3 como un \u201catropello\u201d que viola \u201cun principio esencial para la convivencia entre naciones\u201d.Los hechos ocurrieron en el Aeropuerto Internacional de Tocumen en Ciudad de Panam\u00e1, la\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1472693,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/03\/30\/eeuu-reabre-embajada-caracas-orix\/","url_meta":{"origin":1463780,"position":1},"title":"Estados Unidos anunci\u00f3 que reanuda operaciones de su Embajada en Caracas","author":"","date":"marzo 30, 2026","format":false,"excerpt":"El Departamento de Estado de EE.UU. anunci\u00f3 este lunes la reanudaci\u00f3n de las operaciones de su embajada en Caracas, como parte del restablecimiento de las relaciones diplom\u00e1ticas que estaban rotas desde 2019.La medida parece tener un car\u00e1cter principalmente simb\u00f3lico. Seg\u00fan la nota de prensa del Departamento de Estado de EE.UU.,\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1464318,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/07\/08\/autoridad-maritima-panama-asistencia-tripulacion-buque-detenido-venezuela-orix\/","url_meta":{"origin":1463780,"position":2},"title":"Autoridad Mar\u00edtima de Panam\u00e1 dice que gestiona asistencia a tripulaci\u00f3n de buque detenido en Venezuela","author":"","date":"julio 8, 2025","format":false,"excerpt":"La Autoridad Mar\u00edtima de Panam\u00e1 (AMP) asegur\u00f3 este lunes que est\u00e1n tomando medidas para salvaguardar los derechos laborales de los nueve tripulantes de diversas nacionalidades del buque de bandera paname\u00f1a N35, detenido el 13 de junio por la Armada venezolana.Dicha nave \u201cfue detectada navegando en un \u00e1rea mar\u00edtima restringida y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1449416,"url":"https:\/\/noticiasya.com\/costa-central\/2024\/05\/12\/ecuatorianos-mexico-tramites-servicios-consulares-guatemala-ee-uu-orix\/","url_meta":{"origin":1463780,"position":3},"title":"Ecuatorianos en M\u00e9xico podr\u00e1n realizar tr\u00e1mites a trav\u00e9s de servicios consulares en Guatemala y EE.UU.","author":"","date":"mayo 12, 2024","format":false,"excerpt":"(CNN Espa\u00f1ol) -- La Canciller\u00eda de Ecuador anunci\u00f3 el s\u00e1bado una nueva disposici\u00f3n para tr\u00e1mites consulares de ecuatorianos en M\u00e9xico.En un comunicado difundido en la red social X (antes Twitter), la Canciller\u00eda detall\u00f3 que, a partir del 16 de mayo, los servicios de sus consulados en Ciudad de M\u00e9xico y\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1458087,"url":"https:\/\/noticiasya.com\/costa-central\/2025\/01\/31\/cese-servicios-consulados-chilenos-caracas-puerto-ordaz-orix\/","url_meta":{"origin":1463780,"position":4},"title":"Venezuela pide el cese de servicios de los consulados chilenos en Caracas y Puerto Ordaz","author":"","date":"enero 31, 2025","format":false,"excerpt":"La Canciller\u00eda de Venezuela solicit\u00f3 que los consulados de Chile en Caracas y Puerto Ordaz \u201ccesen sus servicios consulares como consecuencia de la suspensi\u00f3n de las relaciones diplom\u00e1ticas entre ambos pa\u00edses\u201d, inform\u00f3 este viernes la Canciller\u00eda chilena. Ambos consulados tendr\u00e1n que permanecer cerrados y sin atenci\u00f3n al p\u00fablico.\u201cEl Gobierno de\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1470047,"url":"https:\/\/noticiasya.com\/costa-central\/2026\/01\/13\/eeuu-panama-rubio-venezuela-orix\/","url_meta":{"origin":1463780,"position":5},"title":"EE.UU. y Panam\u00e1 destacan su &#171;s\u00f3lida alianza&#187; y los esfuerzos regionales para &#171;promover la estabilidad en Venezuela&#187;","author":"","date":"enero 13, 2026","format":false,"excerpt":"El ministro de Relaciones Exteriores de Panam\u00e1, Javier Mart\u00ednez-Acha, se reuni\u00f3 este martes con el secretario de Estado de EE.UU., Marco Rubio, en Washington, donde hablaron sobre la cooperaci\u00f3n en temas de seguridad, lucha contra el crimen organizado, migraci\u00f3n y proyectos de inversi\u00f3n, en el contexto de la crisis en\u2026","rel":"","context":"In &quot;Noticias Nacionales&quot;","block_context":{"text":"Noticias Nacionales","link":"https:\/\/noticiasya.com\/costa-central\/categoria\/noticias-nacionales"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/types\/post"}],"replies":[{"embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/comments?post=1463780"}],"version-history":[{"count":0,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/posts\/1463780\/revisions"}],"wp:attachment":[{"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/media?parent=1463780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/categories?post=1463780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/noticiasya.com\/costa-central\/wp-json\/wp\/v2\/tags?post=1463780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}